{"id":7993,"date":"2024-10-10T09:12:55","date_gmt":"2024-10-10T13:12:55","guid":{"rendered":"https:\/\/folhadems.com.br\/site\/?p=7993"},"modified":"2024-10-10T09:13:12","modified_gmt":"2024-10-10T13:13:12","slug":"festival-de-praia-2024-coxim-sedia-penultima-etapa-com-atividades-de-esporte-e-lazer-neste-fim-de-semana","status":"publish","type":"post","link":"https:\/\/folhadems.com.br\/site\/2024\/10\/10\/festival-de-praia-2024-coxim-sedia-penultima-etapa-com-atividades-de-esporte-e-lazer-neste-fim-de-semana\/","title":{"rendered":"Festival de Praia 2024: Coxim sedia pen\u00faltima etapa com atividades de esporte e lazer neste fim de semana"},"content":{"rendered":"\n<p>A pen\u00faltima etapa do Festival de Praia 2024 ser\u00e1 realizada em Coxim neste fim de semana, nos dias 12 e 13 de outubro, na Pra\u00e7a do Flutuante. O evento contar\u00e1 com competi\u00e7\u00f5es de beach tennis, futev\u00f4lei, v\u00f4lei de praia e diversas atividades de lazer. A organiza\u00e7\u00e3o \u00e9 do Governo de Mato Grosso do Sul, por meio da Fundesporte (Funda\u00e7\u00e3o de Desporto e Lazer) e da Setesc (Secretaria de Estado de Turismo, Esporte e Cultura).<\/p>\n\n\n\n<p>Al\u00e9m das competi\u00e7\u00f5es esportivas, o festival oferecer\u00e1 uma \u00e1rea de lazer com atividades como pintura facial, brinquedos infl\u00e1veis e brinquedoteca. Durante o evento, tamb\u00e9m ser\u00e3o promovidas a\u00e7\u00f5es do projeto de lazer &#8220;Intergeracionalidade&#8221;, que busca oferecer atividades voltadas para idosos, como jogos de mesa, malha e bocha, incentivando a participa\u00e7\u00e3o conjunta de idosos e suas fam\u00edlias.<\/p>\n\n\n\n<p>O secret\u00e1rio de Estado de Turismo, Esporte e Cultura, Marcelo Miranda, destacou a import\u00e2ncia do festival para a regi\u00e3o. &#8220;O Festival de Praia em Coxim tem como objetivo impulsionar o turismo e fortalecer a economia local. Al\u00e9m de proporcionar entretenimento e atividades esportivas, o evento contribui para divulgar as modalidades de areia e atrair visitantes para nossas cidades em Mato Grosso do Sul&#8221;, afirmou o secret\u00e1rio.<\/p>\n\n\n\n<p>J\u00e1 o diretor-presidente da Fundesporte, Paulo Ricardo Nu\u00f1ez, ressaltou que o evento \u00e9 uma oportunidade de valorizar os esportes de areia no estado. &#8220;As modalidades de areia v\u00eam crescendo e ganhando visibilidade, e \u00e9 por isso que a Fundesporte se empenha em realizar eventos como este, tornando esses esportes ainda mais acess\u00edveis para todos&#8221;, disse Nu\u00f1ez.<\/p>\n\n\n\n<p>As inscri\u00e7\u00f5es para as competi\u00e7\u00f5es podem ser feitas no local do evento ou nos sites das federa\u00e7\u00f5es de beach tennis, futev\u00f4lei e v\u00f4lei de praia. A \u00faltima etapa do Festival de Praia 2024 est\u00e1 marcada para os dias 16 e 17 de novembro, em Aparecida do Taboado.<\/p>\n\n\n\n<p><strong>Servi\u00e7o<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Evento: <\/strong>Festival de Praia\u00a0<\/li>\n\n\n\n<li><strong>Data:<\/strong> 12 e 13 de outubro (s\u00e1bado e domingo)<\/li>\n\n\n\n<li><strong>Local:<\/strong> Pra\u00e7a do Flutuante &#8211; R. Cel. Ponce, 41 &#8211; Centro, Coxim (MS)<\/li>\n\n\n\n<li><strong>Hor\u00e1rios:<\/strong>\n<ul class=\"wp-block-list\">\n<li>S\u00e1bado: 8h \u00e0s 17h<\/li>\n\n\n\n<li>Domingo: 8h \u00e0s 12h<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n\n\n\n<p><em>Bel Manvailer, Comunica\u00e7\u00e3o Setesc<br>Foto: arquivo\/Fundesporte<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A pen\u00faltima etapa do Festival de Praia 2024 ser\u00e1 realizada em Coxim neste fim de semana, nos dias 12 e<\/p>\n","protected":false},"author":1,"featured_media":7994,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":["post-7993","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-esportes"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.1.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Festival de Praia 2024: Coxim sedia pen\u00faltima etapa com atividades de esporte e lazer neste fim de semana - Folha de Mato Grosso do Sul<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/folhadems.com.br\/site\/2024\/10\/10\/festival-de-praia-2024-coxim-sedia-penultima-etapa-com-atividades-de-esporte-e-lazer-neste-fim-de-semana\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Festival de Praia 2024: Coxim sedia pen\u00faltima etapa com atividades de esporte e lazer neste fim de semana - Folha de Mato Grosso do Sul\" \/>\n<meta property=\"og:description\" content=\"A pen\u00faltima etapa do Festival de Praia 2024 ser\u00e1 realizada em Coxim neste fim de semana, nos dias 12 e\" \/>\n<meta property=\"og:url\" content=\"https:\/\/folhadems.com.br\/site\/2024\/10\/10\/festival-de-praia-2024-coxim-sedia-penultima-etapa-com-atividades-de-esporte-e-lazer-neste-fim-de-semana\/\" \/>\n<meta property=\"og:site_name\" content=\"Folha de Mato Grosso do Sul\" \/>\n<meta property=\"article:published_time\" content=\"2024-10-10T13:12:55+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-10-10T13:13:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2024\/10\/volei1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"450\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Elite Midia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Elite Midia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/folhadems.com.br\/site\/2024\/10\/10\/festival-de-praia-2024-coxim-sedia-penultima-etapa-com-atividades-de-esporte-e-lazer-neste-fim-de-semana\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/folhadems.com.br\/site\/2024\/10\/10\/festival-de-praia-2024-coxim-sedia-penultima-etapa-com-atividades-de-esporte-e-lazer-neste-fim-de-semana\/\"},\"author\":{\"name\":\"Elite Midia\",\"@id\":\"https:\/\/folhadems.com.br\/site\/#\/schema\/person\/e4a04038e5c2e7040e19ef252ae9d940\"},\"headline\":\"Festival de Praia 2024: Coxim sedia pen\u00faltima etapa com atividades de esporte e lazer neste fim de semana\",\"datePublished\":\"2024-10-10T13:12:55+00:00\",\"dateModified\":\"2024-10-10T13:13:12+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/folhadems.com.br\/site\/2024\/10\/10\/festival-de-praia-2024-coxim-sedia-penultima-etapa-com-atividades-de-esporte-e-lazer-neste-fim-de-semana\/\"},\"wordCount\":381,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/folhadems.com.br\/site\/#organization\"},\"image\":{\"@id\":\"https:\/\/folhadems.com.br\/site\/2024\/10\/10\/festival-de-praia-2024-coxim-sedia-penultima-etapa-com-atividades-de-esporte-e-lazer-neste-fim-de-semana\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2024\/10\/volei1.jpg\",\"articleSection\":[\"Esportes\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/folhadems.com.br\/site\/2024\/10\/10\/festival-de-praia-2024-coxim-sedia-penultima-etapa-com-atividades-de-esporte-e-lazer-neste-fim-de-semana\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/folhadems.com.br\/site\/2024\/10\/10\/festival-de-praia-2024-coxim-sedia-penultima-etapa-com-atividades-de-esporte-e-lazer-neste-fim-de-semana\/\",\"url\":\"https:\/\/folhadems.com.br\/site\/2024\/10\/10\/festival-de-praia-2024-coxim-sedia-penultima-etapa-com-atividades-de-esporte-e-lazer-neste-fim-de-semana\/\",\"name\":\"Festival de Praia 2024: Coxim sedia pen\u00faltima etapa com atividades de esporte e lazer neste fim de semana - Folha de Mato Grosso do Sul\",\"isPartOf\":{\"@id\":\"https:\/\/folhadems.com.br\/site\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/folhadems.com.br\/site\/2024\/10\/10\/festival-de-praia-2024-coxim-sedia-penultima-etapa-com-atividades-de-esporte-e-lazer-neste-fim-de-semana\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/folhadems.com.br\/site\/2024\/10\/10\/festival-de-praia-2024-coxim-sedia-penultima-etapa-com-atividades-de-esporte-e-lazer-neste-fim-de-semana\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2024\/10\/volei1.jpg\",\"datePublished\":\"2024-10-10T13:12:55+00:00\",\"dateModified\":\"2024-10-10T13:13:12+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/folhadems.com.br\/site\/2024\/10\/10\/festival-de-praia-2024-coxim-sedia-penultima-etapa-com-atividades-de-esporte-e-lazer-neste-fim-de-semana\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/folhadems.com.br\/site\/2024\/10\/10\/festival-de-praia-2024-coxim-sedia-penultima-etapa-com-atividades-de-esporte-e-lazer-neste-fim-de-semana\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/folhadems.com.br\/site\/2024\/10\/10\/festival-de-praia-2024-coxim-sedia-penultima-etapa-com-atividades-de-esporte-e-lazer-neste-fim-de-semana\/#primaryimage\",\"url\":\"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2024\/10\/volei1.jpg\",\"contentUrl\":\"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2024\/10\/volei1.jpg\",\"width\":800,\"height\":450},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/folhadems.com.br\/site\/2024\/10\/10\/festival-de-praia-2024-coxim-sedia-penultima-etapa-com-atividades-de-esporte-e-lazer-neste-fim-de-semana\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/folhadems.com.br\/site\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Festival de Praia 2024: Coxim sedia pen\u00faltima etapa com atividades de esporte e lazer neste fim de semana\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/folhadems.com.br\/site\/#website\",\"url\":\"https:\/\/folhadems.com.br\/site\/\",\"name\":\"Folha de Mato Grosso do Sul\",\"description\":\"Jornal Online\",\"publisher\":{\"@id\":\"https:\/\/folhadems.com.br\/site\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/folhadems.com.br\/site\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/folhadems.com.br\/site\/#organization\",\"name\":\"Folha de Mato Grosso do Sul\",\"url\":\"https:\/\/folhadems.com.br\/site\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/folhadems.com.br\/site\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2023\/01\/logo-folha-de-ms-380x90-1.jpg\",\"contentUrl\":\"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2023\/01\/logo-folha-de-ms-380x90-1.jpg\",\"width\":380,\"height\":90,\"caption\":\"Folha de Mato Grosso do Sul\"},\"image\":{\"@id\":\"https:\/\/folhadems.com.br\/site\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/folhadems.com.br\/site\/#\/schema\/person\/e4a04038e5c2e7040e19ef252ae9d940\",\"name\":\"Elite Midia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/folhadems.com.br\/site\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/f76a80f01119f7fec6909ab9feea8819031f391155be021b685479d77496f055?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/f76a80f01119f7fec6909ab9feea8819031f391155be021b685479d77496f055?s=96&d=mm&r=g\",\"caption\":\"Elite Midia\"},\"sameAs\":[\"https:\/\/folhadems.com.br\/site\"],\"url\":\"https:\/\/folhadems.com.br\/site\/author\/elite-midia\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Festival de Praia 2024: Coxim sedia pen\u00faltima etapa com atividades de esporte e lazer neste fim de semana - Folha de Mato Grosso do Sul","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/folhadems.com.br\/site\/2024\/10\/10\/festival-de-praia-2024-coxim-sedia-penultima-etapa-com-atividades-de-esporte-e-lazer-neste-fim-de-semana\/","og_locale":"pt_BR","og_type":"article","og_title":"Festival de Praia 2024: Coxim sedia pen\u00faltima etapa com atividades de esporte e lazer neste fim de semana - Folha de Mato Grosso do Sul","og_description":"A pen\u00faltima etapa do Festival de Praia 2024 ser\u00e1 realizada em Coxim neste fim de semana, nos dias 12 e","og_url":"https:\/\/folhadems.com.br\/site\/2024\/10\/10\/festival-de-praia-2024-coxim-sedia-penultima-etapa-com-atividades-de-esporte-e-lazer-neste-fim-de-semana\/","og_site_name":"Folha de Mato Grosso do Sul","article_published_time":"2024-10-10T13:12:55+00:00","article_modified_time":"2024-10-10T13:13:12+00:00","og_image":[{"width":800,"height":450,"url":"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2024\/10\/volei1.jpg","type":"image\/jpeg"}],"author":"Elite Midia","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Elite Midia","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/folhadems.com.br\/site\/2024\/10\/10\/festival-de-praia-2024-coxim-sedia-penultima-etapa-com-atividades-de-esporte-e-lazer-neste-fim-de-semana\/#article","isPartOf":{"@id":"https:\/\/folhadems.com.br\/site\/2024\/10\/10\/festival-de-praia-2024-coxim-sedia-penultima-etapa-com-atividades-de-esporte-e-lazer-neste-fim-de-semana\/"},"author":{"name":"Elite Midia","@id":"https:\/\/folhadems.com.br\/site\/#\/schema\/person\/e4a04038e5c2e7040e19ef252ae9d940"},"headline":"Festival de Praia 2024: Coxim sedia pen\u00faltima etapa com atividades de esporte e lazer neste fim de semana","datePublished":"2024-10-10T13:12:55+00:00","dateModified":"2024-10-10T13:13:12+00:00","mainEntityOfPage":{"@id":"https:\/\/folhadems.com.br\/site\/2024\/10\/10\/festival-de-praia-2024-coxim-sedia-penultima-etapa-com-atividades-de-esporte-e-lazer-neste-fim-de-semana\/"},"wordCount":381,"commentCount":0,"publisher":{"@id":"https:\/\/folhadems.com.br\/site\/#organization"},"image":{"@id":"https:\/\/folhadems.com.br\/site\/2024\/10\/10\/festival-de-praia-2024-coxim-sedia-penultima-etapa-com-atividades-de-esporte-e-lazer-neste-fim-de-semana\/#primaryimage"},"thumbnailUrl":"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2024\/10\/volei1.jpg","articleSection":["Esportes"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/folhadems.com.br\/site\/2024\/10\/10\/festival-de-praia-2024-coxim-sedia-penultima-etapa-com-atividades-de-esporte-e-lazer-neste-fim-de-semana\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/folhadems.com.br\/site\/2024\/10\/10\/festival-de-praia-2024-coxim-sedia-penultima-etapa-com-atividades-de-esporte-e-lazer-neste-fim-de-semana\/","url":"https:\/\/folhadems.com.br\/site\/2024\/10\/10\/festival-de-praia-2024-coxim-sedia-penultima-etapa-com-atividades-de-esporte-e-lazer-neste-fim-de-semana\/","name":"Festival de Praia 2024: Coxim sedia pen\u00faltima etapa com atividades de esporte e lazer neste fim de semana - Folha de Mato Grosso do Sul","isPartOf":{"@id":"https:\/\/folhadems.com.br\/site\/#website"},"primaryImageOfPage":{"@id":"https:\/\/folhadems.com.br\/site\/2024\/10\/10\/festival-de-praia-2024-coxim-sedia-penultima-etapa-com-atividades-de-esporte-e-lazer-neste-fim-de-semana\/#primaryimage"},"image":{"@id":"https:\/\/folhadems.com.br\/site\/2024\/10\/10\/festival-de-praia-2024-coxim-sedia-penultima-etapa-com-atividades-de-esporte-e-lazer-neste-fim-de-semana\/#primaryimage"},"thumbnailUrl":"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2024\/10\/volei1.jpg","datePublished":"2024-10-10T13:12:55+00:00","dateModified":"2024-10-10T13:13:12+00:00","breadcrumb":{"@id":"https:\/\/folhadems.com.br\/site\/2024\/10\/10\/festival-de-praia-2024-coxim-sedia-penultima-etapa-com-atividades-de-esporte-e-lazer-neste-fim-de-semana\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/folhadems.com.br\/site\/2024\/10\/10\/festival-de-praia-2024-coxim-sedia-penultima-etapa-com-atividades-de-esporte-e-lazer-neste-fim-de-semana\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/folhadems.com.br\/site\/2024\/10\/10\/festival-de-praia-2024-coxim-sedia-penultima-etapa-com-atividades-de-esporte-e-lazer-neste-fim-de-semana\/#primaryimage","url":"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2024\/10\/volei1.jpg","contentUrl":"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2024\/10\/volei1.jpg","width":800,"height":450},{"@type":"BreadcrumbList","@id":"https:\/\/folhadems.com.br\/site\/2024\/10\/10\/festival-de-praia-2024-coxim-sedia-penultima-etapa-com-atividades-de-esporte-e-lazer-neste-fim-de-semana\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/folhadems.com.br\/site\/"},{"@type":"ListItem","position":2,"name":"Festival de Praia 2024: Coxim sedia pen\u00faltima etapa com atividades de esporte e lazer neste fim de semana"}]},{"@type":"WebSite","@id":"https:\/\/folhadems.com.br\/site\/#website","url":"https:\/\/folhadems.com.br\/site\/","name":"Folha de Mato Grosso do Sul","description":"Jornal Online","publisher":{"@id":"https:\/\/folhadems.com.br\/site\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/folhadems.com.br\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/folhadems.com.br\/site\/#organization","name":"Folha de Mato Grosso do Sul","url":"https:\/\/folhadems.com.br\/site\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/folhadems.com.br\/site\/#\/schema\/logo\/image\/","url":"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2023\/01\/logo-folha-de-ms-380x90-1.jpg","contentUrl":"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2023\/01\/logo-folha-de-ms-380x90-1.jpg","width":380,"height":90,"caption":"Folha de Mato Grosso do Sul"},"image":{"@id":"https:\/\/folhadems.com.br\/site\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/folhadems.com.br\/site\/#\/schema\/person\/e4a04038e5c2e7040e19ef252ae9d940","name":"Elite Midia","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/folhadems.com.br\/site\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/f76a80f01119f7fec6909ab9feea8819031f391155be021b685479d77496f055?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f76a80f01119f7fec6909ab9feea8819031f391155be021b685479d77496f055?s=96&d=mm&r=g","caption":"Elite Midia"},"sameAs":["https:\/\/folhadems.com.br\/site"],"url":"https:\/\/folhadems.com.br\/site\/author\/elite-midia\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-20 19:27:41","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/posts\/7993","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/comments?post=7993"}],"version-history":[{"count":1,"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/posts\/7993\/revisions"}],"predecessor-version":[{"id":7995,"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/posts\/7993\/revisions\/7995"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/media\/7994"}],"wp:attachment":[{"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/media?parent=7993"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/categories?post=7993"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/tags?post=7993"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}