{"id":5394,"date":"2024-03-03T10:39:18","date_gmt":"2024-03-03T14:39:18","guid":{"rendered":"https:\/\/folhadems.com.br\/site\/?p=5394"},"modified":"2024-03-03T10:39:21","modified_gmt":"2024-03-03T14:39:21","slug":"entenda-regras-do-tse-para-uso-de-inteligencia-artificial-nas-eleicoes","status":"publish","type":"post","link":"https:\/\/folhadems.com.br\/site\/2024\/03\/03\/entenda-regras-do-tse-para-uso-de-inteligencia-artificial-nas-eleicoes\/","title":{"rendered":"Entenda regras do TSE para uso de intelig\u00eancia artificial nas elei\u00e7\u00f5es"},"content":{"rendered":"\n<p>O Tribunal Superior Eleitoral (TSE) aprovou na \u00faltima ter\u00e7a-feira (27) as 12 resolu\u00e7\u00f5es eleitorais com as regras finais para a elei\u00e7\u00e3o municipal de outubro. O passo \u00e9 obrigat\u00f3rio e deve ser realizado at\u00e9 5 de mar\u00e7o, no ano do pleito.<img decoding=\"async\" src=\"https:\/\/agenciabrasil.ebc.com.br\/ebc.png?id=1583777&amp;o=node\"><img decoding=\"async\" src=\"https:\/\/agenciabrasil.ebc.com.br\/ebc.gif?id=1583777&amp;o=node\"><\/p>\n\n\n\n<p>Por meio desses normativos, os ministros do TSE buscam adaptar o processo eleitoral \u00e0s mudan\u00e7as na realidade, embora sempre limitados ao que prev\u00ea a legisla\u00e7\u00e3o eleitoral e a Constitui\u00e7\u00e3o.<\/p>\n\n\n\n<p>Com os avan\u00e7os tecnol\u00f3gicos cada vez mais r\u00e1pidos, neste ano foram alvo de preocupa\u00e7\u00e3o temas que na elei\u00e7\u00e3o anterior sequer estavam no radar. Um exemplo \u00e9 a intelig\u00eancia artificial (IA) e seu potencial de turbinar problemas j\u00e1 de dif\u00edcil controle, como as not\u00edcias falsas e a desinforma\u00e7\u00e3o sobre o processo eleitoral.<\/p>\n\n\n\n<p>Diante da in\u00e9rcia do Congresso em regulamentar o tema, a Justi\u00e7a Eleitoral <a href=\"https:\/\/agenciabrasil.ebc.com.br\/justica\/noticia\/2024-02\/tse-define-regras-para-inteligencia-artificial-nas-eleicoes-de-outubro\" target=\"_blank\" rel=\"noreferrer noopener\">decidiu colocar balizas ao uso da IA nas elei\u00e7\u00f5es<\/a>, de modo a tentar proteger a decis\u00e3o bem informada do eleitor.<\/p>\n\n\n\n<p>As medidas foram bem recebidas pela comunidade jur\u00eddica, que viu na iniciativa uma tentativa de adequar o tempo mais lento da cria\u00e7\u00e3o de normas \u00e0 velocidade acelerada das atualiza\u00e7\u00f5es tecnol\u00f3gicas.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>\u201c\u00c9 uma corrida cont\u00ednua, onde a tecnologia, os m\u00e9todos de manipula\u00e7\u00e3o, evoluem exponencialmente, ent\u00e3o as estrat\u00e9gias de defesa devem ser igualmente din\u00e2micas\u201d, ressalta o advogado Alexander Coelho, especialista em direito digital e prote\u00e7\u00e3o de dados.<\/p>\n<\/blockquote>\n\n\n\n<p>H\u00e1 d\u00favidas sobre a efic\u00e1cia das regras ante manipula\u00e7\u00f5es cada vez mais realistas, mas a avalia\u00e7\u00e3o \u00e9 que, uma vez havendo normas, fica mais f\u00e1cil outros atores sociais auxiliarem a Justi\u00e7a Eleitoral na fiscaliza\u00e7\u00e3o das campanhas.<\/p>\n\n\n\n<p>\u201cMuitos casos v\u00e3o chegar \u00e0 Justi\u00e7a por meio dos advogados dos candidatos e partidos\u201d, aposta o professor e advogado Renato Ribeiro de Almeida, coordenador acad\u00eamico da Associa\u00e7\u00e3o Brasileira de Direito Eleitoral e Pol\u00edtico (Abradep). \u201cCom certeza teremos elei\u00e7\u00f5es muito judicializadas, seguindo a tend\u00eancia de pleitos anteriores\u201d, acrescenta.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Confira abaixo as regras aprovadas pelo TSE sobre o uso de intelig\u00eancia artificial nas elei\u00e7\u00f5es:&nbsp;<\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Exig\u00eancia de r\u00f3tulos de identifica\u00e7\u00e3o de conte\u00fado multim\u00eddia fabricado \u2013&nbsp;qualquer material visual feito por meio de intelig\u00eancia artificial dever\u00e1 trazer o aviso expl\u00edcito sobre o uso da tecnologia;<\/li>\n\n\n\n<li>Restri\u00e7\u00e3o ao uso de <em>chatbots<\/em> e avatares para intermediar a comunica\u00e7\u00e3o da campanha \u2013&nbsp;fica proibido simular conversas com o candidato ou outro avatar que aparente ser uma pessoa real;&nbsp;<\/li>\n\n\n\n<li>Veda\u00e7\u00e3o absoluta, seja contra ou a favor de candidato, do uso de <em>deep fake<\/em>&nbsp;\u2013&nbsp;conte\u00fado fabricado em formato de \u00e1udio, v\u00eddeo ou combina\u00e7\u00e3o de ambos e que tenha sido gerado ou manipulado digitalmente para criar, substituir ou alterar imagem ou voz de pessoa viva, falecida ou fict\u00edcia;&nbsp;<\/li>\n\n\n\n<li>Paralelamente, os provedores de aplica\u00e7\u00f5es na internet (redes sociais e aplicativos de mensagem, por exemplo) ficam obrigados a retirar do ar, sem a necessidade de ordem judicial, contas e materiais que promovam condutas e atos antidemocr\u00e1ticos e tamb\u00e9m discursos de \u00f3dio, como racismo, homofobia, fascismo e qualquer tipo de preconceito.<\/li>\n<\/ul>\n\n\n\n<p><strong><em>Fonte: Ag\u00eancia Brasil<\/em><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Tribunal Superior Eleitoral (TSE) aprovou na \u00faltima ter\u00e7a-feira (27) as 12 resolu\u00e7\u00f5es eleitorais com as regras finais para a<\/p>\n","protected":false},"author":1,"featured_media":5395,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[16],"tags":[],"class_list":["post-5394","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-justica"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.1.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Entenda regras do TSE para uso de intelig\u00eancia artificial nas elei\u00e7\u00f5es - Folha de Mato Grosso do Sul<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/folhadems.com.br\/site\/2024\/03\/03\/entenda-regras-do-tse-para-uso-de-inteligencia-artificial-nas-eleicoes\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Entenda regras do TSE para uso de intelig\u00eancia artificial nas elei\u00e7\u00f5es - Folha de Mato Grosso do Sul\" \/>\n<meta property=\"og:description\" content=\"O Tribunal Superior Eleitoral (TSE) aprovou na \u00faltima ter\u00e7a-feira (27) as 12 resolu\u00e7\u00f5es eleitorais com as regras finais para a\" \/>\n<meta property=\"og:url\" content=\"https:\/\/folhadems.com.br\/site\/2024\/03\/03\/entenda-regras-do-tse-para-uso-de-inteligencia-artificial-nas-eleicoes\/\" \/>\n<meta property=\"og:site_name\" content=\"Folha de Mato Grosso do Sul\" \/>\n<meta property=\"article:published_time\" content=\"2024-03-03T14:39:18+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-03-03T14:39:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2024\/03\/ai.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1170\" \/>\n\t<meta property=\"og:image:height\" content=\"700\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"Elite Midia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Elite Midia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/folhadems.com.br\/site\/2024\/03\/03\/entenda-regras-do-tse-para-uso-de-inteligencia-artificial-nas-eleicoes\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/folhadems.com.br\/site\/2024\/03\/03\/entenda-regras-do-tse-para-uso-de-inteligencia-artificial-nas-eleicoes\/\"},\"author\":{\"name\":\"Elite Midia\",\"@id\":\"https:\/\/folhadems.com.br\/site\/#\/schema\/person\/e4a04038e5c2e7040e19ef252ae9d940\"},\"headline\":\"Entenda regras do TSE para uso de intelig\u00eancia artificial nas elei\u00e7\u00f5es\",\"datePublished\":\"2024-03-03T14:39:18+00:00\",\"dateModified\":\"2024-03-03T14:39:21+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/folhadems.com.br\/site\/2024\/03\/03\/entenda-regras-do-tse-para-uso-de-inteligencia-artificial-nas-eleicoes\/\"},\"wordCount\":549,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/folhadems.com.br\/site\/#organization\"},\"image\":{\"@id\":\"https:\/\/folhadems.com.br\/site\/2024\/03\/03\/entenda-regras-do-tse-para-uso-de-inteligencia-artificial-nas-eleicoes\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2024\/03\/ai.webp\",\"articleSection\":[\"Justi\u00e7a\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/folhadems.com.br\/site\/2024\/03\/03\/entenda-regras-do-tse-para-uso-de-inteligencia-artificial-nas-eleicoes\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/folhadems.com.br\/site\/2024\/03\/03\/entenda-regras-do-tse-para-uso-de-inteligencia-artificial-nas-eleicoes\/\",\"url\":\"https:\/\/folhadems.com.br\/site\/2024\/03\/03\/entenda-regras-do-tse-para-uso-de-inteligencia-artificial-nas-eleicoes\/\",\"name\":\"Entenda regras do TSE para uso de intelig\u00eancia artificial nas elei\u00e7\u00f5es - Folha de Mato Grosso do Sul\",\"isPartOf\":{\"@id\":\"https:\/\/folhadems.com.br\/site\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/folhadems.com.br\/site\/2024\/03\/03\/entenda-regras-do-tse-para-uso-de-inteligencia-artificial-nas-eleicoes\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/folhadems.com.br\/site\/2024\/03\/03\/entenda-regras-do-tse-para-uso-de-inteligencia-artificial-nas-eleicoes\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2024\/03\/ai.webp\",\"datePublished\":\"2024-03-03T14:39:18+00:00\",\"dateModified\":\"2024-03-03T14:39:21+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/folhadems.com.br\/site\/2024\/03\/03\/entenda-regras-do-tse-para-uso-de-inteligencia-artificial-nas-eleicoes\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/folhadems.com.br\/site\/2024\/03\/03\/entenda-regras-do-tse-para-uso-de-inteligencia-artificial-nas-eleicoes\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/folhadems.com.br\/site\/2024\/03\/03\/entenda-regras-do-tse-para-uso-de-inteligencia-artificial-nas-eleicoes\/#primaryimage\",\"url\":\"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2024\/03\/ai.webp\",\"contentUrl\":\"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2024\/03\/ai.webp\",\"width\":1170,\"height\":700},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/folhadems.com.br\/site\/2024\/03\/03\/entenda-regras-do-tse-para-uso-de-inteligencia-artificial-nas-eleicoes\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/folhadems.com.br\/site\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Entenda regras do TSE para uso de intelig\u00eancia artificial nas elei\u00e7\u00f5es\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/folhadems.com.br\/site\/#website\",\"url\":\"https:\/\/folhadems.com.br\/site\/\",\"name\":\"Folha de Mato Grosso do Sul\",\"description\":\"Jornal Online\",\"publisher\":{\"@id\":\"https:\/\/folhadems.com.br\/site\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/folhadems.com.br\/site\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/folhadems.com.br\/site\/#organization\",\"name\":\"Folha de Mato Grosso do Sul\",\"url\":\"https:\/\/folhadems.com.br\/site\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/folhadems.com.br\/site\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2023\/01\/logo-folha-de-ms-380x90-1.jpg\",\"contentUrl\":\"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2023\/01\/logo-folha-de-ms-380x90-1.jpg\",\"width\":380,\"height\":90,\"caption\":\"Folha de Mato Grosso do Sul\"},\"image\":{\"@id\":\"https:\/\/folhadems.com.br\/site\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/folhadems.com.br\/site\/#\/schema\/person\/e4a04038e5c2e7040e19ef252ae9d940\",\"name\":\"Elite Midia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/folhadems.com.br\/site\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/f76a80f01119f7fec6909ab9feea8819031f391155be021b685479d77496f055?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/f76a80f01119f7fec6909ab9feea8819031f391155be021b685479d77496f055?s=96&d=mm&r=g\",\"caption\":\"Elite Midia\"},\"sameAs\":[\"https:\/\/folhadems.com.br\/site\"],\"url\":\"https:\/\/folhadems.com.br\/site\/author\/elite-midia\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Entenda regras do TSE para uso de intelig\u00eancia artificial nas elei\u00e7\u00f5es - Folha de Mato Grosso do Sul","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/folhadems.com.br\/site\/2024\/03\/03\/entenda-regras-do-tse-para-uso-de-inteligencia-artificial-nas-eleicoes\/","og_locale":"pt_BR","og_type":"article","og_title":"Entenda regras do TSE para uso de intelig\u00eancia artificial nas elei\u00e7\u00f5es - Folha de Mato Grosso do Sul","og_description":"O Tribunal Superior Eleitoral (TSE) aprovou na \u00faltima ter\u00e7a-feira (27) as 12 resolu\u00e7\u00f5es eleitorais com as regras finais para a","og_url":"https:\/\/folhadems.com.br\/site\/2024\/03\/03\/entenda-regras-do-tse-para-uso-de-inteligencia-artificial-nas-eleicoes\/","og_site_name":"Folha de Mato Grosso do Sul","article_published_time":"2024-03-03T14:39:18+00:00","article_modified_time":"2024-03-03T14:39:21+00:00","og_image":[{"width":1170,"height":700,"url":"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2024\/03\/ai.webp","type":"image\/webp"}],"author":"Elite Midia","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Elite Midia","Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/folhadems.com.br\/site\/2024\/03\/03\/entenda-regras-do-tse-para-uso-de-inteligencia-artificial-nas-eleicoes\/#article","isPartOf":{"@id":"https:\/\/folhadems.com.br\/site\/2024\/03\/03\/entenda-regras-do-tse-para-uso-de-inteligencia-artificial-nas-eleicoes\/"},"author":{"name":"Elite Midia","@id":"https:\/\/folhadems.com.br\/site\/#\/schema\/person\/e4a04038e5c2e7040e19ef252ae9d940"},"headline":"Entenda regras do TSE para uso de intelig\u00eancia artificial nas elei\u00e7\u00f5es","datePublished":"2024-03-03T14:39:18+00:00","dateModified":"2024-03-03T14:39:21+00:00","mainEntityOfPage":{"@id":"https:\/\/folhadems.com.br\/site\/2024\/03\/03\/entenda-regras-do-tse-para-uso-de-inteligencia-artificial-nas-eleicoes\/"},"wordCount":549,"commentCount":0,"publisher":{"@id":"https:\/\/folhadems.com.br\/site\/#organization"},"image":{"@id":"https:\/\/folhadems.com.br\/site\/2024\/03\/03\/entenda-regras-do-tse-para-uso-de-inteligencia-artificial-nas-eleicoes\/#primaryimage"},"thumbnailUrl":"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2024\/03\/ai.webp","articleSection":["Justi\u00e7a"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/folhadems.com.br\/site\/2024\/03\/03\/entenda-regras-do-tse-para-uso-de-inteligencia-artificial-nas-eleicoes\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/folhadems.com.br\/site\/2024\/03\/03\/entenda-regras-do-tse-para-uso-de-inteligencia-artificial-nas-eleicoes\/","url":"https:\/\/folhadems.com.br\/site\/2024\/03\/03\/entenda-regras-do-tse-para-uso-de-inteligencia-artificial-nas-eleicoes\/","name":"Entenda regras do TSE para uso de intelig\u00eancia artificial nas elei\u00e7\u00f5es - Folha de Mato Grosso do Sul","isPartOf":{"@id":"https:\/\/folhadems.com.br\/site\/#website"},"primaryImageOfPage":{"@id":"https:\/\/folhadems.com.br\/site\/2024\/03\/03\/entenda-regras-do-tse-para-uso-de-inteligencia-artificial-nas-eleicoes\/#primaryimage"},"image":{"@id":"https:\/\/folhadems.com.br\/site\/2024\/03\/03\/entenda-regras-do-tse-para-uso-de-inteligencia-artificial-nas-eleicoes\/#primaryimage"},"thumbnailUrl":"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2024\/03\/ai.webp","datePublished":"2024-03-03T14:39:18+00:00","dateModified":"2024-03-03T14:39:21+00:00","breadcrumb":{"@id":"https:\/\/folhadems.com.br\/site\/2024\/03\/03\/entenda-regras-do-tse-para-uso-de-inteligencia-artificial-nas-eleicoes\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/folhadems.com.br\/site\/2024\/03\/03\/entenda-regras-do-tse-para-uso-de-inteligencia-artificial-nas-eleicoes\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/folhadems.com.br\/site\/2024\/03\/03\/entenda-regras-do-tse-para-uso-de-inteligencia-artificial-nas-eleicoes\/#primaryimage","url":"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2024\/03\/ai.webp","contentUrl":"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2024\/03\/ai.webp","width":1170,"height":700},{"@type":"BreadcrumbList","@id":"https:\/\/folhadems.com.br\/site\/2024\/03\/03\/entenda-regras-do-tse-para-uso-de-inteligencia-artificial-nas-eleicoes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/folhadems.com.br\/site\/"},{"@type":"ListItem","position":2,"name":"Entenda regras do TSE para uso de intelig\u00eancia artificial nas elei\u00e7\u00f5es"}]},{"@type":"WebSite","@id":"https:\/\/folhadems.com.br\/site\/#website","url":"https:\/\/folhadems.com.br\/site\/","name":"Folha de Mato Grosso do Sul","description":"Jornal Online","publisher":{"@id":"https:\/\/folhadems.com.br\/site\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/folhadems.com.br\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/folhadems.com.br\/site\/#organization","name":"Folha de Mato Grosso do Sul","url":"https:\/\/folhadems.com.br\/site\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/folhadems.com.br\/site\/#\/schema\/logo\/image\/","url":"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2023\/01\/logo-folha-de-ms-380x90-1.jpg","contentUrl":"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2023\/01\/logo-folha-de-ms-380x90-1.jpg","width":380,"height":90,"caption":"Folha de Mato Grosso do Sul"},"image":{"@id":"https:\/\/folhadems.com.br\/site\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/folhadems.com.br\/site\/#\/schema\/person\/e4a04038e5c2e7040e19ef252ae9d940","name":"Elite Midia","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/folhadems.com.br\/site\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/f76a80f01119f7fec6909ab9feea8819031f391155be021b685479d77496f055?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f76a80f01119f7fec6909ab9feea8819031f391155be021b685479d77496f055?s=96&d=mm&r=g","caption":"Elite Midia"},"sameAs":["https:\/\/folhadems.com.br\/site"],"url":"https:\/\/folhadems.com.br\/site\/author\/elite-midia\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-20 19:25:38","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/posts\/5394","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/comments?post=5394"}],"version-history":[{"count":1,"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/posts\/5394\/revisions"}],"predecessor-version":[{"id":5396,"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/posts\/5394\/revisions\/5396"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/media\/5395"}],"wp:attachment":[{"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/media?parent=5394"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/categories?post=5394"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/tags?post=5394"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}