{"id":3586,"date":"2023-10-10T08:59:41","date_gmt":"2023-10-10T12:59:41","guid":{"rendered":"https:\/\/folhadems.com.br\/site\/?p=3586"},"modified":"2023-10-10T08:59:43","modified_gmt":"2023-10-10T12:59:43","slug":"israel-ataca-mais-de-200-alvos-em-4-dias-de-guerra-mortes-passam-de-1-600","status":"publish","type":"post","link":"https:\/\/folhadems.com.br\/site\/2023\/10\/10\/israel-ataca-mais-de-200-alvos-em-4-dias-de-guerra-mortes-passam-de-1-600\/","title":{"rendered":"Israel ataca mais de 200 alvos; em 4 dias de guerra, mortes passam de 1.600"},"content":{"rendered":"\n<p><div id=\"page\" class=\"hfeed site\"><div id=\"main\" class=\"clearfix\"><div class=\"inner-wrap clearfix\"><div id=\"primary\"><div id=\"content\" class=\"clearfix\"><article id=\"post-5025\" class=\"post-5025 post type-post status-publish format-standard has-post-thumbnail hentry category-mundo\"><div class=\"article-content clearfix\"><div class=\"entry-content clearfix\"><div class=\"container\" dir=\"ltr\" lang=\"pt-br\"><div class=\"content\">         <div class=\"moz-reader-content reader-show-element\"><div id=\"readability-page-1\" class=\"page\"><div data-v-16434e43=\"\" data-v-a982b9ff=\"\"><p data-v-16434e43=\"\"><span><strong>At\u00e9 o momento, mais de 1.600 pessoas morreram em Israel e em Gaza desde s\u00e1bado<\/strong>. O balan\u00e7o oficial d\u00e1 conta que s\u00e3o pelo menos 900 v\u00edtimas em Israel, <a href=\"https:\/\/www1.folha.uol.com.br\/mundo\/2023\/10\/cem-corpos-sao-encontrados-em-kibutz-proximo-a-gaza-invadido-por-hamas.shtml\" target=\"_blank\" rel=\"noopener\">100 delas encontradas em um kibutz<\/a>   (habita\u00e7\u00e3o coletiva) em Be\u2019eri, no sul do pa\u00eds. J\u00e1 na Palestina s\u00e3o  770  mortes confirmadas, segundo o Minist\u00e9rio da Sa\u00fade local. Na  Cisjord\u00e2nia  s\u00e3o 7 mortes registradas.<strong>A <a href=\"https:\/\/noticias.uol.com.br\/internacional\/ultimas-noticias\/2023\/10\/10\/morte-brasileiro-guerra-hamas-israel.htm\" target=\"_blank\" rel=\"noopener\">primeira morte de um cidad\u00e3o brasileiro<\/a> foi confirmada na manh\u00e3 de hoje. <\/strong>Ranani   Nidejelski Glazer, natural do Rio Grande do Sul, estava em uma rave  nas  proximidades da Faixa de Gaza quando o Hamas invadiu a regi\u00e3o.<strong>O governo israelense afirmou <a href=\"https:\/\/noticias.uol.com.br\/ultimas-noticias\/rfi\/2023\/10\/09\/israel-afirma-ter-retomado-o-controle-total-das-localidades-atacadas-no-sul-pelo-hamas.htm\" target=\"_blank\" rel=\"noopener\">ter retomado o \u201ccontrole total\u201d<\/a> das regi\u00f5es no sul do pa\u00eds que haviam sido atacadas pelo Hamas<\/strong>. Essas \u00e1reas, pr\u00f3ximas \u00e0 Faixa de Gaza, foram atacadas pelos palestinos por ar, por terra e pelo mar.<strong>Ap\u00f3s declarar guerra ao Hamas, Israel intensificou os ataques \u00e0 Faixa de Gaza e convocou 300 mil reservistas<\/strong>. Al\u00e9m de bombardear o territ\u00f3rio palestino, os israelenses <a href=\"https:\/\/noticias.uol.com.br\/colunas\/leonardo-sakamoto\/2023\/10\/09\/israel-bloqueou-medicamentos-para-gaza-denuncia-organizacao-de-saude.htm\" target=\"_blank\" rel=\"noopener\">bloqueiam a chegada de \u00e1gua, comida e luz aos palestinos<\/a>.<strong>O Hamas afirma que tem mais de cem ref\u00e9ns israelenses, que foram sequestrados no s\u00e1bado (7)<\/strong>. Em resposta ao cerco \u00e0 Faixa de Gaza, os extremistas <a href=\"https:\/\/www1.folha.uol.com.br\/mundo\/2023\/10\/hamas-ameaca-matar-civis-sequestrados-caso-israel-siga-com-ataques-a-gaza.shtml\" target=\"_blank\" rel=\"noopener\">amea\u00e7am matar os civis<\/a> se os ataques ao territ\u00f3rio continuarem.<strong>Apesar da amea\u00e7a, o grupo isl\u00e2mico come\u00e7ou a falar em tr\u00e9gua<\/strong>. Segundo a emissora Al Jazeera, um integrante do alto escal\u00e3o do Hamas <a href=\"https:\/\/noticias.uol.com.br\/internacional\/ultimas-noticias\/2023\/10\/09\/hamas-aberto-discussoes-tregua-com-israel.htm\" target=\"_blank\" rel=\"noopener\">declarou que est\u00e1 \u201caberto a discuss\u00f5es\u201d<\/a> para um poss\u00edvel cessar-fogo.<\/span><\/p><\/div><\/div><\/div><\/div><\/div><p><em>Fonte: UOL<\/em><\/p><\/div><\/div><\/article><\/div><\/div><\/div><\/div><\/div> <\/p>\n","protected":false},"excerpt":{"rendered":"<p>At\u00e9 o momento, mais de 1.600 pessoas morreram em Israel e em Gaza desde s\u00e1bado. O balan\u00e7o oficial d\u00e1 conta<\/p>\n","protected":false},"author":1,"featured_media":3587,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8],"tags":[],"class_list":["post-3586","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mundo"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.1.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Israel ataca mais de 200 alvos; em 4 dias de guerra, mortes passam de 1.600 - Folha de Mato Grosso do Sul<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/folhadems.com.br\/site\/2023\/10\/10\/israel-ataca-mais-de-200-alvos-em-4-dias-de-guerra-mortes-passam-de-1-600\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Israel ataca mais de 200 alvos; em 4 dias de guerra, mortes passam de 1.600 - Folha de Mato Grosso do Sul\" \/>\n<meta property=\"og:description\" content=\"At\u00e9 o momento, mais de 1.600 pessoas morreram em Israel e em Gaza desde s\u00e1bado. O balan\u00e7o oficial d\u00e1 conta\" \/>\n<meta property=\"og:url\" content=\"https:\/\/folhadems.com.br\/site\/2023\/10\/10\/israel-ataca-mais-de-200-alvos-em-4-dias-de-guerra-mortes-passam-de-1-600\/\" \/>\n<meta property=\"og:site_name\" content=\"Folha de Mato Grosso do Sul\" \/>\n<meta property=\"article:published_time\" content=\"2023-10-10T12:59:41+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-10-10T12:59:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2023\/10\/guerra.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"640\" \/>\n\t<meta property=\"og:image:height\" content=\"360\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Elite Midia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Elite Midia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/folhadems.com.br\/site\/2023\/10\/10\/israel-ataca-mais-de-200-alvos-em-4-dias-de-guerra-mortes-passam-de-1-600\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/folhadems.com.br\/site\/2023\/10\/10\/israel-ataca-mais-de-200-alvos-em-4-dias-de-guerra-mortes-passam-de-1-600\/\"},\"author\":{\"name\":\"Elite Midia\",\"@id\":\"https:\/\/folhadems.com.br\/site\/#\/schema\/person\/e4a04038e5c2e7040e19ef252ae9d940\"},\"headline\":\"Israel ataca mais de 200 alvos; em 4 dias de guerra, mortes passam de 1.600\",\"datePublished\":\"2023-10-10T12:59:41+00:00\",\"dateModified\":\"2023-10-10T12:59:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/folhadems.com.br\/site\/2023\/10\/10\/israel-ataca-mais-de-200-alvos-em-4-dias-de-guerra-mortes-passam-de-1-600\/\"},\"wordCount\":278,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/folhadems.com.br\/site\/#organization\"},\"image\":{\"@id\":\"https:\/\/folhadems.com.br\/site\/2023\/10\/10\/israel-ataca-mais-de-200-alvos-em-4-dias-de-guerra-mortes-passam-de-1-600\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2023\/10\/guerra.jpg\",\"articleSection\":[\"Mundo\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/folhadems.com.br\/site\/2023\/10\/10\/israel-ataca-mais-de-200-alvos-em-4-dias-de-guerra-mortes-passam-de-1-600\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/folhadems.com.br\/site\/2023\/10\/10\/israel-ataca-mais-de-200-alvos-em-4-dias-de-guerra-mortes-passam-de-1-600\/\",\"url\":\"https:\/\/folhadems.com.br\/site\/2023\/10\/10\/israel-ataca-mais-de-200-alvos-em-4-dias-de-guerra-mortes-passam-de-1-600\/\",\"name\":\"Israel ataca mais de 200 alvos; em 4 dias de guerra, mortes passam de 1.600 - Folha de Mato Grosso do Sul\",\"isPartOf\":{\"@id\":\"https:\/\/folhadems.com.br\/site\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/folhadems.com.br\/site\/2023\/10\/10\/israel-ataca-mais-de-200-alvos-em-4-dias-de-guerra-mortes-passam-de-1-600\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/folhadems.com.br\/site\/2023\/10\/10\/israel-ataca-mais-de-200-alvos-em-4-dias-de-guerra-mortes-passam-de-1-600\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2023\/10\/guerra.jpg\",\"datePublished\":\"2023-10-10T12:59:41+00:00\",\"dateModified\":\"2023-10-10T12:59:43+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/folhadems.com.br\/site\/2023\/10\/10\/israel-ataca-mais-de-200-alvos-em-4-dias-de-guerra-mortes-passam-de-1-600\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/folhadems.com.br\/site\/2023\/10\/10\/israel-ataca-mais-de-200-alvos-em-4-dias-de-guerra-mortes-passam-de-1-600\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/folhadems.com.br\/site\/2023\/10\/10\/israel-ataca-mais-de-200-alvos-em-4-dias-de-guerra-mortes-passam-de-1-600\/#primaryimage\",\"url\":\"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2023\/10\/guerra.jpg\",\"contentUrl\":\"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2023\/10\/guerra.jpg\",\"width\":640,\"height\":360},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/folhadems.com.br\/site\/2023\/10\/10\/israel-ataca-mais-de-200-alvos-em-4-dias-de-guerra-mortes-passam-de-1-600\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/folhadems.com.br\/site\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Israel ataca mais de 200 alvos; em 4 dias de guerra, mortes passam de 1.600\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/folhadems.com.br\/site\/#website\",\"url\":\"https:\/\/folhadems.com.br\/site\/\",\"name\":\"Folha de Mato Grosso do Sul\",\"description\":\"Jornal Online\",\"publisher\":{\"@id\":\"https:\/\/folhadems.com.br\/site\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/folhadems.com.br\/site\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/folhadems.com.br\/site\/#organization\",\"name\":\"Folha de Mato Grosso do Sul\",\"url\":\"https:\/\/folhadems.com.br\/site\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/folhadems.com.br\/site\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2023\/01\/logo-folha-de-ms-380x90-1.jpg\",\"contentUrl\":\"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2023\/01\/logo-folha-de-ms-380x90-1.jpg\",\"width\":380,\"height\":90,\"caption\":\"Folha de Mato Grosso do Sul\"},\"image\":{\"@id\":\"https:\/\/folhadems.com.br\/site\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/folhadems.com.br\/site\/#\/schema\/person\/e4a04038e5c2e7040e19ef252ae9d940\",\"name\":\"Elite Midia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/folhadems.com.br\/site\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/f76a80f01119f7fec6909ab9feea8819031f391155be021b685479d77496f055?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/f76a80f01119f7fec6909ab9feea8819031f391155be021b685479d77496f055?s=96&d=mm&r=g\",\"caption\":\"Elite Midia\"},\"sameAs\":[\"https:\/\/folhadems.com.br\/site\"],\"url\":\"https:\/\/folhadems.com.br\/site\/author\/elite-midia\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Israel ataca mais de 200 alvos; em 4 dias de guerra, mortes passam de 1.600 - Folha de Mato Grosso do Sul","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/folhadems.com.br\/site\/2023\/10\/10\/israel-ataca-mais-de-200-alvos-em-4-dias-de-guerra-mortes-passam-de-1-600\/","og_locale":"pt_BR","og_type":"article","og_title":"Israel ataca mais de 200 alvos; em 4 dias de guerra, mortes passam de 1.600 - Folha de Mato Grosso do Sul","og_description":"At\u00e9 o momento, mais de 1.600 pessoas morreram em Israel e em Gaza desde s\u00e1bado. O balan\u00e7o oficial d\u00e1 conta","og_url":"https:\/\/folhadems.com.br\/site\/2023\/10\/10\/israel-ataca-mais-de-200-alvos-em-4-dias-de-guerra-mortes-passam-de-1-600\/","og_site_name":"Folha de Mato Grosso do Sul","article_published_time":"2023-10-10T12:59:41+00:00","article_modified_time":"2023-10-10T12:59:43+00:00","og_image":[{"width":640,"height":360,"url":"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2023\/10\/guerra.jpg","type":"image\/jpeg"}],"author":"Elite Midia","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Elite Midia","Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/folhadems.com.br\/site\/2023\/10\/10\/israel-ataca-mais-de-200-alvos-em-4-dias-de-guerra-mortes-passam-de-1-600\/#article","isPartOf":{"@id":"https:\/\/folhadems.com.br\/site\/2023\/10\/10\/israel-ataca-mais-de-200-alvos-em-4-dias-de-guerra-mortes-passam-de-1-600\/"},"author":{"name":"Elite Midia","@id":"https:\/\/folhadems.com.br\/site\/#\/schema\/person\/e4a04038e5c2e7040e19ef252ae9d940"},"headline":"Israel ataca mais de 200 alvos; em 4 dias de guerra, mortes passam de 1.600","datePublished":"2023-10-10T12:59:41+00:00","dateModified":"2023-10-10T12:59:43+00:00","mainEntityOfPage":{"@id":"https:\/\/folhadems.com.br\/site\/2023\/10\/10\/israel-ataca-mais-de-200-alvos-em-4-dias-de-guerra-mortes-passam-de-1-600\/"},"wordCount":278,"commentCount":0,"publisher":{"@id":"https:\/\/folhadems.com.br\/site\/#organization"},"image":{"@id":"https:\/\/folhadems.com.br\/site\/2023\/10\/10\/israel-ataca-mais-de-200-alvos-em-4-dias-de-guerra-mortes-passam-de-1-600\/#primaryimage"},"thumbnailUrl":"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2023\/10\/guerra.jpg","articleSection":["Mundo"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/folhadems.com.br\/site\/2023\/10\/10\/israel-ataca-mais-de-200-alvos-em-4-dias-de-guerra-mortes-passam-de-1-600\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/folhadems.com.br\/site\/2023\/10\/10\/israel-ataca-mais-de-200-alvos-em-4-dias-de-guerra-mortes-passam-de-1-600\/","url":"https:\/\/folhadems.com.br\/site\/2023\/10\/10\/israel-ataca-mais-de-200-alvos-em-4-dias-de-guerra-mortes-passam-de-1-600\/","name":"Israel ataca mais de 200 alvos; em 4 dias de guerra, mortes passam de 1.600 - Folha de Mato Grosso do Sul","isPartOf":{"@id":"https:\/\/folhadems.com.br\/site\/#website"},"primaryImageOfPage":{"@id":"https:\/\/folhadems.com.br\/site\/2023\/10\/10\/israel-ataca-mais-de-200-alvos-em-4-dias-de-guerra-mortes-passam-de-1-600\/#primaryimage"},"image":{"@id":"https:\/\/folhadems.com.br\/site\/2023\/10\/10\/israel-ataca-mais-de-200-alvos-em-4-dias-de-guerra-mortes-passam-de-1-600\/#primaryimage"},"thumbnailUrl":"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2023\/10\/guerra.jpg","datePublished":"2023-10-10T12:59:41+00:00","dateModified":"2023-10-10T12:59:43+00:00","breadcrumb":{"@id":"https:\/\/folhadems.com.br\/site\/2023\/10\/10\/israel-ataca-mais-de-200-alvos-em-4-dias-de-guerra-mortes-passam-de-1-600\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/folhadems.com.br\/site\/2023\/10\/10\/israel-ataca-mais-de-200-alvos-em-4-dias-de-guerra-mortes-passam-de-1-600\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/folhadems.com.br\/site\/2023\/10\/10\/israel-ataca-mais-de-200-alvos-em-4-dias-de-guerra-mortes-passam-de-1-600\/#primaryimage","url":"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2023\/10\/guerra.jpg","contentUrl":"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2023\/10\/guerra.jpg","width":640,"height":360},{"@type":"BreadcrumbList","@id":"https:\/\/folhadems.com.br\/site\/2023\/10\/10\/israel-ataca-mais-de-200-alvos-em-4-dias-de-guerra-mortes-passam-de-1-600\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/folhadems.com.br\/site\/"},{"@type":"ListItem","position":2,"name":"Israel ataca mais de 200 alvos; em 4 dias de guerra, mortes passam de 1.600"}]},{"@type":"WebSite","@id":"https:\/\/folhadems.com.br\/site\/#website","url":"https:\/\/folhadems.com.br\/site\/","name":"Folha de Mato Grosso do Sul","description":"Jornal Online","publisher":{"@id":"https:\/\/folhadems.com.br\/site\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/folhadems.com.br\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/folhadems.com.br\/site\/#organization","name":"Folha de Mato Grosso do Sul","url":"https:\/\/folhadems.com.br\/site\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/folhadems.com.br\/site\/#\/schema\/logo\/image\/","url":"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2023\/01\/logo-folha-de-ms-380x90-1.jpg","contentUrl":"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2023\/01\/logo-folha-de-ms-380x90-1.jpg","width":380,"height":90,"caption":"Folha de Mato Grosso do Sul"},"image":{"@id":"https:\/\/folhadems.com.br\/site\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/folhadems.com.br\/site\/#\/schema\/person\/e4a04038e5c2e7040e19ef252ae9d940","name":"Elite Midia","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/folhadems.com.br\/site\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/f76a80f01119f7fec6909ab9feea8819031f391155be021b685479d77496f055?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f76a80f01119f7fec6909ab9feea8819031f391155be021b685479d77496f055?s=96&d=mm&r=g","caption":"Elite Midia"},"sameAs":["https:\/\/folhadems.com.br\/site"],"url":"https:\/\/folhadems.com.br\/site\/author\/elite-midia\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-20 10:43:27","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/posts\/3586","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/comments?post=3586"}],"version-history":[{"count":1,"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/posts\/3586\/revisions"}],"predecessor-version":[{"id":3588,"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/posts\/3586\/revisions\/3588"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/media\/3587"}],"wp:attachment":[{"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/media?parent=3586"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/categories?post=3586"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/tags?post=3586"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}