{"id":2968,"date":"2023-08-08T13:12:01","date_gmt":"2023-08-08T17:12:01","guid":{"rendered":"https:\/\/folhadems.com.br\/site\/?p=2968"},"modified":"2023-08-08T13:12:03","modified_gmt":"2023-08-08T17:12:03","slug":"ms-saude-realiza-mais-de-240-cirurgias-oftalmologicas-na-primeira-semana-de-agosto-em-ms","status":"publish","type":"post","link":"https:\/\/folhadems.com.br\/site\/2023\/08\/08\/ms-saude-realiza-mais-de-240-cirurgias-oftalmologicas-na-primeira-semana-de-agosto-em-ms\/","title":{"rendered":"MS Sa\u00fade realiza mais de 240 cirurgias oftalmol\u00f3gicas na primeira semana de agosto em MS"},"content":{"rendered":"\n<p>O Projeto \u2018MS Sa\u00fade: Mais Sa\u00fade, Menos Filas\u2019 realizou na primeira semana de agosto mais de 240 cirurgias de oftalmologia em Mato Grosso do Sul. Com isso, o projeto avan\u00e7a e levou atendimento de qualidade a pacientes de 14 munic\u00edpios do Estado.<\/p>\n\n\n\n<p>A primeira parada ocorreu no munic\u00edpio de Santa Rita do Pardo, na Unidade Mista de Sa\u00fade Nossa Senhora do Perp\u00e9tuo Socorro, onde nos dias 1\u00ba, 2 e 3 de agosto, foram realizadas 133 cirurgias de catarata.<\/p>\n\n\n\n<p>Pacientes dos munic\u00edpios de Parana\u00edba, Bodoquena, Terenos, Iguatemi, Japor\u00e3, Bataguassu, Santa Rita do Pardo, Alcin\u00f3polis, Amambai, Vicentina, \u00c1gua Clara, Taquarussu, Anauril\u00e2ndia e Bataypor\u00e3 foram atendidos em tr\u00eas dias de mutir\u00e3o oftalmol\u00f3gico.<\/p>\n\n\n\n<p>J\u00e1 no final de semana, s\u00e1bado (5) e domingo (6), mais 115 pacientes tamb\u00e9m passaram por cirurgia de Pter\u00edgio na Santa Casa, no munic\u00edpio da Bataguassu. O mutir\u00e3o atendeu pacientes dos munic\u00edpios de Dourados, Jardim, Bodoquena, Brasil\u00e2ndia, \u00c1gua Clara e Alcin\u00f3polis.<\/p>\n\n\n\n<p>A superintendente de Gest\u00e3o Estrat\u00e9gica da SES (Secretaria de Estado de Sa\u00fade) e coordenadora do MS Sa\u00fade, Maria Ang\u00e9lica Benetasso, lembrou que assim como ocorreu no primeiro mutir\u00e3o realizado no munic\u00edpio de F\u00e1tima do Sul.<\/p>\n\n\n\n<p>\u201cOs atendimentos ocorreram de forma r\u00e1pida, com qualidade e oferecendo atendimento humanizado. Em Bataguassu, recebi a visita dos secret\u00e1rios de Governo e Gest\u00e3o Estrat\u00e9gica, Pedro Arlei Caravina e da Casa Civil, Eduardo Rocha, que foram representando o governador Eduardo Riedel e conferiram de perto a execu\u00e7\u00e3o do Projeto \u2018MS Sa\u00fade: Mais Sa\u00fade, Menos Fila\u2019, ressalta Benetasso.<\/p>\n\n\n\n<p><strong>Pr\u00f3ximas etapas do Projeto<\/strong><\/p>\n\n\n\n<p>Na pr\u00f3xima quinzena de agosto ser\u00e3o realizadas as consultas de pr\u00e9-operat\u00f3rio de catarata nos seguintes munic\u00edpios: Sidrol\u00e2ndia (15 e 16 de agosto \u2013 200 procedimentos de catarata e 200 de YAG laser (procedimento que remove manchas de uma estrutura do olho), Camapu\u00e3 (17 de agosto \u2013 150 cirurgia de catarata), Miranda (18 de agosto \u2013 150 cirurgia de catarata), Bonito (19 de agosto \u2013 150 cirurgia de catarata \/ 120 de YAG laser (procedimento que remove manchas de uma estrutura do olho).<\/p>\n\n\n\n<p>\u201cEsperamos atender nestes munic\u00edpios cerca de 970 pacientes oftalmol\u00f3gicos. E n\u00f3s j\u00e1 estamos organizando para que o Projeto \u2018MS Sa\u00fade: Mais Sa\u00fade, Menos Fila\u2019 avance e chegue a novos munic\u00edpios de nosso Estado\u201d, refor\u00e7a Maria Ang\u00e9lica.<\/p>\n\n\n\n<p><strong>Cirurgias Ortop\u00e9dicas<\/strong><\/p>\n\n\n\n<p>Maracaju tamb\u00e9m j\u00e1 realizou na sexta-feira (4) e s\u00e1bado (5), 14 procedimentos ortop\u00e9dicos no Hospital Soriano Correa da Silva de artroplastia total de quadril, les\u00e3o de menisco, reparo de menisco, colecistectomia, h\u00e9rnia inguinal, h\u00e9rnia umbilical, LCA com pacientes de Maracaju, Jaraguari, Jardim, Miranda, Bandeirantes e Nioaque.<\/p>\n\n\n\n<p>J\u00e1 o munic\u00edpio de Rio Brilhante se prepara para a realiza\u00e7\u00e3o de cirurgias de quadril e joelhos em 18 pacientes, que est\u00e3o agendados para os dias 19, 20, 26 e 27 de agosto, no Hospital Maternidade de Rio Brilhante.<\/p>\n\n\n\n<p><strong>Sobre o Projeto MS Sa\u00fade<\/strong><\/p>\n\n\n\n<p>Para o Ano I do Projeto MS Sa\u00fade, 37 estabelecimentos de Sa\u00fade de 32 munic\u00edpios fizeram a ades\u00e3o ao programa para a realiza\u00e7\u00e3o de cirurgias eletivas. E mais 34 estabelecimentos de sa\u00fade de 19 munic\u00edpios fizeram a ades\u00e3o para a realiza\u00e7\u00e3o de exames com a finalidade diagn\u00f3stica. Com recurso federal, h\u00e1 22 estabelecimentos de sa\u00fade de 20 munic\u00edpios que est\u00e3o credenciados para a realiza\u00e7\u00e3o de cirurgia eletiva.<\/p>\n\n\n\n<p>O Projeto MS Sa\u00fade prev\u00ea que prefeituras e estabelecimentos de sa\u00fade estabele\u00e7am conv\u00eanios que v\u00e3o garantir a realiza\u00e7\u00e3o de 15 mil cirurgias eletivas em diversas especialidades, entre elas: oftalmologia, otorrinolaringologia, cirurgia vascular, cirurgia geral e ortopedia.<\/p>\n\n\n\n<p>Tamb\u00e9m est\u00e3o previstas a realiza\u00e7\u00e3o de 42,5 mil exames diagn\u00f3sticos como resson\u00e2ncia magn\u00e9tica com contraste, resson\u00e2ncia magn\u00e9tica (seda\u00e7\u00e3o), tomografia computadorizada, endoscopia, densitometria, colonoscopia, holter 24 horas, cintilografia, entre outros.<\/p>\n\n\n\n<p>O Governo do Estado disponibilizou R$ 45 milh\u00f5es de recursos pr\u00f3prios e R$ 7,9 milh\u00f5es de recursos federais para atender \u00e0 popula\u00e7\u00e3o.<\/p>\n\n\n\n<p><em>Rodson Lima, SES<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Projeto \u2018MS Sa\u00fade: Mais Sa\u00fade, Menos Filas\u2019 realizou na primeira semana de agosto mais de 240 cirurgias de oftalmologia<\/p>\n","protected":false},"author":1,"featured_media":2969,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-2968","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ciencia-e-saude"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.1.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>MS Sa\u00fade realiza mais de 240 cirurgias oftalmol\u00f3gicas na primeira semana de agosto em MS - Folha de Mato Grosso do Sul<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/folhadems.com.br\/site\/2023\/08\/08\/ms-saude-realiza-mais-de-240-cirurgias-oftalmologicas-na-primeira-semana-de-agosto-em-ms\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"MS Sa\u00fade realiza mais de 240 cirurgias oftalmol\u00f3gicas na primeira semana de agosto em MS - Folha de Mato Grosso do Sul\" \/>\n<meta property=\"og:description\" content=\"O Projeto \u2018MS Sa\u00fade: Mais Sa\u00fade, Menos Filas\u2019 realizou na primeira semana de agosto mais de 240 cirurgias de oftalmologia\" \/>\n<meta property=\"og:url\" content=\"https:\/\/folhadems.com.br\/site\/2023\/08\/08\/ms-saude-realiza-mais-de-240-cirurgias-oftalmologicas-na-primeira-semana-de-agosto-em-ms\/\" \/>\n<meta property=\"og:site_name\" content=\"Folha de Mato Grosso do Sul\" \/>\n<meta property=\"article:published_time\" content=\"2023-08-08T17:12:01+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-08-08T17:12:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2023\/08\/cirurgia.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"450\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Elite Midia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Elite Midia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/folhadems.com.br\/site\/2023\/08\/08\/ms-saude-realiza-mais-de-240-cirurgias-oftalmologicas-na-primeira-semana-de-agosto-em-ms\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/folhadems.com.br\/site\/2023\/08\/08\/ms-saude-realiza-mais-de-240-cirurgias-oftalmologicas-na-primeira-semana-de-agosto-em-ms\/\"},\"author\":{\"name\":\"Elite Midia\",\"@id\":\"https:\/\/folhadems.com.br\/site\/#\/schema\/person\/e4a04038e5c2e7040e19ef252ae9d940\"},\"headline\":\"MS Sa\u00fade realiza mais de 240 cirurgias oftalmol\u00f3gicas na primeira semana de agosto em MS\",\"datePublished\":\"2023-08-08T17:12:01+00:00\",\"dateModified\":\"2023-08-08T17:12:03+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/folhadems.com.br\/site\/2023\/08\/08\/ms-saude-realiza-mais-de-240-cirurgias-oftalmologicas-na-primeira-semana-de-agosto-em-ms\/\"},\"wordCount\":678,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/folhadems.com.br\/site\/#organization\"},\"image\":{\"@id\":\"https:\/\/folhadems.com.br\/site\/2023\/08\/08\/ms-saude-realiza-mais-de-240-cirurgias-oftalmologicas-na-primeira-semana-de-agosto-em-ms\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2023\/08\/cirurgia.jpg\",\"articleSection\":[\"Ci\u00eancia e Sa\u00fade\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/folhadems.com.br\/site\/2023\/08\/08\/ms-saude-realiza-mais-de-240-cirurgias-oftalmologicas-na-primeira-semana-de-agosto-em-ms\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/folhadems.com.br\/site\/2023\/08\/08\/ms-saude-realiza-mais-de-240-cirurgias-oftalmologicas-na-primeira-semana-de-agosto-em-ms\/\",\"url\":\"https:\/\/folhadems.com.br\/site\/2023\/08\/08\/ms-saude-realiza-mais-de-240-cirurgias-oftalmologicas-na-primeira-semana-de-agosto-em-ms\/\",\"name\":\"MS Sa\u00fade realiza mais de 240 cirurgias oftalmol\u00f3gicas na primeira semana de agosto em MS - Folha de Mato Grosso do Sul\",\"isPartOf\":{\"@id\":\"https:\/\/folhadems.com.br\/site\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/folhadems.com.br\/site\/2023\/08\/08\/ms-saude-realiza-mais-de-240-cirurgias-oftalmologicas-na-primeira-semana-de-agosto-em-ms\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/folhadems.com.br\/site\/2023\/08\/08\/ms-saude-realiza-mais-de-240-cirurgias-oftalmologicas-na-primeira-semana-de-agosto-em-ms\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2023\/08\/cirurgia.jpg\",\"datePublished\":\"2023-08-08T17:12:01+00:00\",\"dateModified\":\"2023-08-08T17:12:03+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/folhadems.com.br\/site\/2023\/08\/08\/ms-saude-realiza-mais-de-240-cirurgias-oftalmologicas-na-primeira-semana-de-agosto-em-ms\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/folhadems.com.br\/site\/2023\/08\/08\/ms-saude-realiza-mais-de-240-cirurgias-oftalmologicas-na-primeira-semana-de-agosto-em-ms\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/folhadems.com.br\/site\/2023\/08\/08\/ms-saude-realiza-mais-de-240-cirurgias-oftalmologicas-na-primeira-semana-de-agosto-em-ms\/#primaryimage\",\"url\":\"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2023\/08\/cirurgia.jpg\",\"contentUrl\":\"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2023\/08\/cirurgia.jpg\",\"width\":800,\"height\":450},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/folhadems.com.br\/site\/2023\/08\/08\/ms-saude-realiza-mais-de-240-cirurgias-oftalmologicas-na-primeira-semana-de-agosto-em-ms\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/folhadems.com.br\/site\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"MS Sa\u00fade realiza mais de 240 cirurgias oftalmol\u00f3gicas na primeira semana de agosto em MS\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/folhadems.com.br\/site\/#website\",\"url\":\"https:\/\/folhadems.com.br\/site\/\",\"name\":\"Folha de Mato Grosso do Sul\",\"description\":\"Jornal Online\",\"publisher\":{\"@id\":\"https:\/\/folhadems.com.br\/site\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/folhadems.com.br\/site\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/folhadems.com.br\/site\/#organization\",\"name\":\"Folha de Mato Grosso do Sul\",\"url\":\"https:\/\/folhadems.com.br\/site\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/folhadems.com.br\/site\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2023\/01\/logo-folha-de-ms-380x90-1.jpg\",\"contentUrl\":\"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2023\/01\/logo-folha-de-ms-380x90-1.jpg\",\"width\":380,\"height\":90,\"caption\":\"Folha de Mato Grosso do Sul\"},\"image\":{\"@id\":\"https:\/\/folhadems.com.br\/site\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/folhadems.com.br\/site\/#\/schema\/person\/e4a04038e5c2e7040e19ef252ae9d940\",\"name\":\"Elite Midia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/folhadems.com.br\/site\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/f76a80f01119f7fec6909ab9feea8819031f391155be021b685479d77496f055?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/f76a80f01119f7fec6909ab9feea8819031f391155be021b685479d77496f055?s=96&d=mm&r=g\",\"caption\":\"Elite Midia\"},\"sameAs\":[\"https:\/\/folhadems.com.br\/site\"],\"url\":\"https:\/\/folhadems.com.br\/site\/author\/elite-midia\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"MS Sa\u00fade realiza mais de 240 cirurgias oftalmol\u00f3gicas na primeira semana de agosto em MS - Folha de Mato Grosso do Sul","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/folhadems.com.br\/site\/2023\/08\/08\/ms-saude-realiza-mais-de-240-cirurgias-oftalmologicas-na-primeira-semana-de-agosto-em-ms\/","og_locale":"pt_BR","og_type":"article","og_title":"MS Sa\u00fade realiza mais de 240 cirurgias oftalmol\u00f3gicas na primeira semana de agosto em MS - Folha de Mato Grosso do Sul","og_description":"O Projeto \u2018MS Sa\u00fade: Mais Sa\u00fade, Menos Filas\u2019 realizou na primeira semana de agosto mais de 240 cirurgias de oftalmologia","og_url":"https:\/\/folhadems.com.br\/site\/2023\/08\/08\/ms-saude-realiza-mais-de-240-cirurgias-oftalmologicas-na-primeira-semana-de-agosto-em-ms\/","og_site_name":"Folha de Mato Grosso do Sul","article_published_time":"2023-08-08T17:12:01+00:00","article_modified_time":"2023-08-08T17:12:03+00:00","og_image":[{"width":800,"height":450,"url":"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2023\/08\/cirurgia.jpg","type":"image\/jpeg"}],"author":"Elite Midia","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Elite Midia","Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/folhadems.com.br\/site\/2023\/08\/08\/ms-saude-realiza-mais-de-240-cirurgias-oftalmologicas-na-primeira-semana-de-agosto-em-ms\/#article","isPartOf":{"@id":"https:\/\/folhadems.com.br\/site\/2023\/08\/08\/ms-saude-realiza-mais-de-240-cirurgias-oftalmologicas-na-primeira-semana-de-agosto-em-ms\/"},"author":{"name":"Elite Midia","@id":"https:\/\/folhadems.com.br\/site\/#\/schema\/person\/e4a04038e5c2e7040e19ef252ae9d940"},"headline":"MS Sa\u00fade realiza mais de 240 cirurgias oftalmol\u00f3gicas na primeira semana de agosto em MS","datePublished":"2023-08-08T17:12:01+00:00","dateModified":"2023-08-08T17:12:03+00:00","mainEntityOfPage":{"@id":"https:\/\/folhadems.com.br\/site\/2023\/08\/08\/ms-saude-realiza-mais-de-240-cirurgias-oftalmologicas-na-primeira-semana-de-agosto-em-ms\/"},"wordCount":678,"commentCount":0,"publisher":{"@id":"https:\/\/folhadems.com.br\/site\/#organization"},"image":{"@id":"https:\/\/folhadems.com.br\/site\/2023\/08\/08\/ms-saude-realiza-mais-de-240-cirurgias-oftalmologicas-na-primeira-semana-de-agosto-em-ms\/#primaryimage"},"thumbnailUrl":"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2023\/08\/cirurgia.jpg","articleSection":["Ci\u00eancia e Sa\u00fade"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/folhadems.com.br\/site\/2023\/08\/08\/ms-saude-realiza-mais-de-240-cirurgias-oftalmologicas-na-primeira-semana-de-agosto-em-ms\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/folhadems.com.br\/site\/2023\/08\/08\/ms-saude-realiza-mais-de-240-cirurgias-oftalmologicas-na-primeira-semana-de-agosto-em-ms\/","url":"https:\/\/folhadems.com.br\/site\/2023\/08\/08\/ms-saude-realiza-mais-de-240-cirurgias-oftalmologicas-na-primeira-semana-de-agosto-em-ms\/","name":"MS Sa\u00fade realiza mais de 240 cirurgias oftalmol\u00f3gicas na primeira semana de agosto em MS - Folha de Mato Grosso do Sul","isPartOf":{"@id":"https:\/\/folhadems.com.br\/site\/#website"},"primaryImageOfPage":{"@id":"https:\/\/folhadems.com.br\/site\/2023\/08\/08\/ms-saude-realiza-mais-de-240-cirurgias-oftalmologicas-na-primeira-semana-de-agosto-em-ms\/#primaryimage"},"image":{"@id":"https:\/\/folhadems.com.br\/site\/2023\/08\/08\/ms-saude-realiza-mais-de-240-cirurgias-oftalmologicas-na-primeira-semana-de-agosto-em-ms\/#primaryimage"},"thumbnailUrl":"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2023\/08\/cirurgia.jpg","datePublished":"2023-08-08T17:12:01+00:00","dateModified":"2023-08-08T17:12:03+00:00","breadcrumb":{"@id":"https:\/\/folhadems.com.br\/site\/2023\/08\/08\/ms-saude-realiza-mais-de-240-cirurgias-oftalmologicas-na-primeira-semana-de-agosto-em-ms\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/folhadems.com.br\/site\/2023\/08\/08\/ms-saude-realiza-mais-de-240-cirurgias-oftalmologicas-na-primeira-semana-de-agosto-em-ms\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/folhadems.com.br\/site\/2023\/08\/08\/ms-saude-realiza-mais-de-240-cirurgias-oftalmologicas-na-primeira-semana-de-agosto-em-ms\/#primaryimage","url":"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2023\/08\/cirurgia.jpg","contentUrl":"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2023\/08\/cirurgia.jpg","width":800,"height":450},{"@type":"BreadcrumbList","@id":"https:\/\/folhadems.com.br\/site\/2023\/08\/08\/ms-saude-realiza-mais-de-240-cirurgias-oftalmologicas-na-primeira-semana-de-agosto-em-ms\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/folhadems.com.br\/site\/"},{"@type":"ListItem","position":2,"name":"MS Sa\u00fade realiza mais de 240 cirurgias oftalmol\u00f3gicas na primeira semana de agosto em MS"}]},{"@type":"WebSite","@id":"https:\/\/folhadems.com.br\/site\/#website","url":"https:\/\/folhadems.com.br\/site\/","name":"Folha de Mato Grosso do Sul","description":"Jornal Online","publisher":{"@id":"https:\/\/folhadems.com.br\/site\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/folhadems.com.br\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/folhadems.com.br\/site\/#organization","name":"Folha de Mato Grosso do Sul","url":"https:\/\/folhadems.com.br\/site\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/folhadems.com.br\/site\/#\/schema\/logo\/image\/","url":"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2023\/01\/logo-folha-de-ms-380x90-1.jpg","contentUrl":"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2023\/01\/logo-folha-de-ms-380x90-1.jpg","width":380,"height":90,"caption":"Folha de Mato Grosso do Sul"},"image":{"@id":"https:\/\/folhadems.com.br\/site\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/folhadems.com.br\/site\/#\/schema\/person\/e4a04038e5c2e7040e19ef252ae9d940","name":"Elite Midia","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/folhadems.com.br\/site\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/f76a80f01119f7fec6909ab9feea8819031f391155be021b685479d77496f055?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f76a80f01119f7fec6909ab9feea8819031f391155be021b685479d77496f055?s=96&d=mm&r=g","caption":"Elite Midia"},"sameAs":["https:\/\/folhadems.com.br\/site"],"url":"https:\/\/folhadems.com.br\/site\/author\/elite-midia\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-20 13:15:12","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/posts\/2968","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/comments?post=2968"}],"version-history":[{"count":1,"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/posts\/2968\/revisions"}],"predecessor-version":[{"id":2970,"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/posts\/2968\/revisions\/2970"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/media\/2969"}],"wp:attachment":[{"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/media?parent=2968"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/categories?post=2968"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/tags?post=2968"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}