{"id":16644,"date":"2026-05-29T08:21:18","date_gmt":"2026-05-29T12:21:18","guid":{"rendered":"https:\/\/folhadems.com.br\/site\/?p=16644"},"modified":"2026-05-29T08:21:23","modified_gmt":"2026-05-29T12:21:23","slug":"governo-de-ms-empossa-grupo-de-trabalho-para-celebrar-os-50-anos-do-estado","status":"publish","type":"post","link":"https:\/\/folhadems.com.br\/site\/2026\/05\/29\/governo-de-ms-empossa-grupo-de-trabalho-para-celebrar-os-50-anos-do-estado\/","title":{"rendered":"Governo de MS empossa grupo de trabalho para celebrar os 50 anos do Estado"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">O Governo de Mato Grosso do Sul iniciou a constru\u00e7\u00e3o do projeto de comemora\u00e7\u00e3o dos 50 anos do Estado com a primeira reuni\u00e3o do grupo de trabalho (GT) multidisciplinar que pretende envolver toda a sociedade sul-mato-grossense nas celebra\u00e7\u00f5es. Durante a primeira reuni\u00e3o do GT, o governador Eduardo Riedel afirmou que a proposta \u00e9 organizar um calend\u00e1rio amplo, participativo e estruturado, reunindo representantes de diferentes \u00e1reas do Executivo estadual para elaborar a\u00e7\u00f5es que valorizem a hist\u00f3ria, a identidade e os protagonistas da forma\u00e7\u00e3o de Mato Grosso do Sul.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Na abertura do encontro, Riedel explicou que o objetivo \u00e9 construir um projeto coletivo, aberto \u00e0 participa\u00e7\u00e3o de diversos segmentos da sociedade, contemplando manifesta\u00e7\u00f5es nas \u00e1reas de educa\u00e7\u00e3o, cultura, turismo, esporte e comunica\u00e7\u00e3o. Segundo ele, a inten\u00e7\u00e3o \u00e9 preparar um programa comemorativo capaz de mobilizar o Estado ao longo de todo o ano das celebra\u00e7\u00f5es, com planejamento e integra\u00e7\u00e3o entre as institui\u00e7\u00f5es.<\/p>\n\n\n\n<figure class=\"wp-block-image\" id=\"attachment_542684\"><img decoding=\"async\" src=\"https:\/\/agenciadenoticias.ms.gov.br\/wp-content\/uploads\/2026\/05\/Grupo-de-Trabalho-50-anos-MS-Foto-Alvaro-Rezende-1-1024x683.jpg\" alt=\"\" class=\"wp-image-542684\"\/><figcaption class=\"wp-element-caption\">O objetivo \u00e9 construir um projeto coletivo, aberto \u00e0 participa\u00e7\u00e3o de diversos segmentos da sociedade<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cCada pessoa tem uma hist\u00f3ria bonita para contar dentro desses 50 anos. Por isso, a ideia \u00e9 conversar com o m\u00e1ximo de pessoas poss\u00edvel, ouvir diferentes vis\u00f5es e organizar esse processo para que a comemora\u00e7\u00e3o tenha identidade, participa\u00e7\u00e3o e representatividade\u201d, ressaltou o governador.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O Di\u00e1rio Oficial do Estado <a href=\"https:\/\/agenciadenoticias.ms.gov.br\/wp-content\/uploads\/2026\/05\/DO12171_28_05_2026.pdf\" target=\"_blank\" rel=\"noopener\"><strong>(DOE)<\/strong> <\/a>desta quinta-feira (28) publica os nomes dos dirigentes do Governo do Estado que passam a compor o grupo de trabalho respons\u00e1vel pela organiza\u00e7\u00e3o das comemora\u00e7\u00f5es.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O ex-secret\u00e1rio e ex-presidente da Funda\u00e7\u00e3o de Cultura de Mato Grosso do Sul, Athayde Nery, foi escolhido para coordenar o grupo de trabalho. Segundo ele, o primeiro encontro representa o in\u00edcio de um movimento para provocar a popula\u00e7\u00e3o sul-mato-grossense a refletir sobre a hist\u00f3ria e o futuro do Estado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cAcho que \u00e9 um primeiro movimento para provocar o povo de Mato Grosso do Sul em rela\u00e7\u00e3o \u00e0 hist\u00f3ria desse Estado que \u00e9 t\u00e3o rico. \u00c9 um Estado muito novo, mas que j\u00e1 carrega uma s\u00e9rie de desafios que fazem dele um Estado diferente\u201d, afirmou.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Athayde observou que Mato Grosso do Sul re\u00fane caracter\u00edsticas \u00fanicas pela diversidade cultural e pela posi\u00e7\u00e3o estrat\u00e9gica no continente. \u201cTenho dito sempre que Mato Grosso do Sul \u00e9 o cora\u00e7\u00e3o do Brasil e o cora\u00e7\u00e3o da Am\u00e9rica do Sul. N\u00e3o apenas do ponto de vista geogr\u00e1fico, mas pelo que representa em produ\u00e7\u00e3o agr\u00edcola, cultura e mistura de povos.\u201d<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em><strong>Alexandre Gonzaga, Comunica\u00e7\u00e3o do Governo de MS<\/strong><\/em><br><em><strong>Fotos: \u00c1lvaro Rezende<\/strong><\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Governo de Mato Grosso do Sul iniciou a constru\u00e7\u00e3o do projeto de comemora\u00e7\u00e3o dos 50 anos do Estado com<\/p>\n","protected":false},"author":1,"featured_media":16645,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[28],"tags":[],"class_list":["post-16644","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-governo"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.1.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Governo de MS empossa grupo de trabalho para celebrar os 50 anos do Estado - Folha de Mato Grosso do Sul<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/folhadems.com.br\/site\/2026\/05\/29\/governo-de-ms-empossa-grupo-de-trabalho-para-celebrar-os-50-anos-do-estado\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Governo de MS empossa grupo de trabalho para celebrar os 50 anos do Estado - Folha de Mato Grosso do Sul\" \/>\n<meta property=\"og:description\" content=\"O Governo de Mato Grosso do Sul iniciou a constru\u00e7\u00e3o do projeto de comemora\u00e7\u00e3o dos 50 anos do Estado com\" \/>\n<meta property=\"og:url\" content=\"https:\/\/folhadems.com.br\/site\/2026\/05\/29\/governo-de-ms-empossa-grupo-de-trabalho-para-celebrar-os-50-anos-do-estado\/\" \/>\n<meta property=\"og:site_name\" content=\"Folha de Mato Grosso do Sul\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-29T12:21:18+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-29T12:21:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2026\/05\/gov-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"730\" \/>\n\t<meta property=\"og:image:height\" content=\"480\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Elite Midia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Elite Midia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/folhadems.com.br\/site\/2026\/05\/29\/governo-de-ms-empossa-grupo-de-trabalho-para-celebrar-os-50-anos-do-estado\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/folhadems.com.br\/site\/2026\/05\/29\/governo-de-ms-empossa-grupo-de-trabalho-para-celebrar-os-50-anos-do-estado\/\"},\"author\":{\"name\":\"Elite Midia\",\"@id\":\"https:\/\/folhadems.com.br\/site\/#\/schema\/person\/e4a04038e5c2e7040e19ef252ae9d940\"},\"headline\":\"Governo de MS empossa grupo de trabalho para celebrar os 50 anos do Estado\",\"datePublished\":\"2026-05-29T12:21:18+00:00\",\"dateModified\":\"2026-05-29T12:21:23+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/folhadems.com.br\/site\/2026\/05\/29\/governo-de-ms-empossa-grupo-de-trabalho-para-celebrar-os-50-anos-do-estado\/\"},\"wordCount\":447,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/folhadems.com.br\/site\/#organization\"},\"image\":{\"@id\":\"https:\/\/folhadems.com.br\/site\/2026\/05\/29\/governo-de-ms-empossa-grupo-de-trabalho-para-celebrar-os-50-anos-do-estado\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2026\/05\/gov-2.jpg\",\"articleSection\":[\"Governo\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/folhadems.com.br\/site\/2026\/05\/29\/governo-de-ms-empossa-grupo-de-trabalho-para-celebrar-os-50-anos-do-estado\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/folhadems.com.br\/site\/2026\/05\/29\/governo-de-ms-empossa-grupo-de-trabalho-para-celebrar-os-50-anos-do-estado\/\",\"url\":\"https:\/\/folhadems.com.br\/site\/2026\/05\/29\/governo-de-ms-empossa-grupo-de-trabalho-para-celebrar-os-50-anos-do-estado\/\",\"name\":\"Governo de MS empossa grupo de trabalho para celebrar os 50 anos do Estado - Folha de Mato Grosso do Sul\",\"isPartOf\":{\"@id\":\"https:\/\/folhadems.com.br\/site\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/folhadems.com.br\/site\/2026\/05\/29\/governo-de-ms-empossa-grupo-de-trabalho-para-celebrar-os-50-anos-do-estado\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/folhadems.com.br\/site\/2026\/05\/29\/governo-de-ms-empossa-grupo-de-trabalho-para-celebrar-os-50-anos-do-estado\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2026\/05\/gov-2.jpg\",\"datePublished\":\"2026-05-29T12:21:18+00:00\",\"dateModified\":\"2026-05-29T12:21:23+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/folhadems.com.br\/site\/2026\/05\/29\/governo-de-ms-empossa-grupo-de-trabalho-para-celebrar-os-50-anos-do-estado\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/folhadems.com.br\/site\/2026\/05\/29\/governo-de-ms-empossa-grupo-de-trabalho-para-celebrar-os-50-anos-do-estado\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/folhadems.com.br\/site\/2026\/05\/29\/governo-de-ms-empossa-grupo-de-trabalho-para-celebrar-os-50-anos-do-estado\/#primaryimage\",\"url\":\"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2026\/05\/gov-2.jpg\",\"contentUrl\":\"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2026\/05\/gov-2.jpg\",\"width\":730,\"height\":480},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/folhadems.com.br\/site\/2026\/05\/29\/governo-de-ms-empossa-grupo-de-trabalho-para-celebrar-os-50-anos-do-estado\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/folhadems.com.br\/site\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Governo de MS empossa grupo de trabalho para celebrar os 50 anos do Estado\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/folhadems.com.br\/site\/#website\",\"url\":\"https:\/\/folhadems.com.br\/site\/\",\"name\":\"Folha de Mato Grosso do Sul\",\"description\":\"Jornal Online\",\"publisher\":{\"@id\":\"https:\/\/folhadems.com.br\/site\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/folhadems.com.br\/site\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/folhadems.com.br\/site\/#organization\",\"name\":\"Folha de Mato Grosso do Sul\",\"url\":\"https:\/\/folhadems.com.br\/site\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/folhadems.com.br\/site\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2023\/01\/logo-folha-de-ms-380x90-1.jpg\",\"contentUrl\":\"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2023\/01\/logo-folha-de-ms-380x90-1.jpg\",\"width\":380,\"height\":90,\"caption\":\"Folha de Mato Grosso do Sul\"},\"image\":{\"@id\":\"https:\/\/folhadems.com.br\/site\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/folhadems.com.br\/site\/#\/schema\/person\/e4a04038e5c2e7040e19ef252ae9d940\",\"name\":\"Elite Midia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/folhadems.com.br\/site\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/f76a80f01119f7fec6909ab9feea8819031f391155be021b685479d77496f055?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/f76a80f01119f7fec6909ab9feea8819031f391155be021b685479d77496f055?s=96&d=mm&r=g\",\"caption\":\"Elite Midia\"},\"sameAs\":[\"https:\/\/folhadems.com.br\/site\"],\"url\":\"https:\/\/folhadems.com.br\/site\/author\/elite-midia\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Governo de MS empossa grupo de trabalho para celebrar os 50 anos do Estado - Folha de Mato Grosso do Sul","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/folhadems.com.br\/site\/2026\/05\/29\/governo-de-ms-empossa-grupo-de-trabalho-para-celebrar-os-50-anos-do-estado\/","og_locale":"pt_BR","og_type":"article","og_title":"Governo de MS empossa grupo de trabalho para celebrar os 50 anos do Estado - Folha de Mato Grosso do Sul","og_description":"O Governo de Mato Grosso do Sul iniciou a constru\u00e7\u00e3o do projeto de comemora\u00e7\u00e3o dos 50 anos do Estado com","og_url":"https:\/\/folhadems.com.br\/site\/2026\/05\/29\/governo-de-ms-empossa-grupo-de-trabalho-para-celebrar-os-50-anos-do-estado\/","og_site_name":"Folha de Mato Grosso do Sul","article_published_time":"2026-05-29T12:21:18+00:00","article_modified_time":"2026-05-29T12:21:23+00:00","og_image":[{"width":730,"height":480,"url":"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2026\/05\/gov-2.jpg","type":"image\/jpeg"}],"author":"Elite Midia","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Elite Midia","Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/folhadems.com.br\/site\/2026\/05\/29\/governo-de-ms-empossa-grupo-de-trabalho-para-celebrar-os-50-anos-do-estado\/#article","isPartOf":{"@id":"https:\/\/folhadems.com.br\/site\/2026\/05\/29\/governo-de-ms-empossa-grupo-de-trabalho-para-celebrar-os-50-anos-do-estado\/"},"author":{"name":"Elite Midia","@id":"https:\/\/folhadems.com.br\/site\/#\/schema\/person\/e4a04038e5c2e7040e19ef252ae9d940"},"headline":"Governo de MS empossa grupo de trabalho para celebrar os 50 anos do Estado","datePublished":"2026-05-29T12:21:18+00:00","dateModified":"2026-05-29T12:21:23+00:00","mainEntityOfPage":{"@id":"https:\/\/folhadems.com.br\/site\/2026\/05\/29\/governo-de-ms-empossa-grupo-de-trabalho-para-celebrar-os-50-anos-do-estado\/"},"wordCount":447,"commentCount":0,"publisher":{"@id":"https:\/\/folhadems.com.br\/site\/#organization"},"image":{"@id":"https:\/\/folhadems.com.br\/site\/2026\/05\/29\/governo-de-ms-empossa-grupo-de-trabalho-para-celebrar-os-50-anos-do-estado\/#primaryimage"},"thumbnailUrl":"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2026\/05\/gov-2.jpg","articleSection":["Governo"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/folhadems.com.br\/site\/2026\/05\/29\/governo-de-ms-empossa-grupo-de-trabalho-para-celebrar-os-50-anos-do-estado\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/folhadems.com.br\/site\/2026\/05\/29\/governo-de-ms-empossa-grupo-de-trabalho-para-celebrar-os-50-anos-do-estado\/","url":"https:\/\/folhadems.com.br\/site\/2026\/05\/29\/governo-de-ms-empossa-grupo-de-trabalho-para-celebrar-os-50-anos-do-estado\/","name":"Governo de MS empossa grupo de trabalho para celebrar os 50 anos do Estado - Folha de Mato Grosso do Sul","isPartOf":{"@id":"https:\/\/folhadems.com.br\/site\/#website"},"primaryImageOfPage":{"@id":"https:\/\/folhadems.com.br\/site\/2026\/05\/29\/governo-de-ms-empossa-grupo-de-trabalho-para-celebrar-os-50-anos-do-estado\/#primaryimage"},"image":{"@id":"https:\/\/folhadems.com.br\/site\/2026\/05\/29\/governo-de-ms-empossa-grupo-de-trabalho-para-celebrar-os-50-anos-do-estado\/#primaryimage"},"thumbnailUrl":"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2026\/05\/gov-2.jpg","datePublished":"2026-05-29T12:21:18+00:00","dateModified":"2026-05-29T12:21:23+00:00","breadcrumb":{"@id":"https:\/\/folhadems.com.br\/site\/2026\/05\/29\/governo-de-ms-empossa-grupo-de-trabalho-para-celebrar-os-50-anos-do-estado\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/folhadems.com.br\/site\/2026\/05\/29\/governo-de-ms-empossa-grupo-de-trabalho-para-celebrar-os-50-anos-do-estado\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/folhadems.com.br\/site\/2026\/05\/29\/governo-de-ms-empossa-grupo-de-trabalho-para-celebrar-os-50-anos-do-estado\/#primaryimage","url":"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2026\/05\/gov-2.jpg","contentUrl":"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2026\/05\/gov-2.jpg","width":730,"height":480},{"@type":"BreadcrumbList","@id":"https:\/\/folhadems.com.br\/site\/2026\/05\/29\/governo-de-ms-empossa-grupo-de-trabalho-para-celebrar-os-50-anos-do-estado\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/folhadems.com.br\/site\/"},{"@type":"ListItem","position":2,"name":"Governo de MS empossa grupo de trabalho para celebrar os 50 anos do Estado"}]},{"@type":"WebSite","@id":"https:\/\/folhadems.com.br\/site\/#website","url":"https:\/\/folhadems.com.br\/site\/","name":"Folha de Mato Grosso do Sul","description":"Jornal Online","publisher":{"@id":"https:\/\/folhadems.com.br\/site\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/folhadems.com.br\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/folhadems.com.br\/site\/#organization","name":"Folha de Mato Grosso do Sul","url":"https:\/\/folhadems.com.br\/site\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/folhadems.com.br\/site\/#\/schema\/logo\/image\/","url":"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2023\/01\/logo-folha-de-ms-380x90-1.jpg","contentUrl":"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2023\/01\/logo-folha-de-ms-380x90-1.jpg","width":380,"height":90,"caption":"Folha de Mato Grosso do Sul"},"image":{"@id":"https:\/\/folhadems.com.br\/site\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/folhadems.com.br\/site\/#\/schema\/person\/e4a04038e5c2e7040e19ef252ae9d940","name":"Elite Midia","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/folhadems.com.br\/site\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/f76a80f01119f7fec6909ab9feea8819031f391155be021b685479d77496f055?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f76a80f01119f7fec6909ab9feea8819031f391155be021b685479d77496f055?s=96&d=mm&r=g","caption":"Elite Midia"},"sameAs":["https:\/\/folhadems.com.br\/site"],"url":"https:\/\/folhadems.com.br\/site\/author\/elite-midia\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-07-22 11:37:23","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/posts\/16644","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/comments?post=16644"}],"version-history":[{"count":1,"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/posts\/16644\/revisions"}],"predecessor-version":[{"id":16646,"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/posts\/16644\/revisions\/16646"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/media\/16645"}],"wp:attachment":[{"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/media?parent=16644"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/categories?post=16644"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/tags?post=16644"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}