{"id":16632,"date":"2026-05-28T18:15:00","date_gmt":"2026-05-28T22:15:00","guid":{"rendered":"https:\/\/folhadems.com.br\/site\/?p=16632"},"modified":"2026-05-28T16:12:59","modified_gmt":"2026-05-28T20:12:59","slug":"licitacao-de-reordenamento-na-av-tamandare-e-publicada","status":"publish","type":"post","link":"https:\/\/folhadems.com.br\/site\/2026\/05\/28\/licitacao-de-reordenamento-na-av-tamandare-e-publicada\/","title":{"rendered":"Licita\u00e7\u00e3o de reordenamento na Av. Tamandar\u00e9 \u00e9 publicada"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Foi publicado nesta quinta-feira (28) no Di\u00e1rio Oficial de Campo Grande (Diogrande), o aviso de licita\u00e7\u00e3o para obra de reordenamento vi\u00e1rio na rotat\u00f3ria que une as Avenidas Tamandar\u00e9, Dr. Euler de Azevedo e Dom Ant\u00f4nio Barbosa. O projeto tem investimento previsto de R$ 2.440.397,75 para destravar um dos principais gargalos de tr\u00e2nsito da Capital.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A interven\u00e7\u00e3o vai beneficiar diretamente os moradores dos bairros Nasser, Vila Sobrinho e S\u00e3o Francisco. O pacote de melhorias inclui obras de drenagem, nova pavimenta\u00e7\u00e3o nos trechos modificados, reforma de cal\u00e7adas com acessibilidade e novas aberturas no canteiro central para adequa\u00e7\u00e3o dos retornos. O ponto alto da mudan\u00e7a ser\u00e1 a instala\u00e7\u00e3o de um sistema semaf\u00f3rico e nova sinaliza\u00e7\u00e3o para ordenar o fluxo e eliminar os pontos de conflito.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O processo ser\u00e1 realizado na modalidade de Preg\u00e3o Eletr\u00f4nico (n\u00ba 057\/2026), voltado para empresas especializadas em engenharia sob o regime de ampla concorr\u00eancia. As empresas interessadas em assumir os trabalhos t\u00eam at\u00e9 as 7h44 do dia 22 de junho de 2026 para enviar suas propostas comerciais pelo sistema<br>eletr\u00f4nico do munic\u00edpio.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A sess\u00e3o p\u00fablica virtual para a disputa de pre\u00e7os come\u00e7ar\u00e1 logo em seguida, \u00e0s 7h45 do mesmo dia 22 de junho, seguindo rigorosamente o hor\u00e1rio oficial de Mato Grosso do Sul. Os detalhes t\u00e9cnicos e a \u00edntegra do edital publicado no Diogrande j\u00e1 podem ser consultados no portal de compras do munic\u00edpio, no Portal da Transpar\u00eancia de Campo Grande ou diretamente no Portal Nacional de Contrata\u00e7\u00f5es P\u00fablicas (PNCP) do Governo Federal.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><em>Fonte: PrefCG<\/em><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Foi publicado nesta quinta-feira (28) no Di\u00e1rio Oficial de Campo Grande (Diogrande), o aviso de licita\u00e7\u00e3o para obra de reordenamento<\/p>\n","protected":false},"author":1,"featured_media":16633,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[26],"tags":[],"class_list":["post-16632","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cotidiano"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.1.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Licita\u00e7\u00e3o de reordenamento na Av. Tamandar\u00e9 \u00e9 publicada - Folha de Mato Grosso do Sul<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/folhadems.com.br\/site\/2026\/05\/28\/licitacao-de-reordenamento-na-av-tamandare-e-publicada\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Licita\u00e7\u00e3o de reordenamento na Av. Tamandar\u00e9 \u00e9 publicada - Folha de Mato Grosso do Sul\" \/>\n<meta property=\"og:description\" content=\"Foi publicado nesta quinta-feira (28) no Di\u00e1rio Oficial de Campo Grande (Diogrande), o aviso de licita\u00e7\u00e3o para obra de reordenamento\" \/>\n<meta property=\"og:url\" content=\"https:\/\/folhadems.com.br\/site\/2026\/05\/28\/licitacao-de-reordenamento-na-av-tamandare-e-publicada\/\" \/>\n<meta property=\"og:site_name\" content=\"Folha de Mato Grosso do Sul\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-28T22:15:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2026\/05\/tamandare.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"900\" \/>\n\t<meta property=\"og:image:height\" content=\"506\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Elite Midia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Elite Midia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/folhadems.com.br\/site\/2026\/05\/28\/licitacao-de-reordenamento-na-av-tamandare-e-publicada\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/folhadems.com.br\/site\/2026\/05\/28\/licitacao-de-reordenamento-na-av-tamandare-e-publicada\/\"},\"author\":{\"name\":\"Elite Midia\",\"@id\":\"https:\/\/folhadems.com.br\/site\/#\/schema\/person\/e4a04038e5c2e7040e19ef252ae9d940\"},\"headline\":\"Licita\u00e7\u00e3o de reordenamento na Av. Tamandar\u00e9 \u00e9 publicada\",\"datePublished\":\"2026-05-28T22:15:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/folhadems.com.br\/site\/2026\/05\/28\/licitacao-de-reordenamento-na-av-tamandare-e-publicada\/\"},\"wordCount\":278,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/folhadems.com.br\/site\/#organization\"},\"image\":{\"@id\":\"https:\/\/folhadems.com.br\/site\/2026\/05\/28\/licitacao-de-reordenamento-na-av-tamandare-e-publicada\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2026\/05\/tamandare.jpg\",\"articleSection\":[\"Cotidiano\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/folhadems.com.br\/site\/2026\/05\/28\/licitacao-de-reordenamento-na-av-tamandare-e-publicada\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/folhadems.com.br\/site\/2026\/05\/28\/licitacao-de-reordenamento-na-av-tamandare-e-publicada\/\",\"url\":\"https:\/\/folhadems.com.br\/site\/2026\/05\/28\/licitacao-de-reordenamento-na-av-tamandare-e-publicada\/\",\"name\":\"Licita\u00e7\u00e3o de reordenamento na Av. Tamandar\u00e9 \u00e9 publicada - Folha de Mato Grosso do Sul\",\"isPartOf\":{\"@id\":\"https:\/\/folhadems.com.br\/site\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/folhadems.com.br\/site\/2026\/05\/28\/licitacao-de-reordenamento-na-av-tamandare-e-publicada\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/folhadems.com.br\/site\/2026\/05\/28\/licitacao-de-reordenamento-na-av-tamandare-e-publicada\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2026\/05\/tamandare.jpg\",\"datePublished\":\"2026-05-28T22:15:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/folhadems.com.br\/site\/2026\/05\/28\/licitacao-de-reordenamento-na-av-tamandare-e-publicada\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/folhadems.com.br\/site\/2026\/05\/28\/licitacao-de-reordenamento-na-av-tamandare-e-publicada\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/folhadems.com.br\/site\/2026\/05\/28\/licitacao-de-reordenamento-na-av-tamandare-e-publicada\/#primaryimage\",\"url\":\"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2026\/05\/tamandare.jpg\",\"contentUrl\":\"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2026\/05\/tamandare.jpg\",\"width\":900,\"height\":506},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/folhadems.com.br\/site\/2026\/05\/28\/licitacao-de-reordenamento-na-av-tamandare-e-publicada\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/folhadems.com.br\/site\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Licita\u00e7\u00e3o de reordenamento na Av. Tamandar\u00e9 \u00e9 publicada\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/folhadems.com.br\/site\/#website\",\"url\":\"https:\/\/folhadems.com.br\/site\/\",\"name\":\"Folha de Mato Grosso do Sul\",\"description\":\"Jornal Online\",\"publisher\":{\"@id\":\"https:\/\/folhadems.com.br\/site\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/folhadems.com.br\/site\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/folhadems.com.br\/site\/#organization\",\"name\":\"Folha de Mato Grosso do Sul\",\"url\":\"https:\/\/folhadems.com.br\/site\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/folhadems.com.br\/site\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2023\/01\/logo-folha-de-ms-380x90-1.jpg\",\"contentUrl\":\"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2023\/01\/logo-folha-de-ms-380x90-1.jpg\",\"width\":380,\"height\":90,\"caption\":\"Folha de Mato Grosso do Sul\"},\"image\":{\"@id\":\"https:\/\/folhadems.com.br\/site\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/folhadems.com.br\/site\/#\/schema\/person\/e4a04038e5c2e7040e19ef252ae9d940\",\"name\":\"Elite Midia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/folhadems.com.br\/site\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/f76a80f01119f7fec6909ab9feea8819031f391155be021b685479d77496f055?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/f76a80f01119f7fec6909ab9feea8819031f391155be021b685479d77496f055?s=96&d=mm&r=g\",\"caption\":\"Elite Midia\"},\"sameAs\":[\"https:\/\/folhadems.com.br\/site\"],\"url\":\"https:\/\/folhadems.com.br\/site\/author\/elite-midia\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Licita\u00e7\u00e3o de reordenamento na Av. Tamandar\u00e9 \u00e9 publicada - Folha de Mato Grosso do Sul","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/folhadems.com.br\/site\/2026\/05\/28\/licitacao-de-reordenamento-na-av-tamandare-e-publicada\/","og_locale":"pt_BR","og_type":"article","og_title":"Licita\u00e7\u00e3o de reordenamento na Av. Tamandar\u00e9 \u00e9 publicada - Folha de Mato Grosso do Sul","og_description":"Foi publicado nesta quinta-feira (28) no Di\u00e1rio Oficial de Campo Grande (Diogrande), o aviso de licita\u00e7\u00e3o para obra de reordenamento","og_url":"https:\/\/folhadems.com.br\/site\/2026\/05\/28\/licitacao-de-reordenamento-na-av-tamandare-e-publicada\/","og_site_name":"Folha de Mato Grosso do Sul","article_published_time":"2026-05-28T22:15:00+00:00","og_image":[{"width":900,"height":506,"url":"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2026\/05\/tamandare.jpg","type":"image\/jpeg"}],"author":"Elite Midia","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Elite Midia","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/folhadems.com.br\/site\/2026\/05\/28\/licitacao-de-reordenamento-na-av-tamandare-e-publicada\/#article","isPartOf":{"@id":"https:\/\/folhadems.com.br\/site\/2026\/05\/28\/licitacao-de-reordenamento-na-av-tamandare-e-publicada\/"},"author":{"name":"Elite Midia","@id":"https:\/\/folhadems.com.br\/site\/#\/schema\/person\/e4a04038e5c2e7040e19ef252ae9d940"},"headline":"Licita\u00e7\u00e3o de reordenamento na Av. Tamandar\u00e9 \u00e9 publicada","datePublished":"2026-05-28T22:15:00+00:00","mainEntityOfPage":{"@id":"https:\/\/folhadems.com.br\/site\/2026\/05\/28\/licitacao-de-reordenamento-na-av-tamandare-e-publicada\/"},"wordCount":278,"commentCount":0,"publisher":{"@id":"https:\/\/folhadems.com.br\/site\/#organization"},"image":{"@id":"https:\/\/folhadems.com.br\/site\/2026\/05\/28\/licitacao-de-reordenamento-na-av-tamandare-e-publicada\/#primaryimage"},"thumbnailUrl":"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2026\/05\/tamandare.jpg","articleSection":["Cotidiano"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/folhadems.com.br\/site\/2026\/05\/28\/licitacao-de-reordenamento-na-av-tamandare-e-publicada\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/folhadems.com.br\/site\/2026\/05\/28\/licitacao-de-reordenamento-na-av-tamandare-e-publicada\/","url":"https:\/\/folhadems.com.br\/site\/2026\/05\/28\/licitacao-de-reordenamento-na-av-tamandare-e-publicada\/","name":"Licita\u00e7\u00e3o de reordenamento na Av. Tamandar\u00e9 \u00e9 publicada - Folha de Mato Grosso do Sul","isPartOf":{"@id":"https:\/\/folhadems.com.br\/site\/#website"},"primaryImageOfPage":{"@id":"https:\/\/folhadems.com.br\/site\/2026\/05\/28\/licitacao-de-reordenamento-na-av-tamandare-e-publicada\/#primaryimage"},"image":{"@id":"https:\/\/folhadems.com.br\/site\/2026\/05\/28\/licitacao-de-reordenamento-na-av-tamandare-e-publicada\/#primaryimage"},"thumbnailUrl":"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2026\/05\/tamandare.jpg","datePublished":"2026-05-28T22:15:00+00:00","breadcrumb":{"@id":"https:\/\/folhadems.com.br\/site\/2026\/05\/28\/licitacao-de-reordenamento-na-av-tamandare-e-publicada\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/folhadems.com.br\/site\/2026\/05\/28\/licitacao-de-reordenamento-na-av-tamandare-e-publicada\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/folhadems.com.br\/site\/2026\/05\/28\/licitacao-de-reordenamento-na-av-tamandare-e-publicada\/#primaryimage","url":"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2026\/05\/tamandare.jpg","contentUrl":"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2026\/05\/tamandare.jpg","width":900,"height":506},{"@type":"BreadcrumbList","@id":"https:\/\/folhadems.com.br\/site\/2026\/05\/28\/licitacao-de-reordenamento-na-av-tamandare-e-publicada\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/folhadems.com.br\/site\/"},{"@type":"ListItem","position":2,"name":"Licita\u00e7\u00e3o de reordenamento na Av. Tamandar\u00e9 \u00e9 publicada"}]},{"@type":"WebSite","@id":"https:\/\/folhadems.com.br\/site\/#website","url":"https:\/\/folhadems.com.br\/site\/","name":"Folha de Mato Grosso do Sul","description":"Jornal Online","publisher":{"@id":"https:\/\/folhadems.com.br\/site\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/folhadems.com.br\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/folhadems.com.br\/site\/#organization","name":"Folha de Mato Grosso do Sul","url":"https:\/\/folhadems.com.br\/site\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/folhadems.com.br\/site\/#\/schema\/logo\/image\/","url":"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2023\/01\/logo-folha-de-ms-380x90-1.jpg","contentUrl":"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2023\/01\/logo-folha-de-ms-380x90-1.jpg","width":380,"height":90,"caption":"Folha de Mato Grosso do Sul"},"image":{"@id":"https:\/\/folhadems.com.br\/site\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/folhadems.com.br\/site\/#\/schema\/person\/e4a04038e5c2e7040e19ef252ae9d940","name":"Elite Midia","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/folhadems.com.br\/site\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/f76a80f01119f7fec6909ab9feea8819031f391155be021b685479d77496f055?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f76a80f01119f7fec6909ab9feea8819031f391155be021b685479d77496f055?s=96&d=mm&r=g","caption":"Elite Midia"},"sameAs":["https:\/\/folhadems.com.br\/site"],"url":"https:\/\/folhadems.com.br\/site\/author\/elite-midia\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-07-22 04:32:54","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/posts\/16632","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/comments?post=16632"}],"version-history":[{"count":1,"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/posts\/16632\/revisions"}],"predecessor-version":[{"id":16634,"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/posts\/16632\/revisions\/16634"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/media\/16633"}],"wp:attachment":[{"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/media?parent=16632"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/categories?post=16632"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/tags?post=16632"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}