{"id":16624,"date":"2026-05-28T16:05:20","date_gmt":"2026-05-28T20:05:20","guid":{"rendered":"https:\/\/folhadems.com.br\/site\/?p=16624"},"modified":"2026-05-28T16:05:24","modified_gmt":"2026-05-28T20:05:24","slug":"projeto-de-ia-do-detran-ms-conquista-premio-nacional-e-impulsiona-nova-era-digital","status":"publish","type":"post","link":"https:\/\/folhadems.com.br\/site\/2026\/05\/28\/projeto-de-ia-do-detran-ms-conquista-premio-nacional-e-impulsiona-nova-era-digital\/","title":{"rendered":"Projeto de IA do Detran-MS conquista pr\u00eamio nacional e impulsiona nova era digital"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">O Departamento Estadual de Tr\u00e2nsito de Mato Grosso do Sul (Detran-MS) conquistou nesta ter\u00e7a-feira (26) o primeiro lugar no Pr\u00eamio Brasil de Gest\u00e3o P\u00fablica, durante a 4\u00aa edi\u00e7\u00e3o da Expo GovBrasil, realizada no Transam\u00e9rica Expo Center, em S\u00e3o Paulo (SP). O reconhecimento veio na categoria \u201cEfici\u00eancia Administrativa, Desburocratiza\u00e7\u00e3o e Melhoria de Processos\u201d, com o programa DPI \u2013 Defesa Pr\u00e9via Inteligente.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O projeto utiliza Intelig\u00eancia Artificial para automatizar a an\u00e1lise de processos de defesa pr\u00e9via relacionados \u00e0 suspens\u00e3o do direito de dirigir, promovendo mais agilidade, padroniza\u00e7\u00e3o e efici\u00eancia nos julgamentos administrativos. A premia\u00e7\u00e3o reconhece iniciativas que transformam a gest\u00e3o p\u00fablica com impacto concreto para o cidad\u00e3o.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter\"><a href=\"https:\/\/www.detran.ms.gov.br\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-26-at-18.58.30.jpeg\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" src=\"https:\/\/www.detran.ms.gov.br\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-26-at-18.58.30-768x1024.jpeg\" alt=\"\" class=\"wp-image-46138\"\/><\/a><figcaption class=\"wp-element-caption\">Robson Lui, Diretor de TI do Detran-MS com o Secret\u00e1rio da Sejusp, Antonio Carlos Videira<\/figcaption><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">O secret\u00e1rio de Estado de Justi\u00e7a e Seguran\u00e7a P\u00fablica, Antonio Carlos Videira, destacou que o reconhecimento nacional refor\u00e7a o protagonismo do Detran-MS na moderniza\u00e7\u00e3o da gest\u00e3o p\u00fablica e na melhoria dos servi\u00e7os oferecidos \u00e0 popula\u00e7\u00e3o.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cO Detran-MS serve de exemplo para o restante do pa\u00eds. \u00c9 voc\u00ea melhorar o acesso da popula\u00e7\u00e3o aos servi\u00e7os essenciais hoje em dia. E quando voc\u00ea internamente promove celeridade nos procedimentos e processos, voc\u00ea tamb\u00e9m melhora o ambiente de trabalho do servidor p\u00fablico. O Detran-MS tem sido uma refer\u00eancia nacional e, agora, com a aplica\u00e7\u00e3o de tecnologia, solu\u00e7\u00f5es e Intelig\u00eancia Artificial, melhora cada vez mais a presta\u00e7\u00e3o de servi\u00e7os \u00e0 popula\u00e7\u00e3o. \u00c9 isso que a gente almeja: um Mato Grosso do Sul cada vez mais seguro, mais moderno e com servi\u00e7os mais acess\u00edveis ao cidad\u00e3o\u201d, afirmou.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para o diretor-presidente do Detran-MS, Rudel Trindade, a conquista refor\u00e7a o compromisso da gest\u00e3o estadual com inova\u00e7\u00e3o, efici\u00eancia e melhoria cont\u00ednua dos servi\u00e7os p\u00fablicos. \u201cEsse reconhecimento nacional mostra que o Detran-MS est\u00e1 avan\u00e7ando na moderniza\u00e7\u00e3o da gest\u00e3o p\u00fablica, utilizando tecnologia para tornar os processos mais \u00e1geis, eficientes e seguros. O mais importante \u00e9 que esse projeto nasceu a partir de ideias, conhecimento t\u00e9cnico e da expertise dos pr\u00f3prios servidores do Detran-MS, mostrando a capacidade do nosso quadro em desenvolver solu\u00e7\u00f5es inovadoras para melhorar os servi\u00e7os p\u00fablicos. Esse \u00e9 o primeiro de uma s\u00e9rie de projetos alinhados aos pilares de inova\u00e7\u00e3o, transforma\u00e7\u00e3o digital e melhoria cont\u00ednua defendidos pelo Governo do Estado\u201d, afirmou Rudel Trindade que nesta quarta-feira (27) recebeu mo\u00e7\u00e3o de congratula\u00e7\u00e3o na Assembleia Legislativa de Mato Grosso do Sul pelo projeto premiado.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Segundo o diretor de Tecnologia da Informa\u00e7\u00e3o do Detran-MS, Robson Lui, o reconhecimento nacional consolida o protagonismo do \u00f3rg\u00e3o na transforma\u00e7\u00e3o digital aplicada ao servi\u00e7o p\u00fablico. \u201cEsse pr\u00eamio mostra que a tecnologia, quando aplicada com responsabilidade e foco no cidad\u00e3o, tem capacidade real de transformar a gest\u00e3o p\u00fablica. O DPI nasceu para modernizar um processo administrativo interno do Detran-MS, voltado \u00e0 an\u00e1lise de recursos e defesas pr\u00e9vias, trazendo mais agilidade, padroniza\u00e7\u00e3o e efici\u00eancia para o fluxo processual. Hoje, essa solu\u00e7\u00e3o in\u00e9dita desenvolvida com Intelig\u00eancia Artificial se torna refer\u00eancia nacional, garantindo respostas mais r\u00e1pidas e seguras ao cidad\u00e3o\u201d, destacou.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O sistema foi desenvolvido para analisar automaticamente os argumentos apresentados pelos condutores, cruzando informa\u00e7\u00f5es dos autos com a legisla\u00e7\u00e3o vigente, incluindo o C\u00f3digo de Tr\u00e2nsito Brasileiro (CTB) e resolu\u00e7\u00f5es do Contran. Ap\u00f3s a an\u00e1lise, a IA emite um parecer t\u00e9cnico fundamentado, que passa pela valida\u00e7\u00e3o final de um servidor p\u00fablico. Toda a elabora\u00e7\u00e3o da ferramenta premiada contou com a colabora\u00e7\u00e3o de servidores do setor de penalidades do Detran-MS (Sepen) em parceria com a TI.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De acordo com o documento t\u00e9cnico inscrito na premia\u00e7\u00e3o, o projeto j\u00e1 analisou 1.186 processos entre janeiro e mar\u00e7o de 2026, alcan\u00e7ando \u00edndice de precis\u00e3o entre 99,6% e 100%, al\u00e9m de um ganho de produtividade de 17,2% ap\u00f3s a consolida\u00e7\u00e3o do modelo.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter\"><a href=\"https:\/\/www.detran.ms.gov.br\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-26-at-18.57.53.jpeg\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" src=\"https:\/\/www.detran.ms.gov.br\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-26-at-18.57.53-768x1024.jpeg\" alt=\"\" class=\"wp-image-46137\"\/><\/a><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">Antes da implanta\u00e7\u00e3o do DPI, todo o processo era realizado manualmente pelos servidores, demandando horas ou at\u00e9 dias para an\u00e1lise individual dos processos. Com a automa\u00e7\u00e3o, o tempo de tramita\u00e7\u00e3o caiu para poucos minutos na etapa de revis\u00e3o humana, reduzindo gargalos operacionais e aumentando a capacidade de atendimento do \u00f3rg\u00e3o.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A premia\u00e7\u00e3o tamb\u00e9m contou com a presen\u00e7a do secret\u00e1rio de Meio Ambiente, Desenvolvimento, Ci\u00eancia, Tecnologia e Inova\u00e7\u00e3o (Semadesc), Artur Henrique Leite Falcette, da Diretora Presidente da Escolagov, Ana Paula Martins, entre outros gestores de Mato Grosso do Sul que tamb\u00e9m concorreram \u00e0s premia\u00e7\u00f5es nacionais.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O Pr\u00eamio Brasil de Gest\u00e3o P\u00fablica \u00e9 realizado durante a Expo GovBrasil e tem como objetivo reconhecer projetos que fortalecem as institui\u00e7\u00f5es p\u00fablicas, promovem efici\u00eancia administrativa e entregam resultados concretos para a popula\u00e7\u00e3o.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Inova\u00e7\u00e3o<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O sistema vencedor do Pr\u00eamio Brasil de Gest\u00e3o P\u00fablica marca o in\u00edcio de um projeto macro de transforma\u00e7\u00e3o digital e moderniza\u00e7\u00e3o dos processos burocr\u00e1ticos do Detran-MS. A iniciativa foi constru\u00edda a partir de ideias, conhecimento t\u00e9cnico e expertise dos pr\u00f3prios servidores do \u00f3rg\u00e3o, aliados ao desenvolvimento tecnol\u00f3gico da equipe parceira.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A tecnologia aplicada na Defesa Pr\u00e9via Inteligente serviu como base para o novo sistema de Intelig\u00eancia Artificial da JARI, que ser\u00e1 lan\u00e7ado oficialmente nesta sexta-feira (29), \u00e0s 10h, no audit\u00f3rio da Secretaria Municipal de Educa\u00e7\u00e3o de Aquidauana, localizado na Rua Luiz da Costa Gomes, n\u00ba 610.&nbsp; A nova ferramenta vai atuar na an\u00e1lise de recursos administrativos de tr\u00e2nsito, ampliando a capacidade operacional, a padroniza\u00e7\u00e3o dos julgamentos e a agilidade nos processos internos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em><strong>Mireli Obando, Comunica\u00e7\u00e3o Detran-MS<\/strong><\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Departamento Estadual de Tr\u00e2nsito de Mato Grosso do Sul (Detran-MS) conquistou nesta ter\u00e7a-feira (26) o primeiro lugar no Pr\u00eamio<\/p>\n","protected":false},"author":1,"featured_media":16625,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-16624","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-geral-brasil"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.1.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Projeto de IA do Detran-MS conquista pr\u00eamio nacional e impulsiona nova era digital - Folha de Mato Grosso do Sul<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/folhadems.com.br\/site\/2026\/05\/28\/projeto-de-ia-do-detran-ms-conquista-premio-nacional-e-impulsiona-nova-era-digital\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Projeto de IA do Detran-MS conquista pr\u00eamio nacional e impulsiona nova era digital - Folha de Mato Grosso do Sul\" \/>\n<meta property=\"og:description\" content=\"O Departamento Estadual de Tr\u00e2nsito de Mato Grosso do Sul (Detran-MS) conquistou nesta ter\u00e7a-feira (26) o primeiro lugar no Pr\u00eamio\" \/>\n<meta property=\"og:url\" content=\"https:\/\/folhadems.com.br\/site\/2026\/05\/28\/projeto-de-ia-do-detran-ms-conquista-premio-nacional-e-impulsiona-nova-era-digital\/\" \/>\n<meta property=\"og:site_name\" content=\"Folha de Mato Grosso do Sul\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-28T20:05:20+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-28T20:05:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2026\/05\/ia-gov.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"450\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Elite Midia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Elite Midia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/folhadems.com.br\/site\/2026\/05\/28\/projeto-de-ia-do-detran-ms-conquista-premio-nacional-e-impulsiona-nova-era-digital\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/folhadems.com.br\/site\/2026\/05\/28\/projeto-de-ia-do-detran-ms-conquista-premio-nacional-e-impulsiona-nova-era-digital\/\"},\"author\":{\"name\":\"Elite Midia\",\"@id\":\"https:\/\/folhadems.com.br\/site\/#\/schema\/person\/e4a04038e5c2e7040e19ef252ae9d940\"},\"headline\":\"Projeto de IA do Detran-MS conquista pr\u00eamio nacional e impulsiona nova era digital\",\"datePublished\":\"2026-05-28T20:05:20+00:00\",\"dateModified\":\"2026-05-28T20:05:24+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/folhadems.com.br\/site\/2026\/05\/28\/projeto-de-ia-do-detran-ms-conquista-premio-nacional-e-impulsiona-nova-era-digital\/\"},\"wordCount\":998,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/folhadems.com.br\/site\/#organization\"},\"image\":{\"@id\":\"https:\/\/folhadems.com.br\/site\/2026\/05\/28\/projeto-de-ia-do-detran-ms-conquista-premio-nacional-e-impulsiona-nova-era-digital\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2026\/05\/ia-gov.jpg\",\"articleSection\":[\"Geral \/ Brasil\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/folhadems.com.br\/site\/2026\/05\/28\/projeto-de-ia-do-detran-ms-conquista-premio-nacional-e-impulsiona-nova-era-digital\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/folhadems.com.br\/site\/2026\/05\/28\/projeto-de-ia-do-detran-ms-conquista-premio-nacional-e-impulsiona-nova-era-digital\/\",\"url\":\"https:\/\/folhadems.com.br\/site\/2026\/05\/28\/projeto-de-ia-do-detran-ms-conquista-premio-nacional-e-impulsiona-nova-era-digital\/\",\"name\":\"Projeto de IA do Detran-MS conquista pr\u00eamio nacional e impulsiona nova era digital - Folha de Mato Grosso do Sul\",\"isPartOf\":{\"@id\":\"https:\/\/folhadems.com.br\/site\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/folhadems.com.br\/site\/2026\/05\/28\/projeto-de-ia-do-detran-ms-conquista-premio-nacional-e-impulsiona-nova-era-digital\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/folhadems.com.br\/site\/2026\/05\/28\/projeto-de-ia-do-detran-ms-conquista-premio-nacional-e-impulsiona-nova-era-digital\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2026\/05\/ia-gov.jpg\",\"datePublished\":\"2026-05-28T20:05:20+00:00\",\"dateModified\":\"2026-05-28T20:05:24+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/folhadems.com.br\/site\/2026\/05\/28\/projeto-de-ia-do-detran-ms-conquista-premio-nacional-e-impulsiona-nova-era-digital\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/folhadems.com.br\/site\/2026\/05\/28\/projeto-de-ia-do-detran-ms-conquista-premio-nacional-e-impulsiona-nova-era-digital\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/folhadems.com.br\/site\/2026\/05\/28\/projeto-de-ia-do-detran-ms-conquista-premio-nacional-e-impulsiona-nova-era-digital\/#primaryimage\",\"url\":\"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2026\/05\/ia-gov.jpg\",\"contentUrl\":\"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2026\/05\/ia-gov.jpg\",\"width\":800,\"height\":450},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/folhadems.com.br\/site\/2026\/05\/28\/projeto-de-ia-do-detran-ms-conquista-premio-nacional-e-impulsiona-nova-era-digital\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/folhadems.com.br\/site\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Projeto de IA do Detran-MS conquista pr\u00eamio nacional e impulsiona nova era digital\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/folhadems.com.br\/site\/#website\",\"url\":\"https:\/\/folhadems.com.br\/site\/\",\"name\":\"Folha de Mato Grosso do Sul\",\"description\":\"Jornal Online\",\"publisher\":{\"@id\":\"https:\/\/folhadems.com.br\/site\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/folhadems.com.br\/site\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/folhadems.com.br\/site\/#organization\",\"name\":\"Folha de Mato Grosso do Sul\",\"url\":\"https:\/\/folhadems.com.br\/site\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/folhadems.com.br\/site\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2023\/01\/logo-folha-de-ms-380x90-1.jpg\",\"contentUrl\":\"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2023\/01\/logo-folha-de-ms-380x90-1.jpg\",\"width\":380,\"height\":90,\"caption\":\"Folha de Mato Grosso do Sul\"},\"image\":{\"@id\":\"https:\/\/folhadems.com.br\/site\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/folhadems.com.br\/site\/#\/schema\/person\/e4a04038e5c2e7040e19ef252ae9d940\",\"name\":\"Elite Midia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/folhadems.com.br\/site\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/f76a80f01119f7fec6909ab9feea8819031f391155be021b685479d77496f055?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/f76a80f01119f7fec6909ab9feea8819031f391155be021b685479d77496f055?s=96&d=mm&r=g\",\"caption\":\"Elite Midia\"},\"sameAs\":[\"https:\/\/folhadems.com.br\/site\"],\"url\":\"https:\/\/folhadems.com.br\/site\/author\/elite-midia\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Projeto de IA do Detran-MS conquista pr\u00eamio nacional e impulsiona nova era digital - Folha de Mato Grosso do Sul","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/folhadems.com.br\/site\/2026\/05\/28\/projeto-de-ia-do-detran-ms-conquista-premio-nacional-e-impulsiona-nova-era-digital\/","og_locale":"pt_BR","og_type":"article","og_title":"Projeto de IA do Detran-MS conquista pr\u00eamio nacional e impulsiona nova era digital - Folha de Mato Grosso do Sul","og_description":"O Departamento Estadual de Tr\u00e2nsito de Mato Grosso do Sul (Detran-MS) conquistou nesta ter\u00e7a-feira (26) o primeiro lugar no Pr\u00eamio","og_url":"https:\/\/folhadems.com.br\/site\/2026\/05\/28\/projeto-de-ia-do-detran-ms-conquista-premio-nacional-e-impulsiona-nova-era-digital\/","og_site_name":"Folha de Mato Grosso do Sul","article_published_time":"2026-05-28T20:05:20+00:00","article_modified_time":"2026-05-28T20:05:24+00:00","og_image":[{"width":800,"height":450,"url":"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2026\/05\/ia-gov.jpg","type":"image\/jpeg"}],"author":"Elite Midia","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Elite Midia","Est. tempo de leitura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/folhadems.com.br\/site\/2026\/05\/28\/projeto-de-ia-do-detran-ms-conquista-premio-nacional-e-impulsiona-nova-era-digital\/#article","isPartOf":{"@id":"https:\/\/folhadems.com.br\/site\/2026\/05\/28\/projeto-de-ia-do-detran-ms-conquista-premio-nacional-e-impulsiona-nova-era-digital\/"},"author":{"name":"Elite Midia","@id":"https:\/\/folhadems.com.br\/site\/#\/schema\/person\/e4a04038e5c2e7040e19ef252ae9d940"},"headline":"Projeto de IA do Detran-MS conquista pr\u00eamio nacional e impulsiona nova era digital","datePublished":"2026-05-28T20:05:20+00:00","dateModified":"2026-05-28T20:05:24+00:00","mainEntityOfPage":{"@id":"https:\/\/folhadems.com.br\/site\/2026\/05\/28\/projeto-de-ia-do-detran-ms-conquista-premio-nacional-e-impulsiona-nova-era-digital\/"},"wordCount":998,"commentCount":0,"publisher":{"@id":"https:\/\/folhadems.com.br\/site\/#organization"},"image":{"@id":"https:\/\/folhadems.com.br\/site\/2026\/05\/28\/projeto-de-ia-do-detran-ms-conquista-premio-nacional-e-impulsiona-nova-era-digital\/#primaryimage"},"thumbnailUrl":"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2026\/05\/ia-gov.jpg","articleSection":["Geral \/ Brasil"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/folhadems.com.br\/site\/2026\/05\/28\/projeto-de-ia-do-detran-ms-conquista-premio-nacional-e-impulsiona-nova-era-digital\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/folhadems.com.br\/site\/2026\/05\/28\/projeto-de-ia-do-detran-ms-conquista-premio-nacional-e-impulsiona-nova-era-digital\/","url":"https:\/\/folhadems.com.br\/site\/2026\/05\/28\/projeto-de-ia-do-detran-ms-conquista-premio-nacional-e-impulsiona-nova-era-digital\/","name":"Projeto de IA do Detran-MS conquista pr\u00eamio nacional e impulsiona nova era digital - Folha de Mato Grosso do Sul","isPartOf":{"@id":"https:\/\/folhadems.com.br\/site\/#website"},"primaryImageOfPage":{"@id":"https:\/\/folhadems.com.br\/site\/2026\/05\/28\/projeto-de-ia-do-detran-ms-conquista-premio-nacional-e-impulsiona-nova-era-digital\/#primaryimage"},"image":{"@id":"https:\/\/folhadems.com.br\/site\/2026\/05\/28\/projeto-de-ia-do-detran-ms-conquista-premio-nacional-e-impulsiona-nova-era-digital\/#primaryimage"},"thumbnailUrl":"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2026\/05\/ia-gov.jpg","datePublished":"2026-05-28T20:05:20+00:00","dateModified":"2026-05-28T20:05:24+00:00","breadcrumb":{"@id":"https:\/\/folhadems.com.br\/site\/2026\/05\/28\/projeto-de-ia-do-detran-ms-conquista-premio-nacional-e-impulsiona-nova-era-digital\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/folhadems.com.br\/site\/2026\/05\/28\/projeto-de-ia-do-detran-ms-conquista-premio-nacional-e-impulsiona-nova-era-digital\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/folhadems.com.br\/site\/2026\/05\/28\/projeto-de-ia-do-detran-ms-conquista-premio-nacional-e-impulsiona-nova-era-digital\/#primaryimage","url":"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2026\/05\/ia-gov.jpg","contentUrl":"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2026\/05\/ia-gov.jpg","width":800,"height":450},{"@type":"BreadcrumbList","@id":"https:\/\/folhadems.com.br\/site\/2026\/05\/28\/projeto-de-ia-do-detran-ms-conquista-premio-nacional-e-impulsiona-nova-era-digital\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/folhadems.com.br\/site\/"},{"@type":"ListItem","position":2,"name":"Projeto de IA do Detran-MS conquista pr\u00eamio nacional e impulsiona nova era digital"}]},{"@type":"WebSite","@id":"https:\/\/folhadems.com.br\/site\/#website","url":"https:\/\/folhadems.com.br\/site\/","name":"Folha de Mato Grosso do Sul","description":"Jornal Online","publisher":{"@id":"https:\/\/folhadems.com.br\/site\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/folhadems.com.br\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/folhadems.com.br\/site\/#organization","name":"Folha de Mato Grosso do Sul","url":"https:\/\/folhadems.com.br\/site\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/folhadems.com.br\/site\/#\/schema\/logo\/image\/","url":"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2023\/01\/logo-folha-de-ms-380x90-1.jpg","contentUrl":"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2023\/01\/logo-folha-de-ms-380x90-1.jpg","width":380,"height":90,"caption":"Folha de Mato Grosso do Sul"},"image":{"@id":"https:\/\/folhadems.com.br\/site\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/folhadems.com.br\/site\/#\/schema\/person\/e4a04038e5c2e7040e19ef252ae9d940","name":"Elite Midia","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/folhadems.com.br\/site\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/f76a80f01119f7fec6909ab9feea8819031f391155be021b685479d77496f055?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f76a80f01119f7fec6909ab9feea8819031f391155be021b685479d77496f055?s=96&d=mm&r=g","caption":"Elite Midia"},"sameAs":["https:\/\/folhadems.com.br\/site"],"url":"https:\/\/folhadems.com.br\/site\/author\/elite-midia\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-07-22 01:47:09","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/posts\/16624","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/comments?post=16624"}],"version-history":[{"count":1,"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/posts\/16624\/revisions"}],"predecessor-version":[{"id":16626,"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/posts\/16624\/revisions\/16626"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/media\/16625"}],"wp:attachment":[{"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/media?parent=16624"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/categories?post=16624"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/tags?post=16624"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}