{"id":16619,"date":"2026-05-28T12:53:33","date_gmt":"2026-05-28T16:53:33","guid":{"rendered":"https:\/\/folhadems.com.br\/site\/?p=16619"},"modified":"2026-05-28T12:53:37","modified_gmt":"2026-05-28T16:53:37","slug":"dia-do-brincar-e-marcado-por-experiencias-sensoriais","status":"publish","type":"post","link":"https:\/\/folhadems.com.br\/site\/2026\/05\/28\/dia-do-brincar-e-marcado-por-experiencias-sensoriais\/","title":{"rendered":"Dia do Brincar \u00e9 marcado por experi\u00eancias sensoriais"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">O Centro Municipal de Educa\u00e7\u00e3o Especial Inclusiva (CMEEI) da Reme, realizou na manh\u00e3 de ontem (28), o \u201cDia do Brincar\u201d, a\u00e7\u00e3o voltada aos alunos dos grupos 4 e 5.&nbsp;O&nbsp;objetivo&nbsp;\u00e9&nbsp;promover situa\u00e7\u00f5es de aprendizagem por meio do l\u00fadico, da socializa\u00e7\u00e3o e da criatividade em diferentes oficinas pedag\u00f3gicas.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Logo na entrada, as crian\u00e7as encontram um ambiente preparado para despertar a curiosidade e a imagina\u00e7\u00e3o. Com a tem\u00e1tica \u201cfundo do mar\u201d, o espa\u00e7o re\u00fane cores, sons, movimentos e materiais sensoriais que convidam \u00e0 explora\u00e7\u00e3o e \u00e0 intera\u00e7\u00e3o.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A proposta foi pensada para ampliar as possibilidades de aprendizagem a partir das experi\u00eancias dos alunos \u201cA semana do brincar foi planejada com muito carinho, pensando nas experi\u00eancias sensoriais, visuais e nas diferentes possibilidades para que a crian\u00e7a aproveite ao m\u00e1ximo. A ideia do fundo do mar surge justamente porque envolve cores, movimentos, sons e elementos que fazem parte do universo das crian\u00e7as\u201d, explicou Marli Leal de Castro, t\u00e9cnica da Educa\u00e7\u00e3o Inclusiva respons\u00e1vel pelos grupos&nbsp;4 e 5.&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/cdn.campogrande.ms.gov.br\/portal\/prod\/uploads\/sites\/3\/2026\/05\/dad4c839-bcdb-4231-a9b7-a708a7f60a81-1024x767.jpeg\" alt=\"\" class=\"wp-image-162794\"\/><figcaption class=\"wp-element-caption\">Crian\u00e7a em atividade interativa durante o Dia de Brincar<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">As&nbsp;pr\u00e1ticas desenvolvidas no CMEEI tamb\u00e9m fazem parte de um processo cont\u00ednuo de estudo e reflex\u00e3o sobre o trabalho pedag\u00f3gico, considerando as particularidades de cada estudante da Rede Municipal de Ensino de Campo Grande.&nbsp;&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cCada crian\u00e7a tem sua particularidade, sua forma de reagir e aprender. N\u00e3o existe uma receita pronta. Trabalhamos com possibilidades, observando como cada uma responde \u00e0s experi\u00eancias e buscando sempre ampliar esse repert\u00f3rio\u201d, destacou T\u00e2nia Maria&nbsp;Fili\u00fa, coordenadora do Centro Municipal de Educa\u00e7\u00e3o Especial Inclusiva.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Esse trabalho vai al\u00e9m das atividades realizadas no centro e contribui diretamente para a forma\u00e7\u00e3o dos profissionais da rede municipal.&nbsp;\u201cO que a gente vivencia aqui tamb\u00e9m se transforma em conhecimento para compartilhar com as escolas. A gente estuda, pesquisa e leva essas experi\u00eancias para as forma\u00e7\u00f5es, ampliando as possibilidades de atua\u00e7\u00e3o dos professores\u201d, refor\u00e7ou.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A a\u00e7\u00e3o refor\u00e7a o brincar como parte da aprendizagem e mostra, na pr\u00e1tica, como o CMEEI desenvolve propostas que depois chegam \u00e0s escolas da rede municipal.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><em>Fonte: PrefCG<\/em><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Centro Municipal de Educa\u00e7\u00e3o Especial Inclusiva (CMEEI) da Reme, realizou na manh\u00e3 de ontem (28), o \u201cDia do Brincar\u201d,<\/p>\n","protected":false},"author":1,"featured_media":16620,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14],"tags":[],"class_list":["post-16619","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-educacao"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.1.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Dia do Brincar \u00e9 marcado por experi\u00eancias sensoriais - Folha de Mato Grosso do Sul<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/folhadems.com.br\/site\/2026\/05\/28\/dia-do-brincar-e-marcado-por-experiencias-sensoriais\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Dia do Brincar \u00e9 marcado por experi\u00eancias sensoriais - Folha de Mato Grosso do Sul\" \/>\n<meta property=\"og:description\" content=\"O Centro Municipal de Educa\u00e7\u00e3o Especial Inclusiva (CMEEI) da Reme, realizou na manh\u00e3 de ontem (28), o \u201cDia do Brincar\u201d,\" \/>\n<meta property=\"og:url\" content=\"https:\/\/folhadems.com.br\/site\/2026\/05\/28\/dia-do-brincar-e-marcado-por-experiencias-sensoriais\/\" \/>\n<meta property=\"og:site_name\" content=\"Folha de Mato Grosso do Sul\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-28T16:53:33+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-28T16:53:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2026\/05\/brincar.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"900\" \/>\n\t<meta property=\"og:image:height\" content=\"506\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Elite Midia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Elite Midia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/folhadems.com.br\/site\/2026\/05\/28\/dia-do-brincar-e-marcado-por-experiencias-sensoriais\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/folhadems.com.br\/site\/2026\/05\/28\/dia-do-brincar-e-marcado-por-experiencias-sensoriais\/\"},\"author\":{\"name\":\"Elite Midia\",\"@id\":\"https:\/\/folhadems.com.br\/site\/#\/schema\/person\/e4a04038e5c2e7040e19ef252ae9d940\"},\"headline\":\"Dia do Brincar \u00e9 marcado por experi\u00eancias sensoriais\",\"datePublished\":\"2026-05-28T16:53:33+00:00\",\"dateModified\":\"2026-05-28T16:53:37+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/folhadems.com.br\/site\/2026\/05\/28\/dia-do-brincar-e-marcado-por-experiencias-sensoriais\/\"},\"wordCount\":393,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/folhadems.com.br\/site\/#organization\"},\"image\":{\"@id\":\"https:\/\/folhadems.com.br\/site\/2026\/05\/28\/dia-do-brincar-e-marcado-por-experiencias-sensoriais\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2026\/05\/brincar.jpg\",\"articleSection\":[\"Educa\u00e7\u00e3o\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/folhadems.com.br\/site\/2026\/05\/28\/dia-do-brincar-e-marcado-por-experiencias-sensoriais\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/folhadems.com.br\/site\/2026\/05\/28\/dia-do-brincar-e-marcado-por-experiencias-sensoriais\/\",\"url\":\"https:\/\/folhadems.com.br\/site\/2026\/05\/28\/dia-do-brincar-e-marcado-por-experiencias-sensoriais\/\",\"name\":\"Dia do Brincar \u00e9 marcado por experi\u00eancias sensoriais - Folha de Mato Grosso do Sul\",\"isPartOf\":{\"@id\":\"https:\/\/folhadems.com.br\/site\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/folhadems.com.br\/site\/2026\/05\/28\/dia-do-brincar-e-marcado-por-experiencias-sensoriais\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/folhadems.com.br\/site\/2026\/05\/28\/dia-do-brincar-e-marcado-por-experiencias-sensoriais\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2026\/05\/brincar.jpg\",\"datePublished\":\"2026-05-28T16:53:33+00:00\",\"dateModified\":\"2026-05-28T16:53:37+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/folhadems.com.br\/site\/2026\/05\/28\/dia-do-brincar-e-marcado-por-experiencias-sensoriais\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/folhadems.com.br\/site\/2026\/05\/28\/dia-do-brincar-e-marcado-por-experiencias-sensoriais\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/folhadems.com.br\/site\/2026\/05\/28\/dia-do-brincar-e-marcado-por-experiencias-sensoriais\/#primaryimage\",\"url\":\"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2026\/05\/brincar.jpg\",\"contentUrl\":\"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2026\/05\/brincar.jpg\",\"width\":900,\"height\":506},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/folhadems.com.br\/site\/2026\/05\/28\/dia-do-brincar-e-marcado-por-experiencias-sensoriais\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/folhadems.com.br\/site\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Dia do Brincar \u00e9 marcado por experi\u00eancias sensoriais\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/folhadems.com.br\/site\/#website\",\"url\":\"https:\/\/folhadems.com.br\/site\/\",\"name\":\"Folha de Mato Grosso do Sul\",\"description\":\"Jornal Online\",\"publisher\":{\"@id\":\"https:\/\/folhadems.com.br\/site\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/folhadems.com.br\/site\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/folhadems.com.br\/site\/#organization\",\"name\":\"Folha de Mato Grosso do Sul\",\"url\":\"https:\/\/folhadems.com.br\/site\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/folhadems.com.br\/site\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2023\/01\/logo-folha-de-ms-380x90-1.jpg\",\"contentUrl\":\"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2023\/01\/logo-folha-de-ms-380x90-1.jpg\",\"width\":380,\"height\":90,\"caption\":\"Folha de Mato Grosso do Sul\"},\"image\":{\"@id\":\"https:\/\/folhadems.com.br\/site\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/folhadems.com.br\/site\/#\/schema\/person\/e4a04038e5c2e7040e19ef252ae9d940\",\"name\":\"Elite Midia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/folhadems.com.br\/site\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/f76a80f01119f7fec6909ab9feea8819031f391155be021b685479d77496f055?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/f76a80f01119f7fec6909ab9feea8819031f391155be021b685479d77496f055?s=96&d=mm&r=g\",\"caption\":\"Elite Midia\"},\"sameAs\":[\"https:\/\/folhadems.com.br\/site\"],\"url\":\"https:\/\/folhadems.com.br\/site\/author\/elite-midia\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Dia do Brincar \u00e9 marcado por experi\u00eancias sensoriais - Folha de Mato Grosso do Sul","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/folhadems.com.br\/site\/2026\/05\/28\/dia-do-brincar-e-marcado-por-experiencias-sensoriais\/","og_locale":"pt_BR","og_type":"article","og_title":"Dia do Brincar \u00e9 marcado por experi\u00eancias sensoriais - Folha de Mato Grosso do Sul","og_description":"O Centro Municipal de Educa\u00e7\u00e3o Especial Inclusiva (CMEEI) da Reme, realizou na manh\u00e3 de ontem (28), o \u201cDia do Brincar\u201d,","og_url":"https:\/\/folhadems.com.br\/site\/2026\/05\/28\/dia-do-brincar-e-marcado-por-experiencias-sensoriais\/","og_site_name":"Folha de Mato Grosso do Sul","article_published_time":"2026-05-28T16:53:33+00:00","article_modified_time":"2026-05-28T16:53:37+00:00","og_image":[{"width":900,"height":506,"url":"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2026\/05\/brincar.jpg","type":"image\/jpeg"}],"author":"Elite Midia","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Elite Midia","Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/folhadems.com.br\/site\/2026\/05\/28\/dia-do-brincar-e-marcado-por-experiencias-sensoriais\/#article","isPartOf":{"@id":"https:\/\/folhadems.com.br\/site\/2026\/05\/28\/dia-do-brincar-e-marcado-por-experiencias-sensoriais\/"},"author":{"name":"Elite Midia","@id":"https:\/\/folhadems.com.br\/site\/#\/schema\/person\/e4a04038e5c2e7040e19ef252ae9d940"},"headline":"Dia do Brincar \u00e9 marcado por experi\u00eancias sensoriais","datePublished":"2026-05-28T16:53:33+00:00","dateModified":"2026-05-28T16:53:37+00:00","mainEntityOfPage":{"@id":"https:\/\/folhadems.com.br\/site\/2026\/05\/28\/dia-do-brincar-e-marcado-por-experiencias-sensoriais\/"},"wordCount":393,"commentCount":0,"publisher":{"@id":"https:\/\/folhadems.com.br\/site\/#organization"},"image":{"@id":"https:\/\/folhadems.com.br\/site\/2026\/05\/28\/dia-do-brincar-e-marcado-por-experiencias-sensoriais\/#primaryimage"},"thumbnailUrl":"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2026\/05\/brincar.jpg","articleSection":["Educa\u00e7\u00e3o"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/folhadems.com.br\/site\/2026\/05\/28\/dia-do-brincar-e-marcado-por-experiencias-sensoriais\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/folhadems.com.br\/site\/2026\/05\/28\/dia-do-brincar-e-marcado-por-experiencias-sensoriais\/","url":"https:\/\/folhadems.com.br\/site\/2026\/05\/28\/dia-do-brincar-e-marcado-por-experiencias-sensoriais\/","name":"Dia do Brincar \u00e9 marcado por experi\u00eancias sensoriais - Folha de Mato Grosso do Sul","isPartOf":{"@id":"https:\/\/folhadems.com.br\/site\/#website"},"primaryImageOfPage":{"@id":"https:\/\/folhadems.com.br\/site\/2026\/05\/28\/dia-do-brincar-e-marcado-por-experiencias-sensoriais\/#primaryimage"},"image":{"@id":"https:\/\/folhadems.com.br\/site\/2026\/05\/28\/dia-do-brincar-e-marcado-por-experiencias-sensoriais\/#primaryimage"},"thumbnailUrl":"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2026\/05\/brincar.jpg","datePublished":"2026-05-28T16:53:33+00:00","dateModified":"2026-05-28T16:53:37+00:00","breadcrumb":{"@id":"https:\/\/folhadems.com.br\/site\/2026\/05\/28\/dia-do-brincar-e-marcado-por-experiencias-sensoriais\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/folhadems.com.br\/site\/2026\/05\/28\/dia-do-brincar-e-marcado-por-experiencias-sensoriais\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/folhadems.com.br\/site\/2026\/05\/28\/dia-do-brincar-e-marcado-por-experiencias-sensoriais\/#primaryimage","url":"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2026\/05\/brincar.jpg","contentUrl":"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2026\/05\/brincar.jpg","width":900,"height":506},{"@type":"BreadcrumbList","@id":"https:\/\/folhadems.com.br\/site\/2026\/05\/28\/dia-do-brincar-e-marcado-por-experiencias-sensoriais\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/folhadems.com.br\/site\/"},{"@type":"ListItem","position":2,"name":"Dia do Brincar \u00e9 marcado por experi\u00eancias sensoriais"}]},{"@type":"WebSite","@id":"https:\/\/folhadems.com.br\/site\/#website","url":"https:\/\/folhadems.com.br\/site\/","name":"Folha de Mato Grosso do Sul","description":"Jornal Online","publisher":{"@id":"https:\/\/folhadems.com.br\/site\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/folhadems.com.br\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/folhadems.com.br\/site\/#organization","name":"Folha de Mato Grosso do Sul","url":"https:\/\/folhadems.com.br\/site\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/folhadems.com.br\/site\/#\/schema\/logo\/image\/","url":"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2023\/01\/logo-folha-de-ms-380x90-1.jpg","contentUrl":"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2023\/01\/logo-folha-de-ms-380x90-1.jpg","width":380,"height":90,"caption":"Folha de Mato Grosso do Sul"},"image":{"@id":"https:\/\/folhadems.com.br\/site\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/folhadems.com.br\/site\/#\/schema\/person\/e4a04038e5c2e7040e19ef252ae9d940","name":"Elite Midia","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/folhadems.com.br\/site\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/f76a80f01119f7fec6909ab9feea8819031f391155be021b685479d77496f055?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f76a80f01119f7fec6909ab9feea8819031f391155be021b685479d77496f055?s=96&d=mm&r=g","caption":"Elite Midia"},"sameAs":["https:\/\/folhadems.com.br\/site"],"url":"https:\/\/folhadems.com.br\/site\/author\/elite-midia\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-07-22 00:26:03","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/posts\/16619","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/comments?post=16619"}],"version-history":[{"count":1,"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/posts\/16619\/revisions"}],"predecessor-version":[{"id":16621,"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/posts\/16619\/revisions\/16621"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/media\/16620"}],"wp:attachment":[{"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/media?parent=16619"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/categories?post=16619"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/tags?post=16619"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}