{"id":16223,"date":"2026-05-12T13:42:59","date_gmt":"2026-05-12T17:42:59","guid":{"rendered":"https:\/\/folhadems.com.br\/site\/?p=16223"},"modified":"2026-05-12T13:43:01","modified_gmt":"2026-05-12T17:43:01","slug":"sesau-alerta-para-riscos-da-baixa-procura-pela-vacina-da-gripe","status":"publish","type":"post","link":"https:\/\/folhadems.com.br\/site\/2026\/05\/12\/sesau-alerta-para-riscos-da-baixa-procura-pela-vacina-da-gripe\/","title":{"rendered":"Sesau alerta para riscos da baixa procura pela vacina da gripe"},"content":{"rendered":"\n<p>Campo Grande registrou neste ano, at\u00e9 o momento, 753 notifica\u00e7\u00f5es de S\u00edndrome Respirat\u00f3ria Aguda Grave (SRAG) e 49 \u00f3bitos, sendo 11 mortes apenas pelo v\u00edrus Influenza. A preocupa\u00e7\u00e3o com esses registros se intensifica durante o per\u00edodo de baixas temperaturas, onde a circula\u00e7\u00e3o desses v\u00edrus costuma ser mais intensa.<\/p>\n\n\n\n<p>A preocupa\u00e7\u00e3o da Secretaria Municipal de Sa\u00fade (Sesau) \u00e9 que os reflexos dessa primeira onda de frio sejam sentidos nos pr\u00f3ximos dias, com aumento da procura por atendimento nas unidades de sa\u00fade.<\/p>\n\n\n\n<p>\u201cAs frentes frias trazem \u00e0 tona a circula\u00e7\u00e3o de v\u00edrus. O quadro cl\u00ednico do paciente define a gravidade. Idosos e pessoas com comorbidades t\u00eam maior chance de evoluir para casos graves e at\u00e9 morte\u201d, refor\u00e7a a superintendente de Vigil\u00e2ncia em Sa\u00fade, Veruska Lahdo.<\/p>\n\n\n\n<p>A superintendente destaca que as temperaturas mais baixas tendem a elevar os casos de gripes, resfriados e tamb\u00e9m de quadros mais graves, especialmente entre idosos, gestantes, crian\u00e7as e pessoas com comorbidades.<\/p>\n\n\n\n<p><strong>Vacina dispon\u00edvel<\/strong><\/p>\n\n\n\n<p>Apesar das estrat\u00e9gias da Sesau, o \u00edndice de vacina\u00e7\u00e3o contra influenza segue abaixo do esperado, registrando 30,7% de cobertura dos grupos priorit\u00e1rios. A vacina reduz complica\u00e7\u00f5es, risco de interna\u00e7\u00e3o e \u00f3bito por influenza, mas depende da ades\u00e3o desse p\u00fablico.<\/p>\n\n\n\n<p>\u201cA vacina contra influenza \u00e9 fundamental. Precisamos que a popula\u00e7\u00e3o que faz parte do p\u00fablico priorit\u00e1rio fa\u00e7a a ades\u00e3o, procure as unidades de sa\u00fade para se imunizar. A vacina tem justamente esse papel, de reduzir as complica\u00e7\u00f5es\u201d, salienta Veruska.<\/p>\n\n\n\n<p>O imunizante est\u00e1 dispon\u00edvel em todas as unidades de sa\u00fade e para os p\u00fablicos alvos da campanha, que s\u00e3o crian\u00e7as entre seis meses e menores de seis anos de idade, idosos, gestantes, pu\u00e9rperas e pessoas com comorbidades. A amplia\u00e7\u00e3o da vacina\u00e7\u00e3o para outros grupos depende de determina\u00e7\u00e3o do Minist\u00e9rio da Sa\u00fade e do envio de doses pelo Programa Nacional de Imuniza\u00e7\u00f5es. \u201cNosso interesse \u00e9 ampliar o mais r\u00e1pido poss\u00edvel, mas aguardamos orienta\u00e7\u00f5es do Minist\u00e9rio para que isso ocorra na Capital\u201d, completa.<\/p>\n\n\n\n<p>A baixa ades\u00e3o \u00e0 vacina\u00e7\u00e3o contra a influenza agrava o cen\u00e1rio. Mesmo com as estrat\u00e9gias e campanhas j\u00e1 realizadas pela prefeitura, a cobertura vacinal segue abaixo do esperado entre os grupos priorit\u00e1rios e, por isso, as autoridades refor\u00e7am o alerta.<\/p>\n\n\n\n<p>Enquanto isso, a orienta\u00e7\u00e3o \u00e9 manter os cuidados b\u00e1sicos, como higieniza\u00e7\u00e3o frequente das m\u00e3os, uso de m\u00e1scaras em caso de sintomas gripais, evitar locais fechados com aglomera\u00e7\u00e3o e aten\u00e7\u00e3o aos sinais de agravamento, principalmente em pessoas mais vulner\u00e1veis.<\/p>\n\n\n\n<p><strong><em>Fonte: PrefCG<\/em><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Campo Grande registrou neste ano, at\u00e9 o momento, 753 notifica\u00e7\u00f5es de S\u00edndrome Respirat\u00f3ria Aguda Grave (SRAG) e 49 \u00f3bitos, sendo<\/p>\n","protected":false},"author":1,"featured_media":16224,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-16223","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ciencia-e-saude"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.1.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Sesau alerta para riscos da baixa procura pela vacina da gripe - Folha de Mato Grosso do Sul<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/folhadems.com.br\/site\/2026\/05\/12\/sesau-alerta-para-riscos-da-baixa-procura-pela-vacina-da-gripe\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sesau alerta para riscos da baixa procura pela vacina da gripe - Folha de Mato Grosso do Sul\" \/>\n<meta property=\"og:description\" content=\"Campo Grande registrou neste ano, at\u00e9 o momento, 753 notifica\u00e7\u00f5es de S\u00edndrome Respirat\u00f3ria Aguda Grave (SRAG) e 49 \u00f3bitos, sendo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/folhadems.com.br\/site\/2026\/05\/12\/sesau-alerta-para-riscos-da-baixa-procura-pela-vacina-da-gripe\/\" \/>\n<meta property=\"og:site_name\" content=\"Folha de Mato Grosso do Sul\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-12T17:42:59+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-12T17:43:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2026\/05\/vacina_gripe.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"900\" \/>\n\t<meta property=\"og:image:height\" content=\"506\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Elite Midia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Elite Midia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/folhadems.com.br\/site\/2026\/05\/12\/sesau-alerta-para-riscos-da-baixa-procura-pela-vacina-da-gripe\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/folhadems.com.br\/site\/2026\/05\/12\/sesau-alerta-para-riscos-da-baixa-procura-pela-vacina-da-gripe\/\"},\"author\":{\"name\":\"Elite Midia\",\"@id\":\"https:\/\/folhadems.com.br\/site\/#\/schema\/person\/e4a04038e5c2e7040e19ef252ae9d940\"},\"headline\":\"Sesau alerta para riscos da baixa procura pela vacina da gripe\",\"datePublished\":\"2026-05-12T17:42:59+00:00\",\"dateModified\":\"2026-05-12T17:43:01+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/folhadems.com.br\/site\/2026\/05\/12\/sesau-alerta-para-riscos-da-baixa-procura-pela-vacina-da-gripe\/\"},\"wordCount\":462,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/folhadems.com.br\/site\/#organization\"},\"image\":{\"@id\":\"https:\/\/folhadems.com.br\/site\/2026\/05\/12\/sesau-alerta-para-riscos-da-baixa-procura-pela-vacina-da-gripe\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2026\/05\/vacina_gripe.jpg\",\"articleSection\":[\"Ci\u00eancia e Sa\u00fade\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/folhadems.com.br\/site\/2026\/05\/12\/sesau-alerta-para-riscos-da-baixa-procura-pela-vacina-da-gripe\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/folhadems.com.br\/site\/2026\/05\/12\/sesau-alerta-para-riscos-da-baixa-procura-pela-vacina-da-gripe\/\",\"url\":\"https:\/\/folhadems.com.br\/site\/2026\/05\/12\/sesau-alerta-para-riscos-da-baixa-procura-pela-vacina-da-gripe\/\",\"name\":\"Sesau alerta para riscos da baixa procura pela vacina da gripe - Folha de Mato Grosso do Sul\",\"isPartOf\":{\"@id\":\"https:\/\/folhadems.com.br\/site\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/folhadems.com.br\/site\/2026\/05\/12\/sesau-alerta-para-riscos-da-baixa-procura-pela-vacina-da-gripe\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/folhadems.com.br\/site\/2026\/05\/12\/sesau-alerta-para-riscos-da-baixa-procura-pela-vacina-da-gripe\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2026\/05\/vacina_gripe.jpg\",\"datePublished\":\"2026-05-12T17:42:59+00:00\",\"dateModified\":\"2026-05-12T17:43:01+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/folhadems.com.br\/site\/2026\/05\/12\/sesau-alerta-para-riscos-da-baixa-procura-pela-vacina-da-gripe\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/folhadems.com.br\/site\/2026\/05\/12\/sesau-alerta-para-riscos-da-baixa-procura-pela-vacina-da-gripe\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/folhadems.com.br\/site\/2026\/05\/12\/sesau-alerta-para-riscos-da-baixa-procura-pela-vacina-da-gripe\/#primaryimage\",\"url\":\"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2026\/05\/vacina_gripe.jpg\",\"contentUrl\":\"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2026\/05\/vacina_gripe.jpg\",\"width\":900,\"height\":506},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/folhadems.com.br\/site\/2026\/05\/12\/sesau-alerta-para-riscos-da-baixa-procura-pela-vacina-da-gripe\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/folhadems.com.br\/site\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sesau alerta para riscos da baixa procura pela vacina da gripe\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/folhadems.com.br\/site\/#website\",\"url\":\"https:\/\/folhadems.com.br\/site\/\",\"name\":\"Folha de Mato Grosso do Sul\",\"description\":\"Jornal Online\",\"publisher\":{\"@id\":\"https:\/\/folhadems.com.br\/site\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/folhadems.com.br\/site\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/folhadems.com.br\/site\/#organization\",\"name\":\"Folha de Mato Grosso do Sul\",\"url\":\"https:\/\/folhadems.com.br\/site\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/folhadems.com.br\/site\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2023\/01\/logo-folha-de-ms-380x90-1.jpg\",\"contentUrl\":\"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2023\/01\/logo-folha-de-ms-380x90-1.jpg\",\"width\":380,\"height\":90,\"caption\":\"Folha de Mato Grosso do Sul\"},\"image\":{\"@id\":\"https:\/\/folhadems.com.br\/site\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/folhadems.com.br\/site\/#\/schema\/person\/e4a04038e5c2e7040e19ef252ae9d940\",\"name\":\"Elite Midia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/folhadems.com.br\/site\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/f76a80f01119f7fec6909ab9feea8819031f391155be021b685479d77496f055?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/f76a80f01119f7fec6909ab9feea8819031f391155be021b685479d77496f055?s=96&d=mm&r=g\",\"caption\":\"Elite Midia\"},\"sameAs\":[\"https:\/\/folhadems.com.br\/site\"],\"url\":\"https:\/\/folhadems.com.br\/site\/author\/elite-midia\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sesau alerta para riscos da baixa procura pela vacina da gripe - Folha de Mato Grosso do Sul","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/folhadems.com.br\/site\/2026\/05\/12\/sesau-alerta-para-riscos-da-baixa-procura-pela-vacina-da-gripe\/","og_locale":"pt_BR","og_type":"article","og_title":"Sesau alerta para riscos da baixa procura pela vacina da gripe - Folha de Mato Grosso do Sul","og_description":"Campo Grande registrou neste ano, at\u00e9 o momento, 753 notifica\u00e7\u00f5es de S\u00edndrome Respirat\u00f3ria Aguda Grave (SRAG) e 49 \u00f3bitos, sendo","og_url":"https:\/\/folhadems.com.br\/site\/2026\/05\/12\/sesau-alerta-para-riscos-da-baixa-procura-pela-vacina-da-gripe\/","og_site_name":"Folha de Mato Grosso do Sul","article_published_time":"2026-05-12T17:42:59+00:00","article_modified_time":"2026-05-12T17:43:01+00:00","og_image":[{"width":900,"height":506,"url":"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2026\/05\/vacina_gripe.jpg","type":"image\/jpeg"}],"author":"Elite Midia","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Elite Midia","Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/folhadems.com.br\/site\/2026\/05\/12\/sesau-alerta-para-riscos-da-baixa-procura-pela-vacina-da-gripe\/#article","isPartOf":{"@id":"https:\/\/folhadems.com.br\/site\/2026\/05\/12\/sesau-alerta-para-riscos-da-baixa-procura-pela-vacina-da-gripe\/"},"author":{"name":"Elite Midia","@id":"https:\/\/folhadems.com.br\/site\/#\/schema\/person\/e4a04038e5c2e7040e19ef252ae9d940"},"headline":"Sesau alerta para riscos da baixa procura pela vacina da gripe","datePublished":"2026-05-12T17:42:59+00:00","dateModified":"2026-05-12T17:43:01+00:00","mainEntityOfPage":{"@id":"https:\/\/folhadems.com.br\/site\/2026\/05\/12\/sesau-alerta-para-riscos-da-baixa-procura-pela-vacina-da-gripe\/"},"wordCount":462,"commentCount":0,"publisher":{"@id":"https:\/\/folhadems.com.br\/site\/#organization"},"image":{"@id":"https:\/\/folhadems.com.br\/site\/2026\/05\/12\/sesau-alerta-para-riscos-da-baixa-procura-pela-vacina-da-gripe\/#primaryimage"},"thumbnailUrl":"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2026\/05\/vacina_gripe.jpg","articleSection":["Ci\u00eancia e Sa\u00fade"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/folhadems.com.br\/site\/2026\/05\/12\/sesau-alerta-para-riscos-da-baixa-procura-pela-vacina-da-gripe\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/folhadems.com.br\/site\/2026\/05\/12\/sesau-alerta-para-riscos-da-baixa-procura-pela-vacina-da-gripe\/","url":"https:\/\/folhadems.com.br\/site\/2026\/05\/12\/sesau-alerta-para-riscos-da-baixa-procura-pela-vacina-da-gripe\/","name":"Sesau alerta para riscos da baixa procura pela vacina da gripe - Folha de Mato Grosso do Sul","isPartOf":{"@id":"https:\/\/folhadems.com.br\/site\/#website"},"primaryImageOfPage":{"@id":"https:\/\/folhadems.com.br\/site\/2026\/05\/12\/sesau-alerta-para-riscos-da-baixa-procura-pela-vacina-da-gripe\/#primaryimage"},"image":{"@id":"https:\/\/folhadems.com.br\/site\/2026\/05\/12\/sesau-alerta-para-riscos-da-baixa-procura-pela-vacina-da-gripe\/#primaryimage"},"thumbnailUrl":"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2026\/05\/vacina_gripe.jpg","datePublished":"2026-05-12T17:42:59+00:00","dateModified":"2026-05-12T17:43:01+00:00","breadcrumb":{"@id":"https:\/\/folhadems.com.br\/site\/2026\/05\/12\/sesau-alerta-para-riscos-da-baixa-procura-pela-vacina-da-gripe\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/folhadems.com.br\/site\/2026\/05\/12\/sesau-alerta-para-riscos-da-baixa-procura-pela-vacina-da-gripe\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/folhadems.com.br\/site\/2026\/05\/12\/sesau-alerta-para-riscos-da-baixa-procura-pela-vacina-da-gripe\/#primaryimage","url":"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2026\/05\/vacina_gripe.jpg","contentUrl":"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2026\/05\/vacina_gripe.jpg","width":900,"height":506},{"@type":"BreadcrumbList","@id":"https:\/\/folhadems.com.br\/site\/2026\/05\/12\/sesau-alerta-para-riscos-da-baixa-procura-pela-vacina-da-gripe\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/folhadems.com.br\/site\/"},{"@type":"ListItem","position":2,"name":"Sesau alerta para riscos da baixa procura pela vacina da gripe"}]},{"@type":"WebSite","@id":"https:\/\/folhadems.com.br\/site\/#website","url":"https:\/\/folhadems.com.br\/site\/","name":"Folha de Mato Grosso do Sul","description":"Jornal Online","publisher":{"@id":"https:\/\/folhadems.com.br\/site\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/folhadems.com.br\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/folhadems.com.br\/site\/#organization","name":"Folha de Mato Grosso do Sul","url":"https:\/\/folhadems.com.br\/site\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/folhadems.com.br\/site\/#\/schema\/logo\/image\/","url":"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2023\/01\/logo-folha-de-ms-380x90-1.jpg","contentUrl":"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2023\/01\/logo-folha-de-ms-380x90-1.jpg","width":380,"height":90,"caption":"Folha de Mato Grosso do Sul"},"image":{"@id":"https:\/\/folhadems.com.br\/site\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/folhadems.com.br\/site\/#\/schema\/person\/e4a04038e5c2e7040e19ef252ae9d940","name":"Elite Midia","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/folhadems.com.br\/site\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/f76a80f01119f7fec6909ab9feea8819031f391155be021b685479d77496f055?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f76a80f01119f7fec6909ab9feea8819031f391155be021b685479d77496f055?s=96&d=mm&r=g","caption":"Elite Midia"},"sameAs":["https:\/\/folhadems.com.br\/site"],"url":"https:\/\/folhadems.com.br\/site\/author\/elite-midia\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-20 07:38:17","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/posts\/16223","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/comments?post=16223"}],"version-history":[{"count":1,"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/posts\/16223\/revisions"}],"predecessor-version":[{"id":16225,"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/posts\/16223\/revisions\/16225"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/media\/16224"}],"wp:attachment":[{"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/media?parent=16223"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/categories?post=16223"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/tags?post=16223"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}