{"id":16214,"date":"2026-05-12T08:20:24","date_gmt":"2026-05-12T12:20:24","guid":{"rendered":"https:\/\/folhadems.com.br\/site\/?p=16214"},"modified":"2026-05-12T08:20:28","modified_gmt":"2026-05-12T12:20:28","slug":"centelha-ms-ganha-novo-prazo-para-inscricoes-de-ideias-inovadoras","status":"publish","type":"post","link":"https:\/\/folhadems.com.br\/site\/2026\/05\/12\/centelha-ms-ganha-novo-prazo-para-inscricoes-de-ideias-inovadoras\/","title":{"rendered":"Centelha MS ganha novo prazo para inscri\u00e7\u00f5es de ideias inovadoras"},"content":{"rendered":"\n<p>A Fundect (Funda\u00e7\u00e3o de Apoio ao Desenvolvimento do Ensino, Ci\u00eancia e Tecnologia do Estado de Mato Grosso do Sul) prorrogou o prazo de inscri\u00e7\u00f5es para a terceira edi\u00e7\u00e3o do Programa Centelha MS. Agora, os interessados ter\u00e3o at\u00e9 as 18h (hor\u00e1rio de Bras\u00edlia), do dia 25 de maio de 2026 para submeter suas propostas inovadoras. A prorroga\u00e7\u00e3o foi publicada no Di\u00e1rio Oficial do Estado desta segunda-feira (11).<\/p>\n\n\n\n<p>Com a amplia\u00e7\u00e3o do prazo, pesquisadores, professores, empreendedores, inventores e empresas nascentes ganham mais tempo para transformar ideias inovadoras em oportunidades de neg\u00f3cio e participar de um dos principais programas de incentivo ao empreendedorismo tecnol\u00f3gico do pa\u00eds.<\/p>\n\n\n\n<p>O Programa Centelha tem como objetivo estimular a cria\u00e7\u00e3o de empreendimentos de base tecnol\u00f3gica e fortalecer o ecossistema de inova\u00e7\u00e3o sul-mato-grossense. Em Mato Grosso do Sul, a iniciativa \u00e9 executada pela Fundect, vinculada \u00e0 Secretaria de Meio Ambiente, Desenvolvimento, Ci\u00eancia, Tecnologia e Inova\u00e7\u00e3o (Semadesc), com apoio do Sebrae MS, Fiems-Senai, Fecom\u00e9rcio-Senac, Ecossistema de Inova\u00e7\u00e3o e o Conselho de Reitores das Institui\u00e7\u00f5es de Ensino Superior de Mato Grosso do Sul (CRIE-MS).<\/p>\n\n\n\n<p>Coordenado nacionalmente pelo Minist\u00e9rio da Ci\u00eancia, Tecnologia e Inova\u00e7\u00e3o (MCTI), por meio da Finep, em parceria com o CNPq, Confap e Funda\u00e7\u00e3o CERTI, o programa busca apoiar ideias inovadoras em diferentes \u00e1reas do conhecimento e incentivar a gera\u00e7\u00e3o de novos neg\u00f3cios.<\/p>\n\n\n\n<p>Nesta terceira edi\u00e7\u00e3o, o Centelha MS prev\u00ea a sele\u00e7\u00e3o de at\u00e9 47 propostas, com investimento total de R$ 6,5 milh\u00f5es. Cada projeto poder\u00e1 receber at\u00e9 R$ 89,6 mil em recursos de subven\u00e7\u00e3o econ\u00f4mica (modalidade que n\u00e3o exige reembolso) al\u00e9m de at\u00e9 R$ 50 mil em bolsas de fomento tecnol\u00f3gico e extens\u00e3o inovadora concedidas pelo CNPq.<\/p>\n\n\n\n<p>Podem participar pessoas f\u00edsicas com ideias inovadoras, al\u00e9m de empresas com at\u00e9 12 meses de exist\u00eancia. As inscri\u00e7\u00f5es devem ser realizadas exclusivamente pelo site do programa:&nbsp;<a href=\"https:\/\/ms.programacentelha.com.br\/?utm_source=chatgpt.com\" target=\"_blank\" rel=\"noopener\">Programa Centelha MS<\/a>.<\/p>\n\n\n\n<p>Nas duas edi\u00e7\u00f5es anteriores, o Programa Centelha selecionou 79 startups em Mato Grosso do Sul, com investimento superior a R$ 5,9 milh\u00f5es. Para esta edi\u00e7\u00e3o, a expectativa \u00e9 alcan\u00e7ar mil propostas inscritas, ampliando ainda mais o alcance da iniciativa e incentivando o desenvolvimento de solu\u00e7\u00f5es inovadoras no Estado.<\/p>\n\n\n\n<p>O edital do Centelha pode ser conferido na \u00edntegra&nbsp;<a href=\"https:\/\/www.fundect.ms.gov.br\/programa-centelha-ms\/\" target=\"_blank\" rel=\"noopener\">nesta p\u00e1gina<\/a>.<\/p>\n\n\n\n<p><em><strong>Maristela Cantadori, Comunica\u00e7\u00e3o Fundect<\/strong><\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Fundect (Funda\u00e7\u00e3o de Apoio ao Desenvolvimento do Ensino, Ci\u00eancia e Tecnologia do Estado de Mato Grosso do Sul) prorrogou<\/p>\n","protected":false},"author":1,"featured_media":16215,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[38],"tags":[],"class_list":["post-16214","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-desenvolvimento"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.1.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Centelha MS ganha novo prazo para inscri\u00e7\u00f5es de ideias inovadoras - Folha de Mato Grosso do Sul<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/folhadems.com.br\/site\/2026\/05\/12\/centelha-ms-ganha-novo-prazo-para-inscricoes-de-ideias-inovadoras\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Centelha MS ganha novo prazo para inscri\u00e7\u00f5es de ideias inovadoras - Folha de Mato Grosso do Sul\" \/>\n<meta property=\"og:description\" content=\"A Fundect (Funda\u00e7\u00e3o de Apoio ao Desenvolvimento do Ensino, Ci\u00eancia e Tecnologia do Estado de Mato Grosso do Sul) prorrogou\" \/>\n<meta property=\"og:url\" content=\"https:\/\/folhadems.com.br\/site\/2026\/05\/12\/centelha-ms-ganha-novo-prazo-para-inscricoes-de-ideias-inovadoras\/\" \/>\n<meta property=\"og:site_name\" content=\"Folha de Mato Grosso do Sul\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-12T12:20:24+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-12T12:20:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2026\/05\/centelha-768X430-730x430-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"730\" \/>\n\t<meta property=\"og:image:height\" content=\"430\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Elite Midia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Elite Midia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/folhadems.com.br\/site\/2026\/05\/12\/centelha-ms-ganha-novo-prazo-para-inscricoes-de-ideias-inovadoras\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/folhadems.com.br\/site\/2026\/05\/12\/centelha-ms-ganha-novo-prazo-para-inscricoes-de-ideias-inovadoras\/\"},\"author\":{\"name\":\"Elite Midia\",\"@id\":\"https:\/\/folhadems.com.br\/site\/#\/schema\/person\/e4a04038e5c2e7040e19ef252ae9d940\"},\"headline\":\"Centelha MS ganha novo prazo para inscri\u00e7\u00f5es de ideias inovadoras\",\"datePublished\":\"2026-05-12T12:20:24+00:00\",\"dateModified\":\"2026-05-12T12:20:28+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/folhadems.com.br\/site\/2026\/05\/12\/centelha-ms-ganha-novo-prazo-para-inscricoes-de-ideias-inovadoras\/\"},\"wordCount\":408,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/folhadems.com.br\/site\/#organization\"},\"image\":{\"@id\":\"https:\/\/folhadems.com.br\/site\/2026\/05\/12\/centelha-ms-ganha-novo-prazo-para-inscricoes-de-ideias-inovadoras\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2026\/05\/centelha-768X430-730x430-1.jpg\",\"articleSection\":[\"Desenvolvimento\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/folhadems.com.br\/site\/2026\/05\/12\/centelha-ms-ganha-novo-prazo-para-inscricoes-de-ideias-inovadoras\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/folhadems.com.br\/site\/2026\/05\/12\/centelha-ms-ganha-novo-prazo-para-inscricoes-de-ideias-inovadoras\/\",\"url\":\"https:\/\/folhadems.com.br\/site\/2026\/05\/12\/centelha-ms-ganha-novo-prazo-para-inscricoes-de-ideias-inovadoras\/\",\"name\":\"Centelha MS ganha novo prazo para inscri\u00e7\u00f5es de ideias inovadoras - Folha de Mato Grosso do Sul\",\"isPartOf\":{\"@id\":\"https:\/\/folhadems.com.br\/site\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/folhadems.com.br\/site\/2026\/05\/12\/centelha-ms-ganha-novo-prazo-para-inscricoes-de-ideias-inovadoras\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/folhadems.com.br\/site\/2026\/05\/12\/centelha-ms-ganha-novo-prazo-para-inscricoes-de-ideias-inovadoras\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2026\/05\/centelha-768X430-730x430-1.jpg\",\"datePublished\":\"2026-05-12T12:20:24+00:00\",\"dateModified\":\"2026-05-12T12:20:28+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/folhadems.com.br\/site\/2026\/05\/12\/centelha-ms-ganha-novo-prazo-para-inscricoes-de-ideias-inovadoras\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/folhadems.com.br\/site\/2026\/05\/12\/centelha-ms-ganha-novo-prazo-para-inscricoes-de-ideias-inovadoras\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/folhadems.com.br\/site\/2026\/05\/12\/centelha-ms-ganha-novo-prazo-para-inscricoes-de-ideias-inovadoras\/#primaryimage\",\"url\":\"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2026\/05\/centelha-768X430-730x430-1.jpg\",\"contentUrl\":\"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2026\/05\/centelha-768X430-730x430-1.jpg\",\"width\":730,\"height\":430},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/folhadems.com.br\/site\/2026\/05\/12\/centelha-ms-ganha-novo-prazo-para-inscricoes-de-ideias-inovadoras\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/folhadems.com.br\/site\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Centelha MS ganha novo prazo para inscri\u00e7\u00f5es de ideias inovadoras\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/folhadems.com.br\/site\/#website\",\"url\":\"https:\/\/folhadems.com.br\/site\/\",\"name\":\"Folha de Mato Grosso do Sul\",\"description\":\"Jornal Online\",\"publisher\":{\"@id\":\"https:\/\/folhadems.com.br\/site\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/folhadems.com.br\/site\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/folhadems.com.br\/site\/#organization\",\"name\":\"Folha de Mato Grosso do Sul\",\"url\":\"https:\/\/folhadems.com.br\/site\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/folhadems.com.br\/site\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2023\/01\/logo-folha-de-ms-380x90-1.jpg\",\"contentUrl\":\"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2023\/01\/logo-folha-de-ms-380x90-1.jpg\",\"width\":380,\"height\":90,\"caption\":\"Folha de Mato Grosso do Sul\"},\"image\":{\"@id\":\"https:\/\/folhadems.com.br\/site\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/folhadems.com.br\/site\/#\/schema\/person\/e4a04038e5c2e7040e19ef252ae9d940\",\"name\":\"Elite Midia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/folhadems.com.br\/site\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/f76a80f01119f7fec6909ab9feea8819031f391155be021b685479d77496f055?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/f76a80f01119f7fec6909ab9feea8819031f391155be021b685479d77496f055?s=96&d=mm&r=g\",\"caption\":\"Elite Midia\"},\"sameAs\":[\"https:\/\/folhadems.com.br\/site\"],\"url\":\"https:\/\/folhadems.com.br\/site\/author\/elite-midia\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Centelha MS ganha novo prazo para inscri\u00e7\u00f5es de ideias inovadoras - Folha de Mato Grosso do Sul","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/folhadems.com.br\/site\/2026\/05\/12\/centelha-ms-ganha-novo-prazo-para-inscricoes-de-ideias-inovadoras\/","og_locale":"pt_BR","og_type":"article","og_title":"Centelha MS ganha novo prazo para inscri\u00e7\u00f5es de ideias inovadoras - Folha de Mato Grosso do Sul","og_description":"A Fundect (Funda\u00e7\u00e3o de Apoio ao Desenvolvimento do Ensino, Ci\u00eancia e Tecnologia do Estado de Mato Grosso do Sul) prorrogou","og_url":"https:\/\/folhadems.com.br\/site\/2026\/05\/12\/centelha-ms-ganha-novo-prazo-para-inscricoes-de-ideias-inovadoras\/","og_site_name":"Folha de Mato Grosso do Sul","article_published_time":"2026-05-12T12:20:24+00:00","article_modified_time":"2026-05-12T12:20:28+00:00","og_image":[{"width":730,"height":430,"url":"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2026\/05\/centelha-768X430-730x430-1.jpg","type":"image\/jpeg"}],"author":"Elite Midia","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Elite Midia","Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/folhadems.com.br\/site\/2026\/05\/12\/centelha-ms-ganha-novo-prazo-para-inscricoes-de-ideias-inovadoras\/#article","isPartOf":{"@id":"https:\/\/folhadems.com.br\/site\/2026\/05\/12\/centelha-ms-ganha-novo-prazo-para-inscricoes-de-ideias-inovadoras\/"},"author":{"name":"Elite Midia","@id":"https:\/\/folhadems.com.br\/site\/#\/schema\/person\/e4a04038e5c2e7040e19ef252ae9d940"},"headline":"Centelha MS ganha novo prazo para inscri\u00e7\u00f5es de ideias inovadoras","datePublished":"2026-05-12T12:20:24+00:00","dateModified":"2026-05-12T12:20:28+00:00","mainEntityOfPage":{"@id":"https:\/\/folhadems.com.br\/site\/2026\/05\/12\/centelha-ms-ganha-novo-prazo-para-inscricoes-de-ideias-inovadoras\/"},"wordCount":408,"commentCount":0,"publisher":{"@id":"https:\/\/folhadems.com.br\/site\/#organization"},"image":{"@id":"https:\/\/folhadems.com.br\/site\/2026\/05\/12\/centelha-ms-ganha-novo-prazo-para-inscricoes-de-ideias-inovadoras\/#primaryimage"},"thumbnailUrl":"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2026\/05\/centelha-768X430-730x430-1.jpg","articleSection":["Desenvolvimento"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/folhadems.com.br\/site\/2026\/05\/12\/centelha-ms-ganha-novo-prazo-para-inscricoes-de-ideias-inovadoras\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/folhadems.com.br\/site\/2026\/05\/12\/centelha-ms-ganha-novo-prazo-para-inscricoes-de-ideias-inovadoras\/","url":"https:\/\/folhadems.com.br\/site\/2026\/05\/12\/centelha-ms-ganha-novo-prazo-para-inscricoes-de-ideias-inovadoras\/","name":"Centelha MS ganha novo prazo para inscri\u00e7\u00f5es de ideias inovadoras - Folha de Mato Grosso do Sul","isPartOf":{"@id":"https:\/\/folhadems.com.br\/site\/#website"},"primaryImageOfPage":{"@id":"https:\/\/folhadems.com.br\/site\/2026\/05\/12\/centelha-ms-ganha-novo-prazo-para-inscricoes-de-ideias-inovadoras\/#primaryimage"},"image":{"@id":"https:\/\/folhadems.com.br\/site\/2026\/05\/12\/centelha-ms-ganha-novo-prazo-para-inscricoes-de-ideias-inovadoras\/#primaryimage"},"thumbnailUrl":"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2026\/05\/centelha-768X430-730x430-1.jpg","datePublished":"2026-05-12T12:20:24+00:00","dateModified":"2026-05-12T12:20:28+00:00","breadcrumb":{"@id":"https:\/\/folhadems.com.br\/site\/2026\/05\/12\/centelha-ms-ganha-novo-prazo-para-inscricoes-de-ideias-inovadoras\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/folhadems.com.br\/site\/2026\/05\/12\/centelha-ms-ganha-novo-prazo-para-inscricoes-de-ideias-inovadoras\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/folhadems.com.br\/site\/2026\/05\/12\/centelha-ms-ganha-novo-prazo-para-inscricoes-de-ideias-inovadoras\/#primaryimage","url":"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2026\/05\/centelha-768X430-730x430-1.jpg","contentUrl":"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2026\/05\/centelha-768X430-730x430-1.jpg","width":730,"height":430},{"@type":"BreadcrumbList","@id":"https:\/\/folhadems.com.br\/site\/2026\/05\/12\/centelha-ms-ganha-novo-prazo-para-inscricoes-de-ideias-inovadoras\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/folhadems.com.br\/site\/"},{"@type":"ListItem","position":2,"name":"Centelha MS ganha novo prazo para inscri\u00e7\u00f5es de ideias inovadoras"}]},{"@type":"WebSite","@id":"https:\/\/folhadems.com.br\/site\/#website","url":"https:\/\/folhadems.com.br\/site\/","name":"Folha de Mato Grosso do Sul","description":"Jornal Online","publisher":{"@id":"https:\/\/folhadems.com.br\/site\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/folhadems.com.br\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/folhadems.com.br\/site\/#organization","name":"Folha de Mato Grosso do Sul","url":"https:\/\/folhadems.com.br\/site\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/folhadems.com.br\/site\/#\/schema\/logo\/image\/","url":"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2023\/01\/logo-folha-de-ms-380x90-1.jpg","contentUrl":"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2023\/01\/logo-folha-de-ms-380x90-1.jpg","width":380,"height":90,"caption":"Folha de Mato Grosso do Sul"},"image":{"@id":"https:\/\/folhadems.com.br\/site\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/folhadems.com.br\/site\/#\/schema\/person\/e4a04038e5c2e7040e19ef252ae9d940","name":"Elite Midia","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/folhadems.com.br\/site\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/f76a80f01119f7fec6909ab9feea8819031f391155be021b685479d77496f055?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f76a80f01119f7fec6909ab9feea8819031f391155be021b685479d77496f055?s=96&d=mm&r=g","caption":"Elite Midia"},"sameAs":["https:\/\/folhadems.com.br\/site"],"url":"https:\/\/folhadems.com.br\/site\/author\/elite-midia\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-20 09:41:40","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/posts\/16214","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/comments?post=16214"}],"version-history":[{"count":1,"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/posts\/16214\/revisions"}],"predecessor-version":[{"id":16216,"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/posts\/16214\/revisions\/16216"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/media\/16215"}],"wp:attachment":[{"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/media?parent=16214"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/categories?post=16214"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/tags?post=16214"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}