{"id":16183,"date":"2026-05-11T08:15:49","date_gmt":"2026-05-11T12:15:49","guid":{"rendered":"https:\/\/folhadems.com.br\/site\/?p=16183"},"modified":"2026-05-11T08:15:52","modified_gmt":"2026-05-11T12:15:52","slug":"exportacoes-de-ms-crescem-626-e-saldo-da-balanca-comercial-chega-a-us-272-bilhoes-ate-abril","status":"publish","type":"post","link":"https:\/\/folhadems.com.br\/site\/2026\/05\/11\/exportacoes-de-ms-crescem-626-e-saldo-da-balanca-comercial-chega-a-us-272-bilhoes-ate-abril\/","title":{"rendered":"Exporta\u00e7\u00f5es de MS crescem 6,26% e saldo da balan\u00e7a comercial chega a US$ 2,72 bilh\u00f5es at\u00e9 abril"},"content":{"rendered":"\n<p>As exporta\u00e7\u00f5es de Mato Grosso do Sul avan\u00e7aram novamente em abril, mantendo o bom desempenho da balan\u00e7a comercial neste ano. \u00c9 o que mostra a&nbsp;<a href=\"https:\/\/www.semadesc.ms.gov.br\/wp-content\/uploads\/2026\/05\/04.-Carta-de-Conjuntura-do-Setor-Externo-Abril-2026.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">Carta de Conjuntura do Setor Externo<\/a>&nbsp;de m\u00eas de Maio de 2026, elaborada pela Assessoria Especial de Economia e Estat\u00edstica da Secretaria de Estado de Meio Ambiente, Desenvolvimento Ci\u00eancia, Tecnologia e Inova\u00e7\u00e3o (Semadesc).<\/p>\n\n\n\n<p>Os n\u00fameros apontam que as exporta\u00e7\u00f5es sul-mato-grossenses alcan\u00e7aram US$ 3,61 bilh\u00f5es entre janeiro e abril deste ano, crescimento de 6,26% em rela\u00e7\u00e3o ao mesmo per\u00edodo de 2025.<\/p>\n\n\n\n<p>No mesmo per\u00edodo, as importa\u00e7\u00f5es somaram US$ 893,11 milh\u00f5es, alta de 1,51%, garantindo ao Estado um super\u00e1vit comercial de US$ 2,72 bilh\u00f5es, resultado 7,91% superior ao registrado no ano anterior. Al\u00e9m do avan\u00e7o em valor, o volume exportado tamb\u00e9m registrou crescimento expressivo. Entre janeiro e abril de 2026, Mato Grosso do Sul exportou 9,67 milh\u00f5es de toneladas, aumento de 16,61% frente ao mesmo per\u00edodo de 2025.<\/p>\n\n\n\n<p>O agroneg\u00f3cio e a ind\u00fastria de transforma\u00e7\u00e3o continuam puxando os \u00edndices, com destaque entre os principais produtos exportados. A soja lidera com 32,01% da pauta exportadora, seguida pela celulose (26,02%) e carne bovina (19,02%).<\/p>\n\n\n\n<p>A China permanece como principal destino das exporta\u00e7\u00f5es sul-mato-grossenses, respondendo por 48,29% das vendas internacionais do Estado. Na sequ\u00eancia aparecem Estados Unidos (8%) e Pa\u00edses Baixos (4,23%).<\/p>\n\n\n\n<p>Entre os munic\u00edpios, Tr\u00eas Lagoas lidera o ranking estadual de exporta\u00e7\u00f5es, com 17,84% do total comercializado, seguida por Ribas do Rio Pardo (11,62%), Dourados (10,65%) e Campo Grande (7,59%).<\/p>\n\n\n\n<p>O levantamento tamb\u00e9m aponta desempenho positivo da agropecu\u00e1ria, que registrou crescimento de 28,59% nos pre\u00e7os e de 25,16% no volume exportado. J\u00e1 a ind\u00fastria de transforma\u00e7\u00e3o teve alta de 1,15% nos pre\u00e7os e 0,68% no volume comercializado.<\/p>\n\n\n\n<p>Outro destaque \u00e9 a log\u00edstica de exporta\u00e7\u00e3o. O Porto de Paranagu\u00e1 concentrou 40,36% das mercadorias exportadas por Mato Grosso do Sul, seguido pelo Porto de Santos, com 37,62%.<\/p>\n\n\n\n<p><strong>Consolida\u00e7\u00e3o<\/strong><\/p>\n\n\n\n<p>O secret\u00e1rio Artur Falcette, da Semadesc, destacou que o resultado da balan\u00e7a comercial \u00e9 reflexo direto da matura\u00e7\u00e3o dos investimentos realizados em Mato Grosso do Sul nos \u00faltimos anos.<\/p>\n\n\n\n<p>\u201cO Estado vem consolidando um ambiente de seguran\u00e7a jur\u00eddica, infraestrutura, log\u00edstica e competitividade que permitiu ampliar a capacidade industrial, agregar valor \u00e0 produ\u00e7\u00e3o e diversificar mercados internacionais. Hoje vemos os efeitos concretos desse processo, com crescimento das exporta\u00e7\u00f5es, fortalecimento da agroind\u00fastria e gera\u00e7\u00e3o de oportunidades em diferentes regi\u00f5es do Estado\u201d, avaliou.<\/p>\n\n\n\n<p><em><strong>Rosana Siqueira, Comunica\u00e7\u00e3o Semadesc<\/strong><\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>As exporta\u00e7\u00f5es de Mato Grosso do Sul avan\u00e7aram novamente em abril, mantendo o bom desempenho da balan\u00e7a comercial neste ano.<\/p>\n","protected":false},"author":1,"featured_media":16184,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-16183","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-economia"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.1.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Exporta\u00e7\u00f5es de MS crescem 6,26% e saldo da balan\u00e7a comercial chega a US$ 2,72 bilh\u00f5es at\u00e9 abril - Folha de Mato Grosso do Sul<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/folhadems.com.br\/site\/2026\/05\/11\/exportacoes-de-ms-crescem-626-e-saldo-da-balanca-comercial-chega-a-us-272-bilhoes-ate-abril\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Exporta\u00e7\u00f5es de MS crescem 6,26% e saldo da balan\u00e7a comercial chega a US$ 2,72 bilh\u00f5es at\u00e9 abril - Folha de Mato Grosso do Sul\" \/>\n<meta property=\"og:description\" content=\"As exporta\u00e7\u00f5es de Mato Grosso do Sul avan\u00e7aram novamente em abril, mantendo o bom desempenho da balan\u00e7a comercial neste ano.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/folhadems.com.br\/site\/2026\/05\/11\/exportacoes-de-ms-crescem-626-e-saldo-da-balanca-comercial-chega-a-us-272-bilhoes-ate-abril\/\" \/>\n<meta property=\"og:site_name\" content=\"Folha de Mato Grosso do Sul\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-11T12:15:49+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-11T12:15:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2026\/05\/exportacao-paranagua-730x480-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"730\" \/>\n\t<meta property=\"og:image:height\" content=\"480\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Elite Midia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Elite Midia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/folhadems.com.br\/site\/2026\/05\/11\/exportacoes-de-ms-crescem-626-e-saldo-da-balanca-comercial-chega-a-us-272-bilhoes-ate-abril\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/folhadems.com.br\/site\/2026\/05\/11\/exportacoes-de-ms-crescem-626-e-saldo-da-balanca-comercial-chega-a-us-272-bilhoes-ate-abril\/\"},\"author\":{\"name\":\"Elite Midia\",\"@id\":\"https:\/\/folhadems.com.br\/site\/#\/schema\/person\/e4a04038e5c2e7040e19ef252ae9d940\"},\"headline\":\"Exporta\u00e7\u00f5es de MS crescem 6,26% e saldo da balan\u00e7a comercial chega a US$ 2,72 bilh\u00f5es at\u00e9 abril\",\"datePublished\":\"2026-05-11T12:15:49+00:00\",\"dateModified\":\"2026-05-11T12:15:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/folhadems.com.br\/site\/2026\/05\/11\/exportacoes-de-ms-crescem-626-e-saldo-da-balanca-comercial-chega-a-us-272-bilhoes-ate-abril\/\"},\"wordCount\":432,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/folhadems.com.br\/site\/#organization\"},\"image\":{\"@id\":\"https:\/\/folhadems.com.br\/site\/2026\/05\/11\/exportacoes-de-ms-crescem-626-e-saldo-da-balanca-comercial-chega-a-us-272-bilhoes-ate-abril\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2026\/05\/exportacao-paranagua-730x480-1.jpg\",\"articleSection\":[\"Economia\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/folhadems.com.br\/site\/2026\/05\/11\/exportacoes-de-ms-crescem-626-e-saldo-da-balanca-comercial-chega-a-us-272-bilhoes-ate-abril\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/folhadems.com.br\/site\/2026\/05\/11\/exportacoes-de-ms-crescem-626-e-saldo-da-balanca-comercial-chega-a-us-272-bilhoes-ate-abril\/\",\"url\":\"https:\/\/folhadems.com.br\/site\/2026\/05\/11\/exportacoes-de-ms-crescem-626-e-saldo-da-balanca-comercial-chega-a-us-272-bilhoes-ate-abril\/\",\"name\":\"Exporta\u00e7\u00f5es de MS crescem 6,26% e saldo da balan\u00e7a comercial chega a US$ 2,72 bilh\u00f5es at\u00e9 abril - Folha de Mato Grosso do Sul\",\"isPartOf\":{\"@id\":\"https:\/\/folhadems.com.br\/site\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/folhadems.com.br\/site\/2026\/05\/11\/exportacoes-de-ms-crescem-626-e-saldo-da-balanca-comercial-chega-a-us-272-bilhoes-ate-abril\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/folhadems.com.br\/site\/2026\/05\/11\/exportacoes-de-ms-crescem-626-e-saldo-da-balanca-comercial-chega-a-us-272-bilhoes-ate-abril\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2026\/05\/exportacao-paranagua-730x480-1.jpg\",\"datePublished\":\"2026-05-11T12:15:49+00:00\",\"dateModified\":\"2026-05-11T12:15:52+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/folhadems.com.br\/site\/2026\/05\/11\/exportacoes-de-ms-crescem-626-e-saldo-da-balanca-comercial-chega-a-us-272-bilhoes-ate-abril\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/folhadems.com.br\/site\/2026\/05\/11\/exportacoes-de-ms-crescem-626-e-saldo-da-balanca-comercial-chega-a-us-272-bilhoes-ate-abril\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/folhadems.com.br\/site\/2026\/05\/11\/exportacoes-de-ms-crescem-626-e-saldo-da-balanca-comercial-chega-a-us-272-bilhoes-ate-abril\/#primaryimage\",\"url\":\"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2026\/05\/exportacao-paranagua-730x480-1.jpg\",\"contentUrl\":\"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2026\/05\/exportacao-paranagua-730x480-1.jpg\",\"width\":730,\"height\":480},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/folhadems.com.br\/site\/2026\/05\/11\/exportacoes-de-ms-crescem-626-e-saldo-da-balanca-comercial-chega-a-us-272-bilhoes-ate-abril\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/folhadems.com.br\/site\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Exporta\u00e7\u00f5es de MS crescem 6,26% e saldo da balan\u00e7a comercial chega a US$ 2,72 bilh\u00f5es at\u00e9 abril\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/folhadems.com.br\/site\/#website\",\"url\":\"https:\/\/folhadems.com.br\/site\/\",\"name\":\"Folha de Mato Grosso do Sul\",\"description\":\"Jornal Online\",\"publisher\":{\"@id\":\"https:\/\/folhadems.com.br\/site\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/folhadems.com.br\/site\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/folhadems.com.br\/site\/#organization\",\"name\":\"Folha de Mato Grosso do Sul\",\"url\":\"https:\/\/folhadems.com.br\/site\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/folhadems.com.br\/site\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2023\/01\/logo-folha-de-ms-380x90-1.jpg\",\"contentUrl\":\"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2023\/01\/logo-folha-de-ms-380x90-1.jpg\",\"width\":380,\"height\":90,\"caption\":\"Folha de Mato Grosso do Sul\"},\"image\":{\"@id\":\"https:\/\/folhadems.com.br\/site\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/folhadems.com.br\/site\/#\/schema\/person\/e4a04038e5c2e7040e19ef252ae9d940\",\"name\":\"Elite Midia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/folhadems.com.br\/site\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/f76a80f01119f7fec6909ab9feea8819031f391155be021b685479d77496f055?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/f76a80f01119f7fec6909ab9feea8819031f391155be021b685479d77496f055?s=96&d=mm&r=g\",\"caption\":\"Elite Midia\"},\"sameAs\":[\"https:\/\/folhadems.com.br\/site\"],\"url\":\"https:\/\/folhadems.com.br\/site\/author\/elite-midia\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Exporta\u00e7\u00f5es de MS crescem 6,26% e saldo da balan\u00e7a comercial chega a US$ 2,72 bilh\u00f5es at\u00e9 abril - Folha de Mato Grosso do Sul","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/folhadems.com.br\/site\/2026\/05\/11\/exportacoes-de-ms-crescem-626-e-saldo-da-balanca-comercial-chega-a-us-272-bilhoes-ate-abril\/","og_locale":"pt_BR","og_type":"article","og_title":"Exporta\u00e7\u00f5es de MS crescem 6,26% e saldo da balan\u00e7a comercial chega a US$ 2,72 bilh\u00f5es at\u00e9 abril - Folha de Mato Grosso do Sul","og_description":"As exporta\u00e7\u00f5es de Mato Grosso do Sul avan\u00e7aram novamente em abril, mantendo o bom desempenho da balan\u00e7a comercial neste ano.","og_url":"https:\/\/folhadems.com.br\/site\/2026\/05\/11\/exportacoes-de-ms-crescem-626-e-saldo-da-balanca-comercial-chega-a-us-272-bilhoes-ate-abril\/","og_site_name":"Folha de Mato Grosso do Sul","article_published_time":"2026-05-11T12:15:49+00:00","article_modified_time":"2026-05-11T12:15:52+00:00","og_image":[{"width":730,"height":480,"url":"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2026\/05\/exportacao-paranagua-730x480-1.jpg","type":"image\/jpeg"}],"author":"Elite Midia","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Elite Midia","Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/folhadems.com.br\/site\/2026\/05\/11\/exportacoes-de-ms-crescem-626-e-saldo-da-balanca-comercial-chega-a-us-272-bilhoes-ate-abril\/#article","isPartOf":{"@id":"https:\/\/folhadems.com.br\/site\/2026\/05\/11\/exportacoes-de-ms-crescem-626-e-saldo-da-balanca-comercial-chega-a-us-272-bilhoes-ate-abril\/"},"author":{"name":"Elite Midia","@id":"https:\/\/folhadems.com.br\/site\/#\/schema\/person\/e4a04038e5c2e7040e19ef252ae9d940"},"headline":"Exporta\u00e7\u00f5es de MS crescem 6,26% e saldo da balan\u00e7a comercial chega a US$ 2,72 bilh\u00f5es at\u00e9 abril","datePublished":"2026-05-11T12:15:49+00:00","dateModified":"2026-05-11T12:15:52+00:00","mainEntityOfPage":{"@id":"https:\/\/folhadems.com.br\/site\/2026\/05\/11\/exportacoes-de-ms-crescem-626-e-saldo-da-balanca-comercial-chega-a-us-272-bilhoes-ate-abril\/"},"wordCount":432,"commentCount":0,"publisher":{"@id":"https:\/\/folhadems.com.br\/site\/#organization"},"image":{"@id":"https:\/\/folhadems.com.br\/site\/2026\/05\/11\/exportacoes-de-ms-crescem-626-e-saldo-da-balanca-comercial-chega-a-us-272-bilhoes-ate-abril\/#primaryimage"},"thumbnailUrl":"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2026\/05\/exportacao-paranagua-730x480-1.jpg","articleSection":["Economia"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/folhadems.com.br\/site\/2026\/05\/11\/exportacoes-de-ms-crescem-626-e-saldo-da-balanca-comercial-chega-a-us-272-bilhoes-ate-abril\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/folhadems.com.br\/site\/2026\/05\/11\/exportacoes-de-ms-crescem-626-e-saldo-da-balanca-comercial-chega-a-us-272-bilhoes-ate-abril\/","url":"https:\/\/folhadems.com.br\/site\/2026\/05\/11\/exportacoes-de-ms-crescem-626-e-saldo-da-balanca-comercial-chega-a-us-272-bilhoes-ate-abril\/","name":"Exporta\u00e7\u00f5es de MS crescem 6,26% e saldo da balan\u00e7a comercial chega a US$ 2,72 bilh\u00f5es at\u00e9 abril - Folha de Mato Grosso do Sul","isPartOf":{"@id":"https:\/\/folhadems.com.br\/site\/#website"},"primaryImageOfPage":{"@id":"https:\/\/folhadems.com.br\/site\/2026\/05\/11\/exportacoes-de-ms-crescem-626-e-saldo-da-balanca-comercial-chega-a-us-272-bilhoes-ate-abril\/#primaryimage"},"image":{"@id":"https:\/\/folhadems.com.br\/site\/2026\/05\/11\/exportacoes-de-ms-crescem-626-e-saldo-da-balanca-comercial-chega-a-us-272-bilhoes-ate-abril\/#primaryimage"},"thumbnailUrl":"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2026\/05\/exportacao-paranagua-730x480-1.jpg","datePublished":"2026-05-11T12:15:49+00:00","dateModified":"2026-05-11T12:15:52+00:00","breadcrumb":{"@id":"https:\/\/folhadems.com.br\/site\/2026\/05\/11\/exportacoes-de-ms-crescem-626-e-saldo-da-balanca-comercial-chega-a-us-272-bilhoes-ate-abril\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/folhadems.com.br\/site\/2026\/05\/11\/exportacoes-de-ms-crescem-626-e-saldo-da-balanca-comercial-chega-a-us-272-bilhoes-ate-abril\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/folhadems.com.br\/site\/2026\/05\/11\/exportacoes-de-ms-crescem-626-e-saldo-da-balanca-comercial-chega-a-us-272-bilhoes-ate-abril\/#primaryimage","url":"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2026\/05\/exportacao-paranagua-730x480-1.jpg","contentUrl":"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2026\/05\/exportacao-paranagua-730x480-1.jpg","width":730,"height":480},{"@type":"BreadcrumbList","@id":"https:\/\/folhadems.com.br\/site\/2026\/05\/11\/exportacoes-de-ms-crescem-626-e-saldo-da-balanca-comercial-chega-a-us-272-bilhoes-ate-abril\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/folhadems.com.br\/site\/"},{"@type":"ListItem","position":2,"name":"Exporta\u00e7\u00f5es de MS crescem 6,26% e saldo da balan\u00e7a comercial chega a US$ 2,72 bilh\u00f5es at\u00e9 abril"}]},{"@type":"WebSite","@id":"https:\/\/folhadems.com.br\/site\/#website","url":"https:\/\/folhadems.com.br\/site\/","name":"Folha de Mato Grosso do Sul","description":"Jornal Online","publisher":{"@id":"https:\/\/folhadems.com.br\/site\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/folhadems.com.br\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/folhadems.com.br\/site\/#organization","name":"Folha de Mato Grosso do Sul","url":"https:\/\/folhadems.com.br\/site\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/folhadems.com.br\/site\/#\/schema\/logo\/image\/","url":"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2023\/01\/logo-folha-de-ms-380x90-1.jpg","contentUrl":"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2023\/01\/logo-folha-de-ms-380x90-1.jpg","width":380,"height":90,"caption":"Folha de Mato Grosso do Sul"},"image":{"@id":"https:\/\/folhadems.com.br\/site\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/folhadems.com.br\/site\/#\/schema\/person\/e4a04038e5c2e7040e19ef252ae9d940","name":"Elite Midia","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/folhadems.com.br\/site\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/f76a80f01119f7fec6909ab9feea8819031f391155be021b685479d77496f055?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f76a80f01119f7fec6909ab9feea8819031f391155be021b685479d77496f055?s=96&d=mm&r=g","caption":"Elite Midia"},"sameAs":["https:\/\/folhadems.com.br\/site"],"url":"https:\/\/folhadems.com.br\/site\/author\/elite-midia\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-20 12:24:35","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/posts\/16183","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/comments?post=16183"}],"version-history":[{"count":1,"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/posts\/16183\/revisions"}],"predecessor-version":[{"id":16185,"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/posts\/16183\/revisions\/16185"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/media\/16184"}],"wp:attachment":[{"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/media?parent=16183"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/categories?post=16183"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/tags?post=16183"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}