{"id":16165,"date":"2026-05-10T16:50:02","date_gmt":"2026-05-10T20:50:02","guid":{"rendered":"https:\/\/folhadems.com.br\/site\/?p=16165"},"modified":"2026-05-10T16:50:05","modified_gmt":"2026-05-10T20:50:05","slug":"mato-grosso-do-sul-avanca-em-gestao-de-custos-na-saude-e-vira-referencia-nacional","status":"publish","type":"post","link":"https:\/\/folhadems.com.br\/site\/2026\/05\/10\/mato-grosso-do-sul-avanca-em-gestao-de-custos-na-saude-e-vira-referencia-nacional\/","title":{"rendered":"Mato Grosso do Sul avan\u00e7a em gest\u00e3o de custos na sa\u00fade e vira refer\u00eancia nacional"},"content":{"rendered":"\n<p>A gest\u00e3o da sa\u00fade p\u00fablica em Mato Grosso do Sul vem ganhando mais precis\u00e3o e qualidade a partir do uso de dados de custos para orientar decis\u00f5es. Em 2026, o Estado passou a utilizar o modelo ApuraSUS, desenvolvido pelo Minist\u00e9rio da Sa\u00fade e disponibilizado \u00e0s secretarias que aderem ao Programa Nacional de Gest\u00e3o de Custos (PNGC).<\/p>\n\n\n\n<p>A partir dessa base, a SES desenvolveu um painel de Business Intelligence (BI), que permite analisar e qualificar as informa\u00e7\u00f5es de custos, ampliando a capacidade de gest\u00e3o. Essa iniciativa foi compartilhada nacionalmente como experi\u00eancia recente na \u00e1rea de economia da sa\u00fade.<\/p>\n\n\n\n<p>Mais do que controle de despesas, a iniciativa tem permitido ao Estado entender, com base em dados reais, quanto custa cada atendimento, interna\u00e7\u00e3o e procedimento realizado no SUS \u2014 e, principalmente, avaliar se esses investimentos est\u00e3o gerando resultados para o paciente.<\/p>\n\n\n\n<p>Trata-se, portanto, de&nbsp;\u201c uma s\u00e9rie de medidas para qualifica\u00e7\u00e3o dos custos da assist\u00eancia focado no melhor aproveitamento e distribui\u00e7\u00e3o dos recursos em toda a rede, de forma a majorar resultados na presta\u00e7\u00e3o dos servi\u00e7os em sa\u00fade pelo Estado&#8221;, explica&nbsp;o secret\u00e1rio de Estado de Sa\u00fade, Maur\u00edcio Sim\u00f5es Corr\u00eaa.<\/p>\n\n\n\n<p><strong>Dados que orientam decis\u00f5es<\/strong><\/p>\n\n\n\n<p>Atualmente, unidades estrat\u00e9gicas da rede estadual j\u00e1 operam com informa\u00e7\u00f5es consolidadas por meio do ApuraSUS. No Hospital Regional de Mato Grosso do Sul, por exemplo, os dados j\u00e1 permitem calcular o custo m\u00e9dio por atendimento no pronto-socorro, por paciente-dia nas interna\u00e7\u00f5es e por di\u00e1ria em UTI, trazendo uma vis\u00e3o detalhada do funcionamento hospitalar.<\/p>\n\n\n\n<p>Essas informa\u00e7\u00f5es j\u00e1 come\u00e7am a gerar impactos pr\u00e1ticos na gest\u00e3o. Entre os avan\u00e7os, est\u00e1 a identifica\u00e7\u00e3o de diferen\u00e7as de perfil entre unidades, como hospitais com maior volume de atendimentos de baixa complexidade e outros voltados a procedimentos especializados \u2014 fator que influencia diretamente nos custos.<\/p>\n\n\n\n<p><strong>Transpar\u00eancia e controle dos gastos<\/strong><\/p>\n\n\n\n<p>Outro resultado importante \u00e9 a compreens\u00e3o da composi\u00e7\u00e3o das despesas. Os levantamentos mostram que cerca de 70% dos custos hospitalares est\u00e3o relacionados a pessoal, dado essencial para o planejamento e a tomada de decis\u00f5es estrat\u00e9gicas.<\/p>\n\n\n\n<p>Al\u00e9m disso, o Estado j\u00e1 consegue separar custos diretos e indiretos dos servi\u00e7os, identificando, por exemplo, quanto exames, medicamentos e estrutura administrativa impactam em cada atendimento. Esse n\u00edvel de detalhamento permite localizar gargalos, reduzir desperd\u00edcios e direcionar melhor os recursos dispon\u00edveis.<\/p>\n\n\n\n<p>Para ampliar a an\u00e1lise, a SES tamb\u00e9m desenvolve pain\u00e9is de BI (Business Intelligence), que facilitam a visualiza\u00e7\u00e3o dos dados e tornam a gest\u00e3o mais transparente e \u00e1gil. \u201cHoje a gente j\u00e1 consegue entender quanto custa cada servi\u00e7o e onde est\u00e3o os principais gastos. Isso permite tomar decis\u00f5es mais assertivas e melhorar a aplica\u00e7\u00e3o dos recursos\u201d, explica o coordenador do N\u00facleo de Economia da SES, Onofre Junior.<\/p>\n\n\n\n<p><strong>Foco na qualidade do atendimento<\/strong><\/p>\n\n\n\n<p>Mesmo com os avan\u00e7os, o principal desafio ainda est\u00e1 na coleta e padroniza\u00e7\u00e3o das informa\u00e7\u00f5es nas unidades de sa\u00fade. Para isso, o N\u00facleo de Economia em Sa\u00fade tem intensificado a\u00e7\u00f5es de sensibiliza\u00e7\u00e3o junto \u00e0s equipes, refor\u00e7ando que o objetivo n\u00e3o \u00e9 apenas economizar, mas melhorar a qualidade da assist\u00eancia.<\/p>\n\n\n\n<p>\u201cA proposta n\u00e3o \u00e9 cortar custos de forma indiscriminada, mas entender onde \u00e9 poss\u00edvel otimizar para investir melhor e garantir um atendimento mais eficiente e de qualidade para a popula\u00e7\u00e3o\u201d, destaca o coordenador.<\/p>\n\n\n\n<p>A l\u00f3gica adotada segue o conceito de valor em sa\u00fade: investir melhor para garantir melhores desfechos aos pacientes. Na pr\u00e1tica, isso significa reduzir desperd\u00edcios para ampliar acesso, qualificar servi\u00e7os e apoiar novos investimentos, explica Roberta Higa, integrante do N\u00facleo de Economia da SES e diretora de Ensino, Pesquisa e Qualidade Institucional do HRMS.<\/p>\n\n\n\n<p><strong>Expans\u00e3o e refer\u00eancia nacional<\/strong><\/p>\n\n\n\n<p>Com a expans\u00e3o do modelo para outras unidades e a articula\u00e7\u00e3o com munic\u00edpios, MS avan\u00e7a na consolida\u00e7\u00e3o de uma gest\u00e3o mais eficiente, baseada em evid\u00eancias e voltada \u00e0 melhoria cont\u00ednua do atendimento \u00e0 popula\u00e7\u00e3o.<\/p>\n\n\n\n<p>A experi\u00eancia do Estado, j\u00e1 compartilhada nacionalmente em 2026, refor\u00e7a o papel estrat\u00e9gico da gest\u00e3o de custos como ferramenta para fortalecer o SUS (Sistema \u00danico de Sa\u00fade) e ampliar a qualidade dos servi\u00e7os oferecidos.<\/p>\n\n\n\n<p>Esse avan\u00e7o \u00e9 resultado da institucionaliza\u00e7\u00e3o do N\u00facleo de Economia em Sa\u00fade no \u00e2mbito da SES, formalizada pela Resolu\u00e7\u00e3o n\u00ba 227\/SES\/MS, de 11 de junho de 2024, que estruturou oficialmente a \u00e1rea e definiu suas atribui\u00e7\u00f5es. A medida foi complementada pela Resolu\u00e7\u00e3o Conjunta \u201cP\u201d SES\/FUNSAU n\u00ba 01, de 25 de julho de 2025, que designou os servidores respons\u00e1veis por compor o n\u00facleo, garantindo capacidade t\u00e9cnica e continuidade \u00e0s a\u00e7\u00f5es de gest\u00e3o de custos no Estado.<\/p>\n\n\n\n<p><em><a href=\"https:\/\/www.saude.ms.gov.br\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-08-at-14.17.16.jpeg\" target=\"_blank\" rel=\"noopener\"><\/a>Dan\u00fabia Burema, Comunica\u00e7\u00e3o SES<br>Fotos: HRMS e SES<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A gest\u00e3o da sa\u00fade p\u00fablica em Mato Grosso do Sul vem ganhando mais precis\u00e3o e qualidade a partir do uso<\/p>\n","protected":false},"author":1,"featured_media":16166,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-16165","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ciencia-e-saude"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.1.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Mato Grosso do Sul avan\u00e7a em gest\u00e3o de custos na sa\u00fade e vira refer\u00eancia nacional - Folha de Mato Grosso do Sul<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/folhadems.com.br\/site\/2026\/05\/10\/mato-grosso-do-sul-avanca-em-gestao-de-custos-na-saude-e-vira-referencia-nacional\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mato Grosso do Sul avan\u00e7a em gest\u00e3o de custos na sa\u00fade e vira refer\u00eancia nacional - Folha de Mato Grosso do Sul\" \/>\n<meta property=\"og:description\" content=\"A gest\u00e3o da sa\u00fade p\u00fablica em Mato Grosso do Sul vem ganhando mais precis\u00e3o e qualidade a partir do uso\" \/>\n<meta property=\"og:url\" content=\"https:\/\/folhadems.com.br\/site\/2026\/05\/10\/mato-grosso-do-sul-avanca-em-gestao-de-custos-na-saude-e-vira-referencia-nacional\/\" \/>\n<meta property=\"og:site_name\" content=\"Folha de Mato Grosso do Sul\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-10T20:50:02+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-10T20:50:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2026\/05\/hrms3-730x480-1.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"730\" \/>\n\t<meta property=\"og:image:height\" content=\"480\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Elite Midia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Elite Midia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/folhadems.com.br\/site\/2026\/05\/10\/mato-grosso-do-sul-avanca-em-gestao-de-custos-na-saude-e-vira-referencia-nacional\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/folhadems.com.br\/site\/2026\/05\/10\/mato-grosso-do-sul-avanca-em-gestao-de-custos-na-saude-e-vira-referencia-nacional\/\"},\"author\":{\"name\":\"Elite Midia\",\"@id\":\"https:\/\/folhadems.com.br\/site\/#\/schema\/person\/e4a04038e5c2e7040e19ef252ae9d940\"},\"headline\":\"Mato Grosso do Sul avan\u00e7a em gest\u00e3o de custos na sa\u00fade e vira refer\u00eancia nacional\",\"datePublished\":\"2026-05-10T20:50:02+00:00\",\"dateModified\":\"2026-05-10T20:50:05+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/folhadems.com.br\/site\/2026\/05\/10\/mato-grosso-do-sul-avanca-em-gestao-de-custos-na-saude-e-vira-referencia-nacional\/\"},\"wordCount\":847,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/folhadems.com.br\/site\/#organization\"},\"image\":{\"@id\":\"https:\/\/folhadems.com.br\/site\/2026\/05\/10\/mato-grosso-do-sul-avanca-em-gestao-de-custos-na-saude-e-vira-referencia-nacional\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2026\/05\/hrms3-730x480-1.jpeg\",\"articleSection\":[\"Ci\u00eancia e Sa\u00fade\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/folhadems.com.br\/site\/2026\/05\/10\/mato-grosso-do-sul-avanca-em-gestao-de-custos-na-saude-e-vira-referencia-nacional\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/folhadems.com.br\/site\/2026\/05\/10\/mato-grosso-do-sul-avanca-em-gestao-de-custos-na-saude-e-vira-referencia-nacional\/\",\"url\":\"https:\/\/folhadems.com.br\/site\/2026\/05\/10\/mato-grosso-do-sul-avanca-em-gestao-de-custos-na-saude-e-vira-referencia-nacional\/\",\"name\":\"Mato Grosso do Sul avan\u00e7a em gest\u00e3o de custos na sa\u00fade e vira refer\u00eancia nacional - Folha de Mato Grosso do Sul\",\"isPartOf\":{\"@id\":\"https:\/\/folhadems.com.br\/site\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/folhadems.com.br\/site\/2026\/05\/10\/mato-grosso-do-sul-avanca-em-gestao-de-custos-na-saude-e-vira-referencia-nacional\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/folhadems.com.br\/site\/2026\/05\/10\/mato-grosso-do-sul-avanca-em-gestao-de-custos-na-saude-e-vira-referencia-nacional\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2026\/05\/hrms3-730x480-1.jpeg\",\"datePublished\":\"2026-05-10T20:50:02+00:00\",\"dateModified\":\"2026-05-10T20:50:05+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/folhadems.com.br\/site\/2026\/05\/10\/mato-grosso-do-sul-avanca-em-gestao-de-custos-na-saude-e-vira-referencia-nacional\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/folhadems.com.br\/site\/2026\/05\/10\/mato-grosso-do-sul-avanca-em-gestao-de-custos-na-saude-e-vira-referencia-nacional\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/folhadems.com.br\/site\/2026\/05\/10\/mato-grosso-do-sul-avanca-em-gestao-de-custos-na-saude-e-vira-referencia-nacional\/#primaryimage\",\"url\":\"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2026\/05\/hrms3-730x480-1.jpeg\",\"contentUrl\":\"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2026\/05\/hrms3-730x480-1.jpeg\",\"width\":730,\"height\":480},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/folhadems.com.br\/site\/2026\/05\/10\/mato-grosso-do-sul-avanca-em-gestao-de-custos-na-saude-e-vira-referencia-nacional\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/folhadems.com.br\/site\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mato Grosso do Sul avan\u00e7a em gest\u00e3o de custos na sa\u00fade e vira refer\u00eancia nacional\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/folhadems.com.br\/site\/#website\",\"url\":\"https:\/\/folhadems.com.br\/site\/\",\"name\":\"Folha de Mato Grosso do Sul\",\"description\":\"Jornal Online\",\"publisher\":{\"@id\":\"https:\/\/folhadems.com.br\/site\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/folhadems.com.br\/site\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/folhadems.com.br\/site\/#organization\",\"name\":\"Folha de Mato Grosso do Sul\",\"url\":\"https:\/\/folhadems.com.br\/site\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/folhadems.com.br\/site\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2023\/01\/logo-folha-de-ms-380x90-1.jpg\",\"contentUrl\":\"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2023\/01\/logo-folha-de-ms-380x90-1.jpg\",\"width\":380,\"height\":90,\"caption\":\"Folha de Mato Grosso do Sul\"},\"image\":{\"@id\":\"https:\/\/folhadems.com.br\/site\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/folhadems.com.br\/site\/#\/schema\/person\/e4a04038e5c2e7040e19ef252ae9d940\",\"name\":\"Elite Midia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/folhadems.com.br\/site\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/f76a80f01119f7fec6909ab9feea8819031f391155be021b685479d77496f055?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/f76a80f01119f7fec6909ab9feea8819031f391155be021b685479d77496f055?s=96&d=mm&r=g\",\"caption\":\"Elite Midia\"},\"sameAs\":[\"https:\/\/folhadems.com.br\/site\"],\"url\":\"https:\/\/folhadems.com.br\/site\/author\/elite-midia\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mato Grosso do Sul avan\u00e7a em gest\u00e3o de custos na sa\u00fade e vira refer\u00eancia nacional - Folha de Mato Grosso do Sul","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/folhadems.com.br\/site\/2026\/05\/10\/mato-grosso-do-sul-avanca-em-gestao-de-custos-na-saude-e-vira-referencia-nacional\/","og_locale":"pt_BR","og_type":"article","og_title":"Mato Grosso do Sul avan\u00e7a em gest\u00e3o de custos na sa\u00fade e vira refer\u00eancia nacional - Folha de Mato Grosso do Sul","og_description":"A gest\u00e3o da sa\u00fade p\u00fablica em Mato Grosso do Sul vem ganhando mais precis\u00e3o e qualidade a partir do uso","og_url":"https:\/\/folhadems.com.br\/site\/2026\/05\/10\/mato-grosso-do-sul-avanca-em-gestao-de-custos-na-saude-e-vira-referencia-nacional\/","og_site_name":"Folha de Mato Grosso do Sul","article_published_time":"2026-05-10T20:50:02+00:00","article_modified_time":"2026-05-10T20:50:05+00:00","og_image":[{"width":730,"height":480,"url":"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2026\/05\/hrms3-730x480-1.jpeg","type":"image\/jpeg"}],"author":"Elite Midia","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Elite Midia","Est. tempo de leitura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/folhadems.com.br\/site\/2026\/05\/10\/mato-grosso-do-sul-avanca-em-gestao-de-custos-na-saude-e-vira-referencia-nacional\/#article","isPartOf":{"@id":"https:\/\/folhadems.com.br\/site\/2026\/05\/10\/mato-grosso-do-sul-avanca-em-gestao-de-custos-na-saude-e-vira-referencia-nacional\/"},"author":{"name":"Elite Midia","@id":"https:\/\/folhadems.com.br\/site\/#\/schema\/person\/e4a04038e5c2e7040e19ef252ae9d940"},"headline":"Mato Grosso do Sul avan\u00e7a em gest\u00e3o de custos na sa\u00fade e vira refer\u00eancia nacional","datePublished":"2026-05-10T20:50:02+00:00","dateModified":"2026-05-10T20:50:05+00:00","mainEntityOfPage":{"@id":"https:\/\/folhadems.com.br\/site\/2026\/05\/10\/mato-grosso-do-sul-avanca-em-gestao-de-custos-na-saude-e-vira-referencia-nacional\/"},"wordCount":847,"commentCount":0,"publisher":{"@id":"https:\/\/folhadems.com.br\/site\/#organization"},"image":{"@id":"https:\/\/folhadems.com.br\/site\/2026\/05\/10\/mato-grosso-do-sul-avanca-em-gestao-de-custos-na-saude-e-vira-referencia-nacional\/#primaryimage"},"thumbnailUrl":"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2026\/05\/hrms3-730x480-1.jpeg","articleSection":["Ci\u00eancia e Sa\u00fade"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/folhadems.com.br\/site\/2026\/05\/10\/mato-grosso-do-sul-avanca-em-gestao-de-custos-na-saude-e-vira-referencia-nacional\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/folhadems.com.br\/site\/2026\/05\/10\/mato-grosso-do-sul-avanca-em-gestao-de-custos-na-saude-e-vira-referencia-nacional\/","url":"https:\/\/folhadems.com.br\/site\/2026\/05\/10\/mato-grosso-do-sul-avanca-em-gestao-de-custos-na-saude-e-vira-referencia-nacional\/","name":"Mato Grosso do Sul avan\u00e7a em gest\u00e3o de custos na sa\u00fade e vira refer\u00eancia nacional - Folha de Mato Grosso do Sul","isPartOf":{"@id":"https:\/\/folhadems.com.br\/site\/#website"},"primaryImageOfPage":{"@id":"https:\/\/folhadems.com.br\/site\/2026\/05\/10\/mato-grosso-do-sul-avanca-em-gestao-de-custos-na-saude-e-vira-referencia-nacional\/#primaryimage"},"image":{"@id":"https:\/\/folhadems.com.br\/site\/2026\/05\/10\/mato-grosso-do-sul-avanca-em-gestao-de-custos-na-saude-e-vira-referencia-nacional\/#primaryimage"},"thumbnailUrl":"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2026\/05\/hrms3-730x480-1.jpeg","datePublished":"2026-05-10T20:50:02+00:00","dateModified":"2026-05-10T20:50:05+00:00","breadcrumb":{"@id":"https:\/\/folhadems.com.br\/site\/2026\/05\/10\/mato-grosso-do-sul-avanca-em-gestao-de-custos-na-saude-e-vira-referencia-nacional\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/folhadems.com.br\/site\/2026\/05\/10\/mato-grosso-do-sul-avanca-em-gestao-de-custos-na-saude-e-vira-referencia-nacional\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/folhadems.com.br\/site\/2026\/05\/10\/mato-grosso-do-sul-avanca-em-gestao-de-custos-na-saude-e-vira-referencia-nacional\/#primaryimage","url":"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2026\/05\/hrms3-730x480-1.jpeg","contentUrl":"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2026\/05\/hrms3-730x480-1.jpeg","width":730,"height":480},{"@type":"BreadcrumbList","@id":"https:\/\/folhadems.com.br\/site\/2026\/05\/10\/mato-grosso-do-sul-avanca-em-gestao-de-custos-na-saude-e-vira-referencia-nacional\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/folhadems.com.br\/site\/"},{"@type":"ListItem","position":2,"name":"Mato Grosso do Sul avan\u00e7a em gest\u00e3o de custos na sa\u00fade e vira refer\u00eancia nacional"}]},{"@type":"WebSite","@id":"https:\/\/folhadems.com.br\/site\/#website","url":"https:\/\/folhadems.com.br\/site\/","name":"Folha de Mato Grosso do Sul","description":"Jornal Online","publisher":{"@id":"https:\/\/folhadems.com.br\/site\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/folhadems.com.br\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/folhadems.com.br\/site\/#organization","name":"Folha de Mato Grosso do Sul","url":"https:\/\/folhadems.com.br\/site\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/folhadems.com.br\/site\/#\/schema\/logo\/image\/","url":"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2023\/01\/logo-folha-de-ms-380x90-1.jpg","contentUrl":"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2023\/01\/logo-folha-de-ms-380x90-1.jpg","width":380,"height":90,"caption":"Folha de Mato Grosso do Sul"},"image":{"@id":"https:\/\/folhadems.com.br\/site\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/folhadems.com.br\/site\/#\/schema\/person\/e4a04038e5c2e7040e19ef252ae9d940","name":"Elite Midia","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/folhadems.com.br\/site\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/f76a80f01119f7fec6909ab9feea8819031f391155be021b685479d77496f055?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f76a80f01119f7fec6909ab9feea8819031f391155be021b685479d77496f055?s=96&d=mm&r=g","caption":"Elite Midia"},"sameAs":["https:\/\/folhadems.com.br\/site"],"url":"https:\/\/folhadems.com.br\/site\/author\/elite-midia\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-20 13:56:13","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/posts\/16165","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/comments?post=16165"}],"version-history":[{"count":1,"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/posts\/16165\/revisions"}],"predecessor-version":[{"id":16167,"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/posts\/16165\/revisions\/16167"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/media\/16166"}],"wp:attachment":[{"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/media?parent=16165"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/categories?post=16165"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/tags?post=16165"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}