{"id":16139,"date":"2026-05-08T08:24:06","date_gmt":"2026-05-08T12:24:06","guid":{"rendered":"https:\/\/folhadems.com.br\/site\/?p=16139"},"modified":"2026-05-08T08:24:15","modified_gmt":"2026-05-08T12:24:15","slug":"fies-2026-pre-selecionados-devem-validar-informacoes-ate-segunda","status":"publish","type":"post","link":"https:\/\/folhadems.com.br\/site\/2026\/05\/08\/fies-2026-pre-selecionados-devem-validar-informacoes-ate-segunda\/","title":{"rendered":"Fies 2026: pr\u00e9-selecionados devem validar informa\u00e7\u00f5es at\u00e9 segunda"},"content":{"rendered":"\n<p>O estudante de ensino superior pr\u00e9-selecionado no processo de oferta de vagas remanescentes do Fundo de Financiamento Estudantil (Fies), referente ao primeiro semestre de 2026, <strong>deve validar as informa\u00e7\u00f5es declaradas no momento da inscri\u00e7\u00e3o a partir desta sexta-feira (8) at\u00e9 a pr\u00f3xima segunda-feira (11).<\/strong><img decoding=\"async\" src=\"https:\/\/agenciabrasil.ebc.com.br\/ebc.png?id=1688746&amp;o=node\"><img decoding=\"async\" src=\"https:\/\/agenciabrasil.ebc.com.br\/ebc.gif?id=1688746&amp;o=node\"><\/p>\n\n\n\n<p>Para valida\u00e7\u00e3o, o estudante deve procurar a Comiss\u00e3o Permanente de Supervis\u00e3o e Acompanhamento da institui\u00e7\u00e3o de ensino superior privada onde foi pr\u00e9-selecionado.<\/p>\n\n\n\n<p><strong>A documenta\u00e7\u00e3o exigida pode ser entregue no formato f\u00edsico ou digital, conforme definido pela faculdade privada.<\/strong>&nbsp;&nbsp;<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Consulta<\/h2>\n\n\n\n<p>Os nomes dos pr\u00e9-selecionados podem ser consultados na <a href=\"https:\/\/acessounico.mec.gov.br\/fies\" target=\"_blank\" rel=\"noreferrer noopener\">p\u00e1gina do programa no Portal \u00danico de Acesso ao Ensino Superior<\/a>, com a senha da plataforma Gov.br.&nbsp;&nbsp;<\/p>\n\n\n\n<p>O Minist\u00e9rio da Educa\u00e7\u00e3o (MEC) divulgou o <a href=\"https:\/\/agenciabrasil.ebc.com.br\/educacao\/noticia\/2026-05\/fies-2026-mec-divulga-resultado-de-vagas-remanescentes\" target=\"_blank\" rel=\"noreferrer noopener\">resultado das vagas remanescentes do Fies 2026<\/a>, nesta quinta-feira (7).&nbsp;<\/p>\n\n\n\n<p>O Fies financia a gradua\u00e7\u00e3o de estudantes matriculados em cursos presenciais n\u00e3o gratuitos em faculdades privadas e com avalia\u00e7\u00e3o positiva do Minist\u00e9rio da Educa\u00e7\u00e3o.<\/p>\n\n\n\n<p><strong>O programa \u00e9 destinado prioritariamente a estudantes que n\u00e3o tenham conclu\u00eddo o e n\u00e3o tenham sido beneficiados por outro financiamento estudantil.<\/strong><\/p>\n\n\n\n<p>Depois da valida\u00e7\u00e3o das informa\u00e7\u00f5es, ocorrer\u00e1 a valida\u00e7\u00e3o das informa\u00e7\u00f5es pelo banco (agente financeiro) respons\u00e1vel pelo financiamento, conforme previsto no <a href=\"https:\/\/www.gov.br\/mec\/pt-br\/fies\/arquivos\/2026\/edital_n24_02042026.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">edital p\u00fablico<\/a>.<\/p>\n\n\n\n<p>O prazo para essa \u00faltima valida\u00e7\u00e3o \u00e9 de at\u00e9 dez dias, contados a partir do terceiro dia \u00fatil, logo ap\u00f3s a data da valida\u00e7\u00e3o da inscri\u00e7\u00e3o pela faculdade privada para a qual o estudante foi selecionado.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Fies Social<\/h2>\n\n\n\n<p>O pr\u00e9-selecionado na vaga do Fies Social com renda familiar de at\u00e9 meio sal\u00e1rio m\u00ednimo por pessoa tem a situa\u00e7\u00e3o distinta. <strong>Nesse caso, o estudante n\u00e3o precisa comprovar a renda familiar junto \u00e0 Comiss\u00e3o Permanente de Supervis\u00e3o e Acompanhamento (CPSA) da institui\u00e7\u00e3o privada.<\/strong><\/p>\n\n\n\n<p>No entanto, o estudante dever\u00e1 comparecer \u00e0 comiss\u00e3o para validar as demais informa\u00e7\u00f5es no mesmo prazo, de 8 a 11 de maio.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Lista de espera<\/h2>\n\n\n\n<p><strong>Os candidatos que n\u00e3o foram pr\u00e9-selecionados na chamada \u00fanica ser\u00e3o inclu\u00eddos automaticamente na lista de espera.<\/strong><\/p>\n\n\n\n<p>A convoca\u00e7\u00e3o dos candidatos dessa lista ocorrer\u00e1 no per\u00edodo de 15 a 29 de maio.<\/p>\n\n\n\n<p><strong>A classifica\u00e7\u00e3o seguir\u00e1 a ordem decrescente das notas do Exame Nacional do Ensino M\u00e9dio (Enem), com prioridade para candidatos:<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>\u00a0\u00a0\u00a0\u00a0\u00a0 sem ensino superior que nunca foram beneficiados pelo Fies;<\/li>\n\n\n\n<li>\u00a0\u00a0\u00a0\u00a0\u00a0 sem ensino superior que quitaram financiamentos anteriores;<\/li>\n\n\n\n<li>\u00a0\u00a0\u00a0\u00a0\u00a0 com ensino superior que nunca foram beneficiados pelo Fies;<\/li>\n\n\n\n<li>\u00a0\u00a0\u00a0\u00a0\u00a0 candidatos com ensino superior que quitaram financiamentos anteriores.<\/li>\n<\/ul>\n\n\n\n<p>O Fies realiza anualmente dois processos seletivos regulares, um para o primeiro semestre e outro para o segundo semestre de cada ano letivo, al\u00e9m de processos seletivos para vagas remanescentes.<\/p>\n\n\n\n<p><strong>Se ainda tiver d\u00favidas, o interessado pode entrar em contato com o MEC pelo telefone 0800-616161.<\/strong><\/p>\n\n\n\n<p><strong><em>Fonte: Ag\u00eancia Brasil<\/em><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O estudante de ensino superior pr\u00e9-selecionado no processo de oferta de vagas remanescentes do Fundo de Financiamento Estudantil (Fies), referente<\/p>\n","protected":false},"author":1,"featured_media":16140,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14],"tags":[],"class_list":["post-16139","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-educacao"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.1.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Fies 2026: pr\u00e9-selecionados devem validar informa\u00e7\u00f5es at\u00e9 segunda - Folha de Mato Grosso do Sul<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/folhadems.com.br\/site\/2026\/05\/08\/fies-2026-pre-selecionados-devem-validar-informacoes-ate-segunda\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fies 2026: pr\u00e9-selecionados devem validar informa\u00e7\u00f5es at\u00e9 segunda - Folha de Mato Grosso do Sul\" \/>\n<meta property=\"og:description\" content=\"O estudante de ensino superior pr\u00e9-selecionado no processo de oferta de vagas remanescentes do Fundo de Financiamento Estudantil (Fies), referente\" \/>\n<meta property=\"og:url\" content=\"https:\/\/folhadems.com.br\/site\/2026\/05\/08\/fies-2026-pre-selecionados-devem-validar-informacoes-ate-segunda\/\" \/>\n<meta property=\"og:site_name\" content=\"Folha de Mato Grosso do Sul\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-08T12:24:06+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-08T12:24:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2026\/05\/fiess.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1170\" \/>\n\t<meta property=\"og:image:height\" content=\"700\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"Elite Midia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Elite Midia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/folhadems.com.br\/site\/2026\/05\/08\/fies-2026-pre-selecionados-devem-validar-informacoes-ate-segunda\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/folhadems.com.br\/site\/2026\/05\/08\/fies-2026-pre-selecionados-devem-validar-informacoes-ate-segunda\/\"},\"author\":{\"name\":\"Elite Midia\",\"@id\":\"https:\/\/folhadems.com.br\/site\/#\/schema\/person\/e4a04038e5c2e7040e19ef252ae9d940\"},\"headline\":\"Fies 2026: pr\u00e9-selecionados devem validar informa\u00e7\u00f5es at\u00e9 segunda\",\"datePublished\":\"2026-05-08T12:24:06+00:00\",\"dateModified\":\"2026-05-08T12:24:15+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/folhadems.com.br\/site\/2026\/05\/08\/fies-2026-pre-selecionados-devem-validar-informacoes-ate-segunda\/\"},\"wordCount\":486,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/folhadems.com.br\/site\/#organization\"},\"image\":{\"@id\":\"https:\/\/folhadems.com.br\/site\/2026\/05\/08\/fies-2026-pre-selecionados-devem-validar-informacoes-ate-segunda\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2026\/05\/fiess.webp\",\"articleSection\":[\"Educa\u00e7\u00e3o\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/folhadems.com.br\/site\/2026\/05\/08\/fies-2026-pre-selecionados-devem-validar-informacoes-ate-segunda\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/folhadems.com.br\/site\/2026\/05\/08\/fies-2026-pre-selecionados-devem-validar-informacoes-ate-segunda\/\",\"url\":\"https:\/\/folhadems.com.br\/site\/2026\/05\/08\/fies-2026-pre-selecionados-devem-validar-informacoes-ate-segunda\/\",\"name\":\"Fies 2026: pr\u00e9-selecionados devem validar informa\u00e7\u00f5es at\u00e9 segunda - Folha de Mato Grosso do Sul\",\"isPartOf\":{\"@id\":\"https:\/\/folhadems.com.br\/site\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/folhadems.com.br\/site\/2026\/05\/08\/fies-2026-pre-selecionados-devem-validar-informacoes-ate-segunda\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/folhadems.com.br\/site\/2026\/05\/08\/fies-2026-pre-selecionados-devem-validar-informacoes-ate-segunda\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2026\/05\/fiess.webp\",\"datePublished\":\"2026-05-08T12:24:06+00:00\",\"dateModified\":\"2026-05-08T12:24:15+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/folhadems.com.br\/site\/2026\/05\/08\/fies-2026-pre-selecionados-devem-validar-informacoes-ate-segunda\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/folhadems.com.br\/site\/2026\/05\/08\/fies-2026-pre-selecionados-devem-validar-informacoes-ate-segunda\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/folhadems.com.br\/site\/2026\/05\/08\/fies-2026-pre-selecionados-devem-validar-informacoes-ate-segunda\/#primaryimage\",\"url\":\"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2026\/05\/fiess.webp\",\"contentUrl\":\"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2026\/05\/fiess.webp\",\"width\":1170,\"height\":700},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/folhadems.com.br\/site\/2026\/05\/08\/fies-2026-pre-selecionados-devem-validar-informacoes-ate-segunda\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/folhadems.com.br\/site\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Fies 2026: pr\u00e9-selecionados devem validar informa\u00e7\u00f5es at\u00e9 segunda\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/folhadems.com.br\/site\/#website\",\"url\":\"https:\/\/folhadems.com.br\/site\/\",\"name\":\"Folha de Mato Grosso do Sul\",\"description\":\"Jornal Online\",\"publisher\":{\"@id\":\"https:\/\/folhadems.com.br\/site\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/folhadems.com.br\/site\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/folhadems.com.br\/site\/#organization\",\"name\":\"Folha de Mato Grosso do Sul\",\"url\":\"https:\/\/folhadems.com.br\/site\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/folhadems.com.br\/site\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2023\/01\/logo-folha-de-ms-380x90-1.jpg\",\"contentUrl\":\"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2023\/01\/logo-folha-de-ms-380x90-1.jpg\",\"width\":380,\"height\":90,\"caption\":\"Folha de Mato Grosso do Sul\"},\"image\":{\"@id\":\"https:\/\/folhadems.com.br\/site\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/folhadems.com.br\/site\/#\/schema\/person\/e4a04038e5c2e7040e19ef252ae9d940\",\"name\":\"Elite Midia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/folhadems.com.br\/site\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/f76a80f01119f7fec6909ab9feea8819031f391155be021b685479d77496f055?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/f76a80f01119f7fec6909ab9feea8819031f391155be021b685479d77496f055?s=96&d=mm&r=g\",\"caption\":\"Elite Midia\"},\"sameAs\":[\"https:\/\/folhadems.com.br\/site\"],\"url\":\"https:\/\/folhadems.com.br\/site\/author\/elite-midia\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Fies 2026: pr\u00e9-selecionados devem validar informa\u00e7\u00f5es at\u00e9 segunda - Folha de Mato Grosso do Sul","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/folhadems.com.br\/site\/2026\/05\/08\/fies-2026-pre-selecionados-devem-validar-informacoes-ate-segunda\/","og_locale":"pt_BR","og_type":"article","og_title":"Fies 2026: pr\u00e9-selecionados devem validar informa\u00e7\u00f5es at\u00e9 segunda - Folha de Mato Grosso do Sul","og_description":"O estudante de ensino superior pr\u00e9-selecionado no processo de oferta de vagas remanescentes do Fundo de Financiamento Estudantil (Fies), referente","og_url":"https:\/\/folhadems.com.br\/site\/2026\/05\/08\/fies-2026-pre-selecionados-devem-validar-informacoes-ate-segunda\/","og_site_name":"Folha de Mato Grosso do Sul","article_published_time":"2026-05-08T12:24:06+00:00","article_modified_time":"2026-05-08T12:24:15+00:00","og_image":[{"width":1170,"height":700,"url":"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2026\/05\/fiess.webp","type":"image\/webp"}],"author":"Elite Midia","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Elite Midia","Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/folhadems.com.br\/site\/2026\/05\/08\/fies-2026-pre-selecionados-devem-validar-informacoes-ate-segunda\/#article","isPartOf":{"@id":"https:\/\/folhadems.com.br\/site\/2026\/05\/08\/fies-2026-pre-selecionados-devem-validar-informacoes-ate-segunda\/"},"author":{"name":"Elite Midia","@id":"https:\/\/folhadems.com.br\/site\/#\/schema\/person\/e4a04038e5c2e7040e19ef252ae9d940"},"headline":"Fies 2026: pr\u00e9-selecionados devem validar informa\u00e7\u00f5es at\u00e9 segunda","datePublished":"2026-05-08T12:24:06+00:00","dateModified":"2026-05-08T12:24:15+00:00","mainEntityOfPage":{"@id":"https:\/\/folhadems.com.br\/site\/2026\/05\/08\/fies-2026-pre-selecionados-devem-validar-informacoes-ate-segunda\/"},"wordCount":486,"commentCount":0,"publisher":{"@id":"https:\/\/folhadems.com.br\/site\/#organization"},"image":{"@id":"https:\/\/folhadems.com.br\/site\/2026\/05\/08\/fies-2026-pre-selecionados-devem-validar-informacoes-ate-segunda\/#primaryimage"},"thumbnailUrl":"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2026\/05\/fiess.webp","articleSection":["Educa\u00e7\u00e3o"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/folhadems.com.br\/site\/2026\/05\/08\/fies-2026-pre-selecionados-devem-validar-informacoes-ate-segunda\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/folhadems.com.br\/site\/2026\/05\/08\/fies-2026-pre-selecionados-devem-validar-informacoes-ate-segunda\/","url":"https:\/\/folhadems.com.br\/site\/2026\/05\/08\/fies-2026-pre-selecionados-devem-validar-informacoes-ate-segunda\/","name":"Fies 2026: pr\u00e9-selecionados devem validar informa\u00e7\u00f5es at\u00e9 segunda - Folha de Mato Grosso do Sul","isPartOf":{"@id":"https:\/\/folhadems.com.br\/site\/#website"},"primaryImageOfPage":{"@id":"https:\/\/folhadems.com.br\/site\/2026\/05\/08\/fies-2026-pre-selecionados-devem-validar-informacoes-ate-segunda\/#primaryimage"},"image":{"@id":"https:\/\/folhadems.com.br\/site\/2026\/05\/08\/fies-2026-pre-selecionados-devem-validar-informacoes-ate-segunda\/#primaryimage"},"thumbnailUrl":"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2026\/05\/fiess.webp","datePublished":"2026-05-08T12:24:06+00:00","dateModified":"2026-05-08T12:24:15+00:00","breadcrumb":{"@id":"https:\/\/folhadems.com.br\/site\/2026\/05\/08\/fies-2026-pre-selecionados-devem-validar-informacoes-ate-segunda\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/folhadems.com.br\/site\/2026\/05\/08\/fies-2026-pre-selecionados-devem-validar-informacoes-ate-segunda\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/folhadems.com.br\/site\/2026\/05\/08\/fies-2026-pre-selecionados-devem-validar-informacoes-ate-segunda\/#primaryimage","url":"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2026\/05\/fiess.webp","contentUrl":"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2026\/05\/fiess.webp","width":1170,"height":700},{"@type":"BreadcrumbList","@id":"https:\/\/folhadems.com.br\/site\/2026\/05\/08\/fies-2026-pre-selecionados-devem-validar-informacoes-ate-segunda\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/folhadems.com.br\/site\/"},{"@type":"ListItem","position":2,"name":"Fies 2026: pr\u00e9-selecionados devem validar informa\u00e7\u00f5es at\u00e9 segunda"}]},{"@type":"WebSite","@id":"https:\/\/folhadems.com.br\/site\/#website","url":"https:\/\/folhadems.com.br\/site\/","name":"Folha de Mato Grosso do Sul","description":"Jornal Online","publisher":{"@id":"https:\/\/folhadems.com.br\/site\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/folhadems.com.br\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/folhadems.com.br\/site\/#organization","name":"Folha de Mato Grosso do Sul","url":"https:\/\/folhadems.com.br\/site\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/folhadems.com.br\/site\/#\/schema\/logo\/image\/","url":"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2023\/01\/logo-folha-de-ms-380x90-1.jpg","contentUrl":"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2023\/01\/logo-folha-de-ms-380x90-1.jpg","width":380,"height":90,"caption":"Folha de Mato Grosso do Sul"},"image":{"@id":"https:\/\/folhadems.com.br\/site\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/folhadems.com.br\/site\/#\/schema\/person\/e4a04038e5c2e7040e19ef252ae9d940","name":"Elite Midia","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/folhadems.com.br\/site\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/f76a80f01119f7fec6909ab9feea8819031f391155be021b685479d77496f055?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f76a80f01119f7fec6909ab9feea8819031f391155be021b685479d77496f055?s=96&d=mm&r=g","caption":"Elite Midia"},"sameAs":["https:\/\/folhadems.com.br\/site"],"url":"https:\/\/folhadems.com.br\/site\/author\/elite-midia\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-20 09:19:21","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/posts\/16139","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/comments?post=16139"}],"version-history":[{"count":1,"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/posts\/16139\/revisions"}],"predecessor-version":[{"id":16141,"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/posts\/16139\/revisions\/16141"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/media\/16140"}],"wp:attachment":[{"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/media?parent=16139"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/categories?post=16139"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/tags?post=16139"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}