{"id":16041,"date":"2026-05-04T15:07:00","date_gmt":"2026-05-04T19:07:00","guid":{"rendered":"https:\/\/folhadems.com.br\/site\/?p=16041"},"modified":"2026-05-04T10:42:41","modified_gmt":"2026-05-04T14:42:41","slug":"com-dois-dias-de-atracoes-festa-do-queijo-comeca-na-sexta-feira-8","status":"publish","type":"post","link":"https:\/\/folhadems.com.br\/site\/2026\/05\/04\/com-dois-dias-de-atracoes-festa-do-queijo-comeca-na-sexta-feira-8\/","title":{"rendered":"Com dois dias de atra\u00e7\u00f5es, Festa do Queijo come\u00e7a na sexta-feira (8)"},"content":{"rendered":"\n<p>A contagem regressiva j\u00e1 come\u00e7ou: a 9\u00aa edi\u00e7\u00e3o da tradicional Festa do Queijo ser\u00e1 realizada nesta semana, nos dias 8 e 9 de maio, a partir das 17h, em frente \u00e0 Escola Municipal Agr\u00edcola Bar\u00e3o do Rio Branco, no distrito de Rochedinho. O evento chega com programa\u00e7\u00e3o ampliada e atra\u00e7\u00f5es musicais preparadas para animar os dois dias de festa.<\/p>\n\n\n\n<p>Consolidada no calend\u00e1rio local, a Festa do Queijo acontece sempre no m\u00eas de maio, antecedendo o Dia das M\u00e3es, e re\u00fane produtores, moradores e visitantes em um ambiente que valoriza a cultura regional e a produ\u00e7\u00e3o artesanal. Neste ano, a amplia\u00e7\u00e3o para dois dias atende \u00e0 crescente demanda de p\u00fablico e refor\u00e7a a import\u00e2ncia do evento para a economia e o turismo da regi\u00e3o.<\/p>\n\n\n\n<p>A feira contar\u00e1 com diversos expositores, reunindo desde produtores de queijos artesanais, como o inovador queijo de terer\u00e9 at\u00e9 barracas com doces t\u00edpicos, como doce de leite e ambrosia. Entre os destaques, o p\u00fablico tamb\u00e9m poder\u00e1 encontrar o expositor de galeto de pequi, ampliando as op\u00e7\u00f5es gastron\u00f4micas e valorizando sabores regionais.<\/p>\n\n\n\n<p>A programa\u00e7\u00e3o inclui ainda atra\u00e7\u00f5es culturais voltadas para todas as idades, garantindo um ambiente festivo, acolhedor e ideal para as fam\u00edlias.<\/p>\n\n\n\n<p>Outro destaque da edi\u00e7\u00e3o \u00e9 a participa\u00e7\u00e3o dos alunos da Escola Municipal Agr\u00edcola Bar\u00e3o do Rio Branco, que estar\u00e3o presentes como expositores, apresentando produtos desenvolvidos durante as atividades pedag\u00f3gicas, fortalecendo a integra\u00e7\u00e3o entre educa\u00e7\u00e3o, produ\u00e7\u00e3o e comunidade.<\/p>\n\n\n\n<p>No \u00faltimo ano, a festa reuniu cerca de 10 mil pessoas, e a expectativa para 2026 \u00e9 de um p\u00fablico ainda maior, impulsionado pelo novo formato e pela diversidade de atra\u00e7\u00f5es.<\/p>\n\n\n\n<p>A orienta\u00e7\u00e3o \u00e9 para que o p\u00fablico se programe e participe. A Festa do Queijo \u00e9 uma oportunidade de prestigiar os produtores locais, incentivar a economia regional e aproveitar momentos de lazer em fam\u00edlia.<\/p>\n\n\n\n<p><strong><em>Fonte: PrefCG<\/em><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A contagem regressiva j\u00e1 come\u00e7ou: a 9\u00aa edi\u00e7\u00e3o da tradicional Festa do Queijo ser\u00e1 realizada nesta semana, nos dias 8<\/p>\n","protected":false},"author":1,"featured_media":16042,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[19],"tags":[],"class_list":["post-16041","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cultura"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.1.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Com dois dias de atra\u00e7\u00f5es, Festa do Queijo come\u00e7a na sexta-feira (8) - Folha de Mato Grosso do Sul<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/folhadems.com.br\/site\/2026\/05\/04\/com-dois-dias-de-atracoes-festa-do-queijo-comeca-na-sexta-feira-8\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Com dois dias de atra\u00e7\u00f5es, Festa do Queijo come\u00e7a na sexta-feira (8) - Folha de Mato Grosso do Sul\" \/>\n<meta property=\"og:description\" content=\"A contagem regressiva j\u00e1 come\u00e7ou: a 9\u00aa edi\u00e7\u00e3o da tradicional Festa do Queijo ser\u00e1 realizada nesta semana, nos dias 8\" \/>\n<meta property=\"og:url\" content=\"https:\/\/folhadems.com.br\/site\/2026\/05\/04\/com-dois-dias-de-atracoes-festa-do-queijo-comeca-na-sexta-feira-8\/\" \/>\n<meta property=\"og:site_name\" content=\"Folha de Mato Grosso do Sul\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-04T19:07:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2026\/05\/queijo-festa.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1536\" \/>\n\t<meta property=\"og:image:height\" content=\"864\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Elite Midia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Elite Midia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/folhadems.com.br\/site\/2026\/05\/04\/com-dois-dias-de-atracoes-festa-do-queijo-comeca-na-sexta-feira-8\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/folhadems.com.br\/site\/2026\/05\/04\/com-dois-dias-de-atracoes-festa-do-queijo-comeca-na-sexta-feira-8\/\"},\"author\":{\"name\":\"Elite Midia\",\"@id\":\"https:\/\/folhadems.com.br\/site\/#\/schema\/person\/e4a04038e5c2e7040e19ef252ae9d940\"},\"headline\":\"Com dois dias de atra\u00e7\u00f5es, Festa do Queijo come\u00e7a na sexta-feira (8)\",\"datePublished\":\"2026-05-04T19:07:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/folhadems.com.br\/site\/2026\/05\/04\/com-dois-dias-de-atracoes-festa-do-queijo-comeca-na-sexta-feira-8\/\"},\"wordCount\":339,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/folhadems.com.br\/site\/#organization\"},\"image\":{\"@id\":\"https:\/\/folhadems.com.br\/site\/2026\/05\/04\/com-dois-dias-de-atracoes-festa-do-queijo-comeca-na-sexta-feira-8\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2026\/05\/queijo-festa.jpg\",\"articleSection\":[\"Cultura\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/folhadems.com.br\/site\/2026\/05\/04\/com-dois-dias-de-atracoes-festa-do-queijo-comeca-na-sexta-feira-8\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/folhadems.com.br\/site\/2026\/05\/04\/com-dois-dias-de-atracoes-festa-do-queijo-comeca-na-sexta-feira-8\/\",\"url\":\"https:\/\/folhadems.com.br\/site\/2026\/05\/04\/com-dois-dias-de-atracoes-festa-do-queijo-comeca-na-sexta-feira-8\/\",\"name\":\"Com dois dias de atra\u00e7\u00f5es, Festa do Queijo come\u00e7a na sexta-feira (8) - Folha de Mato Grosso do Sul\",\"isPartOf\":{\"@id\":\"https:\/\/folhadems.com.br\/site\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/folhadems.com.br\/site\/2026\/05\/04\/com-dois-dias-de-atracoes-festa-do-queijo-comeca-na-sexta-feira-8\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/folhadems.com.br\/site\/2026\/05\/04\/com-dois-dias-de-atracoes-festa-do-queijo-comeca-na-sexta-feira-8\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2026\/05\/queijo-festa.jpg\",\"datePublished\":\"2026-05-04T19:07:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/folhadems.com.br\/site\/2026\/05\/04\/com-dois-dias-de-atracoes-festa-do-queijo-comeca-na-sexta-feira-8\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/folhadems.com.br\/site\/2026\/05\/04\/com-dois-dias-de-atracoes-festa-do-queijo-comeca-na-sexta-feira-8\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/folhadems.com.br\/site\/2026\/05\/04\/com-dois-dias-de-atracoes-festa-do-queijo-comeca-na-sexta-feira-8\/#primaryimage\",\"url\":\"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2026\/05\/queijo-festa.jpg\",\"contentUrl\":\"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2026\/05\/queijo-festa.jpg\",\"width\":1536,\"height\":864},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/folhadems.com.br\/site\/2026\/05\/04\/com-dois-dias-de-atracoes-festa-do-queijo-comeca-na-sexta-feira-8\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/folhadems.com.br\/site\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Com dois dias de atra\u00e7\u00f5es, Festa do Queijo come\u00e7a na sexta-feira (8)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/folhadems.com.br\/site\/#website\",\"url\":\"https:\/\/folhadems.com.br\/site\/\",\"name\":\"Folha de Mato Grosso do Sul\",\"description\":\"Jornal Online\",\"publisher\":{\"@id\":\"https:\/\/folhadems.com.br\/site\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/folhadems.com.br\/site\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/folhadems.com.br\/site\/#organization\",\"name\":\"Folha de Mato Grosso do Sul\",\"url\":\"https:\/\/folhadems.com.br\/site\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/folhadems.com.br\/site\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2023\/01\/logo-folha-de-ms-380x90-1.jpg\",\"contentUrl\":\"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2023\/01\/logo-folha-de-ms-380x90-1.jpg\",\"width\":380,\"height\":90,\"caption\":\"Folha de Mato Grosso do Sul\"},\"image\":{\"@id\":\"https:\/\/folhadems.com.br\/site\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/folhadems.com.br\/site\/#\/schema\/person\/e4a04038e5c2e7040e19ef252ae9d940\",\"name\":\"Elite Midia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/folhadems.com.br\/site\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/f76a80f01119f7fec6909ab9feea8819031f391155be021b685479d77496f055?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/f76a80f01119f7fec6909ab9feea8819031f391155be021b685479d77496f055?s=96&d=mm&r=g\",\"caption\":\"Elite Midia\"},\"sameAs\":[\"https:\/\/folhadems.com.br\/site\"],\"url\":\"https:\/\/folhadems.com.br\/site\/author\/elite-midia\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Com dois dias de atra\u00e7\u00f5es, Festa do Queijo come\u00e7a na sexta-feira (8) - Folha de Mato Grosso do Sul","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/folhadems.com.br\/site\/2026\/05\/04\/com-dois-dias-de-atracoes-festa-do-queijo-comeca-na-sexta-feira-8\/","og_locale":"pt_BR","og_type":"article","og_title":"Com dois dias de atra\u00e7\u00f5es, Festa do Queijo come\u00e7a na sexta-feira (8) - Folha de Mato Grosso do Sul","og_description":"A contagem regressiva j\u00e1 come\u00e7ou: a 9\u00aa edi\u00e7\u00e3o da tradicional Festa do Queijo ser\u00e1 realizada nesta semana, nos dias 8","og_url":"https:\/\/folhadems.com.br\/site\/2026\/05\/04\/com-dois-dias-de-atracoes-festa-do-queijo-comeca-na-sexta-feira-8\/","og_site_name":"Folha de Mato Grosso do Sul","article_published_time":"2026-05-04T19:07:00+00:00","og_image":[{"width":1536,"height":864,"url":"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2026\/05\/queijo-festa.jpg","type":"image\/jpeg"}],"author":"Elite Midia","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Elite Midia","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/folhadems.com.br\/site\/2026\/05\/04\/com-dois-dias-de-atracoes-festa-do-queijo-comeca-na-sexta-feira-8\/#article","isPartOf":{"@id":"https:\/\/folhadems.com.br\/site\/2026\/05\/04\/com-dois-dias-de-atracoes-festa-do-queijo-comeca-na-sexta-feira-8\/"},"author":{"name":"Elite Midia","@id":"https:\/\/folhadems.com.br\/site\/#\/schema\/person\/e4a04038e5c2e7040e19ef252ae9d940"},"headline":"Com dois dias de atra\u00e7\u00f5es, Festa do Queijo come\u00e7a na sexta-feira (8)","datePublished":"2026-05-04T19:07:00+00:00","mainEntityOfPage":{"@id":"https:\/\/folhadems.com.br\/site\/2026\/05\/04\/com-dois-dias-de-atracoes-festa-do-queijo-comeca-na-sexta-feira-8\/"},"wordCount":339,"commentCount":0,"publisher":{"@id":"https:\/\/folhadems.com.br\/site\/#organization"},"image":{"@id":"https:\/\/folhadems.com.br\/site\/2026\/05\/04\/com-dois-dias-de-atracoes-festa-do-queijo-comeca-na-sexta-feira-8\/#primaryimage"},"thumbnailUrl":"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2026\/05\/queijo-festa.jpg","articleSection":["Cultura"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/folhadems.com.br\/site\/2026\/05\/04\/com-dois-dias-de-atracoes-festa-do-queijo-comeca-na-sexta-feira-8\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/folhadems.com.br\/site\/2026\/05\/04\/com-dois-dias-de-atracoes-festa-do-queijo-comeca-na-sexta-feira-8\/","url":"https:\/\/folhadems.com.br\/site\/2026\/05\/04\/com-dois-dias-de-atracoes-festa-do-queijo-comeca-na-sexta-feira-8\/","name":"Com dois dias de atra\u00e7\u00f5es, Festa do Queijo come\u00e7a na sexta-feira (8) - Folha de Mato Grosso do Sul","isPartOf":{"@id":"https:\/\/folhadems.com.br\/site\/#website"},"primaryImageOfPage":{"@id":"https:\/\/folhadems.com.br\/site\/2026\/05\/04\/com-dois-dias-de-atracoes-festa-do-queijo-comeca-na-sexta-feira-8\/#primaryimage"},"image":{"@id":"https:\/\/folhadems.com.br\/site\/2026\/05\/04\/com-dois-dias-de-atracoes-festa-do-queijo-comeca-na-sexta-feira-8\/#primaryimage"},"thumbnailUrl":"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2026\/05\/queijo-festa.jpg","datePublished":"2026-05-04T19:07:00+00:00","breadcrumb":{"@id":"https:\/\/folhadems.com.br\/site\/2026\/05\/04\/com-dois-dias-de-atracoes-festa-do-queijo-comeca-na-sexta-feira-8\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/folhadems.com.br\/site\/2026\/05\/04\/com-dois-dias-de-atracoes-festa-do-queijo-comeca-na-sexta-feira-8\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/folhadems.com.br\/site\/2026\/05\/04\/com-dois-dias-de-atracoes-festa-do-queijo-comeca-na-sexta-feira-8\/#primaryimage","url":"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2026\/05\/queijo-festa.jpg","contentUrl":"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2026\/05\/queijo-festa.jpg","width":1536,"height":864},{"@type":"BreadcrumbList","@id":"https:\/\/folhadems.com.br\/site\/2026\/05\/04\/com-dois-dias-de-atracoes-festa-do-queijo-comeca-na-sexta-feira-8\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/folhadems.com.br\/site\/"},{"@type":"ListItem","position":2,"name":"Com dois dias de atra\u00e7\u00f5es, Festa do Queijo come\u00e7a na sexta-feira (8)"}]},{"@type":"WebSite","@id":"https:\/\/folhadems.com.br\/site\/#website","url":"https:\/\/folhadems.com.br\/site\/","name":"Folha de Mato Grosso do Sul","description":"Jornal Online","publisher":{"@id":"https:\/\/folhadems.com.br\/site\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/folhadems.com.br\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/folhadems.com.br\/site\/#organization","name":"Folha de Mato Grosso do Sul","url":"https:\/\/folhadems.com.br\/site\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/folhadems.com.br\/site\/#\/schema\/logo\/image\/","url":"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2023\/01\/logo-folha-de-ms-380x90-1.jpg","contentUrl":"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2023\/01\/logo-folha-de-ms-380x90-1.jpg","width":380,"height":90,"caption":"Folha de Mato Grosso do Sul"},"image":{"@id":"https:\/\/folhadems.com.br\/site\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/folhadems.com.br\/site\/#\/schema\/person\/e4a04038e5c2e7040e19ef252ae9d940","name":"Elite Midia","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/folhadems.com.br\/site\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/f76a80f01119f7fec6909ab9feea8819031f391155be021b685479d77496f055?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f76a80f01119f7fec6909ab9feea8819031f391155be021b685479d77496f055?s=96&d=mm&r=g","caption":"Elite Midia"},"sameAs":["https:\/\/folhadems.com.br\/site"],"url":"https:\/\/folhadems.com.br\/site\/author\/elite-midia\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-20 14:26:50","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/posts\/16041","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/comments?post=16041"}],"version-history":[{"count":1,"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/posts\/16041\/revisions"}],"predecessor-version":[{"id":16043,"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/posts\/16041\/revisions\/16043"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/media\/16042"}],"wp:attachment":[{"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/media?parent=16041"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/categories?post=16041"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/tags?post=16041"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}