{"id":15214,"date":"2026-03-25T10:54:26","date_gmt":"2026-03-25T14:54:26","guid":{"rendered":"https:\/\/folhadems.com.br\/site\/?p=15214"},"modified":"2026-03-25T11:10:30","modified_gmt":"2026-03-25T15:10:30","slug":"em-reestruturacao-correios-anunciam-escala-12x36-em-alguns-setores","status":"publish","type":"post","link":"https:\/\/folhadems.com.br\/site\/2026\/03\/25\/em-reestruturacao-correios-anunciam-escala-12x36-em-alguns-setores\/","title":{"rendered":"Em reestrutura\u00e7\u00e3o, Correios anunciam escala 12&#215;36 em alguns setores"},"content":{"rendered":"\n<p>Os Correios informaram nesta ter\u00e7a-feira (24) que ir\u00e3o adotar, de forma gradual, a escala de trabalho 12 horas de trabalho por 36 horas de descanso, a escala 12&#215;36, em atividades espec\u00edficas da empresa. <img decoding=\"async\" src=\"https:\/\/agenciabrasil.ebc.com.br\/ebc.png?id=1683366&amp;o=node\"><img decoding=\"async\" src=\"https:\/\/agenciabrasil.ebc.com.br\/ebc.gif?id=1683366&amp;o=node\"><\/p>\n\n\n\n<p>Segundo informe da empresa, a implementa\u00e7\u00e3o n\u00e3o ser\u00e1 autom\u00e1tica e a ado\u00e7\u00e3o da jornada ocorrer\u00e1 conforme as necessidades do servi\u00e7o. A medida integra o Plano de Reestrutura\u00e7\u00e3o da estatal.<\/p>\n\n\n\n<p>A iniciativa, segundo a estatal,&nbsp;\u201cest\u00e1 alinhada ao processo de moderniza\u00e7\u00e3o dos fluxos operacionais e ao aumento da efici\u00eancia na presta\u00e7\u00e3o dos servi\u00e7os\u201d, permitindo maior adequa\u00e7\u00e3o das equipes e dos turnos ao ritmo real da opera\u00e7\u00e3o e do neg\u00f3cio.<\/p>\n\n\n\n<p>Comunicado da\u00a0empresa diz\u00a0que a escala 12X36 ser\u00e1 aplicada especialmente nas \u00e1reas que demandam funcionamento cont\u00ednuo e maior agilidade na entrega, em raz\u00e3o do crescimento do com\u00e9rcio eletr\u00f4nico.<\/p>\n\n\n\n<p>\u201cA jornada flex\u00edvel se consolida como um diferencial competitivo relevante, ao ampliar a capacidade operacional dos Correios e fortalecer o posicionamento da empresa frente \u00e0 concorr\u00eancia no segmento de encomendas\u201d, disse os Correios.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Trabalhadores s\u00e3o contra<\/h2>\n\n\n\n<p>A Federa\u00e7\u00e3o Nacional dos Trabalhadores em Empresas de Correios e Telegrafos e Similares (Fentect) criticou a ado\u00e7\u00e3o da medida. Segundo a federa\u00e7\u00e3o, a jornada precariza ainda mais as condi\u00e7\u00f5es de trabalho.<\/p>\n\n\n\n<p>S\u00e3o medidas que adoecem, sobrecarregam e desrespeitam quem sustenta a empresa todos os dias, <a href=\"https:\/\/www.instagram.com\/p\/DWHV1Eit9AA\/?hl=pt\" target=\"_blank\" rel=\"noreferrer noopener\">diz a federa\u00e7\u00e3o<\/a>.&nbsp;<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>&#8220;N\u00e3o aceitaremos acordos individuais que fragilizam a organiza\u00e7\u00e3o coletiva, A orienta\u00e7\u00e3o \u00e9 para n\u00e3o assinar e manter a unidade da categoria\u201d, disse a federa\u00e7\u00e3o em uma rede social.<\/p>\n<\/blockquote>\n\n\n\n<p>Os trabalhadores anunciam que est\u00e3o se organizando para evitar a implementa\u00e7\u00e3o da nova escala. \u201cSe insistirem em retirar direitos, a resposta ser\u00e1 organiza\u00e7\u00e3o, mobiliza\u00e7\u00e3o e luta em todo o pa\u00eds. Estamos construindo uma grande rea\u00e7\u00e3o nacional para barrar esses retrocessos. N\u00e3o h\u00e1 negocia\u00e7\u00e3o com retirada de direitos\u201d, segue a publica\u00e7\u00e3o.&nbsp;<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Plano de restrutura\u00e7\u00e3o<\/h2>\n\n\n\n<p>Os Correios passam por um plano de restrutura\u00e7\u00e3o que, entre outros, pontos, tem por objetivo promover a estabiliza\u00e7\u00e3o da empresa.<\/p>\n\n\n\n<p>Diagn\u00f3stico&nbsp;identificou d\u00e9ficit superior a R$ 4 bilh\u00f5es anuais, patrim\u00f4nio l\u00edquido negativo de R$ 10,4 bilh\u00f5es e preju\u00edzo acumulado de R$ 6,057 bilh\u00f5es at\u00e9 setembro de 2025, al\u00e9m da queda acentuada nos indicadores de qualidade e liquidez.<\/p>\n\n\n\n<p>Em dezembro, os Correios anunciaram a <a href=\"https:\/\/agenciabrasil.ebc.com.br\/economia\/noticia\/2025-12\/dou-publica-extrato-de-emprestimo-de-r-12-bilhoes-para-os-correios\" target=\"_blank\" rel=\"noreferrer noopener\">capta\u00e7\u00e3o de R$ 12 bilh\u00f5es em cr\u00e9dito<\/a>&nbsp;para custear as a\u00e7\u00f5es do plano de reestrutura\u00e7\u00e3o voltado \u00e0 estabiliza\u00e7\u00e3o emergencial da empresa.<\/p>\n\n\n\n<p>Como parte deste mesmo plano de reestrutura\u00e7\u00e3o financeira, os Correios tamb\u00e9m anunciaram o <a href=\"https:\/\/agenciabrasil.ebc.com.br\/economia\/noticia\/2025-12\/correios-preve-fechar-mil-agencias-e-15-mil-demissoes-voluntarias\" target=\"_blank\" rel=\"noreferrer noopener\">fechamento de mil ag\u00eancias<\/a>&nbsp;e um&nbsp;Plano de Desligamento Volunt\u00e1rio com a expectativa de ades\u00e3o de at\u00e9 <a href=\"https:\/\/agenciabrasil.ebc.com.br\/economia\/noticia\/2026-01\/correios-reabrem-inscricao-para-plano-de-desligamento-voluntario\" target=\"_blank\" rel=\"noreferrer noopener\">15 mil empregados<\/a>.<\/p>\n\n\n\n<p>Entre as medidas adotadas tamb\u00e9m est\u00e3o a venda de ativos, como im\u00f3veis classificados como ociosos.<\/p>\n\n\n\n<p>Em fevereiro, os Correios fizeram o primeiro <a href=\"https:\/\/agenciabrasil.ebc.com.br\/economia\/noticia\/2026-02\/correios-colocam-21-imoveis-venda-em-11-estados\" target=\"_blank\" rel=\"noreferrer noopener\">leil\u00e3o de im\u00f3veis pr\u00f3prios<\/a>. A oferta inicial abrange 21 im\u00f3veis para venda imediata, localizados em 11 estados: Bahia, Cear\u00e1, Goi\u00e1s, Mato Grosso, Mato Grosso do Sul, Minas Gerais, Par\u00e1, Paran\u00e1, Pernambuco, Rio Grande do Norte e S\u00e3o Paulo.&nbsp;<\/p>\n\n\n\n<p><strong><em>Fonte: Ag\u00eancia Brasil<\/em><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Os Correios informaram nesta ter\u00e7a-feira (24) que ir\u00e3o adotar, de forma gradual, a escala de trabalho 12 horas de trabalho<\/p>\n","protected":false},"author":1,"featured_media":15215,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-15214","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-geral-brasil"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.1.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Em reestrutura\u00e7\u00e3o, Correios anunciam escala 12x36 em alguns setores - Folha de Mato Grosso do Sul<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/folhadems.com.br\/site\/2026\/03\/25\/em-reestruturacao-correios-anunciam-escala-12x36-em-alguns-setores\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Em reestrutura\u00e7\u00e3o, Correios anunciam escala 12x36 em alguns setores - Folha de Mato Grosso do Sul\" \/>\n<meta property=\"og:description\" content=\"Os Correios informaram nesta ter\u00e7a-feira (24) que ir\u00e3o adotar, de forma gradual, a escala de trabalho 12 horas de trabalho\" \/>\n<meta property=\"og:url\" content=\"https:\/\/folhadems.com.br\/site\/2026\/03\/25\/em-reestruturacao-correios-anunciam-escala-12x36-em-alguns-setores\/\" \/>\n<meta property=\"og:site_name\" content=\"Folha de Mato Grosso do Sul\" \/>\n<meta property=\"article:published_time\" content=\"2026-03-25T14:54:26+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-25T15:10:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2026\/03\/correios.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"450\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Elite Midia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Elite Midia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/folhadems.com.br\/site\/2026\/03\/25\/em-reestruturacao-correios-anunciam-escala-12x36-em-alguns-setores\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/folhadems.com.br\/site\/2026\/03\/25\/em-reestruturacao-correios-anunciam-escala-12x36-em-alguns-setores\/\"},\"author\":{\"name\":\"Elite Midia\",\"@id\":\"https:\/\/folhadems.com.br\/site\/#\/schema\/person\/e4a04038e5c2e7040e19ef252ae9d940\"},\"headline\":\"Em reestrutura\u00e7\u00e3o, Correios anunciam escala 12&#215;36 em alguns setores\",\"datePublished\":\"2026-03-25T14:54:26+00:00\",\"dateModified\":\"2026-03-25T15:10:30+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/folhadems.com.br\/site\/2026\/03\/25\/em-reestruturacao-correios-anunciam-escala-12x36-em-alguns-setores\/\"},\"wordCount\":555,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/folhadems.com.br\/site\/#organization\"},\"image\":{\"@id\":\"https:\/\/folhadems.com.br\/site\/2026\/03\/25\/em-reestruturacao-correios-anunciam-escala-12x36-em-alguns-setores\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2026\/03\/correios.jpg\",\"articleSection\":[\"Geral \/ Brasil\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/folhadems.com.br\/site\/2026\/03\/25\/em-reestruturacao-correios-anunciam-escala-12x36-em-alguns-setores\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/folhadems.com.br\/site\/2026\/03\/25\/em-reestruturacao-correios-anunciam-escala-12x36-em-alguns-setores\/\",\"url\":\"https:\/\/folhadems.com.br\/site\/2026\/03\/25\/em-reestruturacao-correios-anunciam-escala-12x36-em-alguns-setores\/\",\"name\":\"Em reestrutura\u00e7\u00e3o, Correios anunciam escala 12x36 em alguns setores - Folha de Mato Grosso do Sul\",\"isPartOf\":{\"@id\":\"https:\/\/folhadems.com.br\/site\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/folhadems.com.br\/site\/2026\/03\/25\/em-reestruturacao-correios-anunciam-escala-12x36-em-alguns-setores\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/folhadems.com.br\/site\/2026\/03\/25\/em-reestruturacao-correios-anunciam-escala-12x36-em-alguns-setores\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2026\/03\/correios.jpg\",\"datePublished\":\"2026-03-25T14:54:26+00:00\",\"dateModified\":\"2026-03-25T15:10:30+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/folhadems.com.br\/site\/2026\/03\/25\/em-reestruturacao-correios-anunciam-escala-12x36-em-alguns-setores\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/folhadems.com.br\/site\/2026\/03\/25\/em-reestruturacao-correios-anunciam-escala-12x36-em-alguns-setores\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/folhadems.com.br\/site\/2026\/03\/25\/em-reestruturacao-correios-anunciam-escala-12x36-em-alguns-setores\/#primaryimage\",\"url\":\"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2026\/03\/correios.jpg\",\"contentUrl\":\"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2026\/03\/correios.jpg\",\"width\":800,\"height\":450},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/folhadems.com.br\/site\/2026\/03\/25\/em-reestruturacao-correios-anunciam-escala-12x36-em-alguns-setores\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/folhadems.com.br\/site\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Em reestrutura\u00e7\u00e3o, Correios anunciam escala 12&#215;36 em alguns setores\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/folhadems.com.br\/site\/#website\",\"url\":\"https:\/\/folhadems.com.br\/site\/\",\"name\":\"Folha de Mato Grosso do Sul\",\"description\":\"Jornal Online\",\"publisher\":{\"@id\":\"https:\/\/folhadems.com.br\/site\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/folhadems.com.br\/site\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/folhadems.com.br\/site\/#organization\",\"name\":\"Folha de Mato Grosso do Sul\",\"url\":\"https:\/\/folhadems.com.br\/site\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/folhadems.com.br\/site\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2023\/01\/logo-folha-de-ms-380x90-1.jpg\",\"contentUrl\":\"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2023\/01\/logo-folha-de-ms-380x90-1.jpg\",\"width\":380,\"height\":90,\"caption\":\"Folha de Mato Grosso do Sul\"},\"image\":{\"@id\":\"https:\/\/folhadems.com.br\/site\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/folhadems.com.br\/site\/#\/schema\/person\/e4a04038e5c2e7040e19ef252ae9d940\",\"name\":\"Elite Midia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/folhadems.com.br\/site\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/f76a80f01119f7fec6909ab9feea8819031f391155be021b685479d77496f055?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/f76a80f01119f7fec6909ab9feea8819031f391155be021b685479d77496f055?s=96&d=mm&r=g\",\"caption\":\"Elite Midia\"},\"sameAs\":[\"https:\/\/folhadems.com.br\/site\"],\"url\":\"https:\/\/folhadems.com.br\/site\/author\/elite-midia\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Em reestrutura\u00e7\u00e3o, Correios anunciam escala 12x36 em alguns setores - Folha de Mato Grosso do Sul","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/folhadems.com.br\/site\/2026\/03\/25\/em-reestruturacao-correios-anunciam-escala-12x36-em-alguns-setores\/","og_locale":"pt_BR","og_type":"article","og_title":"Em reestrutura\u00e7\u00e3o, Correios anunciam escala 12x36 em alguns setores - Folha de Mato Grosso do Sul","og_description":"Os Correios informaram nesta ter\u00e7a-feira (24) que ir\u00e3o adotar, de forma gradual, a escala de trabalho 12 horas de trabalho","og_url":"https:\/\/folhadems.com.br\/site\/2026\/03\/25\/em-reestruturacao-correios-anunciam-escala-12x36-em-alguns-setores\/","og_site_name":"Folha de Mato Grosso do Sul","article_published_time":"2026-03-25T14:54:26+00:00","article_modified_time":"2026-03-25T15:10:30+00:00","og_image":[{"width":800,"height":450,"url":"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2026\/03\/correios.jpg","type":"image\/jpeg"}],"author":"Elite Midia","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Elite Midia","Est. tempo de leitura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/folhadems.com.br\/site\/2026\/03\/25\/em-reestruturacao-correios-anunciam-escala-12x36-em-alguns-setores\/#article","isPartOf":{"@id":"https:\/\/folhadems.com.br\/site\/2026\/03\/25\/em-reestruturacao-correios-anunciam-escala-12x36-em-alguns-setores\/"},"author":{"name":"Elite Midia","@id":"https:\/\/folhadems.com.br\/site\/#\/schema\/person\/e4a04038e5c2e7040e19ef252ae9d940"},"headline":"Em reestrutura\u00e7\u00e3o, Correios anunciam escala 12&#215;36 em alguns setores","datePublished":"2026-03-25T14:54:26+00:00","dateModified":"2026-03-25T15:10:30+00:00","mainEntityOfPage":{"@id":"https:\/\/folhadems.com.br\/site\/2026\/03\/25\/em-reestruturacao-correios-anunciam-escala-12x36-em-alguns-setores\/"},"wordCount":555,"commentCount":0,"publisher":{"@id":"https:\/\/folhadems.com.br\/site\/#organization"},"image":{"@id":"https:\/\/folhadems.com.br\/site\/2026\/03\/25\/em-reestruturacao-correios-anunciam-escala-12x36-em-alguns-setores\/#primaryimage"},"thumbnailUrl":"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2026\/03\/correios.jpg","articleSection":["Geral \/ Brasil"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/folhadems.com.br\/site\/2026\/03\/25\/em-reestruturacao-correios-anunciam-escala-12x36-em-alguns-setores\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/folhadems.com.br\/site\/2026\/03\/25\/em-reestruturacao-correios-anunciam-escala-12x36-em-alguns-setores\/","url":"https:\/\/folhadems.com.br\/site\/2026\/03\/25\/em-reestruturacao-correios-anunciam-escala-12x36-em-alguns-setores\/","name":"Em reestrutura\u00e7\u00e3o, Correios anunciam escala 12x36 em alguns setores - Folha de Mato Grosso do Sul","isPartOf":{"@id":"https:\/\/folhadems.com.br\/site\/#website"},"primaryImageOfPage":{"@id":"https:\/\/folhadems.com.br\/site\/2026\/03\/25\/em-reestruturacao-correios-anunciam-escala-12x36-em-alguns-setores\/#primaryimage"},"image":{"@id":"https:\/\/folhadems.com.br\/site\/2026\/03\/25\/em-reestruturacao-correios-anunciam-escala-12x36-em-alguns-setores\/#primaryimage"},"thumbnailUrl":"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2026\/03\/correios.jpg","datePublished":"2026-03-25T14:54:26+00:00","dateModified":"2026-03-25T15:10:30+00:00","breadcrumb":{"@id":"https:\/\/folhadems.com.br\/site\/2026\/03\/25\/em-reestruturacao-correios-anunciam-escala-12x36-em-alguns-setores\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/folhadems.com.br\/site\/2026\/03\/25\/em-reestruturacao-correios-anunciam-escala-12x36-em-alguns-setores\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/folhadems.com.br\/site\/2026\/03\/25\/em-reestruturacao-correios-anunciam-escala-12x36-em-alguns-setores\/#primaryimage","url":"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2026\/03\/correios.jpg","contentUrl":"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2026\/03\/correios.jpg","width":800,"height":450},{"@type":"BreadcrumbList","@id":"https:\/\/folhadems.com.br\/site\/2026\/03\/25\/em-reestruturacao-correios-anunciam-escala-12x36-em-alguns-setores\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/folhadems.com.br\/site\/"},{"@type":"ListItem","position":2,"name":"Em reestrutura\u00e7\u00e3o, Correios anunciam escala 12&#215;36 em alguns setores"}]},{"@type":"WebSite","@id":"https:\/\/folhadems.com.br\/site\/#website","url":"https:\/\/folhadems.com.br\/site\/","name":"Folha de Mato Grosso do Sul","description":"Jornal Online","publisher":{"@id":"https:\/\/folhadems.com.br\/site\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/folhadems.com.br\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/folhadems.com.br\/site\/#organization","name":"Folha de Mato Grosso do Sul","url":"https:\/\/folhadems.com.br\/site\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/folhadems.com.br\/site\/#\/schema\/logo\/image\/","url":"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2023\/01\/logo-folha-de-ms-380x90-1.jpg","contentUrl":"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2023\/01\/logo-folha-de-ms-380x90-1.jpg","width":380,"height":90,"caption":"Folha de Mato Grosso do Sul"},"image":{"@id":"https:\/\/folhadems.com.br\/site\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/folhadems.com.br\/site\/#\/schema\/person\/e4a04038e5c2e7040e19ef252ae9d940","name":"Elite Midia","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/folhadems.com.br\/site\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/f76a80f01119f7fec6909ab9feea8819031f391155be021b685479d77496f055?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f76a80f01119f7fec6909ab9feea8819031f391155be021b685479d77496f055?s=96&d=mm&r=g","caption":"Elite Midia"},"sameAs":["https:\/\/folhadems.com.br\/site"],"url":"https:\/\/folhadems.com.br\/site\/author\/elite-midia\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-20 13:20:43","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/posts\/15214","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/comments?post=15214"}],"version-history":[{"count":1,"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/posts\/15214\/revisions"}],"predecessor-version":[{"id":15216,"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/posts\/15214\/revisions\/15216"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/media\/15215"}],"wp:attachment":[{"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/media?parent=15214"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/categories?post=15214"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/tags?post=15214"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}