{"id":15058,"date":"2026-03-19T08:43:00","date_gmt":"2026-03-19T12:43:00","guid":{"rendered":"https:\/\/folhadems.com.br\/site\/?p=15058"},"modified":"2026-03-19T03:55:36","modified_gmt":"2026-03-19T07:55:36","slug":"escritura-em-maos-familias-de-mato-grosso-do-sul-celebram-conquista-historica-apos-quatro-decadas","status":"publish","type":"post","link":"https:\/\/folhadems.com.br\/site\/2026\/03\/19\/escritura-em-maos-familias-de-mato-grosso-do-sul-celebram-conquista-historica-apos-quatro-decadas\/","title":{"rendered":"Escritura em m\u00e3os: fam\u00edlias de Mato Grosso do Sul celebram conquista hist\u00f3rica ap\u00f3s quatro d\u00e9cadas"},"content":{"rendered":"\n<p>Ap\u00f3s quatro d\u00e9cadas de espera, 104 fam\u00edlias do Conjunto Jardim Parati, em Campo Grande, receberam a escritura definitiva de seus im\u00f3veis por meio do Programa de Regulariza\u00e7\u00e3o Fundi\u00e1ria do Governo do Estado. A entrega representa mais do que um documento: simboliza seguran\u00e7a jur\u00eddica, dignidade e a realiza\u00e7\u00e3o de um sonho para moradores que constru\u00edram suas hist\u00f3rias no local.<\/p>\n\n\n\n<p>A a\u00e7\u00e3o integra uma pol\u00edtica p\u00fablica estruturada para garantir o direito \u00e0 propriedade e promover inclus\u00e3o social. Ao todo, 725 documentos ser\u00e3o regularizados na regi\u00e3o, ampliando o alcance do programa e consolidando o compromisso do Estado com a popula\u00e7\u00e3o.<\/p>\n\n\n\n<p>Representando o governador Eduardo Riedel, o secret\u00e1rio da Casa Civil, Walter Carneiro J\u00fanior, destacou que a regulariza\u00e7\u00e3o fundi\u00e1ria \u00e9 uma das prioridades da atual gest\u00e3o e um instrumento fundamental de transforma\u00e7\u00e3o social.<\/p>\n\n\n\n<p>\u201cO Governo do Estado vive um momento muito forte de entregas, mas, acima de tudo, de compromisso com as pessoas. A regulariza\u00e7\u00e3o fundi\u00e1ria \u00e9 uma das a\u00e7\u00f5es mais importantes que temos desenvolvido, porque ela toca diretamente na vida das fam\u00edlias. N\u00e3o \u00e9 apenas um papel, \u00e9 a garantia de um direito, \u00e9 cidadania na pr\u00e1tica\u201d, afirmou.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/agenciadenoticias.ms.gov.br\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-18-at-11.34.05-1-1024x682.jpeg\" alt=\"\" class=\"wp-image-536591\"\/><figcaption class=\"wp-element-caption\"><em>Secret\u00e1rio walter Carneiro J\u00fanior (casa Civil), destaca as entregas do Governo do Estado para a Capital e interior<\/em><\/figcaption><\/figure>\n\n\n\n<p>O secret\u00e1rio refor\u00e7ou que a atua\u00e7\u00e3o da Ag\u00eancia de Habita\u00e7\u00e3o Popular de Mato Grosso do Sul (Agehab) tem sido essencial para avan\u00e7ar com a pol\u00edtica em diversas regi\u00f5es. \u201cPor meio da Agehab, estamos resgatando uma d\u00edvida hist\u00f3rica com milhares de fam\u00edlias que aguardavam h\u00e1 d\u00e9cadas por essa regulariza\u00e7\u00e3o. S\u00e3o pessoas que constru\u00edram suas casas, criaram seus filhos e sempre viveram com a incerteza. Hoje, estamos mudando essa realidade\u201d, pontuou.<\/p>\n\n\n\n<p>Walter Carneiro J\u00fanior tamb\u00e9m ressaltou o impacto direto da escritura na vida dos beneficiados, destacando que o documento garante autonomia e abre novas possibilidades.<\/p>\n\n\n\n<p>\u201cQuando o cidad\u00e3o recebe a escritura, ele passa a ter seguran\u00e7a jur\u00eddica, pode investir no im\u00f3vel, acessar cr\u00e9dito, planejar o futuro. \u00c9 a tranquilidade de saber que aquilo que ele construiu ao longo da vida \u00e9, de fato, seu. Isso tem um valor imensur\u00e1vel\u201d, disse.<\/p>\n\n\n\n<p>Em sua fala, o secret\u00e1rio ainda enfatizou que a pol\u00edtica de regulariza\u00e7\u00e3o fundi\u00e1ria continuar\u00e1 avan\u00e7ando em todo o Estado. \u201cEsse trabalho n\u00e3o para aqui. Estamos levando a regulariza\u00e7\u00e3o para diversos bairros de Campo Grande e tamb\u00e9m para o interior. Nosso objetivo \u00e9 garantir que cada vez mais fam\u00edlias tenham acesso a esse direito. \u00c9 um compromisso do governador Eduardo Riedel e de toda a gest\u00e3o\u201d, completou.<\/p>\n\n\n\n<p>Somente em 2026, j\u00e1 foram entregues 1.268 t\u00edtulos de propriedade em Mato Grosso do Sul, totalizando 21.775 desde a cria\u00e7\u00e3o do programa \u2014 n\u00fameros que demonstram a dimens\u00e3o da pol\u00edtica p\u00fablica e seu impacto direto na vida da popula\u00e7\u00e3o.<\/p>\n\n\n\n<p>O diretor-executivo da Agehab, Ubiratan Rebou\u00e7as Chaves, ressaltou que a entrega das escrituras representa o reconhecimento de um direito hist\u00f3rico. \u201cEsse \u00e9 o tipo de pol\u00edtica p\u00fablica que sai do papel e transforma vidas. \u00c9 o Estado chegando onde realmente precisa chegar\u201d, afirmou.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/agenciadenoticias.ms.gov.br\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-18-at-11.11.58-768x1024.jpeg\" alt=\"\" class=\"wp-image-536587\"\/><figcaption class=\"wp-element-caption\"><em>Ademar Freite da Silva<\/em><\/figcaption><\/figure>\n\n\n\n<p>Entre os beneficiados, o aposentado Ademar Freire da Silva celebrou a conquista ap\u00f3s viver desde 1986 no local. \u201cHoje realizo esse sonho e posso dar mais seguran\u00e7a \u00e0 minha fam\u00edlia\u201d, disse. A moradora Odete Ferreira Dotes tamb\u00e9m destacou a emo\u00e7\u00e3o do momento. \u201cEsperei por 40 anos e hoje saio daqui muito feliz. \u00c9 uma alegria que n\u00e3o d\u00e1 para explicar\u201d, afirmou.<\/p>\n\n\n\n<p>J\u00e1 Ant\u00f4nio Pereira Centuri\u00e3o enfatizou o legado que a regulariza\u00e7\u00e3o proporciona. \u201cAgora tenho a certeza de que a casa \u00e9 minha e que vou deixar esse patrim\u00f4nio para meus filhos. \u00c9 uma seguran\u00e7a que a gente n\u00e3o tinha antes\u201d, declarou.<\/p>\n\n\n\n<p>A solenidade contou ainda com a presen\u00e7a de Irwing Ferreira, representando o secret\u00e1rio Markito Perez. A iniciativa refor\u00e7a o compromisso do Governo de Mato Grosso do Sul com a promo\u00e7\u00e3o da cidadania, a redu\u00e7\u00e3o das desigualdades e a implementa\u00e7\u00e3o de pol\u00edticas p\u00fablicas que impactam diretamente a qualidade de vida da popula\u00e7\u00e3o.<\/p>\n\n\n\n<p><strong><em>Beatricce Bruno, Comunica\u00e7\u00e3o Casa Civil<\/em><br><em>Fotos: Max Arantes e Afr\u00e2nio Pissini<\/em><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ap\u00f3s quatro d\u00e9cadas de espera, 104 fam\u00edlias do Conjunto Jardim Parati, em Campo Grande, receberam a escritura definitiva de seus<\/p>\n","protected":false},"author":1,"featured_media":15059,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[26],"tags":[],"class_list":["post-15058","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cotidiano"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.1.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Escritura em m\u00e3os: fam\u00edlias de Mato Grosso do Sul celebram conquista hist\u00f3rica ap\u00f3s quatro d\u00e9cadas - Folha de Mato Grosso do Sul<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/folhadems.com.br\/site\/2026\/03\/19\/escritura-em-maos-familias-de-mato-grosso-do-sul-celebram-conquista-historica-apos-quatro-decadas\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Escritura em m\u00e3os: fam\u00edlias de Mato Grosso do Sul celebram conquista hist\u00f3rica ap\u00f3s quatro d\u00e9cadas - Folha de Mato Grosso do Sul\" \/>\n<meta property=\"og:description\" content=\"Ap\u00f3s quatro d\u00e9cadas de espera, 104 fam\u00edlias do Conjunto Jardim Parati, em Campo Grande, receberam a escritura definitiva de seus\" \/>\n<meta property=\"og:url\" content=\"https:\/\/folhadems.com.br\/site\/2026\/03\/19\/escritura-em-maos-familias-de-mato-grosso-do-sul-celebram-conquista-historica-apos-quatro-decadas\/\" \/>\n<meta property=\"og:site_name\" content=\"Folha de Mato Grosso do Sul\" \/>\n<meta property=\"article:published_time\" content=\"2026-03-19T12:43:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2026\/03\/familias.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"450\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Elite Midia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Elite Midia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/folhadems.com.br\/site\/2026\/03\/19\/escritura-em-maos-familias-de-mato-grosso-do-sul-celebram-conquista-historica-apos-quatro-decadas\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/folhadems.com.br\/site\/2026\/03\/19\/escritura-em-maos-familias-de-mato-grosso-do-sul-celebram-conquista-historica-apos-quatro-decadas\/\"},\"author\":{\"name\":\"Elite Midia\",\"@id\":\"https:\/\/folhadems.com.br\/site\/#\/schema\/person\/e4a04038e5c2e7040e19ef252ae9d940\"},\"headline\":\"Escritura em m\u00e3os: fam\u00edlias de Mato Grosso do Sul celebram conquista hist\u00f3rica ap\u00f3s quatro d\u00e9cadas\",\"datePublished\":\"2026-03-19T12:43:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/folhadems.com.br\/site\/2026\/03\/19\/escritura-em-maos-familias-de-mato-grosso-do-sul-celebram-conquista-historica-apos-quatro-decadas\/\"},\"wordCount\":751,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/folhadems.com.br\/site\/#organization\"},\"image\":{\"@id\":\"https:\/\/folhadems.com.br\/site\/2026\/03\/19\/escritura-em-maos-familias-de-mato-grosso-do-sul-celebram-conquista-historica-apos-quatro-decadas\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2026\/03\/familias.jpg\",\"articleSection\":[\"Cotidiano\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/folhadems.com.br\/site\/2026\/03\/19\/escritura-em-maos-familias-de-mato-grosso-do-sul-celebram-conquista-historica-apos-quatro-decadas\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/folhadems.com.br\/site\/2026\/03\/19\/escritura-em-maos-familias-de-mato-grosso-do-sul-celebram-conquista-historica-apos-quatro-decadas\/\",\"url\":\"https:\/\/folhadems.com.br\/site\/2026\/03\/19\/escritura-em-maos-familias-de-mato-grosso-do-sul-celebram-conquista-historica-apos-quatro-decadas\/\",\"name\":\"Escritura em m\u00e3os: fam\u00edlias de Mato Grosso do Sul celebram conquista hist\u00f3rica ap\u00f3s quatro d\u00e9cadas - Folha de Mato Grosso do Sul\",\"isPartOf\":{\"@id\":\"https:\/\/folhadems.com.br\/site\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/folhadems.com.br\/site\/2026\/03\/19\/escritura-em-maos-familias-de-mato-grosso-do-sul-celebram-conquista-historica-apos-quatro-decadas\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/folhadems.com.br\/site\/2026\/03\/19\/escritura-em-maos-familias-de-mato-grosso-do-sul-celebram-conquista-historica-apos-quatro-decadas\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2026\/03\/familias.jpg\",\"datePublished\":\"2026-03-19T12:43:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/folhadems.com.br\/site\/2026\/03\/19\/escritura-em-maos-familias-de-mato-grosso-do-sul-celebram-conquista-historica-apos-quatro-decadas\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/folhadems.com.br\/site\/2026\/03\/19\/escritura-em-maos-familias-de-mato-grosso-do-sul-celebram-conquista-historica-apos-quatro-decadas\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/folhadems.com.br\/site\/2026\/03\/19\/escritura-em-maos-familias-de-mato-grosso-do-sul-celebram-conquista-historica-apos-quatro-decadas\/#primaryimage\",\"url\":\"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2026\/03\/familias.jpg\",\"contentUrl\":\"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2026\/03\/familias.jpg\",\"width\":800,\"height\":450},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/folhadems.com.br\/site\/2026\/03\/19\/escritura-em-maos-familias-de-mato-grosso-do-sul-celebram-conquista-historica-apos-quatro-decadas\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/folhadems.com.br\/site\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Escritura em m\u00e3os: fam\u00edlias de Mato Grosso do Sul celebram conquista hist\u00f3rica ap\u00f3s quatro d\u00e9cadas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/folhadems.com.br\/site\/#website\",\"url\":\"https:\/\/folhadems.com.br\/site\/\",\"name\":\"Folha de Mato Grosso do Sul\",\"description\":\"Jornal Online\",\"publisher\":{\"@id\":\"https:\/\/folhadems.com.br\/site\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/folhadems.com.br\/site\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/folhadems.com.br\/site\/#organization\",\"name\":\"Folha de Mato Grosso do Sul\",\"url\":\"https:\/\/folhadems.com.br\/site\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/folhadems.com.br\/site\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2023\/01\/logo-folha-de-ms-380x90-1.jpg\",\"contentUrl\":\"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2023\/01\/logo-folha-de-ms-380x90-1.jpg\",\"width\":380,\"height\":90,\"caption\":\"Folha de Mato Grosso do Sul\"},\"image\":{\"@id\":\"https:\/\/folhadems.com.br\/site\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/folhadems.com.br\/site\/#\/schema\/person\/e4a04038e5c2e7040e19ef252ae9d940\",\"name\":\"Elite Midia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/folhadems.com.br\/site\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/f76a80f01119f7fec6909ab9feea8819031f391155be021b685479d77496f055?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/f76a80f01119f7fec6909ab9feea8819031f391155be021b685479d77496f055?s=96&d=mm&r=g\",\"caption\":\"Elite Midia\"},\"sameAs\":[\"https:\/\/folhadems.com.br\/site\"],\"url\":\"https:\/\/folhadems.com.br\/site\/author\/elite-midia\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Escritura em m\u00e3os: fam\u00edlias de Mato Grosso do Sul celebram conquista hist\u00f3rica ap\u00f3s quatro d\u00e9cadas - Folha de Mato Grosso do Sul","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/folhadems.com.br\/site\/2026\/03\/19\/escritura-em-maos-familias-de-mato-grosso-do-sul-celebram-conquista-historica-apos-quatro-decadas\/","og_locale":"pt_BR","og_type":"article","og_title":"Escritura em m\u00e3os: fam\u00edlias de Mato Grosso do Sul celebram conquista hist\u00f3rica ap\u00f3s quatro d\u00e9cadas - Folha de Mato Grosso do Sul","og_description":"Ap\u00f3s quatro d\u00e9cadas de espera, 104 fam\u00edlias do Conjunto Jardim Parati, em Campo Grande, receberam a escritura definitiva de seus","og_url":"https:\/\/folhadems.com.br\/site\/2026\/03\/19\/escritura-em-maos-familias-de-mato-grosso-do-sul-celebram-conquista-historica-apos-quatro-decadas\/","og_site_name":"Folha de Mato Grosso do Sul","article_published_time":"2026-03-19T12:43:00+00:00","og_image":[{"width":800,"height":450,"url":"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2026\/03\/familias.jpg","type":"image\/jpeg"}],"author":"Elite Midia","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Elite Midia","Est. tempo de leitura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/folhadems.com.br\/site\/2026\/03\/19\/escritura-em-maos-familias-de-mato-grosso-do-sul-celebram-conquista-historica-apos-quatro-decadas\/#article","isPartOf":{"@id":"https:\/\/folhadems.com.br\/site\/2026\/03\/19\/escritura-em-maos-familias-de-mato-grosso-do-sul-celebram-conquista-historica-apos-quatro-decadas\/"},"author":{"name":"Elite Midia","@id":"https:\/\/folhadems.com.br\/site\/#\/schema\/person\/e4a04038e5c2e7040e19ef252ae9d940"},"headline":"Escritura em m\u00e3os: fam\u00edlias de Mato Grosso do Sul celebram conquista hist\u00f3rica ap\u00f3s quatro d\u00e9cadas","datePublished":"2026-03-19T12:43:00+00:00","mainEntityOfPage":{"@id":"https:\/\/folhadems.com.br\/site\/2026\/03\/19\/escritura-em-maos-familias-de-mato-grosso-do-sul-celebram-conquista-historica-apos-quatro-decadas\/"},"wordCount":751,"commentCount":0,"publisher":{"@id":"https:\/\/folhadems.com.br\/site\/#organization"},"image":{"@id":"https:\/\/folhadems.com.br\/site\/2026\/03\/19\/escritura-em-maos-familias-de-mato-grosso-do-sul-celebram-conquista-historica-apos-quatro-decadas\/#primaryimage"},"thumbnailUrl":"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2026\/03\/familias.jpg","articleSection":["Cotidiano"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/folhadems.com.br\/site\/2026\/03\/19\/escritura-em-maos-familias-de-mato-grosso-do-sul-celebram-conquista-historica-apos-quatro-decadas\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/folhadems.com.br\/site\/2026\/03\/19\/escritura-em-maos-familias-de-mato-grosso-do-sul-celebram-conquista-historica-apos-quatro-decadas\/","url":"https:\/\/folhadems.com.br\/site\/2026\/03\/19\/escritura-em-maos-familias-de-mato-grosso-do-sul-celebram-conquista-historica-apos-quatro-decadas\/","name":"Escritura em m\u00e3os: fam\u00edlias de Mato Grosso do Sul celebram conquista hist\u00f3rica ap\u00f3s quatro d\u00e9cadas - Folha de Mato Grosso do Sul","isPartOf":{"@id":"https:\/\/folhadems.com.br\/site\/#website"},"primaryImageOfPage":{"@id":"https:\/\/folhadems.com.br\/site\/2026\/03\/19\/escritura-em-maos-familias-de-mato-grosso-do-sul-celebram-conquista-historica-apos-quatro-decadas\/#primaryimage"},"image":{"@id":"https:\/\/folhadems.com.br\/site\/2026\/03\/19\/escritura-em-maos-familias-de-mato-grosso-do-sul-celebram-conquista-historica-apos-quatro-decadas\/#primaryimage"},"thumbnailUrl":"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2026\/03\/familias.jpg","datePublished":"2026-03-19T12:43:00+00:00","breadcrumb":{"@id":"https:\/\/folhadems.com.br\/site\/2026\/03\/19\/escritura-em-maos-familias-de-mato-grosso-do-sul-celebram-conquista-historica-apos-quatro-decadas\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/folhadems.com.br\/site\/2026\/03\/19\/escritura-em-maos-familias-de-mato-grosso-do-sul-celebram-conquista-historica-apos-quatro-decadas\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/folhadems.com.br\/site\/2026\/03\/19\/escritura-em-maos-familias-de-mato-grosso-do-sul-celebram-conquista-historica-apos-quatro-decadas\/#primaryimage","url":"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2026\/03\/familias.jpg","contentUrl":"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2026\/03\/familias.jpg","width":800,"height":450},{"@type":"BreadcrumbList","@id":"https:\/\/folhadems.com.br\/site\/2026\/03\/19\/escritura-em-maos-familias-de-mato-grosso-do-sul-celebram-conquista-historica-apos-quatro-decadas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/folhadems.com.br\/site\/"},{"@type":"ListItem","position":2,"name":"Escritura em m\u00e3os: fam\u00edlias de Mato Grosso do Sul celebram conquista hist\u00f3rica ap\u00f3s quatro d\u00e9cadas"}]},{"@type":"WebSite","@id":"https:\/\/folhadems.com.br\/site\/#website","url":"https:\/\/folhadems.com.br\/site\/","name":"Folha de Mato Grosso do Sul","description":"Jornal Online","publisher":{"@id":"https:\/\/folhadems.com.br\/site\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/folhadems.com.br\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/folhadems.com.br\/site\/#organization","name":"Folha de Mato Grosso do Sul","url":"https:\/\/folhadems.com.br\/site\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/folhadems.com.br\/site\/#\/schema\/logo\/image\/","url":"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2023\/01\/logo-folha-de-ms-380x90-1.jpg","contentUrl":"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2023\/01\/logo-folha-de-ms-380x90-1.jpg","width":380,"height":90,"caption":"Folha de Mato Grosso do Sul"},"image":{"@id":"https:\/\/folhadems.com.br\/site\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/folhadems.com.br\/site\/#\/schema\/person\/e4a04038e5c2e7040e19ef252ae9d940","name":"Elite Midia","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/folhadems.com.br\/site\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/f76a80f01119f7fec6909ab9feea8819031f391155be021b685479d77496f055?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f76a80f01119f7fec6909ab9feea8819031f391155be021b685479d77496f055?s=96&d=mm&r=g","caption":"Elite Midia"},"sameAs":["https:\/\/folhadems.com.br\/site"],"url":"https:\/\/folhadems.com.br\/site\/author\/elite-midia\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-20 14:29:31","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/posts\/15058","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/comments?post=15058"}],"version-history":[{"count":1,"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/posts\/15058\/revisions"}],"predecessor-version":[{"id":15060,"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/posts\/15058\/revisions\/15060"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/media\/15059"}],"wp:attachment":[{"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/media?parent=15058"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/categories?post=15058"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/tags?post=15058"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}