{"id":14632,"date":"2026-03-03T16:35:00","date_gmt":"2026-03-03T20:35:00","guid":{"rendered":"https:\/\/folhadems.com.br\/site\/?p=14632"},"modified":"2026-03-03T17:43:49","modified_gmt":"2026-03-03T21:43:49","slug":"fiscalizacao-contra-descarte-irregular-de-lixo-ganha-reforco","status":"publish","type":"post","link":"https:\/\/folhadems.com.br\/site\/2026\/03\/03\/fiscalizacao-contra-descarte-irregular-de-lixo-ganha-reforco\/","title":{"rendered":"Fiscaliza\u00e7\u00e3o contra descarte irregular de lixo ganha refor\u00e7o"},"content":{"rendered":"\n<p>A Prefeitura anunciou novas medidas para combater o descarte irregular de res\u00edduos e a regi\u00e3o do bairro Jardim das Hort\u00eancias, na \u00e1rea entre as ruas Gerbera, Pr\u00edmula e\u00a0Tumbergia,\u00a0ser\u00e1 o primeiro ponto onde as novas medidas entrar\u00e3o em vigor.\u00a0O local ter\u00e1 monitoramento 24 horas e ser\u00e1 transformado em espa\u00e7o de uso comunit\u00e1rio.\u00a0<\/p>\n\n\n\n<p>Considerado ponto cr\u00edtico, o espa\u00e7o recebe em m\u00e9dia cinco limpezas por ano. A cada a\u00e7\u00e3o, a&nbsp;Secretaria Municipal de Infraestrutura e Servi\u00e7os P\u00fablicos (Sisep)&nbsp;retira de 50 a 60 caminh\u00f5es de res\u00edduos, inclusive lixo dom\u00e9stico, mesmo com o bairro sendo atendido regularmente pela coleta.&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/cdn.campogrande.ms.gov.br\/portal\/prod\/uploads\/sites\/3\/2026\/03\/WhatsApp-Image-2026-03-03-at-14.03.49-1024x682.jpeg\" alt=\"\" class=\"wp-image-157523\"\/><\/figure>\n\n\n\n<p>\u201cA gente pede a conscientiza\u00e7\u00e3o dos moradores, a Prefeitura faz a sua parte, mas os moradores tamb\u00e9m precisam fazer. Aqui&nbsp;ser\u00e3o&nbsp;constru\u00eddos&nbsp;uma horta comunit\u00e1ria,&nbsp;e os secret\u00e1rios se reuniram tamb\u00e9m para que esse espa\u00e7o seja para a conviv\u00eancia dos moradores\u201d, afirmou a prefeita Adriane Lopes.&nbsp;<\/p>\n\n\n\n<p>Ela informou que ser\u00e1 feito estudo sobre a legalidade da cess\u00e3o da \u00e1rea \u00e0 Associa\u00e7\u00e3o de Moradores para poss\u00edvel constru\u00e7\u00e3o de um Centro Comunit\u00e1rio. \u201cPrecisamos fazer um estudo sobre a legalidade da ced\u00eancia dessa \u00e1rea para a Associa\u00e7\u00e3o\u201d.&nbsp;<\/p>\n\n\n\n<p>Tr\u00eas c\u00e2meras j\u00e1 foram instaladas no entorno. Segundo o secret\u00e1rio Especial de Seguran\u00e7a e Defesa Social, Anderson Gonzaga, a Guarda Civil Metropolitana atuar\u00e1 com plant\u00f5es e apoio da Patrulha Ambiental.&nbsp;&nbsp;<\/p>\n\n\n\n<p>\u201cA Guarda Civil Metropolitana estar\u00e1 presente aqui, juntamente com a Patrulha Ambiental. Vamos fazer v\u00e1rios plant\u00f5es em regime de escala para permanecer aqui. O servi\u00e7o de intelig\u00eancia tamb\u00e9m&nbsp;estar\u00e1 monitorando&nbsp;essa \u00e1rea, colocamos tr\u00eas c\u00e2meras para o monitoramento e para que a gente possa fazer essas pris\u00f5es em flagrante\u201d, explica.&nbsp;<\/p>\n\n\n\n<p>Mesmo ap\u00f3s interven\u00e7\u00f5es anteriores, o descarte continuou. \u201cIsso traz duas situa\u00e7\u00f5es muito ruins para a nossa cidade: a primeira \u00e9 a qualidade de vida que vai l\u00e1 para baixo, isso aqui \u00e9 um risco para a popula\u00e7\u00e3o. Segundo, \u00e9 um custo absurdo de manuten\u00e7\u00e3o para a Prefeitura de Campo Grande, um recurso que poderia estar gastando em outros investimentos\u201d, afirmou o secret\u00e1rio Marcelo Miglioli.&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/cdn.campogrande.ms.gov.br\/portal\/prod\/uploads\/sites\/3\/2026\/03\/WhatsApp-Image-2026-03-03-at-14.03.22-1024x682.jpeg\" alt=\"\" class=\"wp-image-157525\"\/><\/figure>\n\n\n\n<p>A \u00e1rea tamb\u00e9m receber\u00e1 uma horta comunit\u00e1ria. \u201cEstamos come\u00e7ando por aqui hoje, vamos fazer essa limpeza, vamos transformar esse local em um local habit\u00e1vel para a sociedade, para a comunidade local, e principalmente tentar sensibilizar a comunidade a n\u00e3o aceitar esse tipo de descarte e fazer a den\u00fancia\u201d, disse o secret\u00e1rio&nbsp;Municipal de Inova\u00e7\u00e3o, Desenvolvimento Econ\u00f4mico e Agroneg\u00f3cio,&nbsp;Ademar Silva J\u00fanior.&nbsp;<\/p>\n\n\n\n<p>Den\u00fancias&nbsp;de descarte irregular de material inserv\u00edvel&nbsp;podem ser feitas pelo telefone 153. A a\u00e7\u00e3o no bairro marca o in\u00edcio da intensifica\u00e7\u00e3o da fiscaliza\u00e7\u00e3o em cerca de 400 pontos identificados na cidade, dos quais at\u00e9 60 s\u00e3o considerados cr\u00edticos.&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/cdn.campogrande.ms.gov.br\/portal\/prod\/uploads\/sites\/3\/2026\/03\/WhatsApp-Image-2026-03-03-at-14.03.33-1024x682.jpeg\" alt=\"\" class=\"wp-image-157524\"\/><\/figure>\n\n\n\n<p><em><strong>Fonte: PrefCG<\/strong><\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Prefeitura anunciou novas medidas para combater o descarte irregular de res\u00edduos e a regi\u00e3o do bairro Jardim das Hort\u00eancias,<\/p>\n","protected":false},"author":1,"featured_media":14633,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[26],"tags":[],"class_list":["post-14632","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cotidiano"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.1.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Fiscaliza\u00e7\u00e3o contra descarte irregular de lixo ganha refor\u00e7o - Folha de Mato Grosso do Sul<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/folhadems.com.br\/site\/2026\/03\/03\/fiscalizacao-contra-descarte-irregular-de-lixo-ganha-reforco\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fiscaliza\u00e7\u00e3o contra descarte irregular de lixo ganha refor\u00e7o - Folha de Mato Grosso do Sul\" \/>\n<meta property=\"og:description\" content=\"A Prefeitura anunciou novas medidas para combater o descarte irregular de res\u00edduos e a regi\u00e3o do bairro Jardim das Hort\u00eancias,\" \/>\n<meta property=\"og:url\" content=\"https:\/\/folhadems.com.br\/site\/2026\/03\/03\/fiscalizacao-contra-descarte-irregular-de-lixo-ganha-reforco\/\" \/>\n<meta property=\"og:site_name\" content=\"Folha de Mato Grosso do Sul\" \/>\n<meta property=\"article:published_time\" content=\"2026-03-03T20:35:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-03T21:43:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2026\/03\/descarte-llixo.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"450\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Elite Midia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Elite Midia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/folhadems.com.br\/site\/2026\/03\/03\/fiscalizacao-contra-descarte-irregular-de-lixo-ganha-reforco\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/folhadems.com.br\/site\/2026\/03\/03\/fiscalizacao-contra-descarte-irregular-de-lixo-ganha-reforco\/\"},\"author\":{\"name\":\"Elite Midia\",\"@id\":\"https:\/\/folhadems.com.br\/site\/#\/schema\/person\/e4a04038e5c2e7040e19ef252ae9d940\"},\"headline\":\"Fiscaliza\u00e7\u00e3o contra descarte irregular de lixo ganha refor\u00e7o\",\"datePublished\":\"2026-03-03T20:35:00+00:00\",\"dateModified\":\"2026-03-03T21:43:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/folhadems.com.br\/site\/2026\/03\/03\/fiscalizacao-contra-descarte-irregular-de-lixo-ganha-reforco\/\"},\"wordCount\":519,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/folhadems.com.br\/site\/#organization\"},\"image\":{\"@id\":\"https:\/\/folhadems.com.br\/site\/2026\/03\/03\/fiscalizacao-contra-descarte-irregular-de-lixo-ganha-reforco\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2026\/03\/descarte-llixo.jpg\",\"articleSection\":[\"Cotidiano\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/folhadems.com.br\/site\/2026\/03\/03\/fiscalizacao-contra-descarte-irregular-de-lixo-ganha-reforco\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/folhadems.com.br\/site\/2026\/03\/03\/fiscalizacao-contra-descarte-irregular-de-lixo-ganha-reforco\/\",\"url\":\"https:\/\/folhadems.com.br\/site\/2026\/03\/03\/fiscalizacao-contra-descarte-irregular-de-lixo-ganha-reforco\/\",\"name\":\"Fiscaliza\u00e7\u00e3o contra descarte irregular de lixo ganha refor\u00e7o - Folha de Mato Grosso do Sul\",\"isPartOf\":{\"@id\":\"https:\/\/folhadems.com.br\/site\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/folhadems.com.br\/site\/2026\/03\/03\/fiscalizacao-contra-descarte-irregular-de-lixo-ganha-reforco\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/folhadems.com.br\/site\/2026\/03\/03\/fiscalizacao-contra-descarte-irregular-de-lixo-ganha-reforco\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2026\/03\/descarte-llixo.jpg\",\"datePublished\":\"2026-03-03T20:35:00+00:00\",\"dateModified\":\"2026-03-03T21:43:49+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/folhadems.com.br\/site\/2026\/03\/03\/fiscalizacao-contra-descarte-irregular-de-lixo-ganha-reforco\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/folhadems.com.br\/site\/2026\/03\/03\/fiscalizacao-contra-descarte-irregular-de-lixo-ganha-reforco\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/folhadems.com.br\/site\/2026\/03\/03\/fiscalizacao-contra-descarte-irregular-de-lixo-ganha-reforco\/#primaryimage\",\"url\":\"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2026\/03\/descarte-llixo.jpg\",\"contentUrl\":\"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2026\/03\/descarte-llixo.jpg\",\"width\":800,\"height\":450},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/folhadems.com.br\/site\/2026\/03\/03\/fiscalizacao-contra-descarte-irregular-de-lixo-ganha-reforco\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/folhadems.com.br\/site\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Fiscaliza\u00e7\u00e3o contra descarte irregular de lixo ganha refor\u00e7o\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/folhadems.com.br\/site\/#website\",\"url\":\"https:\/\/folhadems.com.br\/site\/\",\"name\":\"Folha de Mato Grosso do Sul\",\"description\":\"Jornal Online\",\"publisher\":{\"@id\":\"https:\/\/folhadems.com.br\/site\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/folhadems.com.br\/site\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/folhadems.com.br\/site\/#organization\",\"name\":\"Folha de Mato Grosso do Sul\",\"url\":\"https:\/\/folhadems.com.br\/site\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/folhadems.com.br\/site\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2023\/01\/logo-folha-de-ms-380x90-1.jpg\",\"contentUrl\":\"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2023\/01\/logo-folha-de-ms-380x90-1.jpg\",\"width\":380,\"height\":90,\"caption\":\"Folha de Mato Grosso do Sul\"},\"image\":{\"@id\":\"https:\/\/folhadems.com.br\/site\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/folhadems.com.br\/site\/#\/schema\/person\/e4a04038e5c2e7040e19ef252ae9d940\",\"name\":\"Elite Midia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/folhadems.com.br\/site\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/f76a80f01119f7fec6909ab9feea8819031f391155be021b685479d77496f055?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/f76a80f01119f7fec6909ab9feea8819031f391155be021b685479d77496f055?s=96&d=mm&r=g\",\"caption\":\"Elite Midia\"},\"sameAs\":[\"https:\/\/folhadems.com.br\/site\"],\"url\":\"https:\/\/folhadems.com.br\/site\/author\/elite-midia\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Fiscaliza\u00e7\u00e3o contra descarte irregular de lixo ganha refor\u00e7o - Folha de Mato Grosso do Sul","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/folhadems.com.br\/site\/2026\/03\/03\/fiscalizacao-contra-descarte-irregular-de-lixo-ganha-reforco\/","og_locale":"pt_BR","og_type":"article","og_title":"Fiscaliza\u00e7\u00e3o contra descarte irregular de lixo ganha refor\u00e7o - Folha de Mato Grosso do Sul","og_description":"A Prefeitura anunciou novas medidas para combater o descarte irregular de res\u00edduos e a regi\u00e3o do bairro Jardim das Hort\u00eancias,","og_url":"https:\/\/folhadems.com.br\/site\/2026\/03\/03\/fiscalizacao-contra-descarte-irregular-de-lixo-ganha-reforco\/","og_site_name":"Folha de Mato Grosso do Sul","article_published_time":"2026-03-03T20:35:00+00:00","article_modified_time":"2026-03-03T21:43:49+00:00","og_image":[{"width":800,"height":450,"url":"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2026\/03\/descarte-llixo.jpg","type":"image\/jpeg"}],"author":"Elite Midia","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Elite Midia","Est. tempo de leitura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/folhadems.com.br\/site\/2026\/03\/03\/fiscalizacao-contra-descarte-irregular-de-lixo-ganha-reforco\/#article","isPartOf":{"@id":"https:\/\/folhadems.com.br\/site\/2026\/03\/03\/fiscalizacao-contra-descarte-irregular-de-lixo-ganha-reforco\/"},"author":{"name":"Elite Midia","@id":"https:\/\/folhadems.com.br\/site\/#\/schema\/person\/e4a04038e5c2e7040e19ef252ae9d940"},"headline":"Fiscaliza\u00e7\u00e3o contra descarte irregular de lixo ganha refor\u00e7o","datePublished":"2026-03-03T20:35:00+00:00","dateModified":"2026-03-03T21:43:49+00:00","mainEntityOfPage":{"@id":"https:\/\/folhadems.com.br\/site\/2026\/03\/03\/fiscalizacao-contra-descarte-irregular-de-lixo-ganha-reforco\/"},"wordCount":519,"commentCount":0,"publisher":{"@id":"https:\/\/folhadems.com.br\/site\/#organization"},"image":{"@id":"https:\/\/folhadems.com.br\/site\/2026\/03\/03\/fiscalizacao-contra-descarte-irregular-de-lixo-ganha-reforco\/#primaryimage"},"thumbnailUrl":"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2026\/03\/descarte-llixo.jpg","articleSection":["Cotidiano"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/folhadems.com.br\/site\/2026\/03\/03\/fiscalizacao-contra-descarte-irregular-de-lixo-ganha-reforco\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/folhadems.com.br\/site\/2026\/03\/03\/fiscalizacao-contra-descarte-irregular-de-lixo-ganha-reforco\/","url":"https:\/\/folhadems.com.br\/site\/2026\/03\/03\/fiscalizacao-contra-descarte-irregular-de-lixo-ganha-reforco\/","name":"Fiscaliza\u00e7\u00e3o contra descarte irregular de lixo ganha refor\u00e7o - Folha de Mato Grosso do Sul","isPartOf":{"@id":"https:\/\/folhadems.com.br\/site\/#website"},"primaryImageOfPage":{"@id":"https:\/\/folhadems.com.br\/site\/2026\/03\/03\/fiscalizacao-contra-descarte-irregular-de-lixo-ganha-reforco\/#primaryimage"},"image":{"@id":"https:\/\/folhadems.com.br\/site\/2026\/03\/03\/fiscalizacao-contra-descarte-irregular-de-lixo-ganha-reforco\/#primaryimage"},"thumbnailUrl":"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2026\/03\/descarte-llixo.jpg","datePublished":"2026-03-03T20:35:00+00:00","dateModified":"2026-03-03T21:43:49+00:00","breadcrumb":{"@id":"https:\/\/folhadems.com.br\/site\/2026\/03\/03\/fiscalizacao-contra-descarte-irregular-de-lixo-ganha-reforco\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/folhadems.com.br\/site\/2026\/03\/03\/fiscalizacao-contra-descarte-irregular-de-lixo-ganha-reforco\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/folhadems.com.br\/site\/2026\/03\/03\/fiscalizacao-contra-descarte-irregular-de-lixo-ganha-reforco\/#primaryimage","url":"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2026\/03\/descarte-llixo.jpg","contentUrl":"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2026\/03\/descarte-llixo.jpg","width":800,"height":450},{"@type":"BreadcrumbList","@id":"https:\/\/folhadems.com.br\/site\/2026\/03\/03\/fiscalizacao-contra-descarte-irregular-de-lixo-ganha-reforco\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/folhadems.com.br\/site\/"},{"@type":"ListItem","position":2,"name":"Fiscaliza\u00e7\u00e3o contra descarte irregular de lixo ganha refor\u00e7o"}]},{"@type":"WebSite","@id":"https:\/\/folhadems.com.br\/site\/#website","url":"https:\/\/folhadems.com.br\/site\/","name":"Folha de Mato Grosso do Sul","description":"Jornal Online","publisher":{"@id":"https:\/\/folhadems.com.br\/site\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/folhadems.com.br\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/folhadems.com.br\/site\/#organization","name":"Folha de Mato Grosso do Sul","url":"https:\/\/folhadems.com.br\/site\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/folhadems.com.br\/site\/#\/schema\/logo\/image\/","url":"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2023\/01\/logo-folha-de-ms-380x90-1.jpg","contentUrl":"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2023\/01\/logo-folha-de-ms-380x90-1.jpg","width":380,"height":90,"caption":"Folha de Mato Grosso do Sul"},"image":{"@id":"https:\/\/folhadems.com.br\/site\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/folhadems.com.br\/site\/#\/schema\/person\/e4a04038e5c2e7040e19ef252ae9d940","name":"Elite Midia","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/folhadems.com.br\/site\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/f76a80f01119f7fec6909ab9feea8819031f391155be021b685479d77496f055?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f76a80f01119f7fec6909ab9feea8819031f391155be021b685479d77496f055?s=96&d=mm&r=g","caption":"Elite Midia"},"sameAs":["https:\/\/folhadems.com.br\/site"],"url":"https:\/\/folhadems.com.br\/site\/author\/elite-midia\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-20 14:26:06","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/posts\/14632","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/comments?post=14632"}],"version-history":[{"count":2,"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/posts\/14632\/revisions"}],"predecessor-version":[{"id":14635,"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/posts\/14632\/revisions\/14635"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/media\/14633"}],"wp:attachment":[{"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/media?parent=14632"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/categories?post=14632"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/tags?post=14632"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}