{"id":14112,"date":"2026-02-05T12:10:56","date_gmt":"2026-02-05T16:10:56","guid":{"rendered":"https:\/\/folhadems.com.br\/site\/?p=14112"},"modified":"2026-02-05T12:10:59","modified_gmt":"2026-02-05T16:10:59","slug":"alerta-de-emergencia-e-emitido-para-o-distrito-de-palmeiras-apos-elevacao-do-nivel-do-rio-aquidauana","status":"publish","type":"post","link":"https:\/\/folhadems.com.br\/site\/2026\/02\/05\/alerta-de-emergencia-e-emitido-para-o-distrito-de-palmeiras-apos-elevacao-do-nivel-do-rio-aquidauana\/","title":{"rendered":"Alerta de emerg\u00eancia \u00e9 emitido para o distrito de Palmeiras ap\u00f3s eleva\u00e7\u00e3o do n\u00edvel do rio Aquidauana"},"content":{"rendered":"\n<p>Ap\u00f3s <a href=\"https:\/\/agenciadenoticias.ms.gov.br\/aviso-de-emergencia-e-emitido-devido-a-elevacao-dos-niveis-dos-rios-taquari-e-aquidauana\/\" target=\"_blank\" rel=\"noopener\">dois alertas serem emitidos para Aquidauana e Coxim devido a eleva\u00e7\u00e3o dos rios Aquidauana e Taquari<\/a>, respectivamente, o Imasul (Instituto de Meio Ambiente de Mato Grosso do Sul), por meio da Sala de Situa\u00e7\u00e3o do GRH (Gerenciamento de Recursos H\u00eddricos), emitiu novo o Aviso de Evento Cr\u00edtico.<\/p>\n\n\n\n<p>Dessa vez o risco foi detectado no distrito de Palmeiras, no territ\u00f3rio municipal de Dois Irm\u00e3os do Buriti. Ali, passa o rio Aquidauana, onde foi verificada eleva\u00e7\u00e3o consider\u00e1vel do n\u00edvel tamb\u00e9m naquele trecho. O comunicado foi registrado \u00e0s 22h40 desta ter\u00e7a-feira (4).<\/p>\n\n\n\n<p>De acordo com as medi\u00e7\u00f5es realizadas pela Plataforma de Coleta de Dados (PCD), o rio atingiu a cota de 661 cent\u00edmetros \u00e0s 22h30, superando o n\u00edvel de emerg\u00eancia estabelecido em 650 cent\u00edmetros, considerado patamar de inunda\u00e7\u00e3o. A situa\u00e7\u00e3o representa potencial para danos materiais significativos e riscos \u00e0 integridade da popula\u00e7\u00e3o ribeirinha.<\/p>\n\n\n\n<p>O Imasul aponta que o aumento do volume do Rio Aquidauana est\u00e1 diretamente relacionado \u00e0s chuvas registradas desde o \u00faltimo fim de semana na regi\u00e3o. Mesmo com a previs\u00e3o de redu\u00e7\u00e3o do acumulado nos pr\u00f3ximos dias, ainda s\u00e3o esperadas pancadas de chuva na bacia hidrogr\u00e1fica.<\/p>\n\n\n\n<p>Segundo o Cemtec (Centro de Monitoramento do Tempo e do Clima) de Mato Grosso do Sul, h\u00e1 previs\u00e3o de continuidade das precipita\u00e7\u00f5es entre os dias 4 e 5 de fevereiro de 2026.<\/p>\n\n\n\n<p>O cen\u00e1rio \u00e9 refor\u00e7ado por avisos meteorol\u00f3gicos nacionais: o Inmet (Instituto Nacional de Meteorologia) emitiu alerta com grau de severidade &#8216;perigo&#8217; para o per\u00edodo. O CPTEC (Centro de Previs\u00e3o de Tempo e Estudos Clim\u00e1ticos) classificou a previs\u00e3o de chuvas intensas como n\u00edvel 2 para a mesma janela de tempo.<\/p>\n\n\n\n<p><strong>Invas\u00e3o de \u00e1reas pr\u00f3ximas ao rio<\/strong><\/p>\n\n\n\n<p>Com a eleva\u00e7\u00e3o do n\u00edvel, j\u00e1 foi observado o in\u00edcio do processo de invas\u00e3o das \u00e1guas em \u00e1reas lindeiras ao curso do rio, o que pode agravar o cen\u00e1rio caso as chuvas persistam e a vaz\u00e3o continue aumentando. O gerente de Recursos H\u00eddricos do Imasul, Leonardo Sampaio, destacou que a situa\u00e7\u00e3o exige aten\u00e7\u00e3o cont\u00ednua das autoridades e da popula\u00e7\u00e3o local.<\/p>\n\n\n\n<p>&#8220;Estamos acompanhando o comportamento do rio em tempo real por meio das plataformas de monitoramento. O n\u00edvel j\u00e1 ultrapassou a cota de emerg\u00eancia e pode provocar alagamentos em \u00e1reas ribeirinhas. A orienta\u00e7\u00e3o \u00e9 para que a popula\u00e7\u00e3o fique atenta aos comunicados oficiais e siga as recomenda\u00e7\u00f5es da Defesa Civil&#8221;, afirmou.<\/p>\n\n\n\n<p>O diretor-presidente do Imasul, Andr\u00e9 Borges, ressaltou que o trabalho integrado entre os \u00f3rg\u00e3os p\u00fablicos \u00e9 fundamental para reduzir riscos e proteger vidas. &#8220;Esse tipo de evento exige resposta r\u00e1pida e articulada. O Imasul mant\u00e9m o monitoramento permanente das bacias hidrogr\u00e1ficas e j\u00e1 atua em conjunto com a Defesa Civil e demais institui\u00e7\u00f5es para antecipar medidas preventivas, minimizar impactos e garantir a seguran\u00e7a da popula\u00e7\u00e3o&#8221;, declarou.<\/p>\n\n\n\n<p><em>Comunica\u00e7\u00e3o Imasul<br>Foto: \u00c1lvaro Rezende\/Secom\/Arquivo<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ap\u00f3s dois alertas serem emitidos para Aquidauana e Coxim devido a eleva\u00e7\u00e3o dos rios Aquidauana e Taquari, respectivamente, o Imasul<\/p>\n","protected":false},"author":1,"featured_media":14113,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[20],"tags":[],"class_list":["post-14112","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-meio-ambiente"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.1.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Alerta de emerg\u00eancia \u00e9 emitido para o distrito de Palmeiras ap\u00f3s eleva\u00e7\u00e3o do n\u00edvel do rio Aquidauana - Folha de Mato Grosso do Sul<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/folhadems.com.br\/site\/2026\/02\/05\/alerta-de-emergencia-e-emitido-para-o-distrito-de-palmeiras-apos-elevacao-do-nivel-do-rio-aquidauana\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Alerta de emerg\u00eancia \u00e9 emitido para o distrito de Palmeiras ap\u00f3s eleva\u00e7\u00e3o do n\u00edvel do rio Aquidauana - Folha de Mato Grosso do Sul\" \/>\n<meta property=\"og:description\" content=\"Ap\u00f3s dois alertas serem emitidos para Aquidauana e Coxim devido a eleva\u00e7\u00e3o dos rios Aquidauana e Taquari, respectivamente, o Imasul\" \/>\n<meta property=\"og:url\" content=\"https:\/\/folhadems.com.br\/site\/2026\/02\/05\/alerta-de-emergencia-e-emitido-para-o-distrito-de-palmeiras-apos-elevacao-do-nivel-do-rio-aquidauana\/\" \/>\n<meta property=\"og:site_name\" content=\"Folha de Mato Grosso do Sul\" \/>\n<meta property=\"article:published_time\" content=\"2026-02-05T16:10:56+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-05T16:10:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2026\/02\/Rio-Aquidauana.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"450\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Elite Midia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Elite Midia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/folhadems.com.br\/site\/2026\/02\/05\/alerta-de-emergencia-e-emitido-para-o-distrito-de-palmeiras-apos-elevacao-do-nivel-do-rio-aquidauana\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/folhadems.com.br\/site\/2026\/02\/05\/alerta-de-emergencia-e-emitido-para-o-distrito-de-palmeiras-apos-elevacao-do-nivel-do-rio-aquidauana\/\"},\"author\":{\"name\":\"Elite Midia\",\"@id\":\"https:\/\/folhadems.com.br\/site\/#\/schema\/person\/e4a04038e5c2e7040e19ef252ae9d940\"},\"headline\":\"Alerta de emerg\u00eancia \u00e9 emitido para o distrito de Palmeiras ap\u00f3s eleva\u00e7\u00e3o do n\u00edvel do rio Aquidauana\",\"datePublished\":\"2026-02-05T16:10:56+00:00\",\"dateModified\":\"2026-02-05T16:10:59+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/folhadems.com.br\/site\/2026\/02\/05\/alerta-de-emergencia-e-emitido-para-o-distrito-de-palmeiras-apos-elevacao-do-nivel-do-rio-aquidauana\/\"},\"wordCount\":527,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/folhadems.com.br\/site\/#organization\"},\"image\":{\"@id\":\"https:\/\/folhadems.com.br\/site\/2026\/02\/05\/alerta-de-emergencia-e-emitido-para-o-distrito-de-palmeiras-apos-elevacao-do-nivel-do-rio-aquidauana\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2026\/02\/Rio-Aquidauana.jpg\",\"articleSection\":[\"Meio Ambiente\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/folhadems.com.br\/site\/2026\/02\/05\/alerta-de-emergencia-e-emitido-para-o-distrito-de-palmeiras-apos-elevacao-do-nivel-do-rio-aquidauana\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/folhadems.com.br\/site\/2026\/02\/05\/alerta-de-emergencia-e-emitido-para-o-distrito-de-palmeiras-apos-elevacao-do-nivel-do-rio-aquidauana\/\",\"url\":\"https:\/\/folhadems.com.br\/site\/2026\/02\/05\/alerta-de-emergencia-e-emitido-para-o-distrito-de-palmeiras-apos-elevacao-do-nivel-do-rio-aquidauana\/\",\"name\":\"Alerta de emerg\u00eancia \u00e9 emitido para o distrito de Palmeiras ap\u00f3s eleva\u00e7\u00e3o do n\u00edvel do rio Aquidauana - Folha de Mato Grosso do Sul\",\"isPartOf\":{\"@id\":\"https:\/\/folhadems.com.br\/site\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/folhadems.com.br\/site\/2026\/02\/05\/alerta-de-emergencia-e-emitido-para-o-distrito-de-palmeiras-apos-elevacao-do-nivel-do-rio-aquidauana\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/folhadems.com.br\/site\/2026\/02\/05\/alerta-de-emergencia-e-emitido-para-o-distrito-de-palmeiras-apos-elevacao-do-nivel-do-rio-aquidauana\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2026\/02\/Rio-Aquidauana.jpg\",\"datePublished\":\"2026-02-05T16:10:56+00:00\",\"dateModified\":\"2026-02-05T16:10:59+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/folhadems.com.br\/site\/2026\/02\/05\/alerta-de-emergencia-e-emitido-para-o-distrito-de-palmeiras-apos-elevacao-do-nivel-do-rio-aquidauana\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/folhadems.com.br\/site\/2026\/02\/05\/alerta-de-emergencia-e-emitido-para-o-distrito-de-palmeiras-apos-elevacao-do-nivel-do-rio-aquidauana\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/folhadems.com.br\/site\/2026\/02\/05\/alerta-de-emergencia-e-emitido-para-o-distrito-de-palmeiras-apos-elevacao-do-nivel-do-rio-aquidauana\/#primaryimage\",\"url\":\"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2026\/02\/Rio-Aquidauana.jpg\",\"contentUrl\":\"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2026\/02\/Rio-Aquidauana.jpg\",\"width\":800,\"height\":450},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/folhadems.com.br\/site\/2026\/02\/05\/alerta-de-emergencia-e-emitido-para-o-distrito-de-palmeiras-apos-elevacao-do-nivel-do-rio-aquidauana\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/folhadems.com.br\/site\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Alerta de emerg\u00eancia \u00e9 emitido para o distrito de Palmeiras ap\u00f3s eleva\u00e7\u00e3o do n\u00edvel do rio Aquidauana\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/folhadems.com.br\/site\/#website\",\"url\":\"https:\/\/folhadems.com.br\/site\/\",\"name\":\"Folha de Mato Grosso do Sul\",\"description\":\"Jornal Online\",\"publisher\":{\"@id\":\"https:\/\/folhadems.com.br\/site\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/folhadems.com.br\/site\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/folhadems.com.br\/site\/#organization\",\"name\":\"Folha de Mato Grosso do Sul\",\"url\":\"https:\/\/folhadems.com.br\/site\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/folhadems.com.br\/site\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2023\/01\/logo-folha-de-ms-380x90-1.jpg\",\"contentUrl\":\"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2023\/01\/logo-folha-de-ms-380x90-1.jpg\",\"width\":380,\"height\":90,\"caption\":\"Folha de Mato Grosso do Sul\"},\"image\":{\"@id\":\"https:\/\/folhadems.com.br\/site\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/folhadems.com.br\/site\/#\/schema\/person\/e4a04038e5c2e7040e19ef252ae9d940\",\"name\":\"Elite Midia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/folhadems.com.br\/site\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/f76a80f01119f7fec6909ab9feea8819031f391155be021b685479d77496f055?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/f76a80f01119f7fec6909ab9feea8819031f391155be021b685479d77496f055?s=96&d=mm&r=g\",\"caption\":\"Elite Midia\"},\"sameAs\":[\"https:\/\/folhadems.com.br\/site\"],\"url\":\"https:\/\/folhadems.com.br\/site\/author\/elite-midia\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Alerta de emerg\u00eancia \u00e9 emitido para o distrito de Palmeiras ap\u00f3s eleva\u00e7\u00e3o do n\u00edvel do rio Aquidauana - Folha de Mato Grosso do Sul","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/folhadems.com.br\/site\/2026\/02\/05\/alerta-de-emergencia-e-emitido-para-o-distrito-de-palmeiras-apos-elevacao-do-nivel-do-rio-aquidauana\/","og_locale":"pt_BR","og_type":"article","og_title":"Alerta de emerg\u00eancia \u00e9 emitido para o distrito de Palmeiras ap\u00f3s eleva\u00e7\u00e3o do n\u00edvel do rio Aquidauana - Folha de Mato Grosso do Sul","og_description":"Ap\u00f3s dois alertas serem emitidos para Aquidauana e Coxim devido a eleva\u00e7\u00e3o dos rios Aquidauana e Taquari, respectivamente, o Imasul","og_url":"https:\/\/folhadems.com.br\/site\/2026\/02\/05\/alerta-de-emergencia-e-emitido-para-o-distrito-de-palmeiras-apos-elevacao-do-nivel-do-rio-aquidauana\/","og_site_name":"Folha de Mato Grosso do Sul","article_published_time":"2026-02-05T16:10:56+00:00","article_modified_time":"2026-02-05T16:10:59+00:00","og_image":[{"width":800,"height":450,"url":"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2026\/02\/Rio-Aquidauana.jpg","type":"image\/jpeg"}],"author":"Elite Midia","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Elite Midia","Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/folhadems.com.br\/site\/2026\/02\/05\/alerta-de-emergencia-e-emitido-para-o-distrito-de-palmeiras-apos-elevacao-do-nivel-do-rio-aquidauana\/#article","isPartOf":{"@id":"https:\/\/folhadems.com.br\/site\/2026\/02\/05\/alerta-de-emergencia-e-emitido-para-o-distrito-de-palmeiras-apos-elevacao-do-nivel-do-rio-aquidauana\/"},"author":{"name":"Elite Midia","@id":"https:\/\/folhadems.com.br\/site\/#\/schema\/person\/e4a04038e5c2e7040e19ef252ae9d940"},"headline":"Alerta de emerg\u00eancia \u00e9 emitido para o distrito de Palmeiras ap\u00f3s eleva\u00e7\u00e3o do n\u00edvel do rio Aquidauana","datePublished":"2026-02-05T16:10:56+00:00","dateModified":"2026-02-05T16:10:59+00:00","mainEntityOfPage":{"@id":"https:\/\/folhadems.com.br\/site\/2026\/02\/05\/alerta-de-emergencia-e-emitido-para-o-distrito-de-palmeiras-apos-elevacao-do-nivel-do-rio-aquidauana\/"},"wordCount":527,"commentCount":0,"publisher":{"@id":"https:\/\/folhadems.com.br\/site\/#organization"},"image":{"@id":"https:\/\/folhadems.com.br\/site\/2026\/02\/05\/alerta-de-emergencia-e-emitido-para-o-distrito-de-palmeiras-apos-elevacao-do-nivel-do-rio-aquidauana\/#primaryimage"},"thumbnailUrl":"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2026\/02\/Rio-Aquidauana.jpg","articleSection":["Meio Ambiente"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/folhadems.com.br\/site\/2026\/02\/05\/alerta-de-emergencia-e-emitido-para-o-distrito-de-palmeiras-apos-elevacao-do-nivel-do-rio-aquidauana\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/folhadems.com.br\/site\/2026\/02\/05\/alerta-de-emergencia-e-emitido-para-o-distrito-de-palmeiras-apos-elevacao-do-nivel-do-rio-aquidauana\/","url":"https:\/\/folhadems.com.br\/site\/2026\/02\/05\/alerta-de-emergencia-e-emitido-para-o-distrito-de-palmeiras-apos-elevacao-do-nivel-do-rio-aquidauana\/","name":"Alerta de emerg\u00eancia \u00e9 emitido para o distrito de Palmeiras ap\u00f3s eleva\u00e7\u00e3o do n\u00edvel do rio Aquidauana - Folha de Mato Grosso do Sul","isPartOf":{"@id":"https:\/\/folhadems.com.br\/site\/#website"},"primaryImageOfPage":{"@id":"https:\/\/folhadems.com.br\/site\/2026\/02\/05\/alerta-de-emergencia-e-emitido-para-o-distrito-de-palmeiras-apos-elevacao-do-nivel-do-rio-aquidauana\/#primaryimage"},"image":{"@id":"https:\/\/folhadems.com.br\/site\/2026\/02\/05\/alerta-de-emergencia-e-emitido-para-o-distrito-de-palmeiras-apos-elevacao-do-nivel-do-rio-aquidauana\/#primaryimage"},"thumbnailUrl":"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2026\/02\/Rio-Aquidauana.jpg","datePublished":"2026-02-05T16:10:56+00:00","dateModified":"2026-02-05T16:10:59+00:00","breadcrumb":{"@id":"https:\/\/folhadems.com.br\/site\/2026\/02\/05\/alerta-de-emergencia-e-emitido-para-o-distrito-de-palmeiras-apos-elevacao-do-nivel-do-rio-aquidauana\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/folhadems.com.br\/site\/2026\/02\/05\/alerta-de-emergencia-e-emitido-para-o-distrito-de-palmeiras-apos-elevacao-do-nivel-do-rio-aquidauana\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/folhadems.com.br\/site\/2026\/02\/05\/alerta-de-emergencia-e-emitido-para-o-distrito-de-palmeiras-apos-elevacao-do-nivel-do-rio-aquidauana\/#primaryimage","url":"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2026\/02\/Rio-Aquidauana.jpg","contentUrl":"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2026\/02\/Rio-Aquidauana.jpg","width":800,"height":450},{"@type":"BreadcrumbList","@id":"https:\/\/folhadems.com.br\/site\/2026\/02\/05\/alerta-de-emergencia-e-emitido-para-o-distrito-de-palmeiras-apos-elevacao-do-nivel-do-rio-aquidauana\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/folhadems.com.br\/site\/"},{"@type":"ListItem","position":2,"name":"Alerta de emerg\u00eancia \u00e9 emitido para o distrito de Palmeiras ap\u00f3s eleva\u00e7\u00e3o do n\u00edvel do rio Aquidauana"}]},{"@type":"WebSite","@id":"https:\/\/folhadems.com.br\/site\/#website","url":"https:\/\/folhadems.com.br\/site\/","name":"Folha de Mato Grosso do Sul","description":"Jornal Online","publisher":{"@id":"https:\/\/folhadems.com.br\/site\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/folhadems.com.br\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/folhadems.com.br\/site\/#organization","name":"Folha de Mato Grosso do Sul","url":"https:\/\/folhadems.com.br\/site\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/folhadems.com.br\/site\/#\/schema\/logo\/image\/","url":"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2023\/01\/logo-folha-de-ms-380x90-1.jpg","contentUrl":"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2023\/01\/logo-folha-de-ms-380x90-1.jpg","width":380,"height":90,"caption":"Folha de Mato Grosso do Sul"},"image":{"@id":"https:\/\/folhadems.com.br\/site\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/folhadems.com.br\/site\/#\/schema\/person\/e4a04038e5c2e7040e19ef252ae9d940","name":"Elite Midia","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/folhadems.com.br\/site\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/f76a80f01119f7fec6909ab9feea8819031f391155be021b685479d77496f055?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f76a80f01119f7fec6909ab9feea8819031f391155be021b685479d77496f055?s=96&d=mm&r=g","caption":"Elite Midia"},"sameAs":["https:\/\/folhadems.com.br\/site"],"url":"https:\/\/folhadems.com.br\/site\/author\/elite-midia\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-20 11:47:31","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/posts\/14112","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/comments?post=14112"}],"version-history":[{"count":1,"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/posts\/14112\/revisions"}],"predecessor-version":[{"id":14114,"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/posts\/14112\/revisions\/14114"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/media\/14113"}],"wp:attachment":[{"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/media?parent=14112"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/categories?post=14112"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/tags?post=14112"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}