{"id":14066,"date":"2026-02-03T15:59:29","date_gmt":"2026-02-03T19:59:29","guid":{"rendered":"https:\/\/folhadems.com.br\/site\/?p=14066"},"modified":"2026-02-03T16:03:01","modified_gmt":"2026-02-03T20:03:01","slug":"portabilidade-de-credito-ja-pode-ser-feita-de-forma-digital","status":"publish","type":"post","link":"https:\/\/folhadems.com.br\/site\/2026\/02\/03\/portabilidade-de-credito-ja-pode-ser-feita-de-forma-digital\/","title":{"rendered":"Portabilidade de cr\u00e9dito j\u00e1 pode ser feita de forma digital"},"content":{"rendered":"\n<p>A partir desta semana, os correntistas podem pedir a portabilidade de cr\u00e9dito via open finance, com a transfer\u00eancia de empr\u00e9stimos entre institui\u00e7\u00f5es financeiras de forma totalmente digital, diretamente pelos aplicativos dos bancos. Lan\u00e7ada dias ap\u00f3s o open finance completar cinco anos, a novidade marca um novo passo na amplia\u00e7\u00e3o da concorr\u00eancia no mercado de cr\u00e9dito.<img decoding=\"async\" src=\"https:\/\/agenciabrasil.ebc.com.br\/ebc.png?id=1676935&amp;o=node\"><img decoding=\"async\" src=\"https:\/\/agenciabrasil.ebc.com.br\/ebc.gif?id=1676935&amp;o=node\"><\/p>\n\n\n\n<p><strong>Fora do ambiente do open finance, a portabilidade de cr\u00e9dito costuma levar de 20 a 25 dias.<\/strong> Com a nova funcionalidade, o consumidor ganha mais agilidade, transpar\u00eancia e poder de escolha na hora de renegociar seus empr\u00e9stimos.<\/p>\n\n\n\n<p>Nesta fase inicial, o servi\u00e7o est\u00e1 dispon\u00edvel apenas para opera\u00e7\u00f5es de cr\u00e9dito pessoal sem consigna\u00e7\u00e3o, conhecido como cr\u00e9dito \u201cclean\u201d. A expectativa \u00e9 que, gradualmente, outras modalidades sejam incorporadas ao sistema, ampliando o alcance da funcionalidade.<\/p>\n\n\n\n<p>Em entrevista coletiva concedida nesta ter\u00e7a-feira (3), a presidente-executiva da Associa\u00e7\u00e3o Open Finance Brasil, Ana Carla Abr\u00e3o, classificou o lan\u00e7amento como um marco para o ecossistema financeiro. <strong>Segundo ela, o objetivo \u00e9 tornar o mercado mais transparente, compar\u00e1vel e acess\u00edvel para o consumidor.<\/strong><\/p>\n\n\n\n<p>\u201cA ideia \u00e9 chegar ao cr\u00e9dito imobili\u00e1rio, ou seja, abarcar o mercado de uma maneira muito ampla do ponto de vista de portabilidade\u201d, explicou Abr\u00e3o.&nbsp;<\/p>\n\n\n\n<p><strong>De acordo com o cronograma atual, a portabilidade do consignado do INSS deve entrar em opera\u00e7\u00e3o a partir de novembro de 2026.<\/strong><\/p>\n\n\n\n<p>Lan\u00e7ado em 1\u00ba de fevereiro de 2021, o open finance \u00e9 o sistema que permite o compartilhamento padronizado e seguro de dados financeiros entre institui\u00e7\u00f5es, sempre com o consentimento do cliente. <strong>Criado pelo Banco Central (BC), o modelo ampliou o antigo open banking ao incluir n\u00e3o apenas dados banc\u00e1rios, mas tamb\u00e9m informa\u00e7\u00f5es de cr\u00e9dito, investimentos, seguros e previd\u00eancia.<\/strong><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Redu\u00e7\u00e3o de juros<\/h2>\n\n\n\n<p>A troca de dados proporcionada pelo open finance pretende aumentar a concorr\u00eancia, melhorar ofertas e dar mais controle ao consumidor sobre sua vida financeira.&nbsp;<\/p>\n\n\n\n<p><strong>Segundo a Ana Carla Abr\u00e3o, a ferramenta tem espa\u00e7o para reduzir juros, especialmente no cr\u00e9dito sem garantia (sem ativos usados para cobrir eventuais inadimpl\u00eancias).<\/strong><\/p>\n\n\n\n<p>Atualmente, o cr\u00e9dito sem garantia apresenta grande varia\u00e7\u00e3o de taxas, com juros de 4% at\u00e9 20% ao m\u00eas. Com ofertas padronizadas, a presidente da Associa\u00e7\u00e3o Open Finance Brasil diz que o cliente consegue visualizar com clareza a economia nas parcelas e no custo total do contrato.<\/p>\n\n\n\n<p><strong>O open finance j\u00e1 soma cerca de 100 milh\u00f5es de consentimentos \u00fanicos ativos, o equivalente a cerca de 30 milh\u00f5es de pessoas com ao menos uma conta conectada.<\/strong> Para a associa\u00e7\u00e3o, a portabilidade tende a impulsionar ainda mais o uso do sistema e estimular a competi\u00e7\u00e3o entre as institui\u00e7\u00f5es financeiras.<\/p>\n\n\n\n<p><strong>Como pedir a portabilidade de cr\u00e9dito no open finance<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>\u00a0\u00a0\u00a0\u00a0\u00a0Acesse o aplicativo do banco para o qual deseja levar o empr\u00e9stimo;<\/li>\n\n\n\n<li>\u00a0\u00a0\u00a0\u00a0\u00a0Entre no menu de cr\u00e9dito e autorize o compartilhamento de dados via open finance;<\/li>\n\n\n\n<li>\u00a0\u00a0\u00a0\u00a0\u00a0Visualize os contratos eleg\u00edveis, que nesta etapa s\u00e3o apenas de cr\u00e9dito pessoal sem consigna\u00e7\u00e3o;<\/li>\n\n\n\n<li>\u00a0\u00a0\u00a0\u00a0\u00a0Compare as condi\u00e7\u00f5es do contrato atual com a nova oferta, incluindo prazo, valor das parcelas e custo total;<\/li>\n\n\n\n<li>\u00a0\u00a0\u00a0\u00a0\u00a0Baixe e leia o contrato, se desejar, antes de tomar a decis\u00e3o;<\/li>\n\n\n\n<li>\u00a0\u00a0\u00a0\u00a0\u00a0Aceite a proposta e assine digitalmente, usando o m\u00e9todo adotado pela institui\u00e7\u00e3o (token, SMS, biometria, entre outros);<\/li>\n\n\n\n<li>\u00a0\u00a0\u00a0\u00a0\u00a0Aguarde a conclus\u00e3o, que pode levar at\u00e9 cinco dias \u00fateis, tr\u00eas dias para eventual contraproposta do banco original e dois dias para liquida\u00e7\u00e3o.<\/li>\n<\/ul>\n\n\n\n<p><strong><em>Fonte: Ag\u00eancia Brasil<\/em><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A partir desta semana, os correntistas podem pedir a portabilidade de cr\u00e9dito via open finance, com a transfer\u00eancia de empr\u00e9stimos<\/p>\n","protected":false},"author":1,"featured_media":13578,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-14066","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-economia"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.1.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Portabilidade de cr\u00e9dito j\u00e1 pode ser feita de forma digital - Folha de Mato Grosso do Sul<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/folhadems.com.br\/site\/2026\/02\/03\/portabilidade-de-credito-ja-pode-ser-feita-de-forma-digital\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Portabilidade de cr\u00e9dito j\u00e1 pode ser feita de forma digital - Folha de Mato Grosso do Sul\" \/>\n<meta property=\"og:description\" content=\"A partir desta semana, os correntistas podem pedir a portabilidade de cr\u00e9dito via open finance, com a transfer\u00eancia de empr\u00e9stimos\" \/>\n<meta property=\"og:url\" content=\"https:\/\/folhadems.com.br\/site\/2026\/02\/03\/portabilidade-de-credito-ja-pode-ser-feita-de-forma-digital\/\" \/>\n<meta property=\"og:site_name\" content=\"Folha de Mato Grosso do Sul\" \/>\n<meta property=\"article:published_time\" content=\"2026-02-03T19:59:29+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-03T20:03:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2026\/01\/reais.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"450\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Elite Midia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Elite Midia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/folhadems.com.br\/site\/2026\/02\/03\/portabilidade-de-credito-ja-pode-ser-feita-de-forma-digital\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/folhadems.com.br\/site\/2026\/02\/03\/portabilidade-de-credito-ja-pode-ser-feita-de-forma-digital\/\"},\"author\":{\"name\":\"Elite Midia\",\"@id\":\"https:\/\/folhadems.com.br\/site\/#\/schema\/person\/e4a04038e5c2e7040e19ef252ae9d940\"},\"headline\":\"Portabilidade de cr\u00e9dito j\u00e1 pode ser feita de forma digital\",\"datePublished\":\"2026-02-03T19:59:29+00:00\",\"dateModified\":\"2026-02-03T20:03:01+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/folhadems.com.br\/site\/2026\/02\/03\/portabilidade-de-credito-ja-pode-ser-feita-de-forma-digital\/\"},\"wordCount\":609,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/folhadems.com.br\/site\/#organization\"},\"image\":{\"@id\":\"https:\/\/folhadems.com.br\/site\/2026\/02\/03\/portabilidade-de-credito-ja-pode-ser-feita-de-forma-digital\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2026\/01\/reais.jpg\",\"articleSection\":[\"Economia\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/folhadems.com.br\/site\/2026\/02\/03\/portabilidade-de-credito-ja-pode-ser-feita-de-forma-digital\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/folhadems.com.br\/site\/2026\/02\/03\/portabilidade-de-credito-ja-pode-ser-feita-de-forma-digital\/\",\"url\":\"https:\/\/folhadems.com.br\/site\/2026\/02\/03\/portabilidade-de-credito-ja-pode-ser-feita-de-forma-digital\/\",\"name\":\"Portabilidade de cr\u00e9dito j\u00e1 pode ser feita de forma digital - Folha de Mato Grosso do Sul\",\"isPartOf\":{\"@id\":\"https:\/\/folhadems.com.br\/site\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/folhadems.com.br\/site\/2026\/02\/03\/portabilidade-de-credito-ja-pode-ser-feita-de-forma-digital\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/folhadems.com.br\/site\/2026\/02\/03\/portabilidade-de-credito-ja-pode-ser-feita-de-forma-digital\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2026\/01\/reais.jpg\",\"datePublished\":\"2026-02-03T19:59:29+00:00\",\"dateModified\":\"2026-02-03T20:03:01+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/folhadems.com.br\/site\/2026\/02\/03\/portabilidade-de-credito-ja-pode-ser-feita-de-forma-digital\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/folhadems.com.br\/site\/2026\/02\/03\/portabilidade-de-credito-ja-pode-ser-feita-de-forma-digital\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/folhadems.com.br\/site\/2026\/02\/03\/portabilidade-de-credito-ja-pode-ser-feita-de-forma-digital\/#primaryimage\",\"url\":\"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2026\/01\/reais.jpg\",\"contentUrl\":\"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2026\/01\/reais.jpg\",\"width\":800,\"height\":450},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/folhadems.com.br\/site\/2026\/02\/03\/portabilidade-de-credito-ja-pode-ser-feita-de-forma-digital\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/folhadems.com.br\/site\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Portabilidade de cr\u00e9dito j\u00e1 pode ser feita de forma digital\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/folhadems.com.br\/site\/#website\",\"url\":\"https:\/\/folhadems.com.br\/site\/\",\"name\":\"Folha de Mato Grosso do Sul\",\"description\":\"Jornal Online\",\"publisher\":{\"@id\":\"https:\/\/folhadems.com.br\/site\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/folhadems.com.br\/site\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/folhadems.com.br\/site\/#organization\",\"name\":\"Folha de Mato Grosso do Sul\",\"url\":\"https:\/\/folhadems.com.br\/site\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/folhadems.com.br\/site\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2023\/01\/logo-folha-de-ms-380x90-1.jpg\",\"contentUrl\":\"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2023\/01\/logo-folha-de-ms-380x90-1.jpg\",\"width\":380,\"height\":90,\"caption\":\"Folha de Mato Grosso do Sul\"},\"image\":{\"@id\":\"https:\/\/folhadems.com.br\/site\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/folhadems.com.br\/site\/#\/schema\/person\/e4a04038e5c2e7040e19ef252ae9d940\",\"name\":\"Elite Midia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/folhadems.com.br\/site\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/f76a80f01119f7fec6909ab9feea8819031f391155be021b685479d77496f055?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/f76a80f01119f7fec6909ab9feea8819031f391155be021b685479d77496f055?s=96&d=mm&r=g\",\"caption\":\"Elite Midia\"},\"sameAs\":[\"https:\/\/folhadems.com.br\/site\"],\"url\":\"https:\/\/folhadems.com.br\/site\/author\/elite-midia\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Portabilidade de cr\u00e9dito j\u00e1 pode ser feita de forma digital - Folha de Mato Grosso do Sul","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/folhadems.com.br\/site\/2026\/02\/03\/portabilidade-de-credito-ja-pode-ser-feita-de-forma-digital\/","og_locale":"pt_BR","og_type":"article","og_title":"Portabilidade de cr\u00e9dito j\u00e1 pode ser feita de forma digital - Folha de Mato Grosso do Sul","og_description":"A partir desta semana, os correntistas podem pedir a portabilidade de cr\u00e9dito via open finance, com a transfer\u00eancia de empr\u00e9stimos","og_url":"https:\/\/folhadems.com.br\/site\/2026\/02\/03\/portabilidade-de-credito-ja-pode-ser-feita-de-forma-digital\/","og_site_name":"Folha de Mato Grosso do Sul","article_published_time":"2026-02-03T19:59:29+00:00","article_modified_time":"2026-02-03T20:03:01+00:00","og_image":[{"width":800,"height":450,"url":"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2026\/01\/reais.jpg","type":"image\/jpeg"}],"author":"Elite Midia","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Elite Midia","Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/folhadems.com.br\/site\/2026\/02\/03\/portabilidade-de-credito-ja-pode-ser-feita-de-forma-digital\/#article","isPartOf":{"@id":"https:\/\/folhadems.com.br\/site\/2026\/02\/03\/portabilidade-de-credito-ja-pode-ser-feita-de-forma-digital\/"},"author":{"name":"Elite Midia","@id":"https:\/\/folhadems.com.br\/site\/#\/schema\/person\/e4a04038e5c2e7040e19ef252ae9d940"},"headline":"Portabilidade de cr\u00e9dito j\u00e1 pode ser feita de forma digital","datePublished":"2026-02-03T19:59:29+00:00","dateModified":"2026-02-03T20:03:01+00:00","mainEntityOfPage":{"@id":"https:\/\/folhadems.com.br\/site\/2026\/02\/03\/portabilidade-de-credito-ja-pode-ser-feita-de-forma-digital\/"},"wordCount":609,"commentCount":0,"publisher":{"@id":"https:\/\/folhadems.com.br\/site\/#organization"},"image":{"@id":"https:\/\/folhadems.com.br\/site\/2026\/02\/03\/portabilidade-de-credito-ja-pode-ser-feita-de-forma-digital\/#primaryimage"},"thumbnailUrl":"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2026\/01\/reais.jpg","articleSection":["Economia"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/folhadems.com.br\/site\/2026\/02\/03\/portabilidade-de-credito-ja-pode-ser-feita-de-forma-digital\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/folhadems.com.br\/site\/2026\/02\/03\/portabilidade-de-credito-ja-pode-ser-feita-de-forma-digital\/","url":"https:\/\/folhadems.com.br\/site\/2026\/02\/03\/portabilidade-de-credito-ja-pode-ser-feita-de-forma-digital\/","name":"Portabilidade de cr\u00e9dito j\u00e1 pode ser feita de forma digital - Folha de Mato Grosso do Sul","isPartOf":{"@id":"https:\/\/folhadems.com.br\/site\/#website"},"primaryImageOfPage":{"@id":"https:\/\/folhadems.com.br\/site\/2026\/02\/03\/portabilidade-de-credito-ja-pode-ser-feita-de-forma-digital\/#primaryimage"},"image":{"@id":"https:\/\/folhadems.com.br\/site\/2026\/02\/03\/portabilidade-de-credito-ja-pode-ser-feita-de-forma-digital\/#primaryimage"},"thumbnailUrl":"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2026\/01\/reais.jpg","datePublished":"2026-02-03T19:59:29+00:00","dateModified":"2026-02-03T20:03:01+00:00","breadcrumb":{"@id":"https:\/\/folhadems.com.br\/site\/2026\/02\/03\/portabilidade-de-credito-ja-pode-ser-feita-de-forma-digital\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/folhadems.com.br\/site\/2026\/02\/03\/portabilidade-de-credito-ja-pode-ser-feita-de-forma-digital\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/folhadems.com.br\/site\/2026\/02\/03\/portabilidade-de-credito-ja-pode-ser-feita-de-forma-digital\/#primaryimage","url":"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2026\/01\/reais.jpg","contentUrl":"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2026\/01\/reais.jpg","width":800,"height":450},{"@type":"BreadcrumbList","@id":"https:\/\/folhadems.com.br\/site\/2026\/02\/03\/portabilidade-de-credito-ja-pode-ser-feita-de-forma-digital\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/folhadems.com.br\/site\/"},{"@type":"ListItem","position":2,"name":"Portabilidade de cr\u00e9dito j\u00e1 pode ser feita de forma digital"}]},{"@type":"WebSite","@id":"https:\/\/folhadems.com.br\/site\/#website","url":"https:\/\/folhadems.com.br\/site\/","name":"Folha de Mato Grosso do Sul","description":"Jornal Online","publisher":{"@id":"https:\/\/folhadems.com.br\/site\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/folhadems.com.br\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/folhadems.com.br\/site\/#organization","name":"Folha de Mato Grosso do Sul","url":"https:\/\/folhadems.com.br\/site\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/folhadems.com.br\/site\/#\/schema\/logo\/image\/","url":"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2023\/01\/logo-folha-de-ms-380x90-1.jpg","contentUrl":"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2023\/01\/logo-folha-de-ms-380x90-1.jpg","width":380,"height":90,"caption":"Folha de Mato Grosso do Sul"},"image":{"@id":"https:\/\/folhadems.com.br\/site\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/folhadems.com.br\/site\/#\/schema\/person\/e4a04038e5c2e7040e19ef252ae9d940","name":"Elite Midia","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/folhadems.com.br\/site\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/f76a80f01119f7fec6909ab9feea8819031f391155be021b685479d77496f055?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f76a80f01119f7fec6909ab9feea8819031f391155be021b685479d77496f055?s=96&d=mm&r=g","caption":"Elite Midia"},"sameAs":["https:\/\/folhadems.com.br\/site"],"url":"https:\/\/folhadems.com.br\/site\/author\/elite-midia\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-20 14:47:43","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/posts\/14066","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/comments?post=14066"}],"version-history":[{"count":1,"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/posts\/14066\/revisions"}],"predecessor-version":[{"id":14067,"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/posts\/14066\/revisions\/14067"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/media\/13578"}],"wp:attachment":[{"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/media?parent=14066"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/categories?post=14066"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/tags?post=14066"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}