{"id":14057,"date":"2026-02-03T08:22:00","date_gmt":"2026-02-03T12:22:00","guid":{"rendered":"https:\/\/folhadems.com.br\/site\/?p=14057"},"modified":"2026-02-03T08:10:55","modified_gmt":"2026-02-03T12:10:55","slug":"empresas-anunciam-1-177-vagas-para-110-profissoes-na-funsat-hoje","status":"publish","type":"post","link":"https:\/\/folhadems.com.br\/site\/2026\/02\/03\/empresas-anunciam-1-177-vagas-para-110-profissoes-na-funsat-hoje\/","title":{"rendered":"Empresas anunciam 1.177 vagas para 110 profiss\u00f5es na Funsat hoje"},"content":{"rendered":"\n<p>A Funda\u00e7\u00e3o Social do Trabalho (Funsat) anuncia, para esta ter\u00e7a-feira (3), a oferta de 1.177 vagas de emprego, distribu\u00eddas entre 110 profiss\u00f5es, em 119 empresas de Campo Grande.<\/p>\n\n\n\n<p>Para participar dos processos seletivos, \u00e9 indispens\u00e1vel que o candidato esteja com o cadastro atualizado no Sine (Sistema Nacional do Emprego). Isso porque, por meio de uma an\u00e1lise de perfil realizada na plataforma, gerida pela Ag\u00eancia de Empregos da Funsat, o trabalhador \u00e9 direcionado \u00e0s oportunidades compat\u00edveis com sua experi\u00eancia e disponibilidade.<\/p>\n\n\n\n<p>Entre as vagas dispon\u00edveis est\u00e3o: acougueiro (5), agente de saneamento (10), atendente de farm\u00e1cia (2), engenheiro civil (8), magarefe (5), operador de caixa (140), padeiro (6), pedreiro (22) e t\u00e9cnico de controle de qualidade, entre outras.<\/p>\n\n\n\n<p>Com foco em facilitar o recrutamento, a Funda\u00e7\u00e3o tamb\u00e9m destaca oportunidades voltadas para \u201cperfil aberto\u201d e trabalho tempor\u00e1rio. No caso do perfil aberto, o v\u00ednculo prev\u00ea treinamento remunerado, com destaque para vagas \u00fanicas nas fun\u00e7\u00f5es de ajudante de a\u00e7ougueiro, ajudante de cozinha, ajudante de eletricista, ajudante de serralheiro, auxiliar de lavanderia, caixa de supermercado e fiscal de viagens.<\/p>\n\n\n\n<p>J\u00e1 para trabalho tempor\u00e1rio, h\u00e1 oportunidades para classificador de gr\u00e3os (5 vagas) e gar\u00e7om (10 vagas).<\/p>\n\n\n\n<p>O p\u00fablico PCD (Pessoa com Defici\u00eancia) conta com prioridade em 94 an\u00fancios, distribu\u00eddos entre cinco fun\u00e7\u00f5es: auxiliar de confec\u00e7\u00e3o (80), vigilante (10), auxiliar de limpeza (2), auxiliar de linha de produ\u00e7\u00e3o (1) e auxiliar administrativo (1).<\/p>\n\n\n\n<p>A Funsat est\u00e1 localizada na Rua 14 de Julho, n\u00ba 992, Vila Gl\u00f3ria. A Ag\u00eancia de Empregos funciona das 7h \u00e0s 16h, sem intervalo. Informa\u00e7\u00f5es sobre a intermedia\u00e7\u00e3o de vagas podem ser obtidas pelo telefone (67) 4042-0585, ramal 5837.<\/p>\n\n\n\n<p>Confira o painel completo com todas as profiss\u00f5es dispon\u00edveis nos processos seletivos das empresas. <a href=\"https:\/\/www.campogrande.ms.gov.br\/funsat\/sec-artigos\/vagas-ofertadas\/\" target=\"_blank\" rel=\"noopener\">https:\/\/www.campogrande.ms.gov.br\/funsat\/sec-artigos\/vagas-ofertadas\/<\/a><\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/cdn.campogrande.ms.gov.br\/portal\/prod\/uploads\/sites\/3\/2026\/02\/a79a77f4250647b093564a3556ac6468-821x1024.jpg\" alt=\"\" class=\"wp-image-156190\"\/><\/figure>\n\n\n\n<p><strong><em>Fonte: PrefCG<\/em><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Funda\u00e7\u00e3o Social do Trabalho (Funsat) anuncia, para esta ter\u00e7a-feira (3), a oferta de 1.177 vagas de emprego, distribu\u00eddas entre<\/p>\n","protected":false},"author":1,"featured_media":14058,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[26],"tags":[],"class_list":["post-14057","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cotidiano"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.1.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Empresas anunciam 1.177 vagas para 110 profiss\u00f5es na Funsat hoje - Folha de Mato Grosso do Sul<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/folhadems.com.br\/site\/2026\/02\/03\/empresas-anunciam-1-177-vagas-para-110-profissoes-na-funsat-hoje\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Empresas anunciam 1.177 vagas para 110 profiss\u00f5es na Funsat hoje - Folha de Mato Grosso do Sul\" \/>\n<meta property=\"og:description\" content=\"A Funda\u00e7\u00e3o Social do Trabalho (Funsat) anuncia, para esta ter\u00e7a-feira (3), a oferta de 1.177 vagas de emprego, distribu\u00eddas entre\" \/>\n<meta property=\"og:url\" content=\"https:\/\/folhadems.com.br\/site\/2026\/02\/03\/empresas-anunciam-1-177-vagas-para-110-profissoes-na-funsat-hoje\/\" \/>\n<meta property=\"og:site_name\" content=\"Folha de Mato Grosso do Sul\" \/>\n<meta property=\"article:published_time\" content=\"2026-02-03T12:22:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2026\/02\/funsat.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"450\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Elite Midia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Elite Midia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/folhadems.com.br\/site\/2026\/02\/03\/empresas-anunciam-1-177-vagas-para-110-profissoes-na-funsat-hoje\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/folhadems.com.br\/site\/2026\/02\/03\/empresas-anunciam-1-177-vagas-para-110-profissoes-na-funsat-hoje\/\"},\"author\":{\"name\":\"Elite Midia\",\"@id\":\"https:\/\/folhadems.com.br\/site\/#\/schema\/person\/e4a04038e5c2e7040e19ef252ae9d940\"},\"headline\":\"Empresas anunciam 1.177 vagas para 110 profiss\u00f5es na Funsat hoje\",\"datePublished\":\"2026-02-03T12:22:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/folhadems.com.br\/site\/2026\/02\/03\/empresas-anunciam-1-177-vagas-para-110-profissoes-na-funsat-hoje\/\"},\"wordCount\":308,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/folhadems.com.br\/site\/#organization\"},\"image\":{\"@id\":\"https:\/\/folhadems.com.br\/site\/2026\/02\/03\/empresas-anunciam-1-177-vagas-para-110-profissoes-na-funsat-hoje\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2026\/02\/funsat.jpg\",\"articleSection\":[\"Cotidiano\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/folhadems.com.br\/site\/2026\/02\/03\/empresas-anunciam-1-177-vagas-para-110-profissoes-na-funsat-hoje\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/folhadems.com.br\/site\/2026\/02\/03\/empresas-anunciam-1-177-vagas-para-110-profissoes-na-funsat-hoje\/\",\"url\":\"https:\/\/folhadems.com.br\/site\/2026\/02\/03\/empresas-anunciam-1-177-vagas-para-110-profissoes-na-funsat-hoje\/\",\"name\":\"Empresas anunciam 1.177 vagas para 110 profiss\u00f5es na Funsat hoje - Folha de Mato Grosso do Sul\",\"isPartOf\":{\"@id\":\"https:\/\/folhadems.com.br\/site\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/folhadems.com.br\/site\/2026\/02\/03\/empresas-anunciam-1-177-vagas-para-110-profissoes-na-funsat-hoje\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/folhadems.com.br\/site\/2026\/02\/03\/empresas-anunciam-1-177-vagas-para-110-profissoes-na-funsat-hoje\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2026\/02\/funsat.jpg\",\"datePublished\":\"2026-02-03T12:22:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/folhadems.com.br\/site\/2026\/02\/03\/empresas-anunciam-1-177-vagas-para-110-profissoes-na-funsat-hoje\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/folhadems.com.br\/site\/2026\/02\/03\/empresas-anunciam-1-177-vagas-para-110-profissoes-na-funsat-hoje\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/folhadems.com.br\/site\/2026\/02\/03\/empresas-anunciam-1-177-vagas-para-110-profissoes-na-funsat-hoje\/#primaryimage\",\"url\":\"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2026\/02\/funsat.jpg\",\"contentUrl\":\"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2026\/02\/funsat.jpg\",\"width\":800,\"height\":450},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/folhadems.com.br\/site\/2026\/02\/03\/empresas-anunciam-1-177-vagas-para-110-profissoes-na-funsat-hoje\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/folhadems.com.br\/site\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Empresas anunciam 1.177 vagas para 110 profiss\u00f5es na Funsat hoje\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/folhadems.com.br\/site\/#website\",\"url\":\"https:\/\/folhadems.com.br\/site\/\",\"name\":\"Folha de Mato Grosso do Sul\",\"description\":\"Jornal Online\",\"publisher\":{\"@id\":\"https:\/\/folhadems.com.br\/site\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/folhadems.com.br\/site\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/folhadems.com.br\/site\/#organization\",\"name\":\"Folha de Mato Grosso do Sul\",\"url\":\"https:\/\/folhadems.com.br\/site\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/folhadems.com.br\/site\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2023\/01\/logo-folha-de-ms-380x90-1.jpg\",\"contentUrl\":\"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2023\/01\/logo-folha-de-ms-380x90-1.jpg\",\"width\":380,\"height\":90,\"caption\":\"Folha de Mato Grosso do Sul\"},\"image\":{\"@id\":\"https:\/\/folhadems.com.br\/site\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/folhadems.com.br\/site\/#\/schema\/person\/e4a04038e5c2e7040e19ef252ae9d940\",\"name\":\"Elite Midia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/folhadems.com.br\/site\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/f76a80f01119f7fec6909ab9feea8819031f391155be021b685479d77496f055?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/f76a80f01119f7fec6909ab9feea8819031f391155be021b685479d77496f055?s=96&d=mm&r=g\",\"caption\":\"Elite Midia\"},\"sameAs\":[\"https:\/\/folhadems.com.br\/site\"],\"url\":\"https:\/\/folhadems.com.br\/site\/author\/elite-midia\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Empresas anunciam 1.177 vagas para 110 profiss\u00f5es na Funsat hoje - Folha de Mato Grosso do Sul","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/folhadems.com.br\/site\/2026\/02\/03\/empresas-anunciam-1-177-vagas-para-110-profissoes-na-funsat-hoje\/","og_locale":"pt_BR","og_type":"article","og_title":"Empresas anunciam 1.177 vagas para 110 profiss\u00f5es na Funsat hoje - Folha de Mato Grosso do Sul","og_description":"A Funda\u00e7\u00e3o Social do Trabalho (Funsat) anuncia, para esta ter\u00e7a-feira (3), a oferta de 1.177 vagas de emprego, distribu\u00eddas entre","og_url":"https:\/\/folhadems.com.br\/site\/2026\/02\/03\/empresas-anunciam-1-177-vagas-para-110-profissoes-na-funsat-hoje\/","og_site_name":"Folha de Mato Grosso do Sul","article_published_time":"2026-02-03T12:22:00+00:00","og_image":[{"width":800,"height":450,"url":"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2026\/02\/funsat.jpg","type":"image\/jpeg"}],"author":"Elite Midia","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Elite Midia","Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/folhadems.com.br\/site\/2026\/02\/03\/empresas-anunciam-1-177-vagas-para-110-profissoes-na-funsat-hoje\/#article","isPartOf":{"@id":"https:\/\/folhadems.com.br\/site\/2026\/02\/03\/empresas-anunciam-1-177-vagas-para-110-profissoes-na-funsat-hoje\/"},"author":{"name":"Elite Midia","@id":"https:\/\/folhadems.com.br\/site\/#\/schema\/person\/e4a04038e5c2e7040e19ef252ae9d940"},"headline":"Empresas anunciam 1.177 vagas para 110 profiss\u00f5es na Funsat hoje","datePublished":"2026-02-03T12:22:00+00:00","mainEntityOfPage":{"@id":"https:\/\/folhadems.com.br\/site\/2026\/02\/03\/empresas-anunciam-1-177-vagas-para-110-profissoes-na-funsat-hoje\/"},"wordCount":308,"commentCount":0,"publisher":{"@id":"https:\/\/folhadems.com.br\/site\/#organization"},"image":{"@id":"https:\/\/folhadems.com.br\/site\/2026\/02\/03\/empresas-anunciam-1-177-vagas-para-110-profissoes-na-funsat-hoje\/#primaryimage"},"thumbnailUrl":"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2026\/02\/funsat.jpg","articleSection":["Cotidiano"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/folhadems.com.br\/site\/2026\/02\/03\/empresas-anunciam-1-177-vagas-para-110-profissoes-na-funsat-hoje\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/folhadems.com.br\/site\/2026\/02\/03\/empresas-anunciam-1-177-vagas-para-110-profissoes-na-funsat-hoje\/","url":"https:\/\/folhadems.com.br\/site\/2026\/02\/03\/empresas-anunciam-1-177-vagas-para-110-profissoes-na-funsat-hoje\/","name":"Empresas anunciam 1.177 vagas para 110 profiss\u00f5es na Funsat hoje - Folha de Mato Grosso do Sul","isPartOf":{"@id":"https:\/\/folhadems.com.br\/site\/#website"},"primaryImageOfPage":{"@id":"https:\/\/folhadems.com.br\/site\/2026\/02\/03\/empresas-anunciam-1-177-vagas-para-110-profissoes-na-funsat-hoje\/#primaryimage"},"image":{"@id":"https:\/\/folhadems.com.br\/site\/2026\/02\/03\/empresas-anunciam-1-177-vagas-para-110-profissoes-na-funsat-hoje\/#primaryimage"},"thumbnailUrl":"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2026\/02\/funsat.jpg","datePublished":"2026-02-03T12:22:00+00:00","breadcrumb":{"@id":"https:\/\/folhadems.com.br\/site\/2026\/02\/03\/empresas-anunciam-1-177-vagas-para-110-profissoes-na-funsat-hoje\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/folhadems.com.br\/site\/2026\/02\/03\/empresas-anunciam-1-177-vagas-para-110-profissoes-na-funsat-hoje\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/folhadems.com.br\/site\/2026\/02\/03\/empresas-anunciam-1-177-vagas-para-110-profissoes-na-funsat-hoje\/#primaryimage","url":"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2026\/02\/funsat.jpg","contentUrl":"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2026\/02\/funsat.jpg","width":800,"height":450},{"@type":"BreadcrumbList","@id":"https:\/\/folhadems.com.br\/site\/2026\/02\/03\/empresas-anunciam-1-177-vagas-para-110-profissoes-na-funsat-hoje\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/folhadems.com.br\/site\/"},{"@type":"ListItem","position":2,"name":"Empresas anunciam 1.177 vagas para 110 profiss\u00f5es na Funsat hoje"}]},{"@type":"WebSite","@id":"https:\/\/folhadems.com.br\/site\/#website","url":"https:\/\/folhadems.com.br\/site\/","name":"Folha de Mato Grosso do Sul","description":"Jornal Online","publisher":{"@id":"https:\/\/folhadems.com.br\/site\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/folhadems.com.br\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/folhadems.com.br\/site\/#organization","name":"Folha de Mato Grosso do Sul","url":"https:\/\/folhadems.com.br\/site\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/folhadems.com.br\/site\/#\/schema\/logo\/image\/","url":"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2023\/01\/logo-folha-de-ms-380x90-1.jpg","contentUrl":"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2023\/01\/logo-folha-de-ms-380x90-1.jpg","width":380,"height":90,"caption":"Folha de Mato Grosso do Sul"},"image":{"@id":"https:\/\/folhadems.com.br\/site\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/folhadems.com.br\/site\/#\/schema\/person\/e4a04038e5c2e7040e19ef252ae9d940","name":"Elite Midia","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/folhadems.com.br\/site\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/f76a80f01119f7fec6909ab9feea8819031f391155be021b685479d77496f055?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f76a80f01119f7fec6909ab9feea8819031f391155be021b685479d77496f055?s=96&d=mm&r=g","caption":"Elite Midia"},"sameAs":["https:\/\/folhadems.com.br\/site"],"url":"https:\/\/folhadems.com.br\/site\/author\/elite-midia\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-20 13:36:08","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/posts\/14057","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/comments?post=14057"}],"version-history":[{"count":1,"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/posts\/14057\/revisions"}],"predecessor-version":[{"id":14059,"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/posts\/14057\/revisions\/14059"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/media\/14058"}],"wp:attachment":[{"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/media?parent=14057"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/categories?post=14057"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/tags?post=14057"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}