{"id":13971,"date":"2026-01-30T12:54:24","date_gmt":"2026-01-30T16:54:24","guid":{"rendered":"https:\/\/folhadems.com.br\/site\/?p=13971"},"modified":"2026-01-30T12:54:27","modified_gmt":"2026-01-30T16:54:27","slug":"emha-convoca-suplentes-do-residencial-jardim-antartica","status":"publish","type":"post","link":"https:\/\/folhadems.com.br\/site\/2026\/01\/30\/emha-convoca-suplentes-do-residencial-jardim-antartica\/","title":{"rendered":"EMHA convoca suplentes do Residencial Jardim Ant\u00e1rtica"},"content":{"rendered":"\n<p>A Prefeitura de Campo Grande, por meio da Ag\u00eancia Municipal de Habita\u00e7\u00e3o e Assuntos Fundi\u00e1rios (EMHA), publicou nesta sexta-feira (30), por meio do Diogrande n\u00ba 8.206, o Edital de Comparecimento n\u00ba 05\/2026, que convoca os suplentes pr\u00e9-selecionados para 30 apartamentos do Programa Minha Casa Minha Vida \u2013 Faixa 1, referentes ao Condom\u00ednio Residencial Jardim Ant\u00e1rtica.<\/p>\n\n\n\n<p>Os convocados devem comparecer \u00e0 sede da EMHA para entrega de documentos e comprova\u00e7\u00e3o dos crit\u00e9rios de pontua\u00e7\u00e3o, etapa que tem como objetivo subsidiar eventual reclassifica\u00e7\u00e3o dos candidatos, conforme an\u00e1lise e valida\u00e7\u00e3o das informa\u00e7\u00f5es apresentadas.<\/p>\n\n\n\n<p>O atendimento ser\u00e1 realizado na EMHA, localizada na Rua \u00cdria Loureiro Viana, n\u00ba 415, Vila Oriente, no per\u00edodo de 2 a 9 de fevereiro de 2026, das 8h \u00e0s 12h. Os convocados devem comparecer munidos de toda a documenta\u00e7\u00e3o necess\u00e1ria para confer\u00eancia.<\/p>\n\n\n\n<p>Cabe destacar que a apresenta\u00e7\u00e3o da documenta\u00e7\u00e3o n\u00e3o garante a destina\u00e7\u00e3o definitiva da unidade habitacional, estando o processo condicionado \u00e0 confer\u00eancia e valida\u00e7\u00e3o dos dados informados no ato da inscri\u00e7\u00e3o.<\/p>\n\n\n\n<p>Confira a lista completa dos suplentes <a href=\"https:\/\/diogrande.campogrande.ms.gov.br\/download_edicao\/eyJjb2RpZ29kaWEiOiIxMDE5MSJ9.pdf\" target=\"_blank\" rel=\"noopener\">convocados aqui<\/a>.<\/p>\n\n\n\n<p><strong>Sobre o empreendimento<\/strong><\/p>\n\n\n\n<p>O Residencial Jardim Ant\u00e1rtica est\u00e1 localizado no bairro Jardim Ant\u00e1rtica, na Regi\u00e3o Urbana do Lagoa, e far\u00e1 parte de um novo empreendimento do programa habitacional federal garantindo moradia digna para quem mais precisa. Cada unidade possui dois quartos, sala, cozinha, banheiro e \u00e1rea de servi\u00e7o, al\u00e9m de contar com infraestrutura completa e \u00e1reas de conviv\u00eancia no condom\u00ednio.<\/p>\n\n\n\n<p><em><strong>Fonte: PrefCG<\/strong><\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Prefeitura de Campo Grande, por meio da Ag\u00eancia Municipal de Habita\u00e7\u00e3o e Assuntos Fundi\u00e1rios (EMHA), publicou nesta sexta-feira (30),<\/p>\n","protected":false},"author":1,"featured_media":13972,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[26],"tags":[],"class_list":["post-13971","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cotidiano"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.1.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>EMHA convoca suplentes do Residencial Jardim Ant\u00e1rtica - Folha de Mato Grosso do Sul<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/folhadems.com.br\/site\/2026\/01\/30\/emha-convoca-suplentes-do-residencial-jardim-antartica\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"EMHA convoca suplentes do Residencial Jardim Ant\u00e1rtica - Folha de Mato Grosso do Sul\" \/>\n<meta property=\"og:description\" content=\"A Prefeitura de Campo Grande, por meio da Ag\u00eancia Municipal de Habita\u00e7\u00e3o e Assuntos Fundi\u00e1rios (EMHA), publicou nesta sexta-feira (30),\" \/>\n<meta property=\"og:url\" content=\"https:\/\/folhadems.com.br\/site\/2026\/01\/30\/emha-convoca-suplentes-do-residencial-jardim-antartica\/\" \/>\n<meta property=\"og:site_name\" content=\"Folha de Mato Grosso do Sul\" \/>\n<meta property=\"article:published_time\" content=\"2026-01-30T16:54:24+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-30T16:54:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2026\/01\/moradia.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2048\" \/>\n\t<meta property=\"og:image:height\" content=\"1365\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Elite Midia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Elite Midia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/folhadems.com.br\/site\/2026\/01\/30\/emha-convoca-suplentes-do-residencial-jardim-antartica\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/folhadems.com.br\/site\/2026\/01\/30\/emha-convoca-suplentes-do-residencial-jardim-antartica\/\"},\"author\":{\"name\":\"Elite Midia\",\"@id\":\"https:\/\/folhadems.com.br\/site\/#\/schema\/person\/e4a04038e5c2e7040e19ef252ae9d940\"},\"headline\":\"EMHA convoca suplentes do Residencial Jardim Ant\u00e1rtica\",\"datePublished\":\"2026-01-30T16:54:24+00:00\",\"dateModified\":\"2026-01-30T16:54:27+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/folhadems.com.br\/site\/2026\/01\/30\/emha-convoca-suplentes-do-residencial-jardim-antartica\/\"},\"wordCount\":259,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/folhadems.com.br\/site\/#organization\"},\"image\":{\"@id\":\"https:\/\/folhadems.com.br\/site\/2026\/01\/30\/emha-convoca-suplentes-do-residencial-jardim-antartica\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2026\/01\/moradia.jpg\",\"articleSection\":[\"Cotidiano\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/folhadems.com.br\/site\/2026\/01\/30\/emha-convoca-suplentes-do-residencial-jardim-antartica\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/folhadems.com.br\/site\/2026\/01\/30\/emha-convoca-suplentes-do-residencial-jardim-antartica\/\",\"url\":\"https:\/\/folhadems.com.br\/site\/2026\/01\/30\/emha-convoca-suplentes-do-residencial-jardim-antartica\/\",\"name\":\"EMHA convoca suplentes do Residencial Jardim Ant\u00e1rtica - Folha de Mato Grosso do Sul\",\"isPartOf\":{\"@id\":\"https:\/\/folhadems.com.br\/site\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/folhadems.com.br\/site\/2026\/01\/30\/emha-convoca-suplentes-do-residencial-jardim-antartica\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/folhadems.com.br\/site\/2026\/01\/30\/emha-convoca-suplentes-do-residencial-jardim-antartica\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2026\/01\/moradia.jpg\",\"datePublished\":\"2026-01-30T16:54:24+00:00\",\"dateModified\":\"2026-01-30T16:54:27+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/folhadems.com.br\/site\/2026\/01\/30\/emha-convoca-suplentes-do-residencial-jardim-antartica\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/folhadems.com.br\/site\/2026\/01\/30\/emha-convoca-suplentes-do-residencial-jardim-antartica\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/folhadems.com.br\/site\/2026\/01\/30\/emha-convoca-suplentes-do-residencial-jardim-antartica\/#primaryimage\",\"url\":\"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2026\/01\/moradia.jpg\",\"contentUrl\":\"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2026\/01\/moradia.jpg\",\"width\":2048,\"height\":1365},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/folhadems.com.br\/site\/2026\/01\/30\/emha-convoca-suplentes-do-residencial-jardim-antartica\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/folhadems.com.br\/site\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"EMHA convoca suplentes do Residencial Jardim Ant\u00e1rtica\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/folhadems.com.br\/site\/#website\",\"url\":\"https:\/\/folhadems.com.br\/site\/\",\"name\":\"Folha de Mato Grosso do Sul\",\"description\":\"Jornal Online\",\"publisher\":{\"@id\":\"https:\/\/folhadems.com.br\/site\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/folhadems.com.br\/site\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/folhadems.com.br\/site\/#organization\",\"name\":\"Folha de Mato Grosso do Sul\",\"url\":\"https:\/\/folhadems.com.br\/site\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/folhadems.com.br\/site\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2023\/01\/logo-folha-de-ms-380x90-1.jpg\",\"contentUrl\":\"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2023\/01\/logo-folha-de-ms-380x90-1.jpg\",\"width\":380,\"height\":90,\"caption\":\"Folha de Mato Grosso do Sul\"},\"image\":{\"@id\":\"https:\/\/folhadems.com.br\/site\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/folhadems.com.br\/site\/#\/schema\/person\/e4a04038e5c2e7040e19ef252ae9d940\",\"name\":\"Elite Midia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/folhadems.com.br\/site\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/f76a80f01119f7fec6909ab9feea8819031f391155be021b685479d77496f055?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/f76a80f01119f7fec6909ab9feea8819031f391155be021b685479d77496f055?s=96&d=mm&r=g\",\"caption\":\"Elite Midia\"},\"sameAs\":[\"https:\/\/folhadems.com.br\/site\"],\"url\":\"https:\/\/folhadems.com.br\/site\/author\/elite-midia\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"EMHA convoca suplentes do Residencial Jardim Ant\u00e1rtica - Folha de Mato Grosso do Sul","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/folhadems.com.br\/site\/2026\/01\/30\/emha-convoca-suplentes-do-residencial-jardim-antartica\/","og_locale":"pt_BR","og_type":"article","og_title":"EMHA convoca suplentes do Residencial Jardim Ant\u00e1rtica - Folha de Mato Grosso do Sul","og_description":"A Prefeitura de Campo Grande, por meio da Ag\u00eancia Municipal de Habita\u00e7\u00e3o e Assuntos Fundi\u00e1rios (EMHA), publicou nesta sexta-feira (30),","og_url":"https:\/\/folhadems.com.br\/site\/2026\/01\/30\/emha-convoca-suplentes-do-residencial-jardim-antartica\/","og_site_name":"Folha de Mato Grosso do Sul","article_published_time":"2026-01-30T16:54:24+00:00","article_modified_time":"2026-01-30T16:54:27+00:00","og_image":[{"width":2048,"height":1365,"url":"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2026\/01\/moradia.jpg","type":"image\/jpeg"}],"author":"Elite Midia","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Elite Midia","Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/folhadems.com.br\/site\/2026\/01\/30\/emha-convoca-suplentes-do-residencial-jardim-antartica\/#article","isPartOf":{"@id":"https:\/\/folhadems.com.br\/site\/2026\/01\/30\/emha-convoca-suplentes-do-residencial-jardim-antartica\/"},"author":{"name":"Elite Midia","@id":"https:\/\/folhadems.com.br\/site\/#\/schema\/person\/e4a04038e5c2e7040e19ef252ae9d940"},"headline":"EMHA convoca suplentes do Residencial Jardim Ant\u00e1rtica","datePublished":"2026-01-30T16:54:24+00:00","dateModified":"2026-01-30T16:54:27+00:00","mainEntityOfPage":{"@id":"https:\/\/folhadems.com.br\/site\/2026\/01\/30\/emha-convoca-suplentes-do-residencial-jardim-antartica\/"},"wordCount":259,"commentCount":0,"publisher":{"@id":"https:\/\/folhadems.com.br\/site\/#organization"},"image":{"@id":"https:\/\/folhadems.com.br\/site\/2026\/01\/30\/emha-convoca-suplentes-do-residencial-jardim-antartica\/#primaryimage"},"thumbnailUrl":"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2026\/01\/moradia.jpg","articleSection":["Cotidiano"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/folhadems.com.br\/site\/2026\/01\/30\/emha-convoca-suplentes-do-residencial-jardim-antartica\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/folhadems.com.br\/site\/2026\/01\/30\/emha-convoca-suplentes-do-residencial-jardim-antartica\/","url":"https:\/\/folhadems.com.br\/site\/2026\/01\/30\/emha-convoca-suplentes-do-residencial-jardim-antartica\/","name":"EMHA convoca suplentes do Residencial Jardim Ant\u00e1rtica - Folha de Mato Grosso do Sul","isPartOf":{"@id":"https:\/\/folhadems.com.br\/site\/#website"},"primaryImageOfPage":{"@id":"https:\/\/folhadems.com.br\/site\/2026\/01\/30\/emha-convoca-suplentes-do-residencial-jardim-antartica\/#primaryimage"},"image":{"@id":"https:\/\/folhadems.com.br\/site\/2026\/01\/30\/emha-convoca-suplentes-do-residencial-jardim-antartica\/#primaryimage"},"thumbnailUrl":"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2026\/01\/moradia.jpg","datePublished":"2026-01-30T16:54:24+00:00","dateModified":"2026-01-30T16:54:27+00:00","breadcrumb":{"@id":"https:\/\/folhadems.com.br\/site\/2026\/01\/30\/emha-convoca-suplentes-do-residencial-jardim-antartica\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/folhadems.com.br\/site\/2026\/01\/30\/emha-convoca-suplentes-do-residencial-jardim-antartica\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/folhadems.com.br\/site\/2026\/01\/30\/emha-convoca-suplentes-do-residencial-jardim-antartica\/#primaryimage","url":"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2026\/01\/moradia.jpg","contentUrl":"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2026\/01\/moradia.jpg","width":2048,"height":1365},{"@type":"BreadcrumbList","@id":"https:\/\/folhadems.com.br\/site\/2026\/01\/30\/emha-convoca-suplentes-do-residencial-jardim-antartica\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/folhadems.com.br\/site\/"},{"@type":"ListItem","position":2,"name":"EMHA convoca suplentes do Residencial Jardim Ant\u00e1rtica"}]},{"@type":"WebSite","@id":"https:\/\/folhadems.com.br\/site\/#website","url":"https:\/\/folhadems.com.br\/site\/","name":"Folha de Mato Grosso do Sul","description":"Jornal Online","publisher":{"@id":"https:\/\/folhadems.com.br\/site\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/folhadems.com.br\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/folhadems.com.br\/site\/#organization","name":"Folha de Mato Grosso do Sul","url":"https:\/\/folhadems.com.br\/site\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/folhadems.com.br\/site\/#\/schema\/logo\/image\/","url":"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2023\/01\/logo-folha-de-ms-380x90-1.jpg","contentUrl":"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2023\/01\/logo-folha-de-ms-380x90-1.jpg","width":380,"height":90,"caption":"Folha de Mato Grosso do Sul"},"image":{"@id":"https:\/\/folhadems.com.br\/site\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/folhadems.com.br\/site\/#\/schema\/person\/e4a04038e5c2e7040e19ef252ae9d940","name":"Elite Midia","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/folhadems.com.br\/site\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/f76a80f01119f7fec6909ab9feea8819031f391155be021b685479d77496f055?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f76a80f01119f7fec6909ab9feea8819031f391155be021b685479d77496f055?s=96&d=mm&r=g","caption":"Elite Midia"},"sameAs":["https:\/\/folhadems.com.br\/site"],"url":"https:\/\/folhadems.com.br\/site\/author\/elite-midia\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-20 12:13:24","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/posts\/13971","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/comments?post=13971"}],"version-history":[{"count":1,"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/posts\/13971\/revisions"}],"predecessor-version":[{"id":13973,"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/posts\/13971\/revisions\/13973"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/media\/13972"}],"wp:attachment":[{"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/media?parent=13971"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/categories?post=13971"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/tags?post=13971"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}