{"id":13968,"date":"2026-01-30T12:53:12","date_gmt":"2026-01-30T16:53:12","guid":{"rendered":"https:\/\/folhadems.com.br\/site\/?p=13968"},"modified":"2026-01-30T12:53:19","modified_gmt":"2026-01-30T16:53:19","slug":"a-todo-vapor-prefeitura-prepara-escolas-para-receber-alunos-em-2026","status":"publish","type":"post","link":"https:\/\/folhadems.com.br\/site\/2026\/01\/30\/a-todo-vapor-prefeitura-prepara-escolas-para-receber-alunos-em-2026\/","title":{"rendered":"A todo vapor: prefeitura prepara escolas para receber alunos em 2026"},"content":{"rendered":"\n<p>Com a proximidade do in\u00edcio do ano letivo de 2026, marcado para o dia 9 de fevereiro, a Prefeitura de Campo Grande intensificou os servi\u00e7os de manuten\u00e7\u00e3o nas escolas da Rede Municipal de Ensino.<\/p>\n\n\n\n<p>As a\u00e7\u00f5es s\u00e3o coordenadas pela Secretaria Municipal de Educa\u00e7\u00e3o, com apoio da Secretaria Municipal de Infraestrutura e Servi\u00e7os P\u00fablicos, e t\u00eam como objetivo garantir ambientes seguros, limpos e preparados para receber alunos e profissionais da educa\u00e7\u00e3o. At\u00e9 o momento, mais de oito mil matr\u00edculas j\u00e1 foram realizadas pela Semed.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/cdn.campogrande.ms.gov.br\/portal\/prod\/uploads\/sites\/3\/2027\/01\/WhatsApp-Image-2026-01-29-at-09.33.30-1024x684.jpeg\" alt=\"\" class=\"wp-image-156036\"\/><\/figure>\n\n\n\n<p>Na Escola Municipal Consulesa Margarida Maksoud Trad, os trabalhos est\u00e3o praticamente conclu\u00eddos. A unidade passou por limpeza, organiza\u00e7\u00e3o e manuten\u00e7\u00e3o predial, al\u00e9m de adequa\u00e7\u00f5es estruturais para atender cerca de 900 alunos no modelo de tempo integral.<\/p>\n\n\n\n<p>Segundo o diretor da escola, Orlando Rodrigues Peralta, o planejamento antecipado garante um in\u00edcio de ano mais tranquilo. \u201cEstamos totalmente preparados para receber os alunos. A escola est\u00e1 limpa, organizada e apta. J\u00e1 recebemos os alimentos, incluindo itens secos e prote\u00ednas, com freezer abastecido, al\u00e9m de arroz, feij\u00e3o, leite e macarr\u00e3o\u201d.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter\"><img decoding=\"async\" src=\"https:\/\/cdn.campogrande.ms.gov.br\/portal\/prod\/uploads\/sites\/3\/2027\/01\/diretor-da-escola.jpg\" alt=\"\" class=\"wp-image-156039\"\/><\/figure>\n<\/div>\n\n\n<p>Al\u00e9m da estrutura f\u00edsica, a escola tamb\u00e9m recebeu refor\u00e7o no quadro de profissionais. Professores tempor\u00e1rios, monitores e equipes de apoio j\u00e1 come\u00e7aram a integrar a rotina escolar.<\/p>\n\n\n\n<p>Desde 2018, a unidade vem passando por importantes transforma\u00e7\u00f5es estruturais e, para este ano, novas melhorias est\u00e3o previstas, como a revitaliza\u00e7\u00e3o dos banheiros, da quadra esportiva e a amplia\u00e7\u00e3o da cozinha.<\/p>\n\n\n\n<p>A Escola Municipal Consulesa Margarida Maksoud Trad oferece ensino integral do Grupo 5 ao 9\u00ba ano, al\u00e9m da Educa\u00e7\u00e3o de Jovens e Adultos no per\u00edodo noturno, ampliando as oportunidades educacionais para a comunidade.<\/p>\n\n\n\n<p>A prepara\u00e7\u00e3o da escola tamb\u00e9m \u00e9 reconhecida pelas fam\u00edlias. Como \u00e9 o caso da supervisora em uma empresa, Jessica Mariana Gon\u00e7alves, m\u00e3e da aluna Emilly Victoria, de 10 anos, que cursar\u00e1 o 5\u00ba ano, a evolu\u00e7\u00e3o da escola \u00e9 vis\u00edvel. \u201cEu j\u00e1 estudei aqui e hoje vejo o quanto a escola evoluiu. Est\u00e1 tudo organizado, as salas est\u00e3o preparadas. \u00c9 um trabalho bem feito\u201d.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter\"><img decoding=\"async\" src=\"https:\/\/cdn.campogrande.ms.gov.br\/portal\/prod\/uploads\/sites\/3\/2027\/01\/ESCOLA-1-1.jpg-576x1024.jpeg\" alt=\"\" class=\"wp-image-155972\"\/><\/figure>\n<\/div>\n\n\n<p>Em outro ponto da cidade, na Escola Municipal Arlindo Lima, tamb\u00e9m passa por manuten\u00e7\u00e3o, as equipes seguem fazendo a ro\u00e7ada no local para deixar tudo organizado para a chegada das crian\u00e7as.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter\"><img decoding=\"async\" src=\"https:\/\/cdn.campogrande.ms.gov.br\/portal\/prod\/uploads\/sites\/3\/2027\/01\/WhatsApp-Image-2026-01-29-at-09.17.12-1024x684.jpeg\" alt=\"\" class=\"wp-image-156040\"\/><\/figure>\n<\/div>\n\n\n<p><strong>Estrutura e manuten\u00e7\u00e3o<\/strong><\/p>\n\n\n\n<p>A Secretaria Municipal de Infraestrutura, por meio da concession\u00e1ria Solurb, realiza servi\u00e7os de ro\u00e7ada, limpeza e remo\u00e7\u00e3o de entulho em toda a rede, com atendimento m\u00e9dio de dez escolas por dia. Ao todo, s\u00e3o 206 unidades escolares.<\/p>\n\n\n\n<p>A Rede Municipal de Ensino conta com 99 escolas de Ensino Fundamental e 107 EMEIs. Embora o retorno dos alunos ocorra no dia 9, as equipes t\u00e9cnicas iniciam os trabalhos no dia 5 de fevereiro, preparando os \u00faltimos ajustes.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter\"><img decoding=\"async\" src=\"https:\/\/cdn.campogrande.ms.gov.br\/portal\/prod\/uploads\/sites\/3\/2027\/01\/WhatsApp-Image-2026-01-29-at-09.33.28-1-1024x684.jpeg\" alt=\"\" class=\"wp-image-156037\"\/><\/figure>\n<\/div>\n\n\n<p><strong>Matr\u00edculas seguem em andamento<\/strong><\/p>\n\n\n\n<p>A Semed segue com o processo de matr\u00edculas para novos alunos e para aqueles que n\u00e3o realizaram a rematr\u00edcula no prazo. As solicita\u00e7\u00f5es devem ser feitas pelo site <a href=\"http:\/\/matricula.campogrande.ms.gov.br\" target=\"_blank\" rel=\"noopener\">matricula.campogrande.ms.gov.br<\/a>.<\/p>\n\n\n\n<p>Em caso de d\u00favidas, pais e respons\u00e1veis podem procurar a Central Municipal de Matr\u00edculas pelo telefone 0800 615 1515. O processo \u00e9 gratuito.<\/p>\n\n\n\n<p><strong><em>Fonte: PrefCG<\/em><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Com a proximidade do in\u00edcio do ano letivo de 2026, marcado para o dia 9 de fevereiro, a Prefeitura de<\/p>\n","protected":false},"author":1,"featured_media":13969,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14],"tags":[],"class_list":["post-13968","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-educacao"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.1.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>A todo vapor: prefeitura prepara escolas para receber alunos em 2026 - Folha de Mato Grosso do Sul<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/folhadems.com.br\/site\/2026\/01\/30\/a-todo-vapor-prefeitura-prepara-escolas-para-receber-alunos-em-2026\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"A todo vapor: prefeitura prepara escolas para receber alunos em 2026 - Folha de Mato Grosso do Sul\" \/>\n<meta property=\"og:description\" content=\"Com a proximidade do in\u00edcio do ano letivo de 2026, marcado para o dia 9 de fevereiro, a Prefeitura de\" \/>\n<meta property=\"og:url\" content=\"https:\/\/folhadems.com.br\/site\/2026\/01\/30\/a-todo-vapor-prefeitura-prepara-escolas-para-receber-alunos-em-2026\/\" \/>\n<meta property=\"og:site_name\" content=\"Folha de Mato Grosso do Sul\" \/>\n<meta property=\"article:published_time\" content=\"2026-01-30T16:53:12+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-30T16:53:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2026\/01\/aulas.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"1068\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Elite Midia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Elite Midia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/folhadems.com.br\/site\/2026\/01\/30\/a-todo-vapor-prefeitura-prepara-escolas-para-receber-alunos-em-2026\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/folhadems.com.br\/site\/2026\/01\/30\/a-todo-vapor-prefeitura-prepara-escolas-para-receber-alunos-em-2026\/\"},\"author\":{\"name\":\"Elite Midia\",\"@id\":\"https:\/\/folhadems.com.br\/site\/#\/schema\/person\/e4a04038e5c2e7040e19ef252ae9d940\"},\"headline\":\"A todo vapor: prefeitura prepara escolas para receber alunos em 2026\",\"datePublished\":\"2026-01-30T16:53:12+00:00\",\"dateModified\":\"2026-01-30T16:53:19+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/folhadems.com.br\/site\/2026\/01\/30\/a-todo-vapor-prefeitura-prepara-escolas-para-receber-alunos-em-2026\/\"},\"wordCount\":549,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/folhadems.com.br\/site\/#organization\"},\"image\":{\"@id\":\"https:\/\/folhadems.com.br\/site\/2026\/01\/30\/a-todo-vapor-prefeitura-prepara-escolas-para-receber-alunos-em-2026\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2026\/01\/aulas.jpeg\",\"articleSection\":[\"Educa\u00e7\u00e3o\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/folhadems.com.br\/site\/2026\/01\/30\/a-todo-vapor-prefeitura-prepara-escolas-para-receber-alunos-em-2026\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/folhadems.com.br\/site\/2026\/01\/30\/a-todo-vapor-prefeitura-prepara-escolas-para-receber-alunos-em-2026\/\",\"url\":\"https:\/\/folhadems.com.br\/site\/2026\/01\/30\/a-todo-vapor-prefeitura-prepara-escolas-para-receber-alunos-em-2026\/\",\"name\":\"A todo vapor: prefeitura prepara escolas para receber alunos em 2026 - Folha de Mato Grosso do Sul\",\"isPartOf\":{\"@id\":\"https:\/\/folhadems.com.br\/site\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/folhadems.com.br\/site\/2026\/01\/30\/a-todo-vapor-prefeitura-prepara-escolas-para-receber-alunos-em-2026\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/folhadems.com.br\/site\/2026\/01\/30\/a-todo-vapor-prefeitura-prepara-escolas-para-receber-alunos-em-2026\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2026\/01\/aulas.jpeg\",\"datePublished\":\"2026-01-30T16:53:12+00:00\",\"dateModified\":\"2026-01-30T16:53:19+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/folhadems.com.br\/site\/2026\/01\/30\/a-todo-vapor-prefeitura-prepara-escolas-para-receber-alunos-em-2026\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/folhadems.com.br\/site\/2026\/01\/30\/a-todo-vapor-prefeitura-prepara-escolas-para-receber-alunos-em-2026\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/folhadems.com.br\/site\/2026\/01\/30\/a-todo-vapor-prefeitura-prepara-escolas-para-receber-alunos-em-2026\/#primaryimage\",\"url\":\"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2026\/01\/aulas.jpeg\",\"contentUrl\":\"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2026\/01\/aulas.jpeg\",\"width\":1600,\"height\":1068},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/folhadems.com.br\/site\/2026\/01\/30\/a-todo-vapor-prefeitura-prepara-escolas-para-receber-alunos-em-2026\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/folhadems.com.br\/site\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"A todo vapor: prefeitura prepara escolas para receber alunos em 2026\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/folhadems.com.br\/site\/#website\",\"url\":\"https:\/\/folhadems.com.br\/site\/\",\"name\":\"Folha de Mato Grosso do Sul\",\"description\":\"Jornal Online\",\"publisher\":{\"@id\":\"https:\/\/folhadems.com.br\/site\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/folhadems.com.br\/site\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/folhadems.com.br\/site\/#organization\",\"name\":\"Folha de Mato Grosso do Sul\",\"url\":\"https:\/\/folhadems.com.br\/site\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/folhadems.com.br\/site\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2023\/01\/logo-folha-de-ms-380x90-1.jpg\",\"contentUrl\":\"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2023\/01\/logo-folha-de-ms-380x90-1.jpg\",\"width\":380,\"height\":90,\"caption\":\"Folha de Mato Grosso do Sul\"},\"image\":{\"@id\":\"https:\/\/folhadems.com.br\/site\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/folhadems.com.br\/site\/#\/schema\/person\/e4a04038e5c2e7040e19ef252ae9d940\",\"name\":\"Elite Midia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/folhadems.com.br\/site\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/f76a80f01119f7fec6909ab9feea8819031f391155be021b685479d77496f055?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/f76a80f01119f7fec6909ab9feea8819031f391155be021b685479d77496f055?s=96&d=mm&r=g\",\"caption\":\"Elite Midia\"},\"sameAs\":[\"https:\/\/folhadems.com.br\/site\"],\"url\":\"https:\/\/folhadems.com.br\/site\/author\/elite-midia\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"A todo vapor: prefeitura prepara escolas para receber alunos em 2026 - Folha de Mato Grosso do Sul","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/folhadems.com.br\/site\/2026\/01\/30\/a-todo-vapor-prefeitura-prepara-escolas-para-receber-alunos-em-2026\/","og_locale":"pt_BR","og_type":"article","og_title":"A todo vapor: prefeitura prepara escolas para receber alunos em 2026 - Folha de Mato Grosso do Sul","og_description":"Com a proximidade do in\u00edcio do ano letivo de 2026, marcado para o dia 9 de fevereiro, a Prefeitura de","og_url":"https:\/\/folhadems.com.br\/site\/2026\/01\/30\/a-todo-vapor-prefeitura-prepara-escolas-para-receber-alunos-em-2026\/","og_site_name":"Folha de Mato Grosso do Sul","article_published_time":"2026-01-30T16:53:12+00:00","article_modified_time":"2026-01-30T16:53:19+00:00","og_image":[{"width":1600,"height":1068,"url":"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2026\/01\/aulas.jpeg","type":"image\/jpeg"}],"author":"Elite Midia","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Elite Midia","Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/folhadems.com.br\/site\/2026\/01\/30\/a-todo-vapor-prefeitura-prepara-escolas-para-receber-alunos-em-2026\/#article","isPartOf":{"@id":"https:\/\/folhadems.com.br\/site\/2026\/01\/30\/a-todo-vapor-prefeitura-prepara-escolas-para-receber-alunos-em-2026\/"},"author":{"name":"Elite Midia","@id":"https:\/\/folhadems.com.br\/site\/#\/schema\/person\/e4a04038e5c2e7040e19ef252ae9d940"},"headline":"A todo vapor: prefeitura prepara escolas para receber alunos em 2026","datePublished":"2026-01-30T16:53:12+00:00","dateModified":"2026-01-30T16:53:19+00:00","mainEntityOfPage":{"@id":"https:\/\/folhadems.com.br\/site\/2026\/01\/30\/a-todo-vapor-prefeitura-prepara-escolas-para-receber-alunos-em-2026\/"},"wordCount":549,"commentCount":0,"publisher":{"@id":"https:\/\/folhadems.com.br\/site\/#organization"},"image":{"@id":"https:\/\/folhadems.com.br\/site\/2026\/01\/30\/a-todo-vapor-prefeitura-prepara-escolas-para-receber-alunos-em-2026\/#primaryimage"},"thumbnailUrl":"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2026\/01\/aulas.jpeg","articleSection":["Educa\u00e7\u00e3o"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/folhadems.com.br\/site\/2026\/01\/30\/a-todo-vapor-prefeitura-prepara-escolas-para-receber-alunos-em-2026\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/folhadems.com.br\/site\/2026\/01\/30\/a-todo-vapor-prefeitura-prepara-escolas-para-receber-alunos-em-2026\/","url":"https:\/\/folhadems.com.br\/site\/2026\/01\/30\/a-todo-vapor-prefeitura-prepara-escolas-para-receber-alunos-em-2026\/","name":"A todo vapor: prefeitura prepara escolas para receber alunos em 2026 - Folha de Mato Grosso do Sul","isPartOf":{"@id":"https:\/\/folhadems.com.br\/site\/#website"},"primaryImageOfPage":{"@id":"https:\/\/folhadems.com.br\/site\/2026\/01\/30\/a-todo-vapor-prefeitura-prepara-escolas-para-receber-alunos-em-2026\/#primaryimage"},"image":{"@id":"https:\/\/folhadems.com.br\/site\/2026\/01\/30\/a-todo-vapor-prefeitura-prepara-escolas-para-receber-alunos-em-2026\/#primaryimage"},"thumbnailUrl":"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2026\/01\/aulas.jpeg","datePublished":"2026-01-30T16:53:12+00:00","dateModified":"2026-01-30T16:53:19+00:00","breadcrumb":{"@id":"https:\/\/folhadems.com.br\/site\/2026\/01\/30\/a-todo-vapor-prefeitura-prepara-escolas-para-receber-alunos-em-2026\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/folhadems.com.br\/site\/2026\/01\/30\/a-todo-vapor-prefeitura-prepara-escolas-para-receber-alunos-em-2026\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/folhadems.com.br\/site\/2026\/01\/30\/a-todo-vapor-prefeitura-prepara-escolas-para-receber-alunos-em-2026\/#primaryimage","url":"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2026\/01\/aulas.jpeg","contentUrl":"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2026\/01\/aulas.jpeg","width":1600,"height":1068},{"@type":"BreadcrumbList","@id":"https:\/\/folhadems.com.br\/site\/2026\/01\/30\/a-todo-vapor-prefeitura-prepara-escolas-para-receber-alunos-em-2026\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/folhadems.com.br\/site\/"},{"@type":"ListItem","position":2,"name":"A todo vapor: prefeitura prepara escolas para receber alunos em 2026"}]},{"@type":"WebSite","@id":"https:\/\/folhadems.com.br\/site\/#website","url":"https:\/\/folhadems.com.br\/site\/","name":"Folha de Mato Grosso do Sul","description":"Jornal Online","publisher":{"@id":"https:\/\/folhadems.com.br\/site\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/folhadems.com.br\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/folhadems.com.br\/site\/#organization","name":"Folha de Mato Grosso do Sul","url":"https:\/\/folhadems.com.br\/site\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/folhadems.com.br\/site\/#\/schema\/logo\/image\/","url":"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2023\/01\/logo-folha-de-ms-380x90-1.jpg","contentUrl":"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2023\/01\/logo-folha-de-ms-380x90-1.jpg","width":380,"height":90,"caption":"Folha de Mato Grosso do Sul"},"image":{"@id":"https:\/\/folhadems.com.br\/site\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/folhadems.com.br\/site\/#\/schema\/person\/e4a04038e5c2e7040e19ef252ae9d940","name":"Elite Midia","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/folhadems.com.br\/site\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/f76a80f01119f7fec6909ab9feea8819031f391155be021b685479d77496f055?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f76a80f01119f7fec6909ab9feea8819031f391155be021b685479d77496f055?s=96&d=mm&r=g","caption":"Elite Midia"},"sameAs":["https:\/\/folhadems.com.br\/site"],"url":"https:\/\/folhadems.com.br\/site\/author\/elite-midia\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-20 13:12:28","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/posts\/13968","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/comments?post=13968"}],"version-history":[{"count":1,"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/posts\/13968\/revisions"}],"predecessor-version":[{"id":13970,"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/posts\/13968\/revisions\/13970"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/media\/13969"}],"wp:attachment":[{"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/media?parent=13968"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/categories?post=13968"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/tags?post=13968"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}