{"id":13855,"date":"2026-01-26T08:39:06","date_gmt":"2026-01-26T12:39:06","guid":{"rendered":"https:\/\/folhadems.com.br\/site\/?p=13855"},"modified":"2026-01-26T08:39:13","modified_gmt":"2026-01-26T12:39:13","slug":"funsat-oferta-1-213-vagas-nesta-segunda-feira-26","status":"publish","type":"post","link":"https:\/\/folhadems.com.br\/site\/2026\/01\/26\/funsat-oferta-1-213-vagas-nesta-segunda-feira-26\/","title":{"rendered":"Funsat oferta 1.213 vagas nesta segunda-feira (26)"},"content":{"rendered":"\n<p>A Ag\u00eancia de Empregos da Funda\u00e7\u00e3o Social do Trabalho (Funsat) oferece, nesta segunda-feira (26), um total de 1.213 vagas. As oportunidades s\u00e3o anunciadas por 128 empresas de Campo Grande, que buscam profissionais para 113 fun\u00e7\u00f5es diferentes.<\/p>\n\n\n\n<p>Grande parte das vagas \u00e9 classificada como de \u201coportunidade \u00fanica\u201d, com sele\u00e7\u00f5es abertas para cargos como ajudante de cozinha, ajudante de serralheiro, assistente social, auxiliar de lavanderia, bab\u00e1, desenhista projetista da constru\u00e7\u00e3o civil, gerente comercial, gerente de supermercado, motorista de autom\u00f3vel, office boy e operador de caldeira.<\/p>\n\n\n\n<p>J\u00e1 859 vagas s\u00e3o destinadas a candidatos que poder\u00e3o receber treinamento remunerado. Entre as fun\u00e7\u00f5es est\u00e3o atendente de lojas e mercados (31 vagas), auxiliar nos servi\u00e7os de alimenta\u00e7\u00e3o (66), estoquista (17), leiturista (10), repositor de mercadorias (67) e trabalhador da extra\u00e7\u00e3o vegetal (20).<\/p>\n\n\n\n<p>Sem exig\u00eancia de experi\u00eancia, a Ag\u00eancia tamb\u00e9m disponibiliza 42 vagas tempor\u00e1rias, distribu\u00eddas em cinco fun\u00e7\u00f5es. H\u00e1 ainda oportunidades com recrutamento priorit\u00e1rio para pessoas com defici\u00eancia (PCD), com atendimento espec\u00edfico no Guich\u00ea 1. Para participar dos processos seletivos, \u00e9 necess\u00e1rio manter o cadastro atualizado.<\/p>\n\n\n\n<p>A Funsat est\u00e1 localizada na Rua 14 de Julho, n\u00ba 992, Vila Gl\u00f3ria, com atendimento de segunda a sexta-feira, das 7h \u00e0s 16h. Mais informa\u00e7\u00f5es podem ser obtidas nas redes sociais da Funda\u00e7\u00e3o, no Instagram (@funsat.cg) e no Facebook (Funsatcampograndems), ou pelo telefone (67) 4042-0585, ramal 5837.<\/p>\n\n\n\n<p>Confira o Painel de Intermedia\u00e7\u00e3o completo: <a href=\"https:\/\/www.campogrande.ms.gov.br\/funsat\/sec-artigos\/vagas-ofertadas\/\" target=\"_blank\" rel=\"noopener\">https:\/\/www.campogrande.ms.gov.br\/funsat\/sec-artigos\/vagas-ofertadas\/<\/a><\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/cdn.campogrande.ms.gov.br\/portal\/prod\/uploads\/sites\/3\/2026\/01\/IMG-20260123-WA0024-821x1024.jpg\" alt=\"\" class=\"wp-image-155909\"\/><\/figure>\n\n\n\n<p><strong><em>Fonte: PrefCG<\/em><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Ag\u00eancia de Empregos da Funda\u00e7\u00e3o Social do Trabalho (Funsat) oferece, nesta segunda-feira (26), um total de 1.213 vagas. As<\/p>\n","protected":false},"author":1,"featured_media":4560,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[26],"tags":[],"class_list":["post-13855","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cotidiano"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.1.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Funsat oferta 1.213 vagas nesta segunda-feira (26) - Folha de Mato Grosso do Sul<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/folhadems.com.br\/site\/2026\/01\/26\/funsat-oferta-1-213-vagas-nesta-segunda-feira-26\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Funsat oferta 1.213 vagas nesta segunda-feira (26) - Folha de Mato Grosso do Sul\" \/>\n<meta property=\"og:description\" content=\"A Ag\u00eancia de Empregos da Funda\u00e7\u00e3o Social do Trabalho (Funsat) oferece, nesta segunda-feira (26), um total de 1.213 vagas. As\" \/>\n<meta property=\"og:url\" content=\"https:\/\/folhadems.com.br\/site\/2026\/01\/26\/funsat-oferta-1-213-vagas-nesta-segunda-feira-26\/\" \/>\n<meta property=\"og:site_name\" content=\"Folha de Mato Grosso do Sul\" \/>\n<meta property=\"article:published_time\" content=\"2026-01-26T12:39:06+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-26T12:39:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2023\/12\/feirao-funsat.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"450\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Elite Midia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Elite Midia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/folhadems.com.br\/site\/2026\/01\/26\/funsat-oferta-1-213-vagas-nesta-segunda-feira-26\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/folhadems.com.br\/site\/2026\/01\/26\/funsat-oferta-1-213-vagas-nesta-segunda-feira-26\/\"},\"author\":{\"name\":\"Elite Midia\",\"@id\":\"https:\/\/folhadems.com.br\/site\/#\/schema\/person\/e4a04038e5c2e7040e19ef252ae9d940\"},\"headline\":\"Funsat oferta 1.213 vagas nesta segunda-feira (26)\",\"datePublished\":\"2026-01-26T12:39:06+00:00\",\"dateModified\":\"2026-01-26T12:39:13+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/folhadems.com.br\/site\/2026\/01\/26\/funsat-oferta-1-213-vagas-nesta-segunda-feira-26\/\"},\"wordCount\":249,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/folhadems.com.br\/site\/#organization\"},\"image\":{\"@id\":\"https:\/\/folhadems.com.br\/site\/2026\/01\/26\/funsat-oferta-1-213-vagas-nesta-segunda-feira-26\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2023\/12\/feirao-funsat.jpg\",\"articleSection\":[\"Cotidiano\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/folhadems.com.br\/site\/2026\/01\/26\/funsat-oferta-1-213-vagas-nesta-segunda-feira-26\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/folhadems.com.br\/site\/2026\/01\/26\/funsat-oferta-1-213-vagas-nesta-segunda-feira-26\/\",\"url\":\"https:\/\/folhadems.com.br\/site\/2026\/01\/26\/funsat-oferta-1-213-vagas-nesta-segunda-feira-26\/\",\"name\":\"Funsat oferta 1.213 vagas nesta segunda-feira (26) - Folha de Mato Grosso do Sul\",\"isPartOf\":{\"@id\":\"https:\/\/folhadems.com.br\/site\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/folhadems.com.br\/site\/2026\/01\/26\/funsat-oferta-1-213-vagas-nesta-segunda-feira-26\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/folhadems.com.br\/site\/2026\/01\/26\/funsat-oferta-1-213-vagas-nesta-segunda-feira-26\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2023\/12\/feirao-funsat.jpg\",\"datePublished\":\"2026-01-26T12:39:06+00:00\",\"dateModified\":\"2026-01-26T12:39:13+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/folhadems.com.br\/site\/2026\/01\/26\/funsat-oferta-1-213-vagas-nesta-segunda-feira-26\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/folhadems.com.br\/site\/2026\/01\/26\/funsat-oferta-1-213-vagas-nesta-segunda-feira-26\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/folhadems.com.br\/site\/2026\/01\/26\/funsat-oferta-1-213-vagas-nesta-segunda-feira-26\/#primaryimage\",\"url\":\"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2023\/12\/feirao-funsat.jpg\",\"contentUrl\":\"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2023\/12\/feirao-funsat.jpg\",\"width\":800,\"height\":450},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/folhadems.com.br\/site\/2026\/01\/26\/funsat-oferta-1-213-vagas-nesta-segunda-feira-26\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/folhadems.com.br\/site\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Funsat oferta 1.213 vagas nesta segunda-feira (26)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/folhadems.com.br\/site\/#website\",\"url\":\"https:\/\/folhadems.com.br\/site\/\",\"name\":\"Folha de Mato Grosso do Sul\",\"description\":\"Jornal Online\",\"publisher\":{\"@id\":\"https:\/\/folhadems.com.br\/site\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/folhadems.com.br\/site\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/folhadems.com.br\/site\/#organization\",\"name\":\"Folha de Mato Grosso do Sul\",\"url\":\"https:\/\/folhadems.com.br\/site\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/folhadems.com.br\/site\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2023\/01\/logo-folha-de-ms-380x90-1.jpg\",\"contentUrl\":\"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2023\/01\/logo-folha-de-ms-380x90-1.jpg\",\"width\":380,\"height\":90,\"caption\":\"Folha de Mato Grosso do Sul\"},\"image\":{\"@id\":\"https:\/\/folhadems.com.br\/site\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/folhadems.com.br\/site\/#\/schema\/person\/e4a04038e5c2e7040e19ef252ae9d940\",\"name\":\"Elite Midia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/folhadems.com.br\/site\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/f76a80f01119f7fec6909ab9feea8819031f391155be021b685479d77496f055?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/f76a80f01119f7fec6909ab9feea8819031f391155be021b685479d77496f055?s=96&d=mm&r=g\",\"caption\":\"Elite Midia\"},\"sameAs\":[\"https:\/\/folhadems.com.br\/site\"],\"url\":\"https:\/\/folhadems.com.br\/site\/author\/elite-midia\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Funsat oferta 1.213 vagas nesta segunda-feira (26) - Folha de Mato Grosso do Sul","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/folhadems.com.br\/site\/2026\/01\/26\/funsat-oferta-1-213-vagas-nesta-segunda-feira-26\/","og_locale":"pt_BR","og_type":"article","og_title":"Funsat oferta 1.213 vagas nesta segunda-feira (26) - Folha de Mato Grosso do Sul","og_description":"A Ag\u00eancia de Empregos da Funda\u00e7\u00e3o Social do Trabalho (Funsat) oferece, nesta segunda-feira (26), um total de 1.213 vagas. As","og_url":"https:\/\/folhadems.com.br\/site\/2026\/01\/26\/funsat-oferta-1-213-vagas-nesta-segunda-feira-26\/","og_site_name":"Folha de Mato Grosso do Sul","article_published_time":"2026-01-26T12:39:06+00:00","article_modified_time":"2026-01-26T12:39:13+00:00","og_image":[{"width":800,"height":450,"url":"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2023\/12\/feirao-funsat.jpg","type":"image\/jpeg"}],"author":"Elite Midia","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Elite Midia","Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/folhadems.com.br\/site\/2026\/01\/26\/funsat-oferta-1-213-vagas-nesta-segunda-feira-26\/#article","isPartOf":{"@id":"https:\/\/folhadems.com.br\/site\/2026\/01\/26\/funsat-oferta-1-213-vagas-nesta-segunda-feira-26\/"},"author":{"name":"Elite Midia","@id":"https:\/\/folhadems.com.br\/site\/#\/schema\/person\/e4a04038e5c2e7040e19ef252ae9d940"},"headline":"Funsat oferta 1.213 vagas nesta segunda-feira (26)","datePublished":"2026-01-26T12:39:06+00:00","dateModified":"2026-01-26T12:39:13+00:00","mainEntityOfPage":{"@id":"https:\/\/folhadems.com.br\/site\/2026\/01\/26\/funsat-oferta-1-213-vagas-nesta-segunda-feira-26\/"},"wordCount":249,"commentCount":0,"publisher":{"@id":"https:\/\/folhadems.com.br\/site\/#organization"},"image":{"@id":"https:\/\/folhadems.com.br\/site\/2026\/01\/26\/funsat-oferta-1-213-vagas-nesta-segunda-feira-26\/#primaryimage"},"thumbnailUrl":"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2023\/12\/feirao-funsat.jpg","articleSection":["Cotidiano"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/folhadems.com.br\/site\/2026\/01\/26\/funsat-oferta-1-213-vagas-nesta-segunda-feira-26\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/folhadems.com.br\/site\/2026\/01\/26\/funsat-oferta-1-213-vagas-nesta-segunda-feira-26\/","url":"https:\/\/folhadems.com.br\/site\/2026\/01\/26\/funsat-oferta-1-213-vagas-nesta-segunda-feira-26\/","name":"Funsat oferta 1.213 vagas nesta segunda-feira (26) - Folha de Mato Grosso do Sul","isPartOf":{"@id":"https:\/\/folhadems.com.br\/site\/#website"},"primaryImageOfPage":{"@id":"https:\/\/folhadems.com.br\/site\/2026\/01\/26\/funsat-oferta-1-213-vagas-nesta-segunda-feira-26\/#primaryimage"},"image":{"@id":"https:\/\/folhadems.com.br\/site\/2026\/01\/26\/funsat-oferta-1-213-vagas-nesta-segunda-feira-26\/#primaryimage"},"thumbnailUrl":"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2023\/12\/feirao-funsat.jpg","datePublished":"2026-01-26T12:39:06+00:00","dateModified":"2026-01-26T12:39:13+00:00","breadcrumb":{"@id":"https:\/\/folhadems.com.br\/site\/2026\/01\/26\/funsat-oferta-1-213-vagas-nesta-segunda-feira-26\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/folhadems.com.br\/site\/2026\/01\/26\/funsat-oferta-1-213-vagas-nesta-segunda-feira-26\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/folhadems.com.br\/site\/2026\/01\/26\/funsat-oferta-1-213-vagas-nesta-segunda-feira-26\/#primaryimage","url":"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2023\/12\/feirao-funsat.jpg","contentUrl":"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2023\/12\/feirao-funsat.jpg","width":800,"height":450},{"@type":"BreadcrumbList","@id":"https:\/\/folhadems.com.br\/site\/2026\/01\/26\/funsat-oferta-1-213-vagas-nesta-segunda-feira-26\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/folhadems.com.br\/site\/"},{"@type":"ListItem","position":2,"name":"Funsat oferta 1.213 vagas nesta segunda-feira (26)"}]},{"@type":"WebSite","@id":"https:\/\/folhadems.com.br\/site\/#website","url":"https:\/\/folhadems.com.br\/site\/","name":"Folha de Mato Grosso do Sul","description":"Jornal Online","publisher":{"@id":"https:\/\/folhadems.com.br\/site\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/folhadems.com.br\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/folhadems.com.br\/site\/#organization","name":"Folha de Mato Grosso do Sul","url":"https:\/\/folhadems.com.br\/site\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/folhadems.com.br\/site\/#\/schema\/logo\/image\/","url":"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2023\/01\/logo-folha-de-ms-380x90-1.jpg","contentUrl":"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2023\/01\/logo-folha-de-ms-380x90-1.jpg","width":380,"height":90,"caption":"Folha de Mato Grosso do Sul"},"image":{"@id":"https:\/\/folhadems.com.br\/site\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/folhadems.com.br\/site\/#\/schema\/person\/e4a04038e5c2e7040e19ef252ae9d940","name":"Elite Midia","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/folhadems.com.br\/site\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/f76a80f01119f7fec6909ab9feea8819031f391155be021b685479d77496f055?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f76a80f01119f7fec6909ab9feea8819031f391155be021b685479d77496f055?s=96&d=mm&r=g","caption":"Elite Midia"},"sameAs":["https:\/\/folhadems.com.br\/site"],"url":"https:\/\/folhadems.com.br\/site\/author\/elite-midia\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-20 14:47:31","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/posts\/13855","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/comments?post=13855"}],"version-history":[{"count":1,"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/posts\/13855\/revisions"}],"predecessor-version":[{"id":13856,"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/posts\/13855\/revisions\/13856"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/media\/4560"}],"wp:attachment":[{"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/media?parent=13855"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/categories?post=13855"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/tags?post=13855"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}