{"id":13835,"date":"2026-01-24T16:43:00","date_gmt":"2026-01-24T20:43:00","guid":{"rendered":"https:\/\/folhadems.com.br\/site\/?p=13835"},"modified":"2026-01-24T23:55:41","modified_gmt":"2026-01-25T03:55:41","slug":"aberto-o-primeiro-leilao-do-ano-do-detran-ms-com-vw-up-2015-e-honda-cg","status":"publish","type":"post","link":"https:\/\/folhadems.com.br\/site\/2026\/01\/24\/aberto-o-primeiro-leilao-do-ano-do-detran-ms-com-vw-up-2015-e-honda-cg\/","title":{"rendered":"Aberto o primeiro leil\u00e3o do ano do Detran-MS com VW\/Up 2015 e Honda CG"},"content":{"rendered":"\n<p>O primeiro leil\u00e3o de 2026 do Detran-MS, sob responsabilidade do leiloeiro Carlos Ferrari, de ve\u00edculos de circula\u00e7\u00e3o, sucatas aproveit\u00e1veis e sucatas inserv\u00edveis, foi aberto na quarta-feira, 21 de janeiro, \u00e0s 9h (hor\u00e1rio de Mato Grosso do Sul), e segue at\u00e9 o dia 5 de fevereiro, \u00e0s 9h30 (hor\u00e1rio de Mato Grosso do Sul).<\/p>\n\n\n\n<p>No total, s\u00e3o ofertados 147 lotes de motocicletas e autom\u00f3veis, al\u00e9m de um lote com material ferroso. Os ve\u00edculos foram apreendidos e recolhidos em 10 munic\u00edpios de Mato Grosso do Sul, e os propriet\u00e1rios n\u00e3o efetuaram a retirada dos bens dos p\u00e1tios.<\/p>\n\n\n\n<p>Os lances podem ser realizados pelo site <a href=\"http:\/\/www.carloferrarileiloes.com.br\" target=\"_blank\" rel=\"noopener\">www.carloferrarileiloes.com.br<\/a>. A visita\u00e7\u00e3o aos lotes poder\u00e1 ser feita nos dias 2, 3 e 4 de fevereiro, no p\u00e1tio da Autotran, localizado na Avenida Gerval Bernardino de Souza, n\u00ba 644, no bairro Rita Vieira, das 8h \u00e0s 11h e das 13h30 \u00e0s 16h30.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"alignleft\"><a href=\"https:\/\/www.detran.ms.gov.br\/wp-content\/uploads\/2026\/01\/Honda-Cg-160-fan-LT.35.jpg\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" src=\"https:\/\/www.detran.ms.gov.br\/wp-content\/uploads\/2026\/01\/Honda-Cg-160-fan-LT.35-300x225.jpg\" alt=\"\" class=\"wp-image-43130\"\/><\/a><\/figure>\n<\/div>\n\n\n<p>Na categoria Circula\u00e7\u00e3o, estar\u00e3o dispon\u00edveis 108 lotes, sendo 78 motocicletas e 30 autom\u00f3veis. Entre os ve\u00edculos ofertados est\u00e3o um VW\/Up 2014\/2015, na cor vermelha, com lance inicial de R$ 8.653,00, e uma Honda CG 2021\/2022, tamb\u00e9m na cor vermelha, com lance inicial de R$ 3.702,00. Qualquer pessoa f\u00edsica ou jur\u00eddica pode ofertar lances nessa categoria.<\/p>\n\n\n\n<p>J\u00e1 na categoria Sucatas Aproveit\u00e1veis, apenas pessoas jur\u00eddicas devidamente credenciadas em qualquer Detran do pa\u00eds podem ofertar lances nos 39 lotes, que somam 59 motocicletas e 27 autom\u00f3veis.<\/p>\n\n\n\n<p>O lote \u00fanico de Sucatas Inserv\u00edveis conta com 17 motocicletas e 7 autom\u00f3veis, totalizando aproximadamente 16.830 kg de material ferroso. Podem participar apenas pessoas jur\u00eddicas que atuem nos ramos de siderurgia, fundi\u00e7\u00e3o ou reciclagem, devidamente credenciadas no Detran-MS.<\/p>\n\n\n\n<p><em>Rodrigo Maia<\/em><strong><em>, <\/em><\/strong><em>Comunica\u00e7\u00e3o Detran-MS<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O primeiro leil\u00e3o de 2026 do Detran-MS, sob responsabilidade do leiloeiro Carlos Ferrari, de ve\u00edculos de circula\u00e7\u00e3o, sucatas aproveit\u00e1veis e<\/p>\n","protected":false},"author":1,"featured_media":13836,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[26],"tags":[],"class_list":["post-13835","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cotidiano"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.1.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Aberto o primeiro leil\u00e3o do ano do Detran-MS com VW\/Up 2015 e Honda CG - Folha de Mato Grosso do Sul<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/folhadems.com.br\/site\/2026\/01\/24\/aberto-o-primeiro-leilao-do-ano-do-detran-ms-com-vw-up-2015-e-honda-cg\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Aberto o primeiro leil\u00e3o do ano do Detran-MS com VW\/Up 2015 e Honda CG - Folha de Mato Grosso do Sul\" \/>\n<meta property=\"og:description\" content=\"O primeiro leil\u00e3o de 2026 do Detran-MS, sob responsabilidade do leiloeiro Carlos Ferrari, de ve\u00edculos de circula\u00e7\u00e3o, sucatas aproveit\u00e1veis e\" \/>\n<meta property=\"og:url\" content=\"https:\/\/folhadems.com.br\/site\/2026\/01\/24\/aberto-o-primeiro-leilao-do-ano-do-detran-ms-com-vw-up-2015-e-honda-cg\/\" \/>\n<meta property=\"og:site_name\" content=\"Folha de Mato Grosso do Sul\" \/>\n<meta property=\"article:published_time\" content=\"2026-01-24T20:43:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-25T03:55:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2026\/01\/up.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"730\" \/>\n\t<meta property=\"og:image:height\" content=\"480\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Elite Midia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Elite Midia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/folhadems.com.br\/site\/2026\/01\/24\/aberto-o-primeiro-leilao-do-ano-do-detran-ms-com-vw-up-2015-e-honda-cg\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/folhadems.com.br\/site\/2026\/01\/24\/aberto-o-primeiro-leilao-do-ano-do-detran-ms-com-vw-up-2015-e-honda-cg\/\"},\"author\":{\"name\":\"Elite Midia\",\"@id\":\"https:\/\/folhadems.com.br\/site\/#\/schema\/person\/e4a04038e5c2e7040e19ef252ae9d940\"},\"headline\":\"Aberto o primeiro leil\u00e3o do ano do Detran-MS com VW\/Up 2015 e Honda CG\",\"datePublished\":\"2026-01-24T20:43:00+00:00\",\"dateModified\":\"2026-01-25T03:55:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/folhadems.com.br\/site\/2026\/01\/24\/aberto-o-primeiro-leilao-do-ano-do-detran-ms-com-vw-up-2015-e-honda-cg\/\"},\"wordCount\":301,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/folhadems.com.br\/site\/#organization\"},\"image\":{\"@id\":\"https:\/\/folhadems.com.br\/site\/2026\/01\/24\/aberto-o-primeiro-leilao-do-ano-do-detran-ms-com-vw-up-2015-e-honda-cg\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2026\/01\/up.jpg\",\"articleSection\":[\"Cotidiano\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/folhadems.com.br\/site\/2026\/01\/24\/aberto-o-primeiro-leilao-do-ano-do-detran-ms-com-vw-up-2015-e-honda-cg\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/folhadems.com.br\/site\/2026\/01\/24\/aberto-o-primeiro-leilao-do-ano-do-detran-ms-com-vw-up-2015-e-honda-cg\/\",\"url\":\"https:\/\/folhadems.com.br\/site\/2026\/01\/24\/aberto-o-primeiro-leilao-do-ano-do-detran-ms-com-vw-up-2015-e-honda-cg\/\",\"name\":\"Aberto o primeiro leil\u00e3o do ano do Detran-MS com VW\/Up 2015 e Honda CG - Folha de Mato Grosso do Sul\",\"isPartOf\":{\"@id\":\"https:\/\/folhadems.com.br\/site\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/folhadems.com.br\/site\/2026\/01\/24\/aberto-o-primeiro-leilao-do-ano-do-detran-ms-com-vw-up-2015-e-honda-cg\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/folhadems.com.br\/site\/2026\/01\/24\/aberto-o-primeiro-leilao-do-ano-do-detran-ms-com-vw-up-2015-e-honda-cg\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2026\/01\/up.jpg\",\"datePublished\":\"2026-01-24T20:43:00+00:00\",\"dateModified\":\"2026-01-25T03:55:41+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/folhadems.com.br\/site\/2026\/01\/24\/aberto-o-primeiro-leilao-do-ano-do-detran-ms-com-vw-up-2015-e-honda-cg\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/folhadems.com.br\/site\/2026\/01\/24\/aberto-o-primeiro-leilao-do-ano-do-detran-ms-com-vw-up-2015-e-honda-cg\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/folhadems.com.br\/site\/2026\/01\/24\/aberto-o-primeiro-leilao-do-ano-do-detran-ms-com-vw-up-2015-e-honda-cg\/#primaryimage\",\"url\":\"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2026\/01\/up.jpg\",\"contentUrl\":\"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2026\/01\/up.jpg\",\"width\":730,\"height\":480},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/folhadems.com.br\/site\/2026\/01\/24\/aberto-o-primeiro-leilao-do-ano-do-detran-ms-com-vw-up-2015-e-honda-cg\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/folhadems.com.br\/site\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Aberto o primeiro leil\u00e3o do ano do Detran-MS com VW\/Up 2015 e Honda CG\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/folhadems.com.br\/site\/#website\",\"url\":\"https:\/\/folhadems.com.br\/site\/\",\"name\":\"Folha de Mato Grosso do Sul\",\"description\":\"Jornal Online\",\"publisher\":{\"@id\":\"https:\/\/folhadems.com.br\/site\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/folhadems.com.br\/site\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/folhadems.com.br\/site\/#organization\",\"name\":\"Folha de Mato Grosso do Sul\",\"url\":\"https:\/\/folhadems.com.br\/site\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/folhadems.com.br\/site\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2023\/01\/logo-folha-de-ms-380x90-1.jpg\",\"contentUrl\":\"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2023\/01\/logo-folha-de-ms-380x90-1.jpg\",\"width\":380,\"height\":90,\"caption\":\"Folha de Mato Grosso do Sul\"},\"image\":{\"@id\":\"https:\/\/folhadems.com.br\/site\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/folhadems.com.br\/site\/#\/schema\/person\/e4a04038e5c2e7040e19ef252ae9d940\",\"name\":\"Elite Midia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/folhadems.com.br\/site\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/f76a80f01119f7fec6909ab9feea8819031f391155be021b685479d77496f055?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/f76a80f01119f7fec6909ab9feea8819031f391155be021b685479d77496f055?s=96&d=mm&r=g\",\"caption\":\"Elite Midia\"},\"sameAs\":[\"https:\/\/folhadems.com.br\/site\"],\"url\":\"https:\/\/folhadems.com.br\/site\/author\/elite-midia\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Aberto o primeiro leil\u00e3o do ano do Detran-MS com VW\/Up 2015 e Honda CG - Folha de Mato Grosso do Sul","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/folhadems.com.br\/site\/2026\/01\/24\/aberto-o-primeiro-leilao-do-ano-do-detran-ms-com-vw-up-2015-e-honda-cg\/","og_locale":"pt_BR","og_type":"article","og_title":"Aberto o primeiro leil\u00e3o do ano do Detran-MS com VW\/Up 2015 e Honda CG - Folha de Mato Grosso do Sul","og_description":"O primeiro leil\u00e3o de 2026 do Detran-MS, sob responsabilidade do leiloeiro Carlos Ferrari, de ve\u00edculos de circula\u00e7\u00e3o, sucatas aproveit\u00e1veis e","og_url":"https:\/\/folhadems.com.br\/site\/2026\/01\/24\/aberto-o-primeiro-leilao-do-ano-do-detran-ms-com-vw-up-2015-e-honda-cg\/","og_site_name":"Folha de Mato Grosso do Sul","article_published_time":"2026-01-24T20:43:00+00:00","article_modified_time":"2026-01-25T03:55:41+00:00","og_image":[{"width":730,"height":480,"url":"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2026\/01\/up.jpg","type":"image\/jpeg"}],"author":"Elite Midia","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Elite Midia","Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/folhadems.com.br\/site\/2026\/01\/24\/aberto-o-primeiro-leilao-do-ano-do-detran-ms-com-vw-up-2015-e-honda-cg\/#article","isPartOf":{"@id":"https:\/\/folhadems.com.br\/site\/2026\/01\/24\/aberto-o-primeiro-leilao-do-ano-do-detran-ms-com-vw-up-2015-e-honda-cg\/"},"author":{"name":"Elite Midia","@id":"https:\/\/folhadems.com.br\/site\/#\/schema\/person\/e4a04038e5c2e7040e19ef252ae9d940"},"headline":"Aberto o primeiro leil\u00e3o do ano do Detran-MS com VW\/Up 2015 e Honda CG","datePublished":"2026-01-24T20:43:00+00:00","dateModified":"2026-01-25T03:55:41+00:00","mainEntityOfPage":{"@id":"https:\/\/folhadems.com.br\/site\/2026\/01\/24\/aberto-o-primeiro-leilao-do-ano-do-detran-ms-com-vw-up-2015-e-honda-cg\/"},"wordCount":301,"commentCount":0,"publisher":{"@id":"https:\/\/folhadems.com.br\/site\/#organization"},"image":{"@id":"https:\/\/folhadems.com.br\/site\/2026\/01\/24\/aberto-o-primeiro-leilao-do-ano-do-detran-ms-com-vw-up-2015-e-honda-cg\/#primaryimage"},"thumbnailUrl":"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2026\/01\/up.jpg","articleSection":["Cotidiano"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/folhadems.com.br\/site\/2026\/01\/24\/aberto-o-primeiro-leilao-do-ano-do-detran-ms-com-vw-up-2015-e-honda-cg\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/folhadems.com.br\/site\/2026\/01\/24\/aberto-o-primeiro-leilao-do-ano-do-detran-ms-com-vw-up-2015-e-honda-cg\/","url":"https:\/\/folhadems.com.br\/site\/2026\/01\/24\/aberto-o-primeiro-leilao-do-ano-do-detran-ms-com-vw-up-2015-e-honda-cg\/","name":"Aberto o primeiro leil\u00e3o do ano do Detran-MS com VW\/Up 2015 e Honda CG - Folha de Mato Grosso do Sul","isPartOf":{"@id":"https:\/\/folhadems.com.br\/site\/#website"},"primaryImageOfPage":{"@id":"https:\/\/folhadems.com.br\/site\/2026\/01\/24\/aberto-o-primeiro-leilao-do-ano-do-detran-ms-com-vw-up-2015-e-honda-cg\/#primaryimage"},"image":{"@id":"https:\/\/folhadems.com.br\/site\/2026\/01\/24\/aberto-o-primeiro-leilao-do-ano-do-detran-ms-com-vw-up-2015-e-honda-cg\/#primaryimage"},"thumbnailUrl":"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2026\/01\/up.jpg","datePublished":"2026-01-24T20:43:00+00:00","dateModified":"2026-01-25T03:55:41+00:00","breadcrumb":{"@id":"https:\/\/folhadems.com.br\/site\/2026\/01\/24\/aberto-o-primeiro-leilao-do-ano-do-detran-ms-com-vw-up-2015-e-honda-cg\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/folhadems.com.br\/site\/2026\/01\/24\/aberto-o-primeiro-leilao-do-ano-do-detran-ms-com-vw-up-2015-e-honda-cg\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/folhadems.com.br\/site\/2026\/01\/24\/aberto-o-primeiro-leilao-do-ano-do-detran-ms-com-vw-up-2015-e-honda-cg\/#primaryimage","url":"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2026\/01\/up.jpg","contentUrl":"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2026\/01\/up.jpg","width":730,"height":480},{"@type":"BreadcrumbList","@id":"https:\/\/folhadems.com.br\/site\/2026\/01\/24\/aberto-o-primeiro-leilao-do-ano-do-detran-ms-com-vw-up-2015-e-honda-cg\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/folhadems.com.br\/site\/"},{"@type":"ListItem","position":2,"name":"Aberto o primeiro leil\u00e3o do ano do Detran-MS com VW\/Up 2015 e Honda CG"}]},{"@type":"WebSite","@id":"https:\/\/folhadems.com.br\/site\/#website","url":"https:\/\/folhadems.com.br\/site\/","name":"Folha de Mato Grosso do Sul","description":"Jornal Online","publisher":{"@id":"https:\/\/folhadems.com.br\/site\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/folhadems.com.br\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/folhadems.com.br\/site\/#organization","name":"Folha de Mato Grosso do Sul","url":"https:\/\/folhadems.com.br\/site\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/folhadems.com.br\/site\/#\/schema\/logo\/image\/","url":"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2023\/01\/logo-folha-de-ms-380x90-1.jpg","contentUrl":"https:\/\/folhadems.com.br\/site\/wp-content\/uploads\/2023\/01\/logo-folha-de-ms-380x90-1.jpg","width":380,"height":90,"caption":"Folha de Mato Grosso do Sul"},"image":{"@id":"https:\/\/folhadems.com.br\/site\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/folhadems.com.br\/site\/#\/schema\/person\/e4a04038e5c2e7040e19ef252ae9d940","name":"Elite Midia","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/folhadems.com.br\/site\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/f76a80f01119f7fec6909ab9feea8819031f391155be021b685479d77496f055?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f76a80f01119f7fec6909ab9feea8819031f391155be021b685479d77496f055?s=96&d=mm&r=g","caption":"Elite Midia"},"sameAs":["https:\/\/folhadems.com.br\/site"],"url":"https:\/\/folhadems.com.br\/site\/author\/elite-midia\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-20 13:12:02","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/posts\/13835","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/comments?post=13835"}],"version-history":[{"count":1,"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/posts\/13835\/revisions"}],"predecessor-version":[{"id":13837,"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/posts\/13835\/revisions\/13837"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/media\/13836"}],"wp:attachment":[{"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/media?parent=13835"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/categories?post=13835"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/folhadems.com.br\/site\/wp-json\/wp\/v2\/tags?post=13835"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}